{"id":17131,"date":"2026-06-02T09:00:49","date_gmt":"2026-06-02T12:00:49","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=17131"},"modified":"2026-05-28T01:05:32","modified_gmt":"2026-05-28T04:05:32","slug":"como-lidar-com-a-frustracao-de-nao-conseguir-falar-ingles-fluentemente","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/17131\/","title":{"rendered":"Como lidar com a frustra\u00e7\u00e3o de \u00abn\u00e3o conseguir falar ingl\u00eas fluentemente\u00bb"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quem est\u00e1 aprendendo ingl\u00eas, provavelmente j\u00e1 esbarrou na mesma parede n\u00e3o apenas uma, mas duas vezes ou mais, n\u00e3o \u00e9 mesmo?! E, al\u00e9m disso, n\u00f3s tamb\u00e9m ficamos frequentemente frustrados com \u201cn\u00f3s mesmos, que n\u00e3o conseguimos falar ingl\u00eas com flu\u00eancia\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora todo mundo saiba que n\u00e3o se deve pensar assim, quando vemos pessoas ao nosso redor falando ingl\u00eas com flu\u00eancia, ainda assim n\u00e3o conseguimos evitar de nos comparar com elas e, com isso, acabamos ficando ainda mais frustrados\u2026.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Neste artigo, vamos apresentar justamente \u201cm\u00e9todos de Resposta para manter a motiva\u00e7\u00e3o de aprendizado quando estiver frustrado por <span style=\"font-size: 28px;\"><strong><span style=\"color: #008000;\">n\u00e3o conseguir falar ingl\u00eas com flu\u00eancia<\/span><\/strong><\/span>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>\u201cComparar\u201d \u00e9 f\u00e1cil de deixar a pessoa frustrada<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, vamos pensar: <strong><span style=\"color: #008000;\">\u201c<\/span><span style=\"color: #008000;\">por que quem aprende ingl\u00eas fica frustrado por n\u00e3o falar bem ingl\u00eas\u201d?<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como foi mencionado acima, as pessoas acabam, sem perceber, \u201cse comparando com outras\u201d. Se ao seu redor houver algu\u00e9m que domina o ingl\u00eas melhor do que voc\u00ea, ou se voc\u00ea vir estudantes intercambistas de outros pa\u00edses conseguindo usar o ingl\u00eas com mais liberdade, ent\u00e3o voc\u00ea pode sentir como se todo mundo tivesse dominado o ingl\u00eas muito bem\u2026<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando outra pessoa n\u00e3o consegue fazer algo, talvez a gente n\u00e3o se importe tanto, mas quando \u00e9 a gente que n\u00e3o consegue, passamos a sentir de forma bem concreta essa realidade frustrante e, em seguida, surge a ilus\u00e3o de que \u201cs\u00f3 eu n\u00e3o consigo\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E essa ilus\u00e3o, na verdade, n\u00e3o se limita ao aprendizado de ingl\u00eas; pode acontecer em qualquer \u00e1rea. Aqui, queremos lembrar voc\u00eas tamb\u00e9m para n\u00e3o procurarem \u201cpessoas que s\u00e3o piores do que voc\u00ea\u201d para se consolar e aumentar a pr\u00f3pria confian\u00e7a. Como cada pessoa tem um n\u00edvel de aprendizado, uma velocidade de progresso e um m\u00e9todo de estudo diferentes, comparar com outras pessoas n\u00e3o tem muito sentido. Pelo contr\u00e1rio, quando a gente procura deliberadamente \u201calgu\u00e9m que \u00e9 pior do que voc\u00ea\u201d, isso ainda pode intensificar o sentimento de inferioridade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Isso acontece porque, quando voc\u00ea tem esse h\u00e1bito de <strong><span style=\"color: #008000;\">\u201cse comparar\u201d<\/span><\/strong>, no subconsciente voc\u00ea passa a acreditar que \u201cos outros tamb\u00e9m acham que meu ingl\u00eas n\u00e3o \u00e9 bom\u201d. Portanto, para quem fica frustrado por n\u00e3o conseguir falar ingl\u00eas com flu\u00eancia, o mais importante \u00e9 \u201cparar de se comparar com outras pessoas\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, \u201cter expectativas demais sobre si mesmo\u201d tamb\u00e9m \u00e9 uma das causas da frustra\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se, no seu \u00edntimo, o seu \u201ceu ideal\u201d \u00e9 conseguir falar ingl\u00eas com flu\u00eancia como se fosse em portugu\u00eas, mas o seu eu atual est\u00e1 muito distante desse objetivo, isso tamb\u00e9m pode fazer voc\u00ea sentir frustra\u00e7\u00e3o com o ingl\u00eas. E at\u00e9, quando voc\u00ea fala travando, ou quando n\u00e3o sabe como expressar o que quer dizer, voc\u00ea pode at\u00e9 sentir culpa com a pessoa com quem est\u00e1 conversando.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, na verdade, para falar ingl\u00eas com flu\u00eancia, \u00e9 preciso acumular muita pr\u00e1tica. Essa parte n\u00f3s explicaremos em detalhes mais adiante, mas antes, pedimos que voc\u00eas entendam que o processo de aprender portugu\u00eas tamb\u00e9m passou por \u201cum tempo de estudo bastante longo\u201d e \u201cmuita pr\u00e1tica\u201d! Portanto, n\u00e3o conseguir falar ingl\u00eas com flu\u00eancia por um tempo \u00e9 algo totalmente normal. E j\u00e1 que o seu \u201cestado ideal\u201d \u00e9 \u201co objetivo final\u201d, ent\u00e3o n\u00e3o se compare com \u201co seu eu de agora\u201d em rela\u00e7\u00e3o ao \u201cseu eu do objetivo final\u201d, tudo bem?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, algumas pessoas tamb\u00e9m podem ficar frustradas por <strong><span style=\"color: #008000;\">\u201cn\u00e3o perceberem progresso\u201d<\/span><\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sobre isso, lembrem-se: \u201co progresso no ingl\u00eas \u00e9 muito lento!\u201d Por isso, \u00e9 dif\u00edcil perceber claramente que est\u00e1 melhorando em um curto per\u00edodo. Se voc\u00ea comparar o seu eu da semana passada com o seu eu de agora e n\u00e3o notar progresso, isso \u00e9 totalmente normal. Mas n\u00f3s acreditamos que, em algum dia, voc\u00ea pode perceber de repente: \u201ccomparado com antes, meu ingl\u00eas agora est\u00e1 mais fluente\u201d!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Mesmo quem \u00e9 \u201cavan\u00e7ado em ingl\u00eas\u201d enfrenta os mesmos problemas<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quando todo mundo <strong><span style=\"color: #008000;\">\u201cassiste a programas de TV em ingl\u00eas\u201d<\/span><\/strong> ou <strong><span style=\"color: #008000;\">\u201cde repente \u00e9 abordado falando em ingl\u00eas\u201d<\/span><\/strong>, mas fica frustrado porque n\u00e3o entende nada, vale a pena tentar entender a situa\u00e7\u00e3o de \u201cquem \u00e9 avan\u00e7ado em ingl\u00eas\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na verdade, mesmo quem consegue tirar facilmente 900 pontos no TOEIC n\u00e3o consegue entender completamente todos os programas de TV em ingl\u00eas ou o conte\u00fado de filmes. Como as conversas entre estrangeiros, al\u00e9m de terem uma \u201cvelocidade de fala alta\u201d, tamb\u00e9m costumam usar express\u00f5es \u201ct\u00edpicas do local\u201d, ou piadas relacionadas ao \u201ccontexto cultural\u201d, o que frequentemente faz com que todos os que n\u00e3o s\u00e3o nativos tenham dificuldade para entender.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, se forem obras audiovisuais como dramas de tribunal, dramas m\u00e9dicos\u2026 etc., o conte\u00fado pode estar cheio de \u201ctermos profissionais\u201d. Claro, a menos que voc\u00ea seja especialista nessa \u00e1rea, mesmo \u201cquem \u00e9 avan\u00e7ado em ingl\u00eas\u201d provavelmente ter\u00e1 bastante dificuldade para entender, n\u00e3o \u00e9 mesmo?!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, mesmo para quem \u00e9 avan\u00e7ado em ingl\u00eas, quando de repente algu\u00e9m fala com eles em ingl\u00eas, nem sempre eles conseguem entender imediatamente o que a outra pessoa disse. E, at\u00e9, se a aten\u00e7\u00e3o n\u00e3o estiver bem concentrada, pode acontecer de \u201cn\u00e3o conseguir identificar o conte\u00fado da outra pessoa\u201d, ou, sem estar psicologicamente preparado, surgir o fen\u00f4meno de \u201cachar que o ingl\u00eas soa especialmente dif\u00edcil\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas, na verdade, se voc\u00eas pensarem com calma, mesmo n\u00f3s<span style=\"color: #008000;\"><strong> \u201cfalantes nativos de<\/strong> portugu\u00eas\u201d<\/span>, quando assistimos \u00e0 TV, tamb\u00e9m temos momentos em que n\u00e3o entendemos ou em que, de repente, n\u00e3o ouvimos direito o que a outra pessoa disse, n\u00e3o \u00e9?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nessa hora, normalmente a gente diz \u201chein?\u201d e pede para a pessoa repetir. E quando esse tipo de situa\u00e7\u00e3o acontece em uma conversa em ingl\u00eas, na verdade, basta ter a mesma mentalidade e responder do mesmo jeito, t\u00e1?!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Entender que aprender ingl\u00eas leva tempo<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quando voc\u00eas aprendem portugu\u00eas, mesmo pessoas com muita habilidade no idioma precisam de \u201cquatro anos\u201d para conseguir se expressar completamente. E, mesmo para usar o portugu\u00eas com total flu\u00eancia em<strong><span style=\"color: #008000;\"> \u201cvocabul\u00e1rio\u201d<\/span><\/strong> e<strong><span style=\"color: #008000;\"> \u201ccapacidade de express\u00e3o\u201d<\/span><\/strong>, provavelmente \u00e9 preciso <strong><span style=\"color: #008000;\">\u201cmais de dez anos\u201d.<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mesmo que o c\u00e9rebro tenha alta plasticidade e comece a aprender portugu\u00eas desde a inf\u00e2ncia, se ainda assim for necess\u00e1rio tanto tempo para dominar, ent\u00e3o \u00e9 natural que \u201caprender ingl\u00eas\u201d tamb\u00e9m exija um tempo correspondente, certo?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, se compararmos n\u00f3s de hoje com n\u00f3s mesmos durante o aprendizado de portugu\u00eas, al\u00e9m de o desenvolvimento do c\u00e9rebro j\u00e1 estar mais maduro, a capacidade de aprender idiomas tamb\u00e9m \u00e9 muito mais forte do que na inf\u00e2ncia. Assim, desde que voc\u00eas consigam, \u201ccomo naquela \u00e9poca em que aprendiam portugu\u00eas\u201d, se manter por um longo per\u00edodo imersos no ambiente de ingl\u00eas, ent\u00e3o em \u201calguns anos\u201d \u00e9 poss\u00edvel usar ingl\u00eas com flu\u00eancia, ou at\u00e9 alcan\u00e7ar o objetivo em um ano \u2014 n\u00e3o \u00e9 imposs\u00edvel.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas aqui vai mais um lembrete: como cada pessoa tem tempos e energias diferentes para investir no aprendizado de ingl\u00eas, n\u00e3o se compare com o hist\u00f3rico ou o n\u00edvel de aprendizado de outras pessoas, t\u00e1?<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>O alvo da compara\u00e7\u00e3o deve ser \u201co seu eu do passado\u201d<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">No trecho acima, foi dito que <strong><span style=\"color: #008000;\">\u201ccomparar com outras pessoas\u201d<\/span><\/strong> \u00e9 f\u00e1cil de deixar a pessoa frustrada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando algu\u00e9m faz algo de forma insuficiente, normalmente n\u00e3o nos importamos tanto, mas quando n\u00f3s mesmos nos sa\u00edmos mal ou cometemos erros, percebemos claramente a sensa\u00e7\u00e3o de perda.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, \u00e9 f\u00e1cil surgir a ilus\u00e3o de que \u201cas pessoas ao meu redor parecem ser mais fortes do que eu\u201d. Mas a realidade de como \u00e9 n\u00e3o \u00e9 o mais importante. Embora muitos brasileiros (ou aprendizes) naturalmente tenham esse tipo de pensamento, na verdade \u201ca capacidade dos outros n\u00e3o tem rela\u00e7\u00e3o com a sua\u201d. Por isso, o verdadeiro alvo que devemos comparar n\u00e3o s\u00e3o os outros, e sim o \u00fanico que vale a pena comparar: \u201co seu eu do passado\u201d!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00eas podem tentar revisar \u201co seu eu do passado\u201d e ver em que ele \u00e9 diferente do \u201cseu eu de agora\u201d. Se voc\u00ea perceber que o progresso n\u00e3o foi como esperava, isso definitivamente n\u00e3o \u00e9 motivo para se sentir frustrado, porque \u00e9 uma oportunidade de encontrar uma solu\u00e7\u00e3o e pensar se voc\u00ea deve mudar o m\u00e9todo de estudo. Por outro lado, se voc\u00ea perceber que est\u00e1 melhorando, isso tamb\u00e9m tende a trazer mais tranquilidade. E, para no futuro conseguir entender claramente \u201cque voc\u00ea est\u00e1 crescendo\u201d, voc\u00ea tamb\u00e9m pode gravar suas conversas com um professor de ingl\u00eas online ou registrar sua pron\u00fancia com um gravador. Assim, quando voc\u00ea olhar para \u201co seu eu do passado\u201d, tamb\u00e9m conseguir\u00e1 sentir de forma mais intuitiva o seu progresso!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Aproveite a alegria de \u201cconseguir falar ingl\u00eas\u201d<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Mesmo que agora voc\u00eas ainda n\u00e3o consigam se expressar com flu\u00eancia, desde que continuem mantendo o h\u00e1bito de aprender ingl\u00eas, com certeza conseguir\u00e3o dizer algumas express\u00f5es em ingl\u00eas!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pedimos que voc\u00eas fiquem felizes com a ideia de <strong><span style=\"color: #008000;\">\u201cconseguir falar ingl\u00eas\u201d<\/span><\/strong>. Se voc\u00ea consegue falar ingl\u00eas, pode se comunicar com mais pessoas no mundo. Embora muitos pa\u00edses fora do Brasil tamb\u00e9m tenham muitas pessoas que n\u00e3o s\u00e3o boas em falar ingl\u00eas, ainda assim, o n\u00famero de pessoas que \u201cconseguem falar ingl\u00eas\u201d nesses pa\u00edses \u00e9 muito maior do que o n\u00famero de pessoas que \u201cconseguem falar portugu\u00eas\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, desde que voc\u00eas continuem tendo contato com o ingl\u00eas, mesmo que o progresso seja bem lento, voc\u00eas certamente v\u00e3o aumentando gradualmente a capacidade de \u201cfalar ingl\u00eas\u201d!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por favor, sintam muita alegria por \u201cfalar ingl\u00eas\u201d!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Resumo<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Todo mundo j\u00e1 ficou frustrado por n\u00e3o conseguir <span style=\"font-size: 28px;\"><strong><span style=\"color: #008000;\">\u201cfalar ingl\u00eas com flu\u00eancia\u201d<\/span><\/strong><\/span> como queria. Mas, na verdade, mesmo quem consegue falar com muita flu\u00eancia hoje j\u00e1 passou por essa fase.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esperamos que, mesmo que voc\u00eas sintam frustra\u00e7\u00e3o por um instante, consigam transform\u00e1-la em motiva\u00e7\u00e3o para aprender e em uma oportunidade para fortalecer a pr\u00f3pria for\u00e7a de vontade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ficar imerso em emo\u00e7\u00f5es negativas \u00e9 uma pena, porque um dia, com certeza, voc\u00eas conseguir\u00e3o usar ingl\u00eas com flu\u00eancia!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por favor, acompanhem a gente e aproveitem juntos o tempo de aprendizado de falar ingl\u00eas todos os dias, com essas metas em mente!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Quem est\u00e1 aprendendo ingl\u00eas, provavelmente j\u00e1 esbarrou na mesma parede n\u00e3o apenas uma, mas duas vezes ou mais, n\u00e3o \u00e9 mesmo?! E, al\u00e9m disso, n\u00f3s tamb\u00e9m ficamos frequentemente frustrados com \u201cn\u00f3s mesmos, que n\u00e3o conseguimos falar ingl\u00eas com flu\u00eancia\u201d. Embora todo mundo saiba que n\u00e3o se deve pensar assim, quando vemos pessoas ao nosso redor falando ingl\u00eas com flu\u00eancia, ainda assim n\u00e3o conseguimos evitar de nos comparar com elas e, com isso, acabamos ficando ainda mais frustrados\u2026. Neste artigo, vamos apresentar justamente \u201cm\u00e9todos de Resposta para manter a motiva\u00e7\u00e3o de aprendizado quando estiver frustrado por n\u00e3o conseguir falar ingl\u00eas com flu\u00eancia. &nbsp; \u201cComparar\u201d \u00e9 f\u00e1cil de deixar a pessoa &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/17131\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":17132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=17131","footnotes":""},"categories":[109,111,112],"tags":[],"class_list":["post-17131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-listening","category-exam","category-toeic","pt-BR"],"aioseo_notices":[],"views":88,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/17131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=17131"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/17131\/revisions"}],"predecessor-version":[{"id":17133,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/17131\/revisions\/17133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/17132"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=17131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=17131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=17131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}