{"id":16976,"date":"2026-05-29T09:00:50","date_gmt":"2026-05-29T12:00:50","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=16976"},"modified":"2026-05-22T02:10:51","modified_gmt":"2026-05-22T05:10:51","slug":"como-se-diz-que-chatice-em-ingles","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/16976\/","title":{"rendered":"Como se diz \u201cQue chatice\u201d em ingl\u00eas?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\u300cQue saco!\u300d\u00e9 uma express\u00e3o que se ouve com frequ\u00eancia no dia a dia. Ent\u00e3o, para estrangeiros, como eles costumam dizer isso?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na verdade, em ingl\u00eas n\u00e3o existe uma \u00fanica palavra ou frase espec\u00edfica para expressar \u201cque saco!\u201d. \u00c9 preciso escolher a forma correspondente de acordo com diferentes situa\u00e7\u00f5es. Em outras palavras, a tradu\u00e7\u00e3o de \u201cque saco!\u201d para o ingl\u00eas n\u00e3o \u00e9 apenas uma.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Neste artigo, vamos\u00a0<span style=\"color: #ff0000; font-size: 24px;\"> <strong>acompanhar muitos<\/strong><\/span><\/span><span style=\"color: #ff0000; font-size: 24px;\"><strong>exemplos de frases<\/strong><strong> para explicar em detalhes o uso de palavras e estruturas relacionadas a \u201cque saco!\u201d. Vamos conferir!<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Defini\u00e7\u00e3o de \u201cproblema\u201d<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Antes de entrar na explica\u00e7\u00e3o em ingl\u00eas, vamos pensar no que \u201cque saco!\u201d significa. Afinal, s\u00f3 entendendo com precis\u00e3o o sentido em portugu\u00eas \u00e9 que d\u00e1 para saber como transformar isso em ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No caso de \u201cproblema\u201d, o que isso representa \u00e9 \u201cter muitos passos ou ser muito dif\u00edcil, ent\u00e3o n\u00e3o d\u00e1 para executar com facilidade, ou ent\u00e3o fazer com que a pessoa nem queira come\u00e7ar\u201d. Em outras palavras, o foco est\u00e1 em \u201cn\u00e3o querer fazer\u201d, e n\u00e3o necessariamente em \u201cn\u00e3o saber fazer\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Introdu\u00e7\u00e3o de palavras para expressar \u201cproblema\u201d<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos ver quais s\u00e3o os usos de palavras relacionadas a \u201cproblema\u201d. Em geral, essas palavras s\u00e3o bem parecidas, mas ainda assim \u00e9 preciso distinguir com cuidado as diferen\u00e7as sutis de tom.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Troublesome<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">troublesome \u00e9 um adjetivo que significa\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201cchato, complicado, irritante\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O uso mais comum \u00e9 em situa\u00e7\u00f5es como \u201capesar de ainda estar dentro do que d\u00e1 para fazer, na hora de executar \u00e9 preciso gastar muito tempo e energia, ent\u00e3o parece um saco; n\u00e3o \u00e9 porque a pessoa \u00e9 pregui\u00e7osa e n\u00e3o quer fazer\u201d. Em vez de ser t\u00e3o\u00a0 \u201c<\/span><span style=\"color: #0000ff;\"><b>que saco!<\/b><span style=\"font-weight: 400;\">\u201d,\u00a0 tende mais a ser uma mentalidade de \u201cparece bem dif\u00edcil\u201d<\/span><span style=\"font-weight: 400;\">.<\/span><\/span><\/p>\n<h5><b>I have some troublesome tasks today.<\/b><br \/>\n<span style=\"font-weight: 400;\">Hoje tenho algumas tarefas bem complicadas para resolver.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>He is used to dealing with troublesome customers.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ele est\u00e1 acostumado a lidar com clientes dif\u00edceis.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Annoying<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">annoying \u00e9 um adjetivo que significa\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201cirritante, chato, que d\u00e1 trabalho\u201d<\/b><\/span><span style=\"font-weight: 400;\">. \u00c9 a forma de partic\u00edpio presente do verbo annoy.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O contexto mais comum \u00e9 quando \u201cas coisas n\u00e3o saem como a gente esperava, ent\u00e3o parece um saco\u201d. Ele \u00e9 um pouco diferente de troublesome; a principal diferen\u00e7a \u00e9 que\u00a0 <\/span><b><span style=\"color: #0000ff;\">annoying normalmente s\u00f3 \u00e9 usado em situa\u00e7\u00f5es negativas<\/span>.<\/b><\/p>\n<h5><b>I hate doing dishes. It\u2019s so annoying.<\/b><br \/>\n<span style=\"font-weight: 400;\">Lavar a lou\u00e7a \u00e9 um saco, ent\u00e3o eu odeio lavar a lou\u00e7a.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Everyone says he\u2019s annoying because he can\u2019t stop criticizing everything.<\/b><br \/>\n<span style=\"font-weight: 400;\">Todo mundo diz que ele \u00e9 irritante porque n\u00e3o consegue parar de criticar tudo.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Bothersome<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">bothersome \u00e9 um adjetivo que significa\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201cchato, irritante, que causa preocupa\u00e7\u00e3o\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O uso mais comum \u00e9 quando\u00a0 <\/span><span style=\"color: #0000ff;\"><b>\u201caparece uma tarefa mi\u00fada que incomoda por dentro, mas que ainda assim n\u00e3o d\u00e1 para deixar de fazer\u201d<\/b><\/span><span style=\"font-weight: 400;\">, como ir ao hospital para consultar, por exemplo. No sentido do tom, ele fica entre troublesome e annoying.<\/span><\/p>\n<h5><b>It&#8217;s bothersome to walk to the train station every morning.<\/b><br \/>\n<span style=\"font-weight: 400;\">Caminhar at\u00e9 a esta\u00e7\u00e3o de trem toda manh\u00e3 \u00e9 bem chato.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>I try to do bothersome things first.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu tento resolver primeiro as coisas chatas.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Tedious<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">tedious \u00e9 um adjetivo que significa <\/span><span style=\"color: #ff0000;\"><b>\u201cmon\u00f3tono e sem gra\u00e7a, ma\u00e7ante\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Outros usos que j\u00e1 aprendemos geralmente s\u00e3o por causa de \u201cser muito dif\u00edcil de lidar\u201d, ent\u00e3o a pessoa acha um saco; por\u00e9m, tedious \u00e9 um pouco diferente.\u00a0 <\/span><span style=\"color: #0000ff;\"><b>O contexto em que normalmente se usa essa palavra \u00e9 \u201cencarar algo que n\u00e3o interessa ou que exige tempo, e achar que n\u00e3o d\u00e1 nem vontade de fazer\u201d<\/b><span style=\"font-weight: 400;\">.<\/span><\/span><\/p>\n<h5><b>Preparing documents is a tedious task.<\/b><br \/>\n<span style=\"font-weight: 400;\">Preparar documentos \u00e9 um trabalho bem mon\u00f3tono.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>I think that going out with ladies is very tedious.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu n\u00e3o tenho nem um pouco de vontade de sair com garotas.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>He found a business dinner to be incredibly tedious.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ele achou aquele jantar de neg\u00f3cios extremamente ma\u00e7ante.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Inconvenient<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">inconvenient \u00e9 um adjetivo que significa\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201cinconveniente ou sem tempo para fazer algo\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Podemos entend\u00ea-lo como uma forma mais delicada de dizer \u201cparece um saco\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O conceito que essa palavra quer transmitir \u00e9\u00a0 <\/span><span style=\"color: #0000ff;\"><b>\u201cn\u00e3o d\u00e1 para encaixar no tempo, ent\u00e3o \u00e9 preciso ajustar o plano\u201d, ou ent\u00e3o \u201ca carga de trabalho aumentou, ent\u00e3o lidar com isso \u00e9 mais complicado\u201d, etc., e n\u00e3o porque a pessoa \u00e9 pregui\u00e7osa e acha um saco<\/b><\/span><span style=\"font-weight: 400;\"><span style=\"color: #0000ff;\">.<\/span>Em resumo, ele se aproxima mais do significado de troublesome.<\/span><\/p>\n<h5><b>This house is inconvenient to get around.<\/b><br \/>\n<span style=\"font-weight: 400;\">A circula\u00e7\u00e3o dentro desta casa n\u00e3o \u00e9 muito boa. (Mover-se por esta casa n\u00e3o \u00e9 muito conveniente)<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Frases em ingl\u00eas para \u201cQue chatice\u201d<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Ent\u00e3o, quais frases em ingl\u00eas podem ser usadas para expressar \u201cque saco!\u201d? Elas podem ter diferen\u00e7as de tom em rela\u00e7\u00e3o aos usos das palavras anteriores, ent\u00e3o podem ser usadas em conjunto.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>What a hassle!<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>What a hassle \u00e9 uma forma coloquial de dizer \u201cque saco!\u201d<\/b><span style=\"font-weight: 400;\">.<\/span><\/span><\/p>\n<p><span style=\"color: #0000ff;\"><b>hassle \u00e9 um substantivo, e significa \u201ccoisa chata, situa\u00e7\u00e3o ou circunst\u00e2ncia que causa inc\u00f4modo\u201d<\/b><span style=\"font-weight: 400;\">.<\/span><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Traduzindo literalmente, a frase inteira seria \u201cque saco!\u201d. O what \u00e9 usado como interjei\u00e7\u00e3o, equivalente ao \u201cverdadeiramente&#8230;\u201d ou \u201cque&#8230;\u201d em portugu\u00eas. Mas como \u00e9 uma forma coloquial, o melhor \u00e9 evitar dizer essa frase em situa\u00e7\u00f5es formais.<\/span><\/p>\n<h5><b>You need to clean up your room before dinner.<\/b><br \/>\n<b>Oh, what a hassle!<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea precisa arrumar seu quarto antes do jantar.<\/span><br \/>\n<span style=\"font-weight: 400;\">Ah\u2014que saco!<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>I can\u2019t be bothered.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>I can\u2019t be bothered \u00e9 adequado para situa\u00e7\u00f5es em que \u201cn\u00e3o tenho vontade, ent\u00e3o acho um saco\u201d, ou \u201cporque n\u00e3o tenho tempo para fazer algo, ent\u00e3o acho um saco\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"color: #0000ff;\"><b>bother \u00e9 um verbo transitivo, que significa \u201cdar trabalho para algu\u00e9m, fazer algu\u00e9m se sentir incomodado\u201d<\/b><\/span><span style=\"font-weight: 400;\">; sua forma no partic\u00edpio passado \u00e9 bothered. A explica\u00e7\u00e3o literal da frase \u00e9 \u201ceu n\u00e3o consigo ser incomodado\u201d, na verdade \u00e9 como dizer \u201ceu n\u00e3o tenho tempo para lidar com esses assuntos chatos\u201d.<\/span><\/p>\n<h5><b>I can\u2019t be bothered to go to the party tonight.<\/b><br \/>\n<span style=\"font-weight: 400;\">Hoje \u00e0 noite eu nem vou ao baile, que saco.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>It\u2019s a pain.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>It\u2019s a pain pode ser entendido literalmente como \u201c\u00e9 muito doloroso\u201d, mas tamb\u00e9m pode ser usado para dizer \u201cque saco!\u201d<\/b><\/span><span style=\"font-weight: 400;\">. No dia a dia, \u00e9 comum montar frases usando junto uma parte do corpo, por exemplo: It\u2019s a pain in the neck (meu pesco\u00e7o d\u00f3i), It\u2019s a pain in the butt (meu traseiro d\u00f3i).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas al\u00e9m de indicar dor f\u00edsica, tamb\u00e9m pode ser usado como met\u00e1fora para \u201ccansa\u00e7o mental, irrita\u00e7\u00e3o\u201d, ou seja,\u00a0 <\/span><span style=\"color: #0000ff;\"><b>ficar enjoado\/aborrecido com a necessidade de fazer algum ato<\/b><\/span><span style=\"font-weight: 400;\">. Quem diz essa frase normalmente acompanha com uma descri\u00e7\u00e3o objetiva, tentando buscar concord\u00e2ncia ao redor.<\/span><\/p>\n<h5><b>I love to travel but it\u2019s a pain to pack my bags.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu at\u00e9 gosto de viajar, mas s\u00f3 de pensar em arrumar as malas j\u00e1 acho um saco.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>It\u2019s too much trouble.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>It\u2019s too much trouble significa \u201c\u00e9 realmente muito chato\/um saco\u201d<\/b><\/span><span style=\"font-weight: 400;\">, e \u00e9 uma forma bem direta de se expressar. O alcance de uso dessa frase \u00e9 bem amplo; quase d\u00e1 para dizer que serve para qualquer situa\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso\u00a0 ,<\/span><span style=\"color: #0000ff;\"><b>\u00e9 uma forma mais liter\u00e1ria. Portanto, se voc\u00ea quiser pedir ajuda de forma educada, pode variar um pouco essa estrutura e reescrever como \u201cse n\u00e3o for um inc\u00f4modo demais&#8230;\u201d<\/b><\/span><span style=\"font-weight: 400;\">; veja o uso do exemplo 2.<\/span><\/p>\n<h5><b>It\u2019s too much trouble to drive there at night.<\/b><br \/>\n<span style=\"font-weight: 400;\">Dirigir at\u00e9 l\u00e1 \u00e0 noite \u00e9 realmente um saco.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>If it\u2019s not too much trouble, would you send me that file?<\/b><br \/>\n<span style=\"font-weight: 400;\">Se n\u00e3o for um inc\u00f4modo demais, voc\u00ea poderia me enviar aquele arquivo?<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>I don\u2019t have the energy for this.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>I don\u2019t have the energy for this significa \u201ceu realmente n\u00e3o tenho energia para lidar com isso\u201d<\/b><\/span><span style=\"font-weight: 400;\">. Em outras palavras, \u00e9 porque n\u00e3o tem disposi\u00e7\u00e3o\/energia para tratar, ent\u00e3o fica irritado; n\u00e3o \u00e9 por falta de tempo ou outros fatores objetivos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando essa frase \u00e9 usada na pr\u00e1tica, pode passar para as pessoas dois sentimentos extremos bem diferentes. Uma interpreta\u00e7\u00e3o \u00e9 que o falante est\u00e1 sugerindo que, por n\u00e3o estar bem fisicamente e n\u00e3o conseguir aguentar, est\u00e1 se desculpando; a outra \u00e9 que passa um tom negativo de\u00a0 <\/span><span style=\"color: #0000ff;\"><b>\u201ceu nem ligo para fazer esse tipo de coisa\u201d<\/b><\/span><span style=\"font-weight: 400;\">. Por isso, \u00e9 preciso ter cuidado ao considerar.<\/span><\/p>\n<h5><b>I don\u2019t have the energy for this farce.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu realmente n\u00e3o tenho \u00e2nimo para lidar com esse teatro.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Express\u00f5es em ingl\u00eas para \u201cCansa\u00e7o\u201d<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Depois de apresentar v\u00e1rias formas de dizer \u201cque saco!\u201d, vamos ver express\u00f5es em ingl\u00eas parecidas com o conceito de \u201cCansa\u00e7o\u201d (cansa\u00e7o\/apatia). Se voc\u00ea tratar esses usos com significados pr\u00f3ximos como um mesmo tema para aprender, isso ajuda na memoriza\u00e7\u00e3o e aumenta a efici\u00eancia do estudo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Dull<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>dull significa \u201clento, sem gra\u00e7a, mon\u00f3tono e sem interesse\u201d<\/b><\/span><span style=\"font-weight: 400;\">; \u00e9 um adjetivo.\u00a0 <\/span><span style=\"color: #0000ff;\"><b>dull pain significa \u201cdor surda\u201d, e a express\u00e3o a dull knife \u00e9 \u201cuma faca sem fio\u201d<\/b><span style=\"font-weight: 400;\">.<\/span><\/span><\/p>\n<h5><b>I had nothing to do and didn\u2019t feel like doing anything. It was such a dull weekend.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu n\u00e3o tinha nada para fazer e nem dava vontade de fazer qualquer coisa. Foi um fim de semana t\u00e3o sem gra\u00e7a.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Lazy<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>lazy significa \u201cpregui\u00e7oso, ap\u00e1tico, de pouca disposi\u00e7\u00e3o\u201d<\/b><\/span><span style=\"font-weight: 400;\">; \u00e9 um adjetivo.\u00a0 <\/span><span style=\"color: #0000ff;\"><b>Normalmente \u00e9 usado em contextos negativos, mas \u00e0s vezes tamb\u00e9m pode ser interpretado como \u201crelaxado, pregui\u00e7oso\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h5><b>I feel very lazy today.<\/b><br \/>\n<span style=\"font-weight: 400;\">Hoje eu estou com uma pregui\u00e7a danada.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>I love a lazy summer afternoon like this.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu adoro esse tipo de tarde de ver\u00e3o bem pregui\u00e7osa.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Sluggish<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>sluggish significa \u201clento, arrastado, com pouca agilidade\u201d<\/b><\/span><span style=\"font-weight: 400;\">;\u00a0 \u00e9 um adjetivo. Basta pensar que o substantivo slug significa \u201clesma\u201d, e fica f\u00e1cil entender aquela\u00a0 <\/span><span style=\"color: #0000ff;\"><b>cara de cansa\u00e7o, sem um pingo de energia<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h5><b>The pandas at the zoo were being sluggish all day.<\/b><br \/>\n<span style=\"font-weight: 400;\">As pandas do zool\u00f3gico ficaram o dia inteiro com aquela cara de pregui\u00e7a.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>He is kind of sluggish today because he got sick.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ele est\u00e1 meio sem energia hoje porque ficou doente.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Languid<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">languid tem um significado bem parecido com sluggish; ambos s\u00e3o usados para descrever cansa\u00e7o e falta de energia.<\/span><\/p>\n<p><span style=\"color: #ff0000;\"><b>Al\u00e9m de indicar \u201csensa\u00e7\u00e3o de cansa\u00e7o\u201d, tamb\u00e9m pode ser interpretado como \u201csem \u00e2nimo, sem vontade\u201d<\/b><\/span><span style=\"font-weight: 400;\">. Al\u00e9m disso, tamb\u00e9m pode ser usado para descrever\u00a0 <\/span><span style=\"color: #0000ff;\"><b>objetos que n\u00e3o sejam pessoas<\/b><\/span><span style=\"font-weight: 400;\">, como \u201cclima econ\u00f4mico ruim\u201d, \u201copera\u00e7\u00f5es fracas\u201d, etc.<\/span><\/p>\n<h5><b>I\u2019m not mad at you or anything. I\u2019m just feeling languid.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu n\u00e3o estou com raiva de voc\u00ea, n\u00e3o. Eu s\u00f3 estou cansado.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Lethargic<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>lethergic significa \u201csem \u00e2nimo, ap\u00e1tico, cansado\u201d<\/b><\/span><span style=\"font-weight: 400;\">; \u00e9 um adjetivo e costuma ser usado para indicar\u00a0 <\/span><span style=\"color: #0000ff;\"><b>um estado de exaust\u00e3o, como se a pessoa estivesse t\u00e3o cansada que mal consegue manter os olhos abertos<\/b><\/span><span style=\"font-weight: 400;\">. As causas para isso podem ser muitas: pode ser simplesmente porque a vida est\u00e1 entediante, ou pode ser por influ\u00eancia do tempo\/clima, deixando a pessoa prostrada.<\/span><\/p>\n<h5><b>I feel lethargic because I didn\u2019t get to eat breakfast.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu estou sem energia porque n\u00e3o consegui tomar caf\u00e9 da manh\u00e3.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Under the weather<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>under the weather \u00e9 uma express\u00e3o usada para dizer que a pessoa est\u00e1 passando mal fisicamente<\/b><\/span><span style=\"font-weight: 400;\">. Mas por que usar \u201cunder the weather\u201d (sob o tempo\/clima) para expressar \u201ccansa\u00e7o, mal-estar\u201d? Dizem que vem do h\u00e1bito de viajar de barco.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em geral, durante uma viagem, se a pessoa come\u00e7a a se sentir mal, ela vai para o por\u00e3o\/compartimento inferior do barco para descansar, evitando continuar exposta ao vento e ao sol, o que poderia piorar a situa\u00e7\u00e3o. Por isso, usa-se under the weather para indicar que o corpo est\u00e1 em recupera\u00e7\u00e3o. Por\u00e9m, com o passar do tempo, essa express\u00e3o ficou cada vez mais comum, e mesmo quem n\u00e3o est\u00e1 viajando de barco pode us\u00e1-la para dizer \u201cestou me sentindo mal\u201d.<\/span><\/p>\n<h5><b>I\u2019ve been under the weather all day.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu estou me sentindo mal o dia inteiro.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Unmotivated<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>motivated \u00e9 um adjetivo que significa \u201cmotivado\u201d. A forma negativa \u00e9 unmotivated, ou seja, \u201csem motiva\u00e7\u00e3o\u201d<\/b><\/span><span style=\"font-weight: 400;\">. Isso se refere a perder a motiva\u00e7\u00e3o ou o interesse por algo, e n\u00e3o tem rela\u00e7\u00e3o com o estado de sa\u00fade do corpo; \u00e9 mais voltado para a sensa\u00e7\u00e3o mental de cansa\u00e7o.<\/span><\/p>\n<h5><b>I feel unmotivated in my work these days.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ultimamente eu estou sem motiva\u00e7\u00e3o no trabalho.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Unproductive<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>unproductive significa \u201csem capacidade de produzir, com efici\u00eancia ruim\u201d<\/b><\/span><span style=\"font-weight: 400;\">, mas tamb\u00e9m pode ser traduzido como \u201ccansa\u00e7o\/apatia\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como a pessoa fica com sensa\u00e7\u00e3o de cansa\u00e7o, isso reduz a efici\u00eancia no trabalho, causando queda na produtividade. Por isso, d\u00e1 para entender unproductive como uma forma indireta de expressar cansa\u00e7o.<\/span><\/p>\n<h5><b>I\u2019m sleepy. I can tell I\u2019m being very unproductive.<\/b><br \/>\n<span style=\"font-weight: 400;\">Estou com sono; eu consigo perceber que agora minha produtividade est\u00e1 bem baixa.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Resumo<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Acredito que, depois de ler o artigo, voc\u00eas j\u00e1 devem ter entendido que em ingl\u00eas n\u00e3o existe apenas uma forma de dizer \u201cque saco!\u201d, certo? Embora esses usos tenham significados bem parecidos, ainda h\u00e1 mais detalhes a prestar aten\u00e7\u00e3o na aplica\u00e7\u00e3o pr\u00e1tica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, da pr\u00f3xima vez que voc\u00ea quiser dizer \u201cque saco!\u201d de forma espont\u00e2nea, vale a pena lembrar qual dessas formas \u00e9 mais adequada para aquela situa\u00e7\u00e3o. Se voc\u00ea repetir esse processo de aprendizado sem se incomodar, com certeza a impress\u00e3o vai ficando cada vez mais forte. Ao mesmo tempo, \u00e9 recomendado estudar junto com as aulas de conversa\u00e7\u00e3o do \u201cNativeCamp\u201d para aumentar as oportunidades de pr\u00e1tica; isso certamente vai fazer seu aprendizado de ingl\u00eas render muito mais. Vamos tentar!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u300cQue saco!\u300d\u00e9 uma express\u00e3o que se ouve com frequ\u00eancia no dia a dia. Ent\u00e3o, para estrangeiros, como eles costumam dizer isso? Na verdade, em ingl\u00eas n\u00e3o existe uma \u00fanica palavra ou frase espec\u00edfica para expressar \u201cque saco!\u201d. \u00c9 preciso escolher a forma correspondente de acordo com diferentes situa\u00e7\u00f5es. Em outras palavras, a tradu\u00e7\u00e3o de \u201cque saco!\u201d para o ingl\u00eas n\u00e3o \u00e9 apenas uma. Neste artigo, vamos\u00a0 acompanhar muitosexemplos de frases para explicar em detalhes o uso de palavras e estruturas relacionadas a \u201cque saco!\u201d. Vamos conferir! &nbsp; Defini\u00e7\u00e3o de \u201cproblema\u201d &nbsp; Antes de entrar na explica\u00e7\u00e3o em ingl\u00eas, vamos pensar no que \u201cque saco!\u201d significa. Afinal, s\u00f3 entendendo com precis\u00e3o &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/16976\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":16977,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=16976","footnotes":""},"categories":[139,140,133],"tags":[],"class_list":["post-16976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultural-exchange","category-study-abroad-nc","category-preparation-for-studying-abroad","pt-BR"],"aioseo_notices":[],"views":76,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=16976"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16976\/revisions"}],"predecessor-version":[{"id":16978,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16976\/revisions\/16978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/16977"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=16976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=16976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=16976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}