{"id":16535,"date":"2026-05-08T09:00:05","date_gmt":"2026-05-08T12:00:05","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=16535"},"modified":"2026-05-06T00:12:38","modified_gmt":"2026-05-06T03:12:38","slug":"%e3%80%90nao-e-so-focus%e3%80%91expressoes-em-ingles-relacionadas-a-concentracao-e-atencao","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/16535\/","title":{"rendered":"\u3010N\u00e3o \u00e9 s\u00f3 \u201cFocus\u201d!\u3011Express\u00f5es em ingl\u00eas relacionadas a \u201cconcentra\u00e7\u00e3o\u201d e \u201caten\u00e7\u00e3o\u201d!"},"content":{"rendered":"<p><strong>\u300cEstou me concentrando, n\u00e3o me interrompa\u300d<\/strong><\/p>\n<p><strong>\u300cConcentre-se no livro\uff01\u300d<\/strong><\/p>\n<p><strong>\u300cSua capacidade de concentra\u00e7\u00e3o n\u00e3o est\u00e1 l\u00e1 essas coisas\uff01\u300d<\/strong><\/p>\n<p><span style=\"font-weight: 400;\"><strong>\u00abConcentrar\u00bb\u00a0<\/strong> \u00e9 uma palavra que todo mundo usa com frequ\u00eancia nas conversas do dia a dia; portanto, talvez muitas pessoas j\u00e1 saibam que, em ingl\u00eas, ela \u00e9\u00a0<strong> \u00abfocus\u00bb<\/strong>, certo?!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas voc\u00ea sabia que, no mundo do ingl\u00eas, al\u00e9m de<strong> \u00abfocus\u00bb<\/strong>, existem muitas outras formas de expressar o portugu\u00eas <strong>\u00abConcentrar\u00bb<\/strong>?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nesta mat\u00e9ria, vamos organizar as formas em ingl\u00eas de<strong> \u00abconcentrar\u00bb<\/strong> e, al\u00e9m disso, explicar tamb\u00e9m como dizer<strong> \u00abcapacidade de foco\u00bb<\/strong> em ingl\u00eas. Espero de cora\u00e7\u00e3o que essas express\u00f5es ajudem voc\u00ea no seu aprendizado de ingl\u00eas!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Formas em ingl\u00eas de \u00abconcentrar\u00bb: parte dos substantivos<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, vamos apresentar as formas de \u00abconcentrar\u00bb como<strong> \u00absubstantivo\u00bb<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>\u00abConcentrar\u00bb<\/strong> em ingl\u00eas \u00e9<strong> \u00abconcentration\u00bb<\/strong>, e a pron\u00fancia\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, as defini\u00e7\u00f5es em dicion\u00e1rios ingl\u00eas-portugu\u00eas s\u00e3o as seguintes:<\/span><\/p>\n<h5><b>significado de concentration<\/b><br \/>\n<b>substantivo: (concentra\u00e7\u00e3o mental, aten\u00e7\u00e3o, esfor\u00e7o etc.) concentra\u00e7\u00e3o, foco, dedica\u00e7\u00e3o <\/b><br \/>\n<b>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0(concentra\u00e7\u00e3o de muitas coisas) concentra\u00e7\u00e3o, aglomera\u00e7\u00e3o<\/b><\/h5>\n<p><span style=\"font-weight: 400;\">Como visto acima, \u00abconcentration\u00bb se refere ao estado de \u00abestar focado em algo espec\u00edfico\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos ver algumas formas pr\u00e1ticas de<strong> \u00abconcentration\u00bb<\/strong> e exemplos de frases:<\/span><\/p>\n<h5><b>Lack of concentration<\/b><b><br \/>\n<\/b><b>falta de aten\u00e7\u00e3o<\/b><br \/>\n<b>My lack of concentration affected my exam.<\/b><br \/>\n<span style=\"font-weight: 400;\">A minha falta de aten\u00e7\u00e3o afetou a prova.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Break concentration<\/b><b><br \/>\n<\/b><b>interromper a aten\u00e7\u00e3o<\/b><br \/>\n<b>He broke my concentration.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ele interrompeu a minha aten\u00e7\u00e3o.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Deep concentration<\/b><b><br \/>\n<\/b><b>concentra\u00e7\u00e3o total, foco profundo<\/b><br \/>\n<b>I achieved deep concentration during my meditation.<\/b><br \/>\n<span style=\"font-weight: 400;\">Durante a minha medita\u00e7\u00e3o, alcancei um estado de foco profundo.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Maintain concentration<\/b><b><br \/>\n<\/b><b>manter a aten\u00e7\u00e3o concentrada<\/b><br \/>\n<b>I struggled to maintain concentration during the meeting.<\/b><br \/>\n<span style=\"font-weight: 400;\">Foi dif\u00edcil manter a aten\u00e7\u00e3o concentrada durante a reuni\u00e3o.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Keep concentration<\/b><b><br \/>\n<\/b><b>manter a aten\u00e7\u00e3o concentrada<\/b><br \/>\n<b>During the exam, it&#8217; important to keep concentration.<\/b><br \/>\n<span style=\"font-weight: 400;\">Durante a prova, \u00e9 importante manter a aten\u00e7\u00e3o concentrada.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Formas em ingl\u00eas de \u00abconcentrar\u00bb: parte dos verbos<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><strong>As express\u00f5es verbais<\/strong> de \u00abconcentrar\u00bb t\u00eam as seguintes seis op\u00e7\u00f5es:<\/span><\/p>\n<h5><b>\u30fbfocus<\/b><br \/>\n<b>\u30fbconcentrate<\/b><br \/>\n<b>\u30fbfix on <\/b><br \/>\n<b>\u30fbapply oneself<\/b><br \/>\n<b>\u30fblock in<\/b><br \/>\n<b>\u30fbget stuck into<\/b><\/h5>\n<p><span style=\"font-weight: 400;\">A seguir, vamos analisar uma a uma as nuances de significado e as formas de uso desses \u00abverbos\u00bb. Por favor, n\u00e3o se esque\u00e7am delas!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Focus<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><strong>\u00abfocus\u00bb<\/strong> tem a pron\u00fancia e significa \u00abconcentrar a aten\u00e7\u00e3o em algo espec\u00edfico ou em uma atividade\u00bb.<\/span><\/p>\n<h5><b>significado de focus<\/b><br \/>\n<b>verbo: fazer com que (aten\u00e7\u00e3o, interesse etc.) fique concentrado<\/b><\/h5>\n<p><span style=\"font-weight: 400;\">Quando quiser expressar<strong> \u00abestar focado em algo\u00bb<\/strong>, voc\u00ea pode usar \u00abfocus on\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Agora, vamos ver exemplos concretos de frases com \u00abfocus\u00bb!<\/span><\/p>\n<h5><b>Let&#8217; focus on finding a solution to the problem.<\/b><br \/>\n<span style=\"font-weight: 400;\">Vamos nos concentrar em encontrar uma solu\u00e7\u00e3o para o problema.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>I need to focus on completing the project before the deadline.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu preciso me concentrar em concluir este projeto antes do prazo.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>concentrate<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O<strong> \u00abconcentrate\u00bb<\/strong>, com pron\u00fancia, tamb\u00e9m pode representar<strong> \u00abconcentrar\u00bb<\/strong>, mas \u00e9 um pouco diferente de \u00abfocus\u00bb.<\/span><\/p>\n<h5><b>significado de concentrate<\/b><br \/>\n<b>verbo: concentrar a aten\u00e7\u00e3o ou o esfor\u00e7o em algo<\/b><\/h5>\n<p><span style=\"font-weight: 400;\">Quando<strong> \u00abestiver focado em algo\u00bb<\/strong>, voc\u00ea pode usar \u00abconcentrate on\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora \u00abfocus\u00bb e \u00abconcentrate\u00bb possam ser usados basicamente na mesma situa\u00e7\u00e3o, as duas express\u00f5es t\u00eam diferen\u00e7as sutis de significado. Por exemplo, o<strong> \u00abfocus\u00bb<\/strong> traz a ideia de \u00abescolher uma op\u00e7\u00e3o entre v\u00e1rias para concentrar a aten\u00e7\u00e3o\u00bb, enquanto o<strong> \u00abconcentrate\u00bb<\/strong> traz uma forte ideia de \u00abconcentrar toda a aten\u00e7\u00e3o em um ponto\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ou seja, o<strong> \u00abconcentrate\u00bb<\/strong> tem mais a ideia forte de \u00abconsci\u00eancia de esfor\u00e7o\u00bb do que o<strong> \u00abfocus\u00bb<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos ver exemplos em ingl\u00eas de<strong> \u00abconcentrate\u00bb<\/strong>!<\/span><\/p>\n<h5><b>He needs to concentrate on his studies if he wants to pass the exam.<\/b><br \/>\n<span style=\"font-weight: 400;\">Se ele quiser passar na prova, ele precisa<\/span><span style=\"font-weight: 400;\">se concentrar (direcionar a aten\u00e7\u00e3o) em<\/span><span style=\"font-weight: 400;\">estudos.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Fix<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><strong>\u00abfix\u00bb<\/strong> tamb\u00e9m pode representar<strong> \u00abconcentrar\u00bb<\/strong>.<\/span><\/p>\n<h5><b>significado de fix<\/b><br \/>\n<b>verbo intransitivo: concentrar a aten\u00e7\u00e3o em algo<\/b><\/h5>\n<p><span style=\"font-weight: 400;\"><strong>\u00abfix\u00bb<\/strong> \u00e9 usado em situa\u00e7\u00f5es em que a aten\u00e7\u00e3o \u00e9 direcionada para um \u00abalvo espec\u00edfico ou um problema\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir est\u00e3o exemplos em ingl\u00eas.<\/span><\/p>\n<h5><b>Let&#8217; fix on finding a solution to the problem.<\/b><br \/>\n<span style=\"font-weight: 400;\">Vamos nos concentrar em encontrar uma solu\u00e7\u00e3o para o problema.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>apply oneself<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><strong>\u00abapply oneself\u00bb<\/strong> significa<strong> \u00abse dedicar ao m\u00e1ximo, se empenhar\u00bb<\/strong> e \u00e9 usado em situa\u00e7\u00f5es em que \u00e9 preciso \u00abse esfor\u00e7ar\u00bb para se dedicar ao estudo, ao trabalho ou a esportes etc.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos ver exemplos em ingl\u00eas!<\/span><\/p>\n<h5><b>You need to apply yourself more if you want to succeed in your career.<\/b><br \/>\n<span style=\"font-weight: 400;\">Se voc\u00ea quer ter sucesso no ambiente de trabalho, precisa se dedicar mais ao esfor\u00e7o.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>I realized that I needed to apply myself to improve my skills in programming.<\/b><br \/>\n<span style=\"font-weight: 400;\">Percebi que eu precisava me dedicar para melhorar minhas habilidades em programa\u00e7\u00e3o.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Lock in<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><strong>\u00ablock in\u00bb<\/strong> originalmente significa \u00abtrancar\u00bb, mas na fala do dia a dia tamb\u00e9m pode significar<strong> \u00abse concentrar em algo\u00bb<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, como \u00ablock in\u00bb \u00e9 uma express\u00e3o mais informal, ela combina mais com conversas em ingl\u00eas do cotidiano!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos ver exemplos em ingl\u00eas!<\/span><\/p>\n<h5><b>I need to lock in and work.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu preciso me concentrar no trabalho.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Get stuck into<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><strong>\u00abget stuck into\u00bb<\/strong> \u00e9 uma express\u00e3o informal que significa \u00abcome\u00e7ar a fazer com muita empolga\u00e7\u00e3o, come\u00e7ar com bastante disposi\u00e7\u00e3o\u00bb e \u00e9 comumente usada em situa\u00e7\u00f5es de \u00abse dedicar ao m\u00e1ximo ao trabalho ou a um projeto\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos ver exemplos em ingl\u00eas.<\/span><\/p>\n<h5><b>I&#8217; going to<\/b><b> get stuck into this project and finish it by tomorrow.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu vou me dedicar ao m\u00e1ximo a este projeto e termin\u00e1-lo at\u00e9 amanh\u00e3.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Once I have my coffee, <\/b><b>I&#8217; get stuck into cleaning the room.<\/b><br \/>\n<span style=\"font-weight: 400;\">Depois que eu tomar meu caf\u00e9, eu vou come\u00e7ar a limpar o quarto com tudo.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>V\u00e1rias formas de expressar \u00abconcentrar\u00bb<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos apresentar duas express\u00f5es relacionadas a \u00abconcentrar\u00bb.<\/span><\/p>\n<h5><b>\u30fbtime to concentrate\uff1adar uma concentrada na aten\u00e7\u00e3o<\/b><br \/>\n<b>\u30fbboot camp\uff1atreinamento intensivo de curto prazo<\/b><\/h5>\n<p><span style=\"font-weight: 400;\">A seguir, vamos entender como us\u00e1-las por meio de exemplos!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>time to concentrate<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u00c0s vezes, quando queremos dizer a n\u00f3s mesmos ou \u00e0s crian\u00e7as<strong> \u00abconcentre-se um pouco!\u00bb<\/strong>, podemos usar<strong> \u00abtime to concentrate\u00bb<\/strong>, uma express\u00e3o bem adequada. Nesse caso, <strong>\u00abtime to concentrate\u00bb<\/strong> \u00e9 uma tradu\u00e7\u00e3o literal de<strong> \u00ab\u00e9 hora de se concentrar\u00bb<\/strong> e significa<strong> \u00abdar uma concentrada na aten\u00e7\u00e3o!\u00bb<\/strong><\/span>.<\/p>\n<p><span style=\"font-weight: 400;\">Ela \u00e9 usada em situa\u00e7\u00f5es como \u00abantes de uma prova, antes de come\u00e7ar um trabalho importante\u00bb e tamb\u00e9m pode ser usada quando voc\u00ea quer \u00ablembrar a si mesmo\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos confirmar como usar isso com exemplos em ingl\u00eas!<\/span><\/p>\n<h5><b>A: Are you ready for the big presentation tomorrow?<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea est\u00e1 pronto para a grande apresenta\u00e7\u00e3o de amanh\u00e3?<\/span><br \/>\n<b>B: Not yet, but I&#8217; set aside some time tonight. It&#8217; time to concentrate!<\/b><br \/>\n<span style=\"font-weight: 400;\">Ainda n\u00e3o, mas eu separei um tempo esta noite. \u00c9 hora de se concentrar!<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Boot camp\uff1atreinamento intensivo de curto prazo<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><strong>\u00abboot camp\u00bb pode ser usado para representar \u00abtreinamento intensivo de curto prazo\u00bb.<\/strong><\/p>\n<p><span style=\"font-weight: 400;\"><strong>\u00abboot camp\u00bb<\/strong> originalmente significa<strong> \u00abtreinamento para recrutas\u00bb<\/strong>. Como o treinamento militar \u00e9 curto e tem alta intensidade, essa express\u00e3o tamb\u00e9m \u00e9 frequentemente usada para se referir a \u00abum plano de treinamento intensivo de curto prazo para aprimorar alguma habilidade ou atingir um objetivo\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, <strong>boot camp de fitness (fitness boot camp) ou boot camp de neg\u00f3cios (business boot camp)<\/strong>, etc.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos ver exemplos em ingl\u00eas!<\/span><\/p>\n<h5><b>I enrolled in a two-week boot camp to improve my English skills.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu me inscrevi em um boot camp intensivo de duas semanas para melhorar minhas habilidades em ingl\u00eas.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Como dizer \u00abcapacidade de foco\u00bb em ingl\u00eas?<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Por fim, vamos apresentar algumas formas de expressar \u00abcapacidade de foco\u00bb em ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre elas, as formas b\u00e1sicas em ingl\u00eas de \u00abcapacidade de foco\u00bb s\u00e3o:<\/span><\/p>\n<p><b>Concentration skills<\/b><\/p>\n<h5><b>You have good concentration skills.<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea tem boa capacidade de foco.<\/span><\/h5>\n<p><b>One&#8217; ability to concentrate<\/b><\/p>\n<h5><b>Her ability to concentrate is remarkable.<\/b><br \/>\n<span style=\"font-weight: 400;\">A capacidade de foco dela \u00e9 impressionante.<\/span><\/h5>\n<p><b>Powers of concentration<\/b><\/p>\n<h5><b>Her powers of concentration allowed her to complete the task quickly and accurately.<\/b><br \/>\n<span style=\"font-weight: 400;\">A capacidade de foco dela permitiu que ela conclu\u00edsse a tarefa rapidamente e com precis\u00e3o.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Como existem muitas formas de expressar \u00abcapacidade de foco\u00bb em ingl\u00eas, voc\u00ea pode escolher algumas frases que ache f\u00e1ceis de memorizar ou que considere \u00fateis para guardar de vez.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Resumo das express\u00f5es em ingl\u00eas de \u00abconcentrar\u00bb<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Nesta mat\u00e9ria, apresentamos v\u00e1rias formas de<strong> \u00abconcentrar\u00bb<\/strong> em ingl\u00eas. Por favor, n\u00e3o se esque\u00e7am delas!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, se voc\u00eas quiserem praticar essas express\u00f5es em conversas reais, recomendamos que voc\u00eas experimentem o curso de ingl\u00eas online do<strong> \u00abNative Camp\u00bb<\/strong>. Como o curso n\u00e3o tem limite de vezes, isso d\u00e1 a voc\u00eas mais oportunidades de usar o ingl\u00eas de verdade para praticar a produ\u00e7\u00e3o. Inclusive, agora tamb\u00e9m h\u00e1 uma aula experimental gratuita! Por favor, n\u00e3o deixem de experimentar!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u300cEstou me concentrando, n\u00e3o me interrompa\u300d \u300cConcentre-se no livro\uff01\u300d \u300cSua capacidade de concentra\u00e7\u00e3o n\u00e3o est\u00e1 l\u00e1 essas coisas\uff01\u300d \u00abConcentrar\u00bb\u00a0 \u00e9 uma palavra que todo mundo usa com frequ\u00eancia nas conversas do dia a dia; portanto, talvez muitas pessoas j\u00e1 saibam que, em ingl\u00eas, ela \u00e9\u00a0 \u00abfocus\u00bb, certo?! Mas voc\u00ea sabia que, no mundo do ingl\u00eas, al\u00e9m de \u00abfocus\u00bb, existem muitas outras formas de expressar o portugu\u00eas \u00abConcentrar\u00bb? Nesta mat\u00e9ria, vamos organizar as formas em ingl\u00eas de \u00abconcentrar\u00bb e, al\u00e9m disso, explicar tamb\u00e9m como dizer \u00abcapacidade de foco\u00bb em ingl\u00eas. Espero de cora\u00e7\u00e3o que essas express\u00f5es ajudem voc\u00ea no seu aprendizado de ingl\u00eas! &nbsp; Formas em ingl\u00eas de \u00abconcentrar\u00bb: parte dos &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/16535\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":16652,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=16535","footnotes":""},"categories":[118,122,121],"tags":[],"class_list":["post-16535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-study-abroad","category-pronunciation","category-words","pt-BR"],"aioseo_notices":[],"views":94,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=16535"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16535\/revisions"}],"predecessor-version":[{"id":16537,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16535\/revisions\/16537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/16652"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=16535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=16535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=16535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}