{"id":16313,"date":"2026-04-24T09:00:57","date_gmt":"2026-04-24T12:00:57","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=16313"},"modified":"2026-04-20T22:47:30","modified_gmt":"2026-04-21T01:47:30","slug":"o-significado-e-como-usar-kudos-situacoes-em-que-se-aplica-na-giria-e-pontos-a-serem-observados","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/16313\/","title":{"rendered":"O significado e como usar \u201ckudos\u201d! Situa\u00e7\u00f5es em que se aplica na g\u00edria e pontos a serem observados"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Todo mundo sabe o que significa, em g\u00edrias, ouvir<span style=\"font-size: 32px;\"><strong><span style=\"color: #ff6600;\"> \u00abkudos\u00bb?<\/span><\/strong><\/span><\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00abkudos\u00bb vem do grego e \u00e9 pronunciado como \u00ab<\/span><span style=\"font-weight: 400;\">\/\u02c8ku\u02d0.d\u0251\u02d0s\/<\/span><span style=\"font-weight: 400;\">\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos aprender o significado, como usar e em quais situa\u00e7\u00f5es ele se aplica!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>O significado de \u00abkudos\u00bb<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, \u00abkudos\u00bb \u00e9 um<strong><span style=\"color: #ff0000;\"> \u00absubstantivo incont\u00e1vel\u00bb<\/span><\/strong>; portanto, n\u00e3o \u00e9 a forma plural de \u00abkudo\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, as frases abaixo s\u00e3o um uso incorreto:<\/span><\/p>\n<p><span style=\"color: #ff0000;\"><b>\uff08Erro\uff09He received many kudos for his work.<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">O correto seria: \u00e9 preciso usar \u00abmuch\u00bb para acompanhar um <span style=\"font-weight: 400;\">substantivo incont\u00e1vel<\/span>.\u3000<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"color: #0000ff;\"><b>\uff08Correto\uff09He received much kudos for his work.<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, a origem de \u00abkudos\u00bb vem do grego que representa<strong><span style=\"color: #ff0000;\"> \u00abpraise\uff08<\/span><\/strong><\/span><strong><span style=\"color: #ff0000;\">elogio, admira\u00e7\u00e3o\uff09\u300d<\/span><\/strong> ou \u00abrenown\uff08fama, honra<span style=\"font-weight: 400;\"><span style=\"color: #000000;\"><strong>\uff09\u300d<\/strong><\/span>\u00bb. Por isso, o significado que \u00abkudos\u00bb representa em ingl\u00eas \u00e9 quase o mesmo dessas palavras e, em geral, \u00e9 usado em situa\u00e7\u00f5es positivas ap\u00f3s elogiar algu\u00e9m por \u00abter se esfor\u00e7ado e conclu\u00eddo algo\u00bb, ou por \u00abter enfrentado algo corajosamente\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, como \u00abkudos\u00bb carrega um forte sentido de \u00abelogio\u00bb, quando as pessoas o usam em conversas cotidianas, pode fazer o ouvinte sentir que voc\u00ea est\u00e1 \u00abum pouco fazendo pose\u00bb. Assim, na pr\u00e1tica, \u00abkudos\u00bb aparece com mais frequ\u00eancia em trocas de texto como SNS e e-mails do que em fala do dia a dia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o \u00e9 verdade que, ao pensar no que mencionamos acima sobre \u00abfazer pose\u00bb, isso faz voc\u00eas acharem que talvez n\u00e3o seja t\u00e3o seguro usar \u00abkudos\u00bb?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ent\u00e3o, a seguir, vamos ver juntos como usar \u00abkudos\u00bb de forma adequada e em quais situa\u00e7\u00f5es ele se aplica!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Como usar \u00abkudos\u00bb<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, vamos pensar com quais palavras \u00abkudos\u00bb pode ser combinado!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>kudos to + pessoa (inclui grupos, organiza\u00e7\u00f5es etc.)<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Basicamente, \u00abkudos to + pessoa\u00bb pode ser entendido como<strong><span style=\"color: #ff0000;\">\u00a0 \u00abelogiar algu\u00e9m ou um grupo\u00bb<\/span><\/strong>.<\/span><\/p>\n<h5><b>Kudos to you!<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu te elogio = Voc\u00ea \u00e9 demais! Parab\u00e9ns!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">O uso de \u00abkudos to + pessoa\u00bb \u00e9 parecido com \u00abSr. A, Bravo!\u00bb ou \u00abAplaudam o Sr. A!\u00bb, e em um contexto americano mais descontra\u00eddo, significa algo como \u00abParab\u00e9ns!\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, um YouTuber de aprendizado de ingl\u00eas, em seus v\u00eddeos, incentiva os alunos a gravarem a pr\u00f3pria pron\u00fancia para melhorar a fala:<\/span><\/p>\n<h5><b>You can repeat the word while recording me and yourself. And then, see if the pronunciation is the same. If it is, kudos to you! You are doing great.<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea pode repetir a palavra enquanto grava a minha voz e a sua. Depois, veja se a pron\u00fancia \u00e9 a mesma. Se for, ent\u00e3o parab\u00e9ns! Voc\u00ea est\u00e1 indo muito bem!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, durante a COVID-19 (pandemia do novo coronav\u00edrus), as redes sociais tamb\u00e9m mostravam com frequ\u00eancia frases assim:<\/span><\/p>\n<h5><b>Kudos to all our frontline healthcare workers!<\/b><br \/>\n<span style=\"font-weight: 400;\">Homenagem a todos os profissionais de sa\u00fade da linha de frente!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Nessa frase, a diferen\u00e7a entre \u00abkudos to ~\u00bb e \u00abthanks to ~ (obrigado)\u00bb \u00e9 que \u00abkudos to ~\u00bb traz um sentido de \u00abrespeito\u00bb e \u00abadmira\u00e7\u00e3o\u00bb ainda maior.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ou ent\u00e3o, quando todos querem expressar de forma mais \u00abespec\u00edfica\u00bb o \u00abelogio dado por alguma a\u00e7\u00e3o ou m\u00e9rito\u00bb, podem usar<strong><span style=\"color: #0000ff;\"> \u00abkudos to + pessoa + for + a\u00e7\u00e3o\u00bb<\/span><\/strong> para demonstrar isso.<\/span><\/p>\n<h5><b>Kudos to everyone for working together. It&#8217;s pretty awesome.<\/b><br \/>\n<span style=\"font-weight: 400;\">Homenagem a todos que trabalharam juntos. Isso \u00e9 muito incr\u00edvel!<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>kudos for + a\u00e7\u00e3o \/ coisa<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00eas provavelmente veem ocasionalmente na internet o uso de \u00abkudos for + pessoa\u00bb! Embora n\u00e3o possamos dizer que esteja totalmente errado, em geral, o foco dessa estrutura deve ser \u00abuma certa a\u00e7\u00e3o\u00bb ou \u00abuma certa coisa\u00bb.<\/span><\/p>\n<h5><b>Kudos for your hard work!<\/b><br \/>\n<span style=\"font-weight: 400;\">Homenagem ao seu esfor\u00e7o!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Essa frase passa a sensa\u00e7\u00e3o de \u00abVoc\u00ea realmente se esfor\u00e7ou!\u00bb, e normalmente<strong><span style=\"color: #ff0000;\"> \u00ab\u00e9 usada entre amigos ou como incentivo de um chefe para um subordinado\u00bb<\/span><\/strong>.<\/span><\/p>\n<h5><b>Kudos for a research-based lecture!<\/b><br \/>\n<span style=\"font-weight: 400;\">Homenagem a essa palestra baseada em pesquisa!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Os exemplos acima s\u00e3o adequados para voc\u00eas publicarem seus coment\u00e1rios sobre a palestra ou apresenta\u00e7\u00e3o em SNS, ou ent\u00e3o para expressar respeito por essa palestra em um e-mail.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Sujeito + deserve kudos<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quando \u00abkudos\u00bb \u00e9 usado como \u00absubstantivo\u00bb, ele pode ser combinado com o verbo \u00abdeserve (merecer)\u00bb.<\/span><\/p>\n<h5><b>She deserves this prize.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ela merece esse pr\u00eamio.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">J\u00e1<strong> \u00absujeito + deserve + kudos (substantivo)\u00bb<\/strong> significa<strong><span style=\"color: #ff0000;\"> \u00ab merece receber elogios\u00bb ou \u00ab merece receber honrarias\u00bb<\/span><\/strong>.<\/span><\/p>\n<h5><b>Bridget deserves huge kudos because she worked so hard during the days.<\/b><br \/>\n<span style=\"font-weight: 400;\">A Bridget merece muitos elogios, porque ela se esfor\u00e7ou muito nesses dias.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Inclusive, manchetes de not\u00edcias tamb\u00e9m podem usar esse tipo de express\u00e3o.<\/span><\/p>\n<h5><b>Everyone deserves kudos after a difficult school year.<\/b><br \/>\n<span style=\"font-weight: 400;\">Depois de um ano letivo dif\u00edcil, todo mundo merece ser elogiado.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Devido ao impacto da COVID-19 (pandemia do novo coronav\u00edrus), muitos estudantes enfrentaram a impossibilidade de ir \u00e0 escola ou tiveram, de repente, que adotar um novo modelo de ensino online. Por isso, a frase acima \u00e9 especialmente adequada para elogiar os alunos que se esfor\u00e7aram para estudar durante a pandemia.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Sujeito + get kudos<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff0000;\">Aqui, ao substituir \u00abdeserve\u00bb por \u00abget\u00bb, d\u00e1 para expressar o sentido de \u00abobter fama\u00bb.<\/span><\/strong><\/p>\n<h5><b>She should get great kudos for being a perfect expert.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ela deve obter uma grande fama por ser uma especialista perfeita.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Ou ent\u00e3o, \u00abela deve obter uma grande admira\u00e7\u00e3o por ser uma especialista perfeita\u00bb<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Sujeito + receive kudos.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u00abSujeito + receive kudos\u00bb \u00e9 normalmente usado para descrever situa\u00e7\u00f5es em que algu\u00e9m \u00abrecebe elogios\u00bb.<\/span><\/p>\n<h5><b>She received kudos as well as a Golden Globe nomination.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ela recebeu elogios e tamb\u00e9m uma indica\u00e7\u00e3o ao Globo de Ouro.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Se, no entanto, a pessoa for uma artista pouco conhecida e que s\u00f3 ganhou a simpatia do p\u00fablico por \u00abatua\u00e7\u00e3o\u00bb, traduzir como \u00abobter fama\u00bb talvez combine melhor com esse cen\u00e1rio!<\/span><\/p>\n<h5><b>He received kudos from everyone on his performance.<\/b><br \/>\n<span style=\"font-weight: 400;\">A apresenta\u00e7\u00e3o dele recebeu elogios de todos.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Sujeito + earned kudos.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O uso de \u00abearn (ganhar)\u00bb \u00e9 semelhante ao de \u00abreceive (receber)\u00bb.<\/span><\/p>\n<h5><b>The company has earned kudos for responding so quickly to customers&#8217; concerns.<\/b><br \/>\n<span style=\"font-weight: 400;\">A empresa ganhou elogios por responder t\u00e3o rapidamente \u00e0s preocupa\u00e7\u00f5es dos clientes.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Ou ent\u00e3o, \u00absujeito + earned kudos\u00bb tamb\u00e9m \u00e9 muito adequado para usar no ambiente de trabalho, em relat\u00f3rios internos sobre \u00abum funcion\u00e1rio excelente\u00bb.<\/span><\/p>\n<h5><b>Clifford recently earned kudos from one of our clients.<\/b><br \/>\n<span style=\"font-weight: 400;\">A Clifford recentemente ganhou elogios de um de nossos clientes.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>The Airlines earned kudos as the most-loved traditional airline for the ninth straight year.<\/b><br \/>\n<span style=\"font-weight: 400;\">A companhia a\u00e9rea ganhou a admira\u00e7\u00e3o como a companhia a\u00e9rea tradicional mais amada pelo nono ano consecutivo.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Como visto acima, quando uma empresa elogia um funcion\u00e1rio, pode usar a estrutura \u00absujeito + earned kudos\u00bb!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Sujeito + give kudos to + pessoa<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00eas quiserem, ap\u00f3s \u00abconcluir algum projeto\u00bb,<strong><span style=\"color: #ff0000;\"> \u00abexpressar elogio para algu\u00e9m\u00bb<\/span><\/strong>, podem usar \u00absujeito + give kudos to + pessoa\u00bb.<\/span><\/p>\n<h5><b>I will give kudos to our office.<\/b><br \/>\n<span style=\"font-weight: 400;\">Vou dar elogios aos colegas do nosso escrit\u00f3rio!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Nos \u00faltimos anos, cada vez mais empresas incentivam os funcion\u00e1rios por iniciativa pr\u00f3pria e reconhecem o esfor\u00e7o um do outro. Ou ent\u00e3o, tamb\u00e9m d\u00e1 para dizer que h\u00e1 uma tend\u00eancia de os chefes conseguirem expressar elogios aos subordinados de forma cada vez mais \u00ableve\u00bb. E esse tipo de atitude \u00e9 como se os funcion\u00e1rios se dessem \u00abelogios\u00bb uns aos outros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, na maior plataforma global de networking empresarial, o \u00abLinkedIn\u00bb, os membros podem elogiar uns aos outros de forma descontra\u00edda usando a maneira \u00abGive Kudos (enviar elogios)\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E esse tipo de abordagem n\u00e3o serve apenas para o cen\u00e1rio de \u00abconcluir algum projeto\u00bb dos exemplos acima; tamb\u00e9m pode ser aplicada a situa\u00e7\u00f5es como \u00abmudan\u00e7a de escrit\u00f3rio conclu\u00edda com sucesso\u00bb, \u00abconclus\u00e3o de um curso de treinamento\u00bb&#8230; e outras \u00abcoisas pequenas\u00bb conclu\u00eddas, permitindo que l\u00edderes ou membros da equipe possam enviar \u00abkudos\u00bb um ao outro de forma \u00abf\u00e1cil\u00bb, para expressar reconhecimento e agradecimento.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Em quais situa\u00e7\u00f5es \u00abkudos\u00bb \u00e9 adequado<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos discutir as situa\u00e7\u00f5es em que \u00abkudos\u00bb se aplica e analisar em quais contextos ele pode ser usado.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Em situa\u00e7\u00f5es do dia a dia, de forma leve<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00eas costumam ver no YouTube a forma de express\u00e3o \u00abKudos to you!\u00bb apresentada acima, certo? Mas, na verdade, ela se aplica a situa\u00e7\u00f5es em que h\u00e1 \u00abelogio de cima para baixo\u00bb, como \u00abprofessor para aluno\u00bb, \u00abchefe para subordinado\u00bb etc.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora, entre amigos mais pr\u00f3ximos, tamb\u00e9m seja poss\u00edvel usar \u00abkudos to !\u00bb para transmitir um sentido semelhante ao \u00abdar parab\u00e9ns\/aplaudir algu\u00e9m\u00bb em portugu\u00eas. Por\u00e9m, como foi dito no come\u00e7o do artigo, como \u00abKudos to !\u00bb tem um sentido forte de admira\u00e7\u00e3o, ele \u00e9 usado com menos frequ\u00eancia em conversas do dia a dia e aparece mais em contextos de \u00abelogio\u00bb escritos, como redes sociais (SNS), blogs e e-mails.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Portanto, quando for um cen\u00e1rio como \u00abganhar um pr\u00eamio profissional no trabalho\u00bb, algo que \u00e9 realmente digno de comemora\u00e7\u00e3o, voc\u00eas podem usar \u00abkudos\u00bb sem hesitar para demonstrar reconhecimento e parabenizar a pessoa!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Em contextos de neg\u00f3cios<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Em empresas estrangeiras, quando os funcion\u00e1rios \u00abatingem metas\u00bb, \u00ablan\u00e7am com sucesso um novo produto\u00bb ou \u00abconquistam algum tipo de realiza\u00e7\u00e3o\u00bb, a empresa costuma elogiar os funcion\u00e1rios por meio de e-mails.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E, nesse tipo de situa\u00e7\u00e3o, os funcion\u00e1rios podem usar \u00abkudos\u00bb para parabenizar o outro, do mesmo jeito que se usa \u00abCongrats! (Parab\u00e9ns)\u00bb.<\/span><\/p>\n<h5><b>Kudos to the Marketing team!<\/b><br \/>\n<span style=\"font-weight: 400;\">Homenagem ao time de marketing!<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Kudos to Duke!<\/b><br \/>\n<span style=\"font-weight: 400;\">Homenagem ao Duke!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">A seguir, est\u00e1 a fala de um presidente e CEO de uma empresa de autom\u00f3veis em um comunicado \u00e0 imprensa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A empresa teve, no m\u00eas, o maior volume de vendas dos \u00faltimos 14 anos:<\/span><\/p>\n<h5><b>Once more I have to give kudos to the various XX teams that have worked relentlessly during these challenging times, especially those in our retailer network who are working every day to ensure our stores are clean and safe for our customers.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu preciso mais uma vez prestar homenagem aos diversos times XX que trabalharam incansavelmente durante esses tempos desafiadores, especialmente \u00e0queles da nossa rede de varejo oficial que trabalham todos os dias para garantir que nossas lojas estejam limpas e seguras para nossos clientes.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Aqui, \u00abgive kudos to\u00bb n\u00e3o tem problema mesmo se for dito com um tom de \u00ab\u00e9 preciso, \u00e9 obrigat\u00f3rio dar elogios\u00bb. Nesse sentido, seja traduzindo como \u00abprestar homenagem\u00bb ou \u00ab\u00e9 preciso dar elogios\u00bb, \u00abgive kudos to\u00bb \u00e9 uma forma de demonstrar \u00abagradecimento positivo e reconhecimento\u00bb pelo esfor\u00e7o do time.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, h\u00e1 tamb\u00e9m um coment\u00e1rio de um cliente sobre uma empresa de design de interiores:<\/span><\/p>\n<h5><b>YY Design Company created a beautiful bathroom cabinet which is exactly what I wanted. I love it! Please accept well deserved kudos and a hat tip for your hard work and sense of elegance and style!<\/b><br \/>\n<span style=\"font-weight: 400;\">A YY Design Company criou um lindo arm\u00e1rio de banheiro que \u00e9 exatamente o que eu queria. Eu amei! Por favor, aceite os elogios mais do que merecidos e a minha homenagem pelo trabalho \u00e1rduo de voc\u00eas, bem como pelo senso de eleg\u00e2ncia e estilo!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Nessa fala, na primeira metade aparece<strong><span style=\"color: #ff0000;\"> \u00abwell deserved kudos\u00bb, em que \u00abwell-deserved\u00bb \u00e9 um adjetivo que significa \u00abaceitar sem d\u00favida o que \u00e9 merecido\u00bb<\/span><\/strong>. Portanto, \u00abwell-deserved kudos\u00bb pode ser entendido como \u00abreceber elogios totalmente merecidos\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, aqui a<strong><span style=\"color: #0000ff;\"> express\u00e3o \u00abplease accept well deserved kudos for \u00bb, embora seja formal, tamb\u00e9m consegue transmitir ao outro uma admira\u00e7\u00e3o e elogio \u00abmuito altos\u00bb, e \u00e9 semelhante ao \u00abpor favor, aceite esses elogios totalmente merecidos!\u00bb em portugu\u00eas<\/span><\/strong>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Cuidados ao usar \u00abkudos\u00bb<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">No texto anterior, mencionamos que \u00abkudos\u00bb costuma ser usado em situa\u00e7\u00f5es de \u00abelogio\u00bb para quem \u00abconclui algo com esfor\u00e7o\u00bb ou \u00abdesafia algo corajosamente\u00bb. Mas aqui \u00e9 preciso prestar aten\u00e7\u00e3o que, quando as pessoas usam \u00abkudos\u00bb em conversas do dia a dia, alguns podem achar que essa express\u00e3o soa um pouco \u00abafetada\u00bb. Ent\u00e3o, por favor, lembrem-se! Na verdade, \u00abkudos\u00bb aparece com mais frequ\u00eancia em textos escritos, em redes sociais (SNS) e em e-mails, e \u00e9 usado com menos frequ\u00eancia em conversas cotidianas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, nas redes sociais, voc\u00eas podem enviar \u00abkudos\u00bb de forma descontra\u00edda, como se estivessem dando um like. Mas se! a pessoa for um alvo mais formal, ent\u00e3o \u00e9 preciso confirmar se esse elogio realmente tem \u00abuma conquista espec\u00edfica ou um m\u00e9rito consider\u00e1vel\u00bb para poder ser usado!<\/span><\/p>\n<h5><b>Kudos to all our volunteers in this town!<\/b><br \/>\n<span style=\"font-weight: 400;\">Homenagem a todos os volunt\u00e1rios desta cidade!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Por exemplo, esse tipo de express\u00e3o como acima n\u00e3o faz a pessoa que recebe se sentir desconfort\u00e1vel e, ao contr\u00e1rio, gera uma energia positiva!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, no ingl\u00eas americano, \u00abkudos\u00bb \u00e0s vezes tamb\u00e9m \u00e9 usado diretamente para significar \u00abparab\u00e9ns!\u00bb. Mas se voc\u00eas quiserem dizer \u00abparab\u00e9ns\u00bb de forma mais simples, tamb\u00e9m recomendamos usar \u00abCongrats!\u00bb para ficar mais natural.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Resumo do significado e do uso de \u00abkudos\u00bb<\/b><\/h2>\n<p>&nbsp;<\/p>\n<h6><b>\u00a0\uff08I\uff09\u00abkudos\u00bb \u00e9 usado para elogiar algu\u00e9m que \u00abconcluiu algo com esfor\u00e7o\u00bb ou \u00abdesafiou algo corajosamente\u00bb.<\/b><br \/>\n<b>\uff08II\uff09\u00abkudos to + pessoa\u00bb \u00e9 usado para elogiar um alvo espec\u00edfico.<\/b><br \/>\n<b>\uff08III\uff09Em vez de conversas do dia a dia, \u00abkudos\u00bb \u00e9 mais comum em express\u00f5es escritas como SNS e e-mails.<\/b><\/h6>\n<p><span style=\"font-weight: 400;\">Depois que voc\u00eas entenderem os usos acima, poder\u00e3o aplicar \u00abkudos\u00bb com flexibilidade nas situa\u00e7\u00f5es adequadas, deixando a comunica\u00e7\u00e3o em ingl\u00eas mais natural e apropriada!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todo mundo sabe o que significa, em g\u00edrias, ouvir \u00abkudos\u00bb? \u00abkudos\u00bb vem do grego e \u00e9 pronunciado como \u00ab\/\u02c8ku\u02d0.d\u0251\u02d0s\/\u00bb. A seguir, vamos aprender o significado, como usar e em quais situa\u00e7\u00f5es ele se aplica! &nbsp; O significado de \u00abkudos\u00bb &nbsp; Primeiro, \u00abkudos\u00bb \u00e9 um \u00absubstantivo incont\u00e1vel\u00bb; portanto, n\u00e3o \u00e9 a forma plural de \u00abkudo\u00bb. Por exemplo, as frases abaixo s\u00e3o um uso incorreto: \uff08Erro\uff09He received many kudos for his work. O correto seria: \u00e9 preciso usar \u00abmuch\u00bb para acompanhar um substantivo incont\u00e1vel.\u3000 \uff08Correto\uff09He received much kudos for his work. Al\u00e9m disso, a origem de \u00abkudos\u00bb vem do grego que representa \u00abpraise\uff08elogio, admira\u00e7\u00e3o\uff09\u300d ou \u00abrenown\uff08fama, honra\uff09\u300d\u00bb. Por isso, o significado que &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/16313\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":16314,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=16313","footnotes":""},"categories":[109,107,108],"tags":[],"class_list":["post-16313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-listening","category-speaking","category-writing","pt-BR"],"aioseo_notices":[],"views":176,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=16313"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16313\/revisions"}],"predecessor-version":[{"id":16315,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16313\/revisions\/16315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/16314"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=16313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=16313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=16313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}