{"id":16297,"date":"2026-04-23T09:00:00","date_gmt":"2026-04-23T12:00:00","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=16297"},"modified":"2026-04-20T21:54:20","modified_gmt":"2026-04-21T00:54:20","slug":"qual-e-o-significado-e-o-uso-da-expressao-verbal-go-on-apresentamos-uma-expressao-coloquial-para-dizer-que-algo-continua-acontecendo","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/16297\/","title":{"rendered":"Qual \u00e9 o significado e o uso da express\u00e3o verbal \u201cgo on\u201d? Apresentamos uma express\u00e3o coloquial para dizer que \u201calgo continua acontecendo\u201d!"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">O que diabos aconteceu?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u300cN\u00e3o aguento mais. O barulho do lado continua a noite inteira\u2026\u3002\u300d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como nos di\u00e1logos acima, voc\u00eas podem usar o phrasal verb\u00a0 \u00abgo on\u00bb\u00a0 para expressar isso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00abGo on\u00bb\u00a0 \u00e9 uma combina\u00e7\u00e3o de palavras bem simples, mas muita gente n\u00e3o tem certeza do significado exato e de como us\u00e1-la.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, neste artigo, n\u00f3s vamos\u00a0 \u00a0<span style=\"color: #d609c8;\"><strong>apresentar para voc\u00eas a express\u00e3o em ingl\u00eas\u00a0 <span style=\"font-size: 28px;\">\u00a0\u00abgo on\u00bb\u00a0<\/span> \u00a0por meio de exemplos bem concretos<\/strong><\/span> e fazer com que a sua conversa\u00e7\u00e3o em ingl\u00eas evolua ainda mais, ok?!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>O significado e como usar \u00abgo on\u00bb<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Antes de dominar \u00abgo on\u00bb, \u00e9 necess\u00e1rio entender primeiro os \u00abquatro significados b\u00e1sicos\u00bb que ele representa e como us\u00e1-lo corretamente.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\u00abGo on\u00bb \u00e9 um phrasal verb<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, voc\u00eas precisam entender que \u00abgo on\u00bb \u00e9 um \u00abphrasal verb\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"color: #ff0000;\"><strong>\u00abPhrasal verb\u00bb \u00e9 uma express\u00e3o formada por v\u00e1rias palavras e, na gram\u00e1tica, usada como um \u00abverbo\u00bb<\/strong><\/span>. E, neste artigo, o \u00abgo on\u00bb que vamos apresentar \u00e9 um verbo em forma de frase formado pela combina\u00e7\u00e3o de \u00abgo\u00bb e \u00abon\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, al\u00e9m de \u00abgo on\u00bb, <strong><span style=\"color: #0000ff;\">\u00abturn on\u00bb, \u00abtake off\u00bb, \u00abgive up\u00bb<\/span><\/strong> e outros phrasal verbs tamb\u00e9m s\u00e3o express\u00f5es que estrangeiros usam com frequ\u00eancia no dia a dia. Inclusive, no mercado, voc\u00eas tamb\u00e9m veem muitos materiais did\u00e1ticos de ingl\u00eas feitos com o tema \u00abphrasal verbs\u00bb. Portanto, d\u00e1 para concluir que \u00abphrasal verbs\u00bb s\u00e3o importantes n\u00e3o s\u00f3 para quem est\u00e1 aprendendo ingl\u00eas; depois que voc\u00eas os dominarem, tamb\u00e9m ser\u00e1 poss\u00edvel melhorar suas habilidades em ingl\u00eas naturalmente!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>O significado de \u00abgo on\u00bb<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, ao analisarmos \u00abgo on\u00bb separadamente, percebemos que \u00abgo\u00bb representa o significado de\u00a0 \u00abir\u00bb, que \u00e9 algo bem familiar para todos, e ainda traz a ideia de \u00abmovimento para frente\u00bb. J\u00e1 \u00abon\u00bb representa o significado de\u00a0 \u00ab sobre\u00bb, e tamb\u00e9m carrega uma no\u00e7\u00e3o de \u00abcontinuidade\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, \u00abon\u00bb \u00e9 uma palavra bem interessante. O conceito central dela \u00e9 \u00abcontato\u00bb. Por isso, al\u00e9m de poder expressar \u00abdire\u00e7\u00e3o, posi\u00e7\u00e3o (sobre)\u00bb, tamb\u00e9m pode expressar \u00abna dire\u00e7\u00e3o de , para \u00bb. Por exemplo, \u00abon Monday\u00bb \u00e9 um uso interessante de \u00abon\u00bb no sentido de tempo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ent\u00e3o, depois de entender que \u00abgo\u00bb significa \u00abir\u00bb e que \u00abon\u00bb tem a ideia de \u00abcontinuidade\u00bb, vamos ver juntos o que \u00abgo on\u00bb realmente quer dizer!<\/span><\/p>\n<h6><b>\uff08I\uff09continua, em sequ\u00eancia<\/b><br \/>\n<b>\uff08II\uff09acontece<\/b><br \/>\n<b>\uff08III\uff09come\u00e7a<\/b><br \/>\n<b>\uff08IV\uff09subir em algo, entrar\/usar um meio de transporte<\/b><\/h6>\n<p><span style=\"font-weight: 400;\">Entre esses, \u00abcontinua, em sequ\u00eancia\u00bb e \u00abacontece\u00bb trazem a ideia de \u00abalgo acontecendo continuamente\u00bb. E, ao acrescentar \u00abcome\u00e7a\u00bb, isso vira um contexto de \u00abdepois que algo come\u00e7a, ele continua por um tempo\u00bb.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Como usar \u00abgo on\u00bb<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos explicar detalhadamente as quatro formas de uso de \u00abgo on\u00bb.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\uff08I\uff09continua, em sequ\u00eancia<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O primeiro uso \u00e9<span style=\"color: #ff0000;\"><strong>\u00a0 \u00abcontinua, em sequ\u00eancia\u00bb, e tamb\u00e9m \u00e9 o uso mais comum de \u00abgo on\u00bb<\/strong><\/span>. Ele pode ser usado para expressar situa\u00e7\u00f5es em que \u00abalgo continua acontecendo\u00bb, como \u00abcontinuar falando\u00bb, \u00abcontinuar aumentando\u00bb, \u00abcontinuar ouvindo algum tipo de som\u00bb, etc.<\/span><\/p>\n<h5><b>You\u2019re doing great. Go on. Keep doing what you are doing.<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea est\u00e1 indo muito bem. Continue! Continue fazendo o que voc\u00ea est\u00e1 fazendo.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>The noise from the neighbour has been going on all night. I can\u2019t sleep.<\/b><br \/>\n<span style=\"font-weight: 400;\">O barulho do vizinho continua a noite inteira. Eu n\u00e3o consigo dormir.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Os exemplos acima se referem ao<span style=\"color: #0000ff;\"><strong> \u00abgo on\u00bb que significa \u00abalgo est\u00e1 acontecendo\/continuando\u00bb<\/strong><\/span>. Por exemplo: a a\u00e7\u00e3o de algu\u00e9m, um barulho cont\u00ednuo, etc\u2026.<\/span><br \/>\n<b><\/b><\/p>\n<h5><b>I went on studying English overnight.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu continuei estudando ingl\u00eas a noite toda.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>The teacher\u2019s lecture goes on and on and on.<\/b><br \/>\n<span style=\"font-weight: 400;\">A aula do professor continua sem parar.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Entre eles, \u00abgo on and on and on\u00bb \u00e9 um uso interessante do \u00abgo on\u00bb que significa \u00abcontinuidade\u00bb, e indica a ideia de \u00abcontinuar sem fim, sem parar\u00bb.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>\u00abGo on\u00bb e \u00abcarry on\u00bb<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Em ingl\u00eas, al\u00e9m de \u00abgo on\u00bb, tamb\u00e9m existe a express\u00e3o \u00abcarry on\u00bb para transmitir a ideia de \u00abcontinuar\u00bb. Entre elas, \u00abcarry on\u00bb \u00e9 um phrasal verb que \u00e9 muito usado no Reino Unido. Por\u00e9m, embora \u00abgo on\u00bb e \u00abcarry on\u00bb signifiquem \u00abcontinuar\u00bb, \u00abcarry on\u00bb traz especialmente a ideia de \u00abpersistir com esfor\u00e7o\u00bb!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\uff08II\uff09acontece<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos apresentar o segundo significado de \u00abgo on\u00bb:<strong><span style=\"color: #ff0000;\"> \u00abacontece\u00bb<\/span><\/strong>. Pensamos que, no dia a dia, sempre h\u00e1 v\u00e1rios tipos de coisas \u00abacontecendo\u00bb, certo?<\/span><\/p>\n<h5><b>What\u2019s going on here?<\/b><br \/>\n<span style=\"font-weight: 400;\">O que est\u00e1 acontecendo aqui?<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Nessa frase, ao mesmo tempo em que se pergunta \u00abo que est\u00e1 acontecendo aqui?\u00bb, ela tamb\u00e9m pode carregar a ideia de \u00abo que diabos est\u00e1 acontecendo?\u00bb. Por exemplo, quando voc\u00ea entra em um quarto bagun\u00e7ado pelas crian\u00e7as, pode acabar dizendo essa frase sem perceber!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, <strong><span style=\"color: #0000ff;\">\u00abNo idea what\u2019s going on.\uff08Eu n\u00e3o fa\u00e7o ideia do que est\u00e1 acontecendo\uff09\u00bb<\/span><\/strong><\/span><span style=\"font-weight: 400;\"> tamb\u00e9m \u00e9 uma forma de express\u00e3o muito comum no dia a dia entre estrangeiros!<\/span><\/p>\n<h5><b>Too many things go on day by day.<\/b><br \/>\n<span style=\"font-weight: 400;\">Muitas coisas acontecem dia ap\u00f3s dia.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">\u00abDay by day\u00bb significa \u00abdia ap\u00f3s dia, de um dia para o outro\u00bb, e pode ser usado quando voc\u00eas querem expressar \u00abtodo dia tem coisas acontecendo\u00bb ou at\u00e9 \u00abest\u00e1 uma correria sem fim\u00bb. Por isso, quando muitas coisas v\u00e3o acontecendo ao redor de voc\u00eas em sequ\u00eancia, d\u00e1 para usar \u00abgo on\u00bb para expressar essa situa\u00e7\u00e3o!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\uff08III\uff09come\u00e7a<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Agora, vamos ver como usar<strong><span style=\"color: #ff0000;\"> \u00abgo on\u00bb com o sentido de \u00abcome\u00e7ar\u00bb<\/span><\/strong>!<\/span><\/p>\n<h5><b>She said that she goes on a diet starting next week. I doubt she will do it.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ela disse que vai come\u00e7ar uma dieta a partir da semana que vem. Duvido que ela realmente v\u00e1 fazer.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">\u00abGo on a diet\u00bb significa \u00abcome\u00e7ar a perder peso\/dieta\u00bb, e traz a ideia de \u00abcome\u00e7ar a fazer algo que antes n\u00e3o fazia\u00bb. Como o sujeito da frase \u00e9 \u00abshe\u00bb, \u00abgo on\u00bb fica como \u00abgoes on\u00bb. Por\u00e9m, recomendamos que, quando voc\u00eas decidirem fazer algo, em vez de dizer \u00aba partir da semana que vem\u00bb, \u00e9 melhor agir logo, porque \u00e9 mais pr\u00e1tico!<\/span><\/p>\n<h5><b>The railway company announced that they will go on a 2-week strike.<\/b><br \/>\n<span style=\"font-weight: 400;\">A empresa ferrovi\u00e1ria anunciou que vai fazer uma greve de duas semanas.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Em Londres, onde o autor mora, \u00e9 comum acontecerem greves ferrovi\u00e1rias por muito tempo. Inclusive, eu j\u00e1 nem lembro quando foi a \u00faltima vez que saiu um an\u00fancio assim\u2026 Al\u00e9m disso, se a greve acontecer no fim de semana, a situa\u00e7\u00e3o fica bem pior. Ent\u00e3o, se voc\u00eas forem viajar para Londres, por favor prestem bastante aten\u00e7\u00e3o ao funcionamento dos trens.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">At\u00e9 aqui, confirmamos as formas de express\u00e3o em que \u00abgo on\u00bb significa \u00abcontinua, continua\u00bb, \u00abacontece\u00bb e \u00abcome\u00e7a\u00bb, e percebemos que todas elas carregam a ideia de \u00abalgo est\u00e1 acontecendo ou vai continuar acontecendo\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Depois de lembrar disso, voltem a revisar os exemplos acima mais uma vez!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\uff08IV\uff09subir em algo, entrar\/usar um meio de transporte<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><strong><span style=\"color: #ff0000;\">O quarto significado de \u00abgo on\u00bb \u00e9 \u00absubir em algo\u00bb ou \u00abentrar\/usar um meio de transporte\u00bb<\/span><\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando falamos \u00absubir em algo\u00bb, todo mundo provavelmente pensa primeiro em \u00absubir montanha, subir em \u00e1rvore\u00bb. E quando falamos \u00abentrar\/usar um meio de transporte\u00bb, pensamos em v\u00e1rios \u00abmeios de transporte\u00bb, certo?<\/span><\/p>\n<h5><b>My son likes to go on the tree for fun.<\/b><br \/>\n<span style=\"font-weight: 400;\">Meu filho gosta de brincar em cima da \u00e1rvore.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>We enjoyed going on the roller coaster ride.<\/b><br \/>\n<span style=\"font-weight: 400;\">N\u00f3s nos divertimos andando no trem-bala\/na montanha-russa!<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Express\u00f5es relacionadas a \u00abgo on\u00bb<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"color: #ff0000;\"><strong>No modelo \u00abgo on\uff5eing\u00bb, a ideia \u00e9 \u00abcontinuar fazendo do mesmo jeito uma certa a\u00e7\u00e3o\/coisa\u00bb<\/strong><\/span>,\u00a0 <strong><span style=\"color: #0000ff;\">e\u00a0 \u00abgo on\uff0bwith\u00bb\u00a0 significa \u00abcontinuar fazendo alguma coisa\u00bb<\/span><\/strong>. Como \u00abgo on\u00bb tem muitos tipos de uso, recomendamos que voc\u00eas criem uma lista de \u00abgo on\u00bb no celular e registrem essas express\u00f5es para consultar e revisar sempre que quiserem!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos ver juntos as formas de expressar \u00abgo on\u00bb relacionadas a ele!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre elas, \u00abgo on\u00bb em si tem o sentido de \u00abcontinua, continua\u00bb, e tamb\u00e9m representa o mesmo significado de \u00abcontinue (continuar, manter)\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E quando falamos de \u00abgo on\u00bb com a ideia de \u00abcontinuidade\u00bb, muita gente tamb\u00e9m pensa em \u00abkeep (manter, sustentar algum estado)\u00bb, n\u00e3o \u00e9?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso aqui, vamos apresentar \u00abduas\u00bb express\u00f5es que podem substituir \u00abgo on\u00bb: \u00abkeep talking\u00bb e \u00abkeep going\u00bb.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\u00abKeep talking\u00bb<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><strong><span style=\"color: #ff0000;\">\u00abkeep talking\u00bb significa \u00abcontinuar falando, manter a conversa\u00bb<\/span><\/strong> e tamb\u00e9m pode ser entendido como \u00abfalar sem parar\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aten\u00e7\u00e3o aqui, por favor! Essa express\u00e3o n\u00e3o \u00e9 \u00abkeep to talk\u00bb. O uso correto \u00e9 \u00abkeep talking\u00bb!<\/span><\/p>\n<h5><b>Don\u2019t worry, we are listening to you. Keep talking.<\/b><br \/>\n<span style=\"font-weight: 400;\">N\u00e3o se preocupe, estamos ouvindo voc\u00ea. Continue falando.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>She kept talking about her boyfriend. I couldn\u2019t stand her, so I had to say it was time to leave.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ela ficou falando sem parar sobre o namorado. Eu n\u00e3o aguentava mais ela, ent\u00e3o tive que dizer que era hora de ir embora.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">\u00abConversa\u00bb \u00e9, basicamente, uma intera\u00e7\u00e3o de m\u00e3o dupla. Se voc\u00eas encontrarem algu\u00e9m que n\u00e3o consegue parar um assunto, podem usar \u00abby the way (ali\u00e1s, falando nisso)\u00bb para mudar o tema e tentar deixar a conversa entre os dois mais interessante e com mais conex\u00e3o!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\u00abKeep going\u00bb<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff0000;\">\u00abkeep<\/span><\/strong><span style=\"font-weight: 400;\"><strong><span style=\"color: #ff0000;\"> going\u00bb e \u00abgo on\u00bb significam \u00abcontinuar\u00bb<\/span><\/strong><\/span>, mas \u00abkeep going\u00bb ainda traz especialmente a ideia de \u00abincentivar a pessoa a continuar, for\u00e7a!\u00bb.<\/p>\n<h5><b>Let\u2019s keep going!<\/b><br \/>\n<span style=\"font-weight: 400;\">Vamos continuar!<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>You\u2019ve just started to study English, keep going!<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea acabou de come\u00e7ar a estudar ingl\u00eas, continue com tudo!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">\u00abKeep going\u00bb \u00e9 uma express\u00e3o cheia de energia positiva e parecida com \u00abNever give up (n\u00e3o desista)\u00bb, com a ideia de \u00abj\u00e1 que decidiu, ent\u00e3o deve continuar\u00bb.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>O \u00abgo on then\u00bb do ingl\u00eas brit\u00e2nico<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Por fim, vamos apresentar a express\u00e3o coloquial \u00abgo on then\u00bb do ingl\u00eas brit\u00e2nico. Basicamente, ela tem o mesmo sentido de \u00abgo on\u00bb que significa \u00abcontinua, continua\u00bb, mas no ingl\u00eas falado do Reino Unido, ela ainda carrega uma certa nuance espec\u00edfica!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\u00abGo on then\u00bb<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Se, por exemplo, a outra pessoa estiver falando sem parar, mas voc\u00eas perceberem que ela ainda quer continuar dizendo, ent\u00e3o voc\u00eas podem<strong><span style=\"color: #ff0000;\"> usar \u00abgo on then\u00bb para expressar \u00abt\u00e1 bom, pode continuar\u00bb. Nesse caso, \u00abgo on then\u00bb carrega a ideia de \u00abresigna\u00e7\u00e3o ou aceita\u00e7\u00e3o meio for\u00e7ada\u00bb<\/span><\/strong>, e \u00e9 semelhante a \u00abgo ahead (pode continuar)\u00bb. <\/span><\/p>\n<h5><b>Oh, you wanted to tell me something? But I have a story to tell you.<\/b><br \/>\n<b>Go on then.<\/b><br \/>\n<span style=\"font-weight: 400;\">Oh, voc\u00ea queria me contar alguma coisa? Mas eu tamb\u00e9m tenho uma hist\u00f3ria para te contar.<\/span><br \/>\n<span style=\"font-weight: 400;\">T\u00e1 bom, ent\u00e3o pode falar.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, quando algu\u00e9m quiser lhe oferecer algo, mas voc\u00ea inicialmente pretendia recusar, por\u00e9m depois muda de ideia e aceita, voc\u00eas podem usar \u00abgo on then\u00bb para demonstrar isso.<\/span><\/p>\n<h5><b>Are you sure you don\u2019t want another slice of cake?<\/b><br \/>\n<b>Ok, go on then, just a small one, please.<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea tem certeza de que n\u00e3o quer mais uma fatia de bolo?<\/span><br \/>\n<span style=\"font-weight: 400;\">T\u00e1 bom, ent\u00e3o pode ser, s\u00f3 uma pequena, por favor.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">\u00abGo on then\u00bb \u00e9 uma forma de express\u00e3o bem comum no ingl\u00eas do Reino Unido. Se voc\u00eas conseguirem domin\u00e1-la, a sua conversa vai soar mais natural e mais coloquial!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Resumo<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O significado de \u00abgo on\u00bb \u00e9:<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>\uff08I\uff09continua, continua<\/b><b><br \/>\n<\/b><b>\uff08II\uff09acontece<\/b><b><br \/>\n<\/b><b>\uff08III\uff09come\u00e7a<\/b><b><br \/>\n<\/b><b>\uff08IV\uff09subir em algo, entrar\/usar um meio de transporte<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, tamb\u00e9m apresentamos algumas express\u00f5es relacionadas a \u00abgo on\u00bb. Por exemplo, \u00abgo on then\u00bb. Esperamos que voc\u00eas aproveitem esta oportunidade para aumentar o vocabul\u00e1rio de \u00abphrasal verbs\u00bb e se familiarizarem com como usar \u00abgo on\u00bb, e at\u00e9 colocarem em pr\u00e1tica de verdade!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O que diabos aconteceu? \u300cN\u00e3o aguento mais. O barulho do lado continua a noite inteira\u2026\u3002\u300d Como nos di\u00e1logos acima, voc\u00eas podem usar o phrasal verb\u00a0 \u00abgo on\u00bb\u00a0 para expressar isso. \u00abGo on\u00bb\u00a0 \u00e9 uma combina\u00e7\u00e3o de palavras bem simples, mas muita gente n\u00e3o tem certeza do significado exato e de como us\u00e1-la. Por isso, neste artigo, n\u00f3s vamos\u00a0 \u00a0apresentar para voc\u00eas a express\u00e3o em ingl\u00eas\u00a0 \u00a0\u00abgo on\u00bb\u00a0 \u00a0por meio de exemplos bem concretos e fazer com que a sua conversa\u00e7\u00e3o em ingl\u00eas evolua ainda mais, ok?! &nbsp; O significado e como usar \u00abgo on\u00bb &nbsp; Antes de dominar \u00abgo on\u00bb, \u00e9 necess\u00e1rio entender primeiro os \u00abquatro significados b\u00e1sicos\u00bb que ele &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/16297\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":16298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=16297","footnotes":""},"categories":[139,140,133],"tags":[],"class_list":["post-16297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultural-exchange","category-study-abroad-nc","category-preparation-for-studying-abroad","pt-BR"],"aioseo_notices":[],"views":143,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=16297"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16297\/revisions"}],"predecessor-version":[{"id":16299,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16297\/revisions\/16299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/16298"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=16297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=16297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=16297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}