{"id":16223,"date":"2026-04-19T09:00:54","date_gmt":"2026-04-19T12:00:54","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=16223"},"modified":"2026-04-09T01:47:26","modified_gmt":"2026-04-09T04:47:26","slug":"o-que-significa-a-sigla-r-i-p-uma-introducao-as-girias-em-ingles-comuns-na-internet-e-nas-redes-sociais","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/16223\/","title":{"rendered":"O que significa a sigla \u201cR.I.P.\u201d? Uma introdu\u00e7\u00e3o \u00e0s \u201cg\u00edrias em ingl\u00eas\u201d comuns na internet e nas redes sociais"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Todo mundo j\u00e1 viu essa forma de express\u00e3o em ingl\u00eas, \u201cR.I.P.\u201d? Talvez ela n\u00e3o seja t\u00e3o comum no Brasil, mas, quando todos v\u00e3o para pa\u00edses de l\u00edngua inglesa, percebem que \u201cR.I.P.\u201d \u00e9 frequentemente gravado em l\u00e1pides ou aparece com frequ\u00eancia nas redes sociais. Por isso, pensamos que, mesmo que muitas pessoas j\u00e1 saibam o significado original, elas provavelmente ainda n\u00e3o sabem que \u201cR.I.P.\u201d tamb\u00e9m \u00e9 usado entre estrangeiros como \u201cg\u00edria\u201d, n\u00e3o \u00e9 mesmo!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desta vez, neste artigo, n\u00f3s vamos\u00a0 <span style=\"color: #d904c4;\"><span style=\"color: #000000;\">analisar o significado de<\/span><\/span><span style=\"color: #ff6600; font-size: 32px;\"><strong> \u201cR.I.P.\u201d, <\/strong><\/span><span style=\"color: #d904c4;\"><span style=\"color: #000000;\">como usar e os cuidados ao utiliz\u00e1-lo<\/span><\/span>\u3002Al\u00e9m disso, na segunda metade do artigo, vamos trazer ainda mais informa\u00e7\u00f5es sobre outras g\u00edrias comuns e parecidas. Esperamos que, depois de ler este artigo, voc\u00eas consigam, ao postar nas redes sociais ou ao escrever e-mails, deixar sua forma de se expressar mais pr\u00f3xima da de falantes nativos!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>O que significa a sigla \u201cR.I.P.\u201d?<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"color: #ff0000;\"><strong><span style=\"color: #ff6600;\">\u201cR.I.P.\u201d <\/span><\/strong><span style=\"color: #000000;\">vem do latim<\/span><span style=\"color: #ff6600;\"><strong> \u201crequiescat in pace\u201d<\/strong><\/span><\/span>\u3002<span style=\"color: #ff0000;\"><span style=\"color: #000000;\">Sua tradu\u00e7\u00e3o para o ingl\u00eas \u00e9<\/span><\/span><span style=\"color: #ff6600;\"><strong> \u201crest in peace\u201d<\/strong><\/span>\u3001e \u00e9 a forma de express\u00e3o mais usada atualmente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 em portugu\u00eas, \u201cR.I.P.\u201d \u00e9 traduzido literalmente como \u201cdescansar em paz\u201d, e interpretado como \u201cque descanse em paz\u201d, \u201cque ele\/ela descanse em paz\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Cuidados ao usar<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Como mencionado acima, <span style=\"color: #0000ff;\"><span style=\"color: #000000;\">basicamente<\/span> <\/span><span style=\"color: #ff6600;\"><strong>\u201cR.I.P.\u201d <\/strong><\/span><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">\u00e9 uma forma de expressar\u00a0<\/span><\/span> <strong><span style=\"color: #0000ff;\"><span style=\"color: #ff6600;\">\u201ccondol\u00eancias a quem faleceu\u201d<\/span>.<\/span><\/strong> Mas, como no ingl\u00eas moderno tamb\u00e9m se usa \u201cR.I.P.\u201d em \u201cexpress\u00f5es de g\u00edria\u201d, isso faz com que seja necess\u00e1rio prestar aten\u00e7\u00e3o \u00e0 distin\u00e7\u00e3o entre \u201co significado original\u201d e \u201co uso como g\u00edria\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando as pessoas confundem o uso, o sentido de \u201ccondol\u00eancias\u201d pode acabar virando uma express\u00e3o desrespeitosa com tom de \u201cironia\u201d ou \u201cdeprecia\u00e7\u00e3o\u201d. Por exemplo, se voc\u00ea quiser expressar condol\u00eancias pela morte de um parente, mas acidentalmente usar \u201cR.I.P. to you\uff01\uff08Que voc\u00ea tamb\u00e9m descanse em paz!\uff09\u201d, isso pode ser entendido como um \u201cdesafio mal-intencionado\u201d!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, para evitar que as pessoas confundam o uso, explicaremos em detalhes a seguir a forma correta de usar \u201cR.I.P.\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>O significado e como usar \u201cR.I.P.\u201d<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos explicar o significado b\u00e1sico de \u201cR.I.P.\u201d e como us\u00e1-lo em diferentes situa\u00e7\u00f5es.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No artigo, al\u00e9m de analisar o significado b\u00e1sico de \u201cR.I.P.\u201d, tamb\u00e9m vamos apresentar como usar \u201cR.I.P.\u201d como \u201cg\u00edria\u201d. Queremos que voc\u00eas deixem sua forma de se expressar mais natural e fluida ao longo do texto!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Express\u00e3o de condol\u00eancias ao falecido<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A situa\u00e7\u00e3o em que \u201cR.I.P.\u201d \u00e9 mais usada \u00e9 para \u201cexpressar luto e condol\u00eancias ao falecido\u201d. Ela costuma ser gravada em l\u00e1pides e tamb\u00e9m aparece com frequ\u00eancia em jornais ou em t\u00edtulos de not\u00edcias. Em todos esses casos, o artigo coloca \u201cR.I.P.\u201d antes e depois do nome do falecido, ou no final da frase. Por exemplo, no t\u00edtulo da not\u00edcia \u201cR.I.P. Queen Elizabeth\uff08Que a Rainha Elizabeth descanse em paz\uff09\u201d ou no texto da not\u00edcia \u201cQueen Elizabeth has passed away. R.I.P.\uff08A Rainha Elizabeth faleceu. Que ela descanse em paz\uff09\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Uso como g\u00edria<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Como mencionado acima, \u201cR.I.P.\u201d \u00e9 uma forma de express\u00e3o usada para condol\u00eancias. Mas, nos \u00faltimos anos, estrangeiros tamb\u00e9m come\u00e7aram a us\u00e1-la como \u201cg\u00edria\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos apresentar algumas formas comuns de usar \u201cR.I.P.\u201d como g\u00edria.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Uso para \u201cacabou\u2026\u201d, \u201cGG\u2026\u201d, etc.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">Quando<\/span><\/span><span style=\"color: #ff6600;\"><strong> \u201cR.I.P.\u201d\u00a0 <\/strong><\/span><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">\u00e9 usada como g\u00edria, ela traz o sentido de\u00a0<\/span><\/span><strong><span style=\"color: #ff0000;\"><span style=\"color: #ff6600;\"> \u201calgo acabou, n\u00e3o tem mais jeito\u201d<\/span>\u00a0 <\/span><\/strong><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">e \u00e9 semelhante ao portugu\u00eas\u00a0<\/span><\/span> <span style=\"color: #ff6600;\"><strong>\u201cmorreu de vez\u201d, \u201cGG\u201d, \u201cacabou\u201d<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, em situa\u00e7\u00f5es como quando o celular cai na \u00e1gua ou quando voc\u00ea morre em um jogo, \u00e9 poss\u00edvel usar \u201cR.I.P.\u201d para expressar isso.<\/span><\/p>\n<h5><b>R.I.P. to my phone. I accidentally dropped it in the bathtub!<\/b><br \/>\n<span style=\"font-weight: 400;\">Meu celular GGou. Eu sem querer deixei ele cair dentro da banheira!<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Uso com ironia, maldade ou provoca\u00e7\u00e3o<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"color: #000000;\">Se voc\u00eas usarem<\/span><span style=\"color: #ff6600;\"><strong> \u201cR.I.P.\u201d <\/strong><\/span><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">para algu\u00e9m que ainda est\u00e1 vivo, podem expressar um sentido de<\/span><\/span><span style=\"color: #ff6600;\"><strong> \u201czombaria\u201d <\/strong><\/span><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">e<\/span><\/span> <span style=\"color: #ff6600;\"><strong>\u201cprovoca\u00e7\u00e3o\u201d.<\/strong><\/span> E, al\u00e9m disso, a outra pessoa pode interpretar como se fosse uma esp\u00e9cie de \u201cmaldi\u00e7\u00e3o mal-intencionada\u201d!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, \u201cR.I.P. to you\uff01\uff08V\u00e1 para o inferno!\uff09\u201d \u00e9 uma forma de express\u00e3o com um tom bem forte. Por favor, use com cuidado!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>\u201cRIP\u201d comum na internet, com omiss\u00e3o do ponto!<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u201cR.I.P.\u201d \u00e9 uma sigla de \u201crequiescat in pace\u201d ou \u201crest in peace\u201d e, em situa\u00e7\u00f5es comuns, costuma vir com \u201cpontos\u201d que indicam a omiss\u00e3o de letras. Portanto, sua forma correta deve ser \u201cR.I.P.\u201d, e a pron\u00fancia deve ser feita pelas pr\u00f3prias letras.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, agora, em muitas redes na internet e em m\u00eddias sociais, aparece com frequ\u00eancia a situa\u00e7\u00e3o em que \u201cR.I.P.\u201d omite os \u201cpontos\u201d e \u00e9 escrito como \u201cRIP\u201d. Embora \u201cRIP\u201d e \u201cR.I.P.\u201d n\u00e3o tenham diferen\u00e7a de sentido nem de pron\u00fancia, devido a <span style=\"color: #0000ff;\"><span style=\"color: #000000;\">o significado original da palavra\u00a0<\/span><\/span><span style=\"color: #ff6600;\"><strong> \u201crip\u201d\u00a0<\/strong><\/span><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"> \u00e9\u00a0<\/span><\/span><span style=\"color: #ff6600;\"><strong> \u201crasgar, destruir\u201d<\/strong><\/span><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">, ent\u00e3o quando voc\u00eas virem<\/span><\/span><span style=\"color: #ff6600;\"> \u00a0<strong>\u201cRIP\u201d <\/strong><\/span><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">em um texto, precisam ter cuidado e julgar o verdadeiro significado de<\/span><\/span> <strong><span style=\"color: #0000ff;\"><span style=\"color: #ff6600;\">\u201cRIP\u201d<\/span> <\/span><\/strong><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">com base no contexto.<\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Outras \u201cg\u00edrias da internet\u201d comuns em redes e m\u00eddias sociais<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Acima, entendemos o significado b\u00e1sico de \u201cR.I.P.\u201d, que expressa condol\u00eancias, e tamb\u00e9m como us\u00e1-la em g\u00edrias do ingl\u00eas. Mas, na verdade, no mundo de l\u00edngua inglesa, al\u00e9m de \u201cR.I.P.\u201d, existem muitas outras siglas e g\u00edrias que aparecem com frequ\u00eancia na internet e nas m\u00eddias sociais!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea acompanha com frequ\u00eancia as redes sociais de artistas estrangeiros, modelos ou influenciadores, provavelmente j\u00e1 sabe que existem v\u00e1rias outras express\u00f5es em forma de \u201cg\u00edrias da internet\u201d, certo? Queremos contar a voc\u00eas que, quando voc\u00eas entenderem essas \u201cg\u00edrias da internet\u201d, isso certamente vai deixar suas conversas mais pr\u00f3ximas da forma como os estrangeiros se expressam!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Agora, vamos apresentar algumas g\u00edrias comuns da internet e como us\u00e1-las!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>lol<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff6600;\"><strong>\u201clol\u201d <\/strong><\/span><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">\u00e9 a sigla de<\/span><\/span><span style=\"color: #ff6600;\"><strong> \u201claugh out loud\u201d <\/strong><\/span><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">e, traduzindo literalmente, significa<\/span><\/span><span style=\"color: #ff6600;\"><strong> \u201crir alto\u201d. <\/strong><\/span><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">E o significado de<\/span><\/span> <span style=\"color: #ff6600;\"><strong>\u201clol\u201d <\/strong><\/span><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">na internet \u00e9 bem parecido com<\/span><\/span> <span style=\"color: #ff6600;\"><strong>\u201cdar risada\u201d <\/strong><\/span><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">em portugu\u00eas, ou com o<\/span><\/span><span style=\"color: #ff6600;\"><strong> \u201cwww\u201d.<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, como \u201clol\u201d j\u00e1 \u00e9 popular no exterior h\u00e1 quase 20 anos, os jovens de hoje, em vez de usar esse \u201clol\u201d que parece um pouco ultrapassado, tendem mais a usar \u201cemoji (emoticons)\u201d ou \u201chaha\u201d para expressar \u201crisada\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>btw<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"color: #ff6600;\"><strong>\u201cbtw\u201d <\/strong><\/span><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">\u00e9 a sigla de<\/span><\/span><strong><span style=\"color: #ff0000;\"><span style=\"color: #ff6600;\"> \u201cby the way\u201d.<\/span> <\/span><\/strong><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">Ela costuma aparecer no in\u00edcio ou no fim de uma frase para representar<\/span><\/span> <span style=\"color: #ff6600;\"><strong>\u201ca prop\u00f3sito\u201d, \u201cali\u00e1s\u201d, \u201cvoltando ao assunto\u201d<\/strong> <\/span>e \u00e9 usada em situa\u00e7\u00f5es de \u201cmudan\u00e7a de assunto\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, quando voc\u00eas quiserem mudar para o pr\u00f3ximo assunto, podem usar \u201cBTW, did you see the news?\uff08A prop\u00f3sito, voc\u00ea viu as not\u00edcias?\uff09\u201d ou \u201cWhy didn\u2019t you call me back, btw?\uff08Ali\u00e1s, por que voc\u00ea n\u00e3o me ligou de volta?\uff09\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre eles, no segundo exemplo, o \u201cbtw\u201d pode at\u00e9 ser opcional, mas quando voc\u00eas adicionam \u201cbtw\u201d, isso reduz o tom de cobran\u00e7a e faz a outra pessoa perceber como algo mais leve e f\u00e1cil de ouvir!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>pls \/ plz<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"color: #ff6600;\"><strong>\u201cpls\u201d e \u201cplz\u201d<\/strong><\/span><span style=\"color: #000000;\"> s\u00e3o siglas de <\/span><span style=\"color: #ff6600;\"><strong>\u201cplease\u201d<\/strong><\/span> e s\u00e3o usadas com frequ\u00eancia em situa\u00e7\u00f5es de \u201cpedido\u201d ou \u201cpor favor, fa\u00e7a algo\u201d. Como essas duas formas n\u00e3o t\u00eam nenhuma diferen\u00e7a, voc\u00eas podem escolher a que preferirem.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, se voc\u00eas <span style=\"color: #0000ff;\"><span style=\"color: #000000;\">quiserem refor\u00e7ar o tom de<\/span> <\/span><span style=\"color: #ff6600;\"><strong>\u201cpor favor\u201d,<\/strong><\/span><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"> tamb\u00e9m podem repetir o<\/span><\/span> <span style=\"color: #ff6600;\"><strong>\u201cz\u201d <\/strong><\/span><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">v\u00e1rias vezes e escrever<\/span><\/span> <span style=\"color: #ff6600;\"><strong>\u201cplzzzz\u201d<\/strong><\/span><span style=\"color: #0000ff;\"><span style=\"color: #000000;\"> para expressar o sentido de<\/span><\/span><span style=\"color: #ff6600;\"><strong> \u201cum pedido insistente\u201d<\/strong>.<\/span><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aqui vai um lembrete: embora \u201cplease\u201d seja adequado para situa\u00e7\u00f5es formais, como as siglas \u201cpls\/plz\u201d s\u00e3o mais informais, \u00e9 recomend\u00e1vel evitar us\u00e1-las em contextos formais e us\u00e1-las em situa\u00e7\u00f5es de \u201cconversa descontra\u00edda com amigos e familiares\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>r\uff06u?\uff08are\u2192 r \/ you \u2192 u\uff09<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">Em conversas informais na internet,<\/span><\/span> <strong><span style=\"color: #ff0000;\"><span style=\"color: #ff6600;\">\u201care\u201d<\/span> <\/span><\/strong><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">costuma ser abreviado para<\/span><\/span><span style=\"color: #ff6600;\"><strong> \u201cr\u201d e \u201cyou\u201d<\/strong><\/span><span style=\"color: #ff0000;\"><span style=\"color: #000000;\"> para<\/span><\/span><span style=\"color: #ff6600;\"> <strong>\u201cu\u201d.<\/strong><\/span> A vantagem desse uso \u00e9 conseguir \u201cdigitar mais r\u00e1pido\u201d e isso \u00e9 especialmente popular entre adolescentes nos Estados Unidos. Por exemplo: \u201cWhat r u doing now? \uff08O que voc\u00ea t\u00e1 fazendo agora?\uff09\u201d ou \u201cr u kidding me? \uff08Voc\u00ea t\u00e1 de brincadeira comigo?\uff09\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, como esse jeito \u00e9 muito casual, por favor n\u00e3o use em situa\u00e7\u00f5es formais!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>idk<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff0000;\"><span style=\"color: #ff6600;\">\u201cidk\u201d<\/span> <\/span><\/strong><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">\u00e9 a sigla de<\/span><\/span> <span style=\"color: #ff6600;\"><strong>\u201cI don\u2019t know\u201d <\/strong><\/span><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">e significa<\/span><\/span> <span style=\"color: #ff6600;\"><strong>\u201cn\u00e3o sei\u201d <\/strong><\/span><span style=\"color: #ff0000;\"><span style=\"color: #000000;\">ou<\/span><\/span><span style=\"color: #ff6600;\"><strong> \u201cn\u00e3o tenho certeza\u201d.<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora \u201cdunno\u201d tamb\u00e9m possa expressar o mesmo sentido que \u201cidk\u201d, como a forma \u201cdunno\u201d \u00e9 ainda mais informal, em compara\u00e7\u00e3o com textos na internet, \u201cdunno\u201d aparece com mais frequ\u00eancia em conversas do dia a dia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vale notar que, embora \u201cidk\u201d seja usado para dizer \u201ceu n\u00e3o sei\u201d, \u00e0s vezes ele tamb\u00e9m pode carregar um sentido de \u201cresposta meio vaga\u201d e dar a impress\u00e3o de <strong><span style=\"color: #ff6600;\">\u201cn\u00e3o t\u00f4 a fim de responder\u201d.<\/span><\/strong> Por isso, quando voc\u00eas usarem, por favor considerem sempre \u201co interlocutor e a situa\u00e7\u00e3o\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">At\u00e9 aqui, no artigo, apresentamos as \u201cg\u00edrias da internet\u201d que s\u00e3o usadas com frequ\u00eancia em redes e m\u00eddias sociais. Ser\u00e1 que voc\u00eas viram quantas delas?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essas g\u00edrias n\u00e3o s\u00f3 deixam a comunica\u00e7\u00e3o no SNS mais fluida, como tamb\u00e9m ajudam a acelerar a velocidade de resposta!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cG\u00edria\u201d, basicamente, \u00e9 algo usado em conversas mais descontra\u00eddas entre \u201camigos\u201d, etc. Por isso, prestem aten\u00e7\u00e3o especial! Se voc\u00eas usarem por engano em <strong><span style=\"color: #ff6600;\">\u201csitua\u00e7\u00f5es formais\u201d,<\/span><\/strong> v\u00e3o acabar passando a impress\u00e3o de que voc\u00eas n\u00e3o s\u00e3o muito educados!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, se voc\u00eas n\u00e3o entenderem bem o significado das \u201cg\u00edrias\u201d e usarem de qualquer jeito, tamb\u00e9m podem acabar ferindo a outra pessoa sem querer, ou at\u00e9 fazendo com que sua forma de se expressar pare\u00e7a estranha&#8230; Portanto, antes de usar qualquer g\u00edria, por favor, entendam primeiro o verdadeiro significado delas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Resumo<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Neste artigo, n\u00f3s explicamos como<span style=\"font-size: 24px;\"><strong><span style=\"color: #ff6600;\"> \u201cR.I.P.\u201d<\/span><\/strong><\/span> \u00e9 usada em pa\u00edses de l\u00edngua inglesa, al\u00e9m de esclarecer o significado original e o sentido quando usada como g\u00edria. Al\u00e9m disso, na segunda metade do artigo, aprendemos juntos muitas outras \u201cg\u00edrias da internet\u201d comuns.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando voc\u00eas conseguirem usar essas g\u00edrias naturalmente em e-mails ou mensagens, isso vai deixar sua conversa mais pr\u00f3xima da fluidez de falantes estrangeiros e, consequentemente, vai melhorar bastante sua capacidade de se expressar em ingl\u00eas. Recomendamos que voc\u00eas comecem usando g\u00edrias que as pessoas ao seu redor usam com frequ\u00eancia, ou aquelas que voc\u00eas acham mais f\u00e1ceis de pegar. Agora, vamos incorporar as \u201cg\u00edrias\u201d no nosso dia a dia!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todo mundo j\u00e1 viu essa forma de express\u00e3o em ingl\u00eas, \u201cR.I.P.\u201d? Talvez ela n\u00e3o seja t\u00e3o comum no Brasil, mas, quando todos v\u00e3o para pa\u00edses de l\u00edngua inglesa, percebem que \u201cR.I.P.\u201d \u00e9 frequentemente gravado em l\u00e1pides ou aparece com frequ\u00eancia nas redes sociais. Por isso, pensamos que, mesmo que muitas pessoas j\u00e1 saibam o significado original, elas provavelmente ainda n\u00e3o sabem que \u201cR.I.P.\u201d tamb\u00e9m \u00e9 usado entre estrangeiros como \u201cg\u00edria\u201d, n\u00e3o \u00e9 mesmo! Desta vez, neste artigo, n\u00f3s vamos\u00a0 analisar o significado de \u201cR.I.P.\u201d, como usar e os cuidados ao utiliz\u00e1-lo\u3002Al\u00e9m disso, na segunda metade do artigo, vamos trazer ainda mais informa\u00e7\u00f5es sobre outras g\u00edrias comuns e parecidas. Esperamos que, &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/16223\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":16224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=16223","footnotes":""},"categories":[120,122,121],"tags":[],"class_list":["post-16223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grammar","category-pronunciation","category-words","pt-BR"],"aioseo_notices":[],"views":265,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=16223"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16223\/revisions"}],"predecessor-version":[{"id":16225,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16223\/revisions\/16225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/16224"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=16223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=16223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=16223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}