{"id":16087,"date":"2026-04-15T09:00:42","date_gmt":"2026-04-15T12:00:42","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=16087"},"modified":"2026-04-06T05:47:58","modified_gmt":"2026-04-06T08:47:58","slug":"como-se-diz-sacrificio-em-ingles-apresentamos-sinonimos-como-victim-e-expense","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/16087\/","title":{"rendered":"Como se diz \u201csacrif\u00edcio\u201d em ingl\u00eas? Apresentamos sin\u00f4nimos como \u201cvictim\u201d e \u201cexpense\u201d!"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Nesta mat\u00e9ria, vamos apresentar <span style=\"font-size: 28px;\"><span style=\"color: #d11bbf;\"><strong>as formas de dizer \u201csacrif\u00edcio\u201d em ingl\u00eas<\/strong><\/span>.<\/span><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Frequentemente, em alguns contextos, ouvimos frases como \u201csacrificar a vida pessoal para conseguir uma promo\u00e7\u00e3o\u201d, \u201ctrocar sacrif\u00edcio por crescimento\u201d, etc. S\u00e3o di\u00e1logos em que se abre m\u00e3o de coisas importantes para alcan\u00e7ar certos objetivos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, \u201cv\u00edtimas de guerra\u201d e \u201cv\u00edtimas de crimes\u201d se referem especificamente \u00e0s pessoas que perderam vidas preciosas por causa de desastres, acidentes ou crimes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cSacrif\u00edcio\u201d, no mundo de l\u00edngua inglesa, costuma ser expresso principalmente por \u201csacrifice\u201d e \u201cvictim\u201d em reportagens de TV ou em cen\u00e1rios comerciais! Quando todos entenderem a origem dessas express\u00f5es, o significado que carregam e os contextos em que se aplicam, isso vai ajudar voc\u00ea a us\u00e1-las com mais precis\u00e3o, ok?!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Formas de dizer \u201csacrif\u00edcio\u201d em ingl\u00eas<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Existem muitos sin\u00f4nimos em ingl\u00eas que podem representar o sentido de \u201csacrif\u00edcio\u201d. Por isso, \u00e9 necess\u00e1rio que todos escolham a express\u00e3o mais adequada de acordo com cada situa\u00e7\u00e3o para us\u00e1-la. E quando voc\u00eas dominarem perfeitamente os significados de cada uma, tamb\u00e9m ser\u00e1 mais f\u00e1cil lembrar como us\u00e1-las, n\u00e3o \u00e9?!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, vamos explicar algumas express\u00f5es comuns de \u201csacrif\u00edcio\u201d em ingl\u00eas: <strong>\u201csacrifice\u201d, \u201cprey\u201d, \u201cvictim\u201d e \u201cexpense\u201d<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E o ponto em comum dessas express\u00f5es \u00e9 que todas carregam a ideia de troca (trade-off) de \u201cperder algo para conseguir algo\u201d.<\/span><\/p>\n<h3><b>sacrifice<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, a primeira palavra que<strong><span style=\"color: #ff0000;\"> voc\u00eas precisam lembrar em ingl\u00eas \u00e9 \u201csacrifice\u201d<\/span><\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201csacrifice\u201d \u00e9 uma palavra formada pela combina\u00e7\u00e3o do latim \u201csacer (sagrado)\u201d e \u201cfacere (fazer, criar)\u201d, e \u00e9 semelhante ao sentido de \u201coferta viva\u201d no Brasil.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como foi dito acima, tanto no Oriente quanto no Ocidente, a palavra \u201csacrif\u00edcio\u201d vem de antigos <span style=\"font-weight: 400;\">\u201crituais religiosos\u201d<\/span>. Por exemplo, nos rituais do juda\u00edsmo, as pessoas oferecem animais como ovelhas, bois e cabras aos deuses. At\u00e9 no <span style=\"font-weight: 400;\">\u201cLev\u00edtico\u201d da B\u00edblia (Antigo Testamento)<\/span> h\u00e1 registros detalhados das regras para os sacrif\u00edcios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como a ideia essencial do sacrif\u00edcio \u00e9 \u201coferecer algo valioso\u201d, a palavra \u201csacrifice\u201d tamb\u00e9m carrega um sentido de \u201cpeso\u201d, \u201cgravidade\u201d.<\/span><\/p>\n<h5><b>Ele teve que sacrificar seu tempo pessoal para conseguir uma promo\u00e7\u00e3o na empresa.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ele teve que sacrificar seu tempo pessoal para conseguir uma promo\u00e7\u00e3o na empresa.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Muitos jovens sacrificaram suas vidas pela guerra.<\/b><br \/>\n<span style=\"font-weight: 400;\">Muitos jovens sacrificaram suas vidas pela guerra.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Ele estava preparado para fazer qualquer sacrif\u00edcio para alcan\u00e7ar seu objetivo.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ele estava preparado para fazer qualquer sacrif\u00edcio para alcan\u00e7ar seu objetivo.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>prey<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><strong><span style=\"color: #ff0000;\">\u201cprey\u201d<\/span><\/strong> \u00e9 uma express\u00e3o de uso mais \u201crestrito\u201d e, normalmente, se refere especificamente a<strong><span style=\"color: #ff0000;\"> \u201cpresas de animais carn\u00edvoros\u201d<\/span><\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00eas tamb\u00e9m podem imaginar a cena de \u201canimais herb\u00edvoros sendo ca\u00e7ados por animais carn\u00edvoros\u201d e estender essa imagem para a ideia de \u201co mais forte predando o mais fraco\u201d nas rela\u00e7\u00f5es humanas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando \u201cprey\u201d \u00e9 usado como substantivo, ele significa \u201cv\u00edtima (animal ou pessoa)\u201d, mas <span style=\"color: #0000ff;\"><strong>quando usado como verbo, \u201cprey on~\u201d significa \u201cca\u00e7ar, ferir, enganar\u201d<\/strong><\/span>. Al\u00e9m disso, <strong><span style=\"color: #39d911;\">\u201crela\u00e7\u00e3o de preda\u00e7\u00e3o\u201d em biologia tamb\u00e9m \u00e9 chamada de \u201cpredator-prey relationship\u201d.<\/span><\/strong><\/span><\/p>\n<h5><b>Na natureza, <\/b><b>carn\u00edvoros predam herb\u00edvoros.<\/b><br \/>\n<span style=\"font-weight: 400;\">Na natureza, animais carn\u00edvoros predam animais herb\u00edvoros.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>O golpista ganhou muito dinheiro explorando mulheres jovens e ing\u00eanuas.<\/b><br \/>\n<span style=\"font-weight: 400;\">O golpista ganhou muito dinheiro explorando mulheres jovens e ing\u00eanuas.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Mulheres e idosos, que n\u00e3o t\u00eam poder para resistir, s\u00e3o presas f\u00e1ceis para o crime.<\/b><br \/>\n<span style=\"font-weight: 400;\">Mulheres e idosos, que n\u00e3o t\u00eam poder para resistir, s\u00e3o presas f\u00e1ceis para o crime.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>victim<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff0000;\">\u201cvictim\u201d \u00e9 uma palavra em ingl\u00eas que significa \u201cv\u00edtima, pessoa que sofreu, falecido em decorr\u00eancia de um evento\u201d.<\/span><\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Ela se aplica<span style=\"color: #0000ff;\"><strong> a situa\u00e7\u00f5es em que algu\u00e9m \u00e9 v\u00edtima por causa de infort\u00fanios como guerra, acidentes e desastres, e ao mesmo tempo representa \u201ca v\u00edtima em um crime\u201d (v\u00edtima de crime)<\/strong><\/span>.<\/span><\/p>\n<h5><b>O tsunami, desencadeado por um forte terremoto, fez v\u00edtimas por toda a regi\u00e3o costeira.<\/b><br \/>\n<span style=\"font-weight: 400;\">O tsunami, desencadeado por um forte terremoto, fez v\u00edtimas por toda a regi\u00e3o costeira.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Os advogados trabalharam arduamente para ajudar as v\u00edtimas de crime.<\/b><br \/>\n<span style=\"font-weight: 400;\">A equipe de advogados trabalhou arduamente para ajudar as v\u00edtimas de crime.<\/span><\/h5>\n<p><strong><span style=\"color: #0000ff;\">Muitas not\u00edcias ou reportagens, especialmente ao descrever \u201cguerra ou grandes desastres\u201d, costumam substituir \u201cvictim\u201d por \u201ccasualty\u201d.<\/span><\/strong><\/p>\n<h5><b>Os ataques do inimigo causaram muitas baixas no ex\u00e9rcito.<\/b><br \/>\n<span style=\"font-weight: 400;\">Os ataques do inimigo causaram muitas<\/span><span style=\"font-weight: 400;\"> baixas no ex\u00e9rcito (v\u00edtimas)<\/span><span style=\"font-weight: 400;\">.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Em compara\u00e7\u00e3o com \u201csacrifice\u201d, que traz a ideia de \u201cdoa\u00e7\u00e3o volunt\u00e1ria\u201d, \u201cvictim\u201d e \u201ccasualty\u201d s\u00e3o usados com mais frequ\u00eancia para descrever situa\u00e7\u00f5es de sacrif\u00edcio em que se sofre um infort\u00fanio e n\u00e3o se consegue resistir.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>expense<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"color: #ff0000;\"><strong>O significado b\u00e1sico de \u201cexpense\u201d \u00e9 \u201cdespesa, gasto\u201d<\/strong><\/span>, e geralmente \u00e9 usado para indicar o dinheiro, o tempo ou a energia despendidos para realizar algo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas, em alguns contextos, <strong><span style=\"color: #0000ff;\">\u201cat the expense of ~\u201d tamb\u00e9m pode significar \u201csacrificar ~\u201d<\/span><\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre as express\u00f5es comuns de \u201cexpense\u201d, est\u00e3o <strong>\u201cworth the expense (vale o gasto)\u201d, \u201cat great expense (com um custo enorme)\u201d, \u201cat someone\u2019s expense (\u00e0s custas de algu\u00e9m)\u201d e \u201cgo to the expense of\u00a0 (gastar dinheiro para )\u201d<\/strong>.<\/span><\/p>\n<h5><b>Ele gastou dinheiro para contratar um advogado.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ele gastou dinheiro para contratar um advogado.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>O terrorismo \u00e9 um meio de alcan\u00e7ar uma declara\u00e7\u00e3o pol\u00edtica por meio da viol\u00eancia e do medo, muitas vezes \u00e0 custa de muitos civis inocentes.<\/b><br \/>\n<span style=\"font-weight: 400;\">O terrorismo \u00e9 um meio de alcan\u00e7ar uma declara\u00e7\u00e3o pol\u00edtica por meio da viol\u00eancia e do medo, muitas vezes sacrificando muitos civis inocentes.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Manter um carro exige uma grande despesa.<\/b><br \/>\n<span style=\"font-weight: 400;\">Manter um carro exige uma grande despesa.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Voo alto para sacrif\u00edcio (abrevia\u00e7\u00e3o: sac fly)<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea gosta de beisebol, provavelmente j\u00e1 deve ter ouvido \u201csac fly\u201d, n\u00e3o \u00e9?!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E \u201csac fly\u201d em ingl\u00eas \u00e9 chamado de <strong><span style=\"color: #ff0000;\">\u201csac fly\u201d ou \u201csacrifice fly\u201d<\/span><\/strong>, enquanto<strong><span style=\"color: #0000ff;\"> \u201csacrif\u00edcio de bunt\u201d<\/span><\/strong> \u00e9 chamado de \u201csac bunt\u201d ou \u201csacrifice bunt\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">At\u00e9 aqui, na mat\u00e9ria, apresentamos algumas express\u00f5es representativas em ingl\u00eas que significam \u201csacrif\u00edcio\u201d. A seguir, vamos ver juntos outros sin\u00f4nimos relacionados a \u201csacrif\u00edcio\u201d!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Sin\u00f4nimos de \u201csacrif\u00edcio\u201d<\/b><\/h2>\n<h3><b>Substituto, bode expiat\u00f3rio scapegoat<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u201cscapegoat\u201d pode ser associado \u00e0 \u201csacrifice\u201d mencionada antes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cscapegoat\u201d vem do <span style=\"font-weight: 400;\">\u201cLev\u00edtico\u201d da B\u00edblia (Antigo Testamento)<\/span>. Ele se refere a uma cabra que, no Dia da Expia\u00e7\u00e3o, carregava os pecados das pessoas e era enviada para o deserto. Nesse caso, \u201cscapegoat\u201d \u00e9 uma palavra formada por \u201cscape (escapar)\u201d + \u201cgoat (cabra)\u201d, e deriva do sentido literal de \u201ccabra que foge\u201d, passando a significar \u201cpara acalmar a insatisfa\u00e7\u00e3o, usar algu\u00e9m ou um grupo inteiro como bode expiat\u00f3rio e assumir essa responsabilidade\u201d. E na sociedade moderna, \u00e0s vezes as pessoas at\u00e9 criam deliberadamente \u201cbodes expiat\u00f3rios\u201d. Por exemplo, durante a pandemia de COVID-19, os EUA tiveram muitos casos de \u201cscapegoating\u201d e isso gerou sentimento de discrimina\u00e7\u00e3o contra pessoas asi\u00e1ticas.<\/span><\/p>\n<h5><b>O diretor executivo usou um departamento como bode expiat\u00f3rio para a piora do desempenho.<\/b><br \/>\n<span style=\"font-weight: 400;\">O diretor executivo usou um departamento como bode expiat\u00f3rio para a piora do desempenho.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Isca, armadilha decoy<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff0000;\">\u201cdecoy\u201d significa \u201cisca, armadilha\u201d.<\/span><\/strong><\/p>\n<p><span style=\"font-weight: 400;\">\u201cdecoy\u201d originalmente se referia a \u201cum ca\u00e7ador usar o comportamento das aves para fabricar modelos parecidos com p\u00e1ssaros e atrair as presas\u201d, e da\u00ed surgiu a ideia de \u201cenganar ou induzir algu\u00e9m a cair em uma armadilha\u201d.<\/span><\/p>\n<h5><b>Os pescadores colocaram iscas de madeira esculpidas no lago para atrair os p\u00e1ssaros.<\/b><br \/>\n<span style=\"font-weight: 400;\">Os pescadores colocaram iscas de madeira esculpidas no lago para atrair os p\u00e1ssaros.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Indeniza\u00e7\u00e3o, compensa\u00e7\u00e3o (dinheiro ou bens) compensation<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">No Brasil<\/span><span style=\"font-weight: 400;\">, n\u00f3s frequentemente dizemos<span style=\"color: #ff0000;\"><strong> \u201cpagar um pre\u00e7o por algo\u201d e, nesse conceito de \u201ccompensa\u00e7\u00e3o, indeniza\u00e7\u00e3o\u201d, podemos usar \u201ccompensation\u201d para express\u00e1-lo.<\/strong><\/span><\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201ccompensation\u201d significa \u201cvalor de indeniza\u00e7\u00e3o, quantia de compensa\u00e7\u00e3o\u201d e \u00e9 um substantivo derivado do verbo \u201ccompensate (compensar, pagar)\u201d.<\/span><\/p>\n<h5><b>O caso, que causou grande como\u00e7\u00e3o p\u00fablica, foi resolvido com o pagamento de indeniza\u00e7\u00e3o \u00e0 v\u00edtima.<\/b><br \/>\n<span style=\"font-weight: 400;\">O caso, que causou grande como\u00e7\u00e3o p\u00fablica, foi resolvido com o pagamento de indeniza\u00e7\u00e3o \u00e0 v\u00edtima.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Aqueles que sofreram problemas de sa\u00fade devido \u00e0 polui\u00e7\u00e3o receberam uma compensa\u00e7\u00e3o substancial das empresas.<\/b><br \/>\n<span style=\"font-weight: 400;\">As pessoas que tiveram problemas de sa\u00fade por causa da polui\u00e7\u00e3o receberam uma indeniza\u00e7\u00e3o substancial das empresas.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Sacrif\u00edcio e dedica\u00e7\u00e3o dedicated, committed<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"color: #ff0000;\"><strong>\u201cdedicated\u201d e \u201ccommitted\u201d v\u00eam dos verbos \u201cdedicate (dedicar)\u201d e \u201ccommit (empenhar-se)\u201d<\/strong><\/span> e ambos podem ser usados para descrever o esp\u00edrito de dedica\u00e7\u00e3o total, etc.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E quando \u201cdedicated\u201d e \u201ccommitted\u201d descrevem uma pessoa, elas s\u00e3o traduzidas como \u201ccheia de entusiasmo\u201d, \u201cengajada\u201d, \u201cdedicada de forma altru\u00edsta\u201d, etc.<\/span><\/p>\n<h5><b>O trabalho dedicado dela se tornou um apoio firme para muitas pessoas em dificuldades.<\/b><br \/>\n<span style=\"font-weight: 400;\">O trabalho dedicado dela se tornou um apoio firme para muitas pessoas em dificuldades.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Nenhum grande projeto teria sido conclu\u00eddo sem o trabalho de pessoas dedicadas.<\/b><br \/>\n<span style=\"font-weight: 400;\">Nenhum grande projeto teria sido conclu\u00eddo sem o trabalho de pessoas dedicadas.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Foi preciso uma equipe de funcion\u00e1rios comprometidos para tornar aquela empresa um grande sucesso.<\/b><br \/>\n<span style=\"font-weight: 400;\">Gra\u00e7as a uma equipe de<\/span><span style=\"font-weight: 400;\"> funcion\u00e1rios dedicados (cheios de entusiasmo)<\/span><span style=\"font-weight: 400;\">, a empresa alcan\u00e7ou um enorme sucesso.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Resumo<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Nesta mat\u00e9ria, explicamos quatro formas em ingl\u00eas que representam o sentido de \u201csacrif\u00edcio\u201d: \u201csacrifice\u201d, \u201cprey\u201d, \u201cvictim\u201d e \u201cexpense\u201d, e na segunda metade do artigo apresentamos ainda muitos outros sin\u00f4nimos relacionados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando todos conseguirem entender a origem dessas palavras e os contextos de uso, isso vai ajudar voc\u00ea a expressar \u201csacrif\u00edcio\u201d de forma mais correta e precisa de acordo com cada situa\u00e7\u00e3o. Al\u00e9m disso, essas palavras aparecem com frequ\u00eancia em contextos formais como not\u00edcias e ambientes comerciais. Esperamos que, ap\u00f3s ler este artigo, voc\u00eas consigam usar essas express\u00f5es de \u201csacrif\u00edcio\u201d com mais flexibilidade!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta mat\u00e9ria, vamos apresentar as formas de dizer \u201csacrif\u00edcio\u201d em ingl\u00eas. Frequentemente, em alguns contextos, ouvimos frases como \u201csacrificar a vida pessoal para conseguir uma promo\u00e7\u00e3o\u201d, \u201ctrocar sacrif\u00edcio por crescimento\u201d, etc. S\u00e3o di\u00e1logos em que se abre m\u00e3o de coisas importantes para alcan\u00e7ar certos objetivos. Al\u00e9m disso, \u201cv\u00edtimas de guerra\u201d e \u201cv\u00edtimas de crimes\u201d se referem especificamente \u00e0s pessoas que perderam vidas preciosas por causa de desastres, acidentes ou crimes. \u201cSacrif\u00edcio\u201d, no mundo de l\u00edngua inglesa, costuma ser expresso principalmente por \u201csacrifice\u201d e \u201cvictim\u201d em reportagens de TV ou em cen\u00e1rios comerciais! Quando todos entenderem a origem dessas express\u00f5es, o significado que carregam e os contextos em que se aplicam, &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/16087\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":16088,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=16087","footnotes":""},"categories":[129,128,127],"tags":[],"class_list":["post-16087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-children","category-business","category-travel","pt-BR"],"aioseo_notices":[],"views":117,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=16087"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16087\/revisions"}],"predecessor-version":[{"id":16089,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/16087\/revisions\/16089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/16088"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=16087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=16087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=16087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}