{"id":15670,"date":"2026-03-19T09:00:57","date_gmt":"2026-03-19T12:00:57","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=15670"},"modified":"2026-03-16T04:00:49","modified_gmt":"2026-03-16T07:00:49","slug":"explicacao-sobre-como-usar-do-you-mind-e-os-pontos-em-que-e-facil-cometer-erros","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/15670\/","title":{"rendered":"Explica\u00e7\u00e3o sobre como usar \u00abDo you mind?\u00bb e os pontos em que \u00e9 f\u00e1cil cometer erros!"},"content":{"rendered":"<p dir=\"ltr\">&#8220;Voc\u00ea pode me ajudar?&#8221;, &#8220;Pode me passar o sal?&#8221;, &#8220;Voc\u00ea poderia me enviar os documentos por e-mail?&#8221; e assim por diante&#8230; Seja na vida cotidiana ou no ambiente de trabalho,\u00a0 <span style=\"text-decoration: underline;\"><strong>fazer pedidos para outras pessoas<\/strong><\/span> \u00e9 algo bastante comum!<\/p>\n<p dir=\"ltr\">Ent\u00e3o, quando voc\u00ea quiser fazer um pedido em ingl\u00eas, qual express\u00e3o voc\u00ea costuma usar? No mundo do ingl\u00eas, h\u00e1 v\u00e1rias formas de expressar esse sentido de \u201cpedido\u201d. Neste artigo, vamos focar na express\u00e3o &#8220;Do you mind?&#8221;, que \u00e9 muito usada por estrangeiros.<\/p>\n<p dir=\"ltr\"><span style=\"font-size: 36px; color: #d502d9;\"><strong>Do you mind?<\/strong><\/span>\u00a0 \u00e9 uma express\u00e3o que deixa uma impress\u00e3o de \u201ccortesia\u201d para o interlocutor. Por isso, depois de aprender a us\u00e1-la, voc\u00ea com certeza s\u00f3 ter\u00e1 a ganhar! O artigo tamb\u00e9m explicar\u00e1 as \u201crespostas que levam a erros\u201d e \u201coutras formas de fazer pedidos\u201d. Cada express\u00e3o ser\u00e1 detalhada com exemplos pr\u00e1ticos. Por isso, n\u00e3o deixe de praticar os exemplos em voz alta v\u00e1rias vezes no final do texto!<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">O significado e o uso de &#8220;Do you mind\uff5e?&#8221;<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"font-size: 36px; color: #04d42e;\">Do you mind?<\/span> significa <span style=\"text-decoration: underline;\"><strong>&#8220;Voc\u00ea pode?&#8221;, &#8220;Voc\u00ea poderia me ajudar a?&#8221;, &#8220;Seria conveniente para voc\u00ea?&#8221;<\/strong><\/span>, e normalmente, <span style=\"text-decoration: underline;\"><strong>usa-se o verbo na forma -ing depois da frase<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">Porque <strong>\u201cmind\u201d<\/strong>, em ingl\u00eas, significa <span style=\"text-decoration: underline;\"><strong>\u201cse importar\u201d, \u201cter obje\u00e7\u00e3o\u201d<\/strong><\/span>. Portanto, <strong>\u201cDo you mind?\u201d<\/strong> expressa um pedido sutil do tipo \u201cVoc\u00ea se importaria de?\u201d, demonstrando considera\u00e7\u00e3o pelo outro.<\/p>\n<p dir=\"ltr\">Al\u00e9m disso, quando &#8220;Do you mind?&#8221; \u00e9 seguido de &#8220;if&#8221;, mudando para <strong>\u201cDo you mind if I?\u201d<\/strong>, significa <span style=\"text-decoration: underline;\"><strong>\u201cEu posso?\u201d, \u201cSe eu, voc\u00ea se importaria?\u201d<\/strong><\/span>.<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">Erro comum! Aten\u00e7\u00e3o \u00e0 forma correta de responder &#8220;Do you mind\uff5e?&#8221;<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Quando algu\u00e9m te diz <strong>\u201cDo you mind?\u201d<\/strong>, preste aten\u00e7\u00e3o se sua resposta est\u00e1\u00a0 <span style=\"text-decoration: underline;\"><strong>correta<\/strong><\/span>!<\/p>\n<p dir=\"ltr\">Como explicado acima, &#8220;Do you mind?&#8221; literalmente significa &#8220;Voc\u00ea se importa em?&#8221;. Se voc\u00ea responder <strong>\u201cYes\u201d<\/strong>, isso quer dizer &#8220;Sim, me importo (ou seja, n\u00e3o pode)&#8221;. S\u00f3 se responder <strong>\u201cNo\u201d<\/strong> \u00e9 que quer dizer &#8220;N\u00e3o, n\u00e3o me importo (ou seja, tudo bem)&#8221;.<\/p>\n<p dir=\"ltr\">Portanto, quando responder a \u201cDo you mind?\u201d e quiser dizer que \u201cn\u00e3o se importa, n\u00e3o tem problema\u201d, lembre-se de dizer <span style=\"text-decoration: underline;\"><strong>\u201cNo, I don\u2019t mind.\u201d (N\u00e3o me importo)<\/strong><\/span>, <span style=\"text-decoration: underline;\"><strong>\u201cNot at all.\u201d (De jeito nenhum)<\/strong><\/span> ou <span style=\"text-decoration: underline;\"><strong>\u201cGo ahead.\u201d (Fique \u00e0 vontade)<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">Apesar de no portugu\u00eas normalmente se usar \u201csim\u201d para concordar, na express\u00e3o em ingl\u00eas &#8220;Do you mind?&#8221; \u00e9 exatamente o oposto! Portanto, \u00e9 fundamental tomar esse cuidado!<\/p>\n<h5 dir=\"ltr\"><strong>A\uff1a Do you mind closing the window?<\/strong><br \/>\nVoc\u00ea se importa de fechar a janela?<br \/>\n<strong>B\uff1aNo, I don&#8217;t mind.<\/strong><br \/>\nN\u00e3o, n\u00e3o me importo \/ Claro, sem problema.<\/h5>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">Outras express\u00f5es para fazer pedidos<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">A seguir, vamos apresentar <span style=\"text-decoration: underline;\"><strong>outras formas de fazer pedidos em ingl\u00eas<\/strong><\/span>. Embora todas possam ser usadas para pedir algo, cada uma tem um grau diferente de cortesia.<\/p>\n<p dir=\"ltr\">Vamos conhec\u00ea-las uma a uma!<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>Will you?<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">\u201cWill you?\u201d \u00e9 uma forma casual muito usada em conversas do dia a dia. Tem o sentido de\u00a0 <span style=\"text-decoration: underline;\"><strong>\u201cVoc\u00ea pode fazer tal coisa para mim?\u201d<\/strong><\/span> e n\u00e3o \u00e9 adequada para ambientes de trabalho.<\/p>\n<p dir=\"ltr\">Al\u00e9m disso, voc\u00ea pode adicionar\u00a0 <span style=\"text-decoration: underline;\"><strong>\u201cplease\u201d<\/strong><\/span>\u00a0 no final para tornar o pedido mais educado.<\/p>\n<p dir=\"ltr\">Exemplos:<\/p>\n<h5 dir=\"ltr\"><strong>Will you send the letter?<\/strong><br \/>\nVoc\u00ea pode enviar a carta?<\/h5>\n<h5 dir=\"ltr\"><strong>Will you give me the receipt, please?<\/strong><br \/>\nPode me dar o recibo, por favor?<\/h5>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>Can you?<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><strong>\u201cCan you?\u201d<\/strong> significa\u00a0 <span style=\"text-decoration: underline;\"><strong>\u201cVoc\u00ea consegue?\u201d<\/strong><\/span>, sendo tamb\u00e9m uma forma casual. Seu uso \u00e9 parecido com o de <strong>\u201cWill you?\u201d<\/strong>, e ao acrescentar \u201cplease\u201d, fica ainda mais educado.<\/p>\n<p dir=\"ltr\">Exemplos:<\/p>\n<h5 dir=\"ltr\"><strong>Can you pick me up at the airport?<\/strong><br \/>\nVoc\u00ea pode me buscar no aeroporto?<\/h5>\n<h5 dir=\"ltr\"><strong>Can you pass me the sugar, please?<\/strong><br \/>\nPode me passar o a\u00e7\u00facar, por favor?<\/h5>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>Could you?<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"text-decoration: underline;\"><strong>&#8220;Could you?&#8221;\u00a0 \u00e9 uma forma mais educada que &#8220;Can you?&#8221;<\/strong><\/span> e \u00e9 bastante apropriada para ambientes profissionais. Quando morei no Reino Unido, ouvia essa express\u00e3o frequentemente no cotidiano.<\/p>\n<p dir=\"ltr\">Se voc\u00ea ainda adicionar <strong>\u201cplease\u201d<\/strong>, sua frase ficar\u00e1 extremamente educada!<\/p>\n<p dir=\"ltr\">Exemplo:<\/p>\n<h5 dir=\"ltr\"><strong>Could you send him an email, please?<\/strong><br \/>\nVoc\u00ea poderia enviar um e-mail para ele, por favor?<\/h5>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>Would you?<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"text-decoration: underline;\"><strong>\u201cWould you?\u201d \u00e9 parecida com \u201cCould you?\u201d<\/strong><\/span>, ambas s\u00e3o bastante educadas. Por\u00e9m, <strong>\u201cCould you?\u201d<\/strong> enfatiza <span style=\"text-decoration: underline;\"><strong>se a pessoa tem capacidade para fazer algo<\/strong><\/span>, enquanto <strong>\u201cWould you\u201d<\/strong> questiona\u00a0 <span style=\"text-decoration: underline;\"><strong>se a pessoa est\u00e1 disposta a fazer algo<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">Exemplo:<\/p>\n<h5 dir=\"ltr\"><strong>Would you look over my essay?<\/strong><br \/>\nVoc\u00ea poderia dar uma olhada no meu ensaio?<\/h5>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>I was wondering if you could<\/strong><\/h3>\n<p dir=\"ltr\"><strong>\u201cI was wondering if you could\u201d<\/strong> \u00e9 uma express\u00e3o muito usada no ambiente de trabalho. Ela tem um tom polido e sutil, sendo ideal para pedidos feitos de maneira delicada.<\/p>\n<p dir=\"ltr\">\u201cI was wondering if you could\u201d significa\u00a0 <span style=\"text-decoration: underline;\"><strong>\u201cGostaria de saber se voc\u00ea poderia\u201d<\/strong><\/span> e \u00e9 apropriada quando n\u00e3o se sente \u00e0 vontade para pedir algo de maneira direta. Existe tamb\u00e9m\u00a0 <strong>\u201cI wonder if\u201d<\/strong>, mas <strong>\u201cI was wondering if\u201d<\/strong> soa mais natural na fala.<\/p>\n<p dir=\"ltr\">Exemplos:<\/p>\n<h5 dir=\"ltr\"><strong>I was wondering if you could help me with printing the documents.<\/strong><br \/>\nGostaria de saber se voc\u00ea poderia me ajudar a imprimir estes documentos.<\/h5>\n<h5 dir=\"ltr\"><strong>I was wondering if you could fix my laptop by Thursday. I need to take it with me to the meeting on Friday.<\/strong><br \/>\nGostaria de saber se voc\u00ea consegue consertar meu laptop at\u00e9 quinta-feira. Preciso lev\u00e1-lo para a reuni\u00e3o na sexta.<\/h5>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>Would it be OK if\u2026?<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><strong>\u201cWould it be OK if\u2026?\u201d\u00a0<\/strong> \u00e9 uma express\u00e3o cort\u00eas e ao mesmo tempo descontra\u00edda, significando <span style=\"text-decoration: underline;\"><strong>\u201cPosso?\u201d ou \u201cSeria conveniente para voc\u00ea se?\u201d<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">Exemplo:<\/p>\n<h5 dir=\"ltr\"><strong>Would it be OK if I drink the orange juice from the fridge?<\/strong><br \/>\nPosso tomar o suco de laranja da geladeira?<\/h5>\n<p dir=\"ltr\">A palavra formal em ingl\u00eas para geladeira \u00e9 <strong>\u201crefrigerator\u201d<\/strong>, mas no dia a dia costuma-se abreviar para <strong>\u201cfridge\u201d<\/strong>.<\/p>\n<h5 dir=\"ltr\"><strong>Would it be OK if I borrow your dictionary?<\/strong><br \/>\nPosso pedir emprestado seu dicion\u00e1rio?<\/h5>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>Could you do me a favor?<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><strong>\u201cfavor\u201d<\/strong> significa \u201cfavor, ajuda\u201d, e <strong>\u201cCould you do me a favor?\u201d<\/strong> quer dizer <span style=\"text-decoration: underline;\"><strong>\u201cTenho um pedido\u201d ou \u201cVoc\u00ea pode me fazer um favor?\u201d<\/strong><\/span>. Normalmente, \u00e9 usada como uma introdu\u00e7\u00e3o antes de fazer o pedido formal. Tamb\u00e9m pode ser usada como <strong>\u201cWould you do me a favor?\u201d<\/strong> ou <strong>\u201cI was wondering if you could do me a favor?\u201d<\/strong>.<\/p>\n<p dir=\"ltr\">Al\u00e9m disso, note que no ingl\u00eas brit\u00e2nico \u201cfavor\u201d se escreve <strong>\u201cfavour\u201d<\/strong>.<\/p>\n<p dir=\"ltr\">Exemplos:<\/p>\n<h5 dir=\"ltr\"><strong>Could you do me a favor and pick up some milk and bread from the supermarket?<\/strong><br \/>\nVoc\u00ea pode me fazer um favor e comprar leite e p\u00e3o no supermercado?<\/h5>\n<h5 dir=\"ltr\"><strong>Could you do me a favor?<\/strong><br \/>\nVoc\u00ea pode me fazer um favor?<\/h5>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>I would appreciate it if you could\u2026<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"text-decoration: underline;\"><strong>\u201cI would appreciate it if you could\u2026\u201d<\/strong><\/span>\u00a0 \u00e9 uma express\u00e3o bastante polida e significa <strong>\u201cEu ficaria muito grato se voc\u00ea pudesse\u2026\u201d<\/strong>.<\/p>\n<p dir=\"ltr\">\u201cI would appreciate it if you could\u2026\u201d \u00e9 apropriada tanto para conversas quanto para e-mails. Em mensagens formais, voc\u00ea tamb\u00e9m pode usar <strong>\u201cIt would be appreciated if\u201d<\/strong>.<\/p>\n<p dir=\"ltr\">Exemplos:<\/p>\n<h5 dir=\"ltr\"><strong>I would appreciate it if you could let me know a convenient date and time.<\/strong><br \/>\nEu ficaria muito grato se voc\u00ea pudesse me informar uma data e hor\u00e1rio convenientes.<\/h5>\n<h5 dir=\"ltr\"><strong>I would appreciate it if you could let us know by Friday whether you are able to participate.<\/strong><br \/>\nEu ficaria muito grato se voc\u00ea pudesse nos informar at\u00e9 sexta-feira se poder\u00e1 participar.<\/h5>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>Would it be possible to\u2026?<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">\u201cWould it be possible to\u2026?\u201d \u00e9 outra express\u00e3o formal de pedido e significa\u00a0 <span style=\"text-decoration: underline;\"><strong>\u201cSeria poss\u00edvel?\u201d<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">Exemplo:<\/p>\n<h5 dir=\"ltr\"><strong>Would it be possible to meet the teacher?<\/strong><br \/>\nSeria poss\u00edvel encontrar o professor?<\/h5>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">&#8220;Do you mind?&#8221; como uma express\u00e3o idiom\u00e1tica<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Quando <strong>\u201cDo you mind?\u201d<\/strong> \u00e9 usada de forma idiom\u00e1tica, se for dita com um tom de raiva ou impaci\u00eancia, pode ser entendida como\u00a0 <span style=\"text-decoration: underline;\"><strong>\u201cVoc\u00ea pode parar com isso?\u201d ou \u201cD\u00e1 pra parar?\u201d<\/strong><\/span>.<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">Resumo<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">O que achou? Neste artigo, apresentamos a express\u00e3o <span style=\"font-size: 36px; color: #d502d9;\"><strong>\u201cDo you mind?\u201d<\/strong><\/span> em ingl\u00eas.<\/p>\n<p dir=\"ltr\"><strong>\u201cDo you mind?\u201d<\/strong> \u00e9 um termo de cortesia muito usado no cotidiano das conversas em ingl\u00eas. Mas, ao responder a <strong>\u201cDo you mind?\u201d<\/strong>, \u00e9 fundamental se atentar para o fato de que ela \u00e9 o oposto do que estamos acostumados no portugu\u00eas, evitando responder de forma equivocada.<\/p>\n<p dir=\"ltr\">Al\u00e9m disso, atrav\u00e9s dos exemplos neste artigo, apresentamos v\u00e1rias outras formas de expressar pedidos. Esperamos que este texto ajude voc\u00ea a entender as diferen\u00e7as entre essas express\u00f5es e a us\u00e1-las com mais precis\u00e3o nas conversas di\u00e1rias!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Voc\u00ea pode me ajudar?&#8221;, &#8220;Pode me passar o sal?&#8221;, &#8220;Voc\u00ea poderia me enviar os documentos por e-mail?&#8221; e assim por diante&#8230; Seja na vida cotidiana ou no ambiente de trabalho,\u00a0 fazer pedidos para outras pessoas \u00e9 algo bastante comum! Ent\u00e3o, quando voc\u00ea quiser fazer um pedido em ingl\u00eas, qual express\u00e3o voc\u00ea costuma usar? No mundo do ingl\u00eas, h\u00e1 v\u00e1rias formas de expressar esse sentido de \u201cpedido\u201d. Neste artigo, vamos focar na express\u00e3o &#8220;Do you mind?&#8221;, que \u00e9 muito usada por estrangeiros. Do you mind?\u00a0 \u00e9 uma express\u00e3o que deixa uma impress\u00e3o de \u201ccortesia\u201d para o interlocutor. Por isso, depois de aprender a us\u00e1-la, voc\u00ea com certeza s\u00f3 ter\u00e1 a ganhar! &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/15670\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":15671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=15670","footnotes":""},"categories":[109,107,108],"tags":[],"class_list":["post-15670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-listening","category-speaking","category-writing","pt-BR"],"aioseo_notices":[],"views":1138,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/15670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=15670"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/15670\/revisions"}],"predecessor-version":[{"id":15672,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/15670\/revisions\/15672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/15671"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=15670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=15670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=15670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}