{"id":15418,"date":"2026-03-07T09:00:12","date_gmt":"2026-03-07T12:00:12","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=15418"},"modified":"2026-03-05T02:19:19","modified_gmt":"2026-03-05T05:19:19","slug":"expressoes-em-ingles-para-situacoes-no-local-de-trabalho-vamos-coloca-las-em-pratica-no-nosso-trabalho","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/15418\/","title":{"rendered":"Express\u00f5es em ingl\u00eas para situa\u00e7\u00f5es no local de trabalho! Vamos coloc\u00e1-las em pr\u00e1tica no nosso trabalho!"},"content":{"rendered":"<p dir=\"ltr\">Se todos precisam se expressar em ingl\u00eas no ambiente de trabalho, express\u00f5es como\u00a0 \u201cdesta vez\u201d definitivamente merecem ser aprendidas.<\/p>\n<p dir=\"ltr\">Por exemplo, \u201cPedimos desculpas sinceras, desta vez n\u00e3o podemos aceitar\u201d ou \u201cO projeto foi aprovado desta vez\u201d s\u00e3o formas frequentemente usadas no trabalho, reuni\u00f5es ou e-mails.<\/p>\n<p dir=\"ltr\">Portanto, neste artigo vamos apresentar a todos\u00a0 \u00a0<span style=\"font-size: 28px;\"><strong><span style=\"color: #d415ca;\">formas de expressar \u201cdesta vez\u201d em conversas em ingl\u00eas<\/span>.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">Formas de expressar \u201cdesta vez\u201d em ingl\u00eas<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Primeiramente, h\u00e1 v\u00e1rias maneiras de expressar o significado de \u201cdesta vez\u201d em ingl\u00eas.<\/p>\n<p dir=\"ltr\">Embora essas formas sejam todas conhecidas e semelhantes, aprender mais delas ajudar\u00e1 voc\u00ea a distingui-las com mais facilidade.<\/p>\n<p dir=\"ltr\">Depois de entender as sutis diferen\u00e7as de significado entre cada express\u00e3o, voc\u00ea conseguir\u00e1 transmitir mensagens muito mais precisas e delicadas!<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">this time<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">\u201cthis time\u201d \u00e9 a forma mais comum e f\u00e1cil de ser utilizada entre as express\u00f5es em ingl\u00eas para \u201cdesta vez\u201d. Aqui, \u201ctime\u201d significa \u201ctempo\u201d ou \u201cvez\u201d, sendo adequado para situa\u00e7\u00f5es que apontam para um momento espec\u00edfico.<\/p>\n<p dir=\"ltr\"><span style=\"color: #0000ff;\"><strong>\u201cthis time\u201d \u00e9 uma express\u00e3o muito simples e, literalmente, parece se referir \u00e0 \u201csitua\u00e7\u00e3o atual\u201d. Por isso, algumas pessoas podem pensar que \u201cthis time\u201d s\u00f3 pode ser usado no tempo presente.<\/strong><\/span><\/p>\n<p dir=\"ltr\">Mas, na verdade, \u201cthis time\u201d pode ser usado com qualquer tempo verbal: presente, passado ou futuro.<\/p>\n<p dir=\"ltr\">A seguir, vamos ver exemplos concretos de como usar \u201cthis time\u201d!<\/p>\n<h5 dir=\"ltr\">I explain about it this time. Desta vez eu explico isso.<\/h5>\n<h5 dir=\"ltr\">I explained about it this time. Desta vez eu expliquei isso.<\/h5>\n<h5 dir=\"ltr\">I will explain about it this time. Desta vez eu explicarei isso.<\/h5>\n<p style=\"text-align: center;\">\u201cthis time\u201d apresenta, como nos exemplos acima, alta versatilidade e praticidade. Assim, voc\u00ea pode us\u00e1-lo quase sem se preocupar com detalhes.<\/p>\n<p dir=\"ltr\">Al\u00e9m disso, embora \u201cthis time\u201d possa aparecer no fim da frase, <span style=\"color: #ff0000;\"><strong>se quiser enfatizar \u201cdesta vez\u201d, tamb\u00e9m pode coloc\u00e1-lo no in\u00edcio da frase<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">Portanto, este pr\u00e1tico \u201cthis time\u201d pode ser considerado a express\u00e3o mais \u00fatil e f\u00e1cil de memorizar entre as formas de dizer \u201cdesta vez\u201d em ingl\u00eas.<\/p>\n<p dir=\"ltr\">A seguir, vamos agora usar \u201cthis time\u201d como base e continuar aprendendo outras formas de expressar \u201cdesta vez\u201d!<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">this once<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Embora \u201cthis once\u201d e \u201cthis time\u201d tenham significado igual,<\/p>\n<p dir=\"ltr\">como \u201conce\u201d significa \u201cuma vez\u201d, <strong><span style=\"color: #ff0000;\">\u201cthis once\u201d enfatiza ainda mais que \u00e9 \u201csomente desta vez\u201d.<\/span><\/strong><\/p>\n<p dir=\"ltr\">Portanto, basta lembrar que \u201cthis once\u201d equivale a \u201capenas esta vez\u201d.<\/p>\n<h5 dir=\"ltr\"><strong>I will make your memo this once.<\/strong><br \/>\nEu vou fazer a sua anota\u00e7\u00e3o s\u00f3 desta vez.<\/h5>\n<p dir=\"ltr\">Pela \u201crigidez\u201d do tom do exemplo acima, percebe-se que se voc\u00ea confundir \u201cthis time\u201d com \u201cthis once\u201d, pode causar mal-entendidos desnecess\u00e1rios. Por exemplo, ao usar \u201cthis once\u201d, dependendo do seu tom, a outra pessoa pode sentir que voc\u00ea est\u00e1 insatisfeito.<\/p>\n<p dir=\"ltr\">Por isso, recomendamos observar a express\u00e3o e situa\u00e7\u00e3o do interlocutor antes de escolher qual express\u00e3o usar!<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">At this moment<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">\u201cat this moment\u201d significa\u00a0 <strong><span style=\"color: #ff0000;\">\u201cno momento\u201d, \u201catualmente\u201d, \u201cagora mesmo\u201d<\/span><\/strong>.<\/p>\n<p dir=\"ltr\">Como \u201cmoment\u201d significa \u201cinstante\u201d, \u201cat this moment\u201d tamb\u00e9m carrega a ideia de algo acontecendo justo neste exato momento.<\/p>\n<p dir=\"ltr\">Por exemplo, a frase \u201cwait a moment\u201d quer dizer para esperar s\u00f3 um instante.<\/p>\n<h5 dir=\"ltr\"><strong>We don\u2019t have any problem at this moment.<\/strong><br \/>\nNo momento, n\u00e3o temos nenhum problema.<\/h5>\n<p dir=\"ltr\">No exemplo acima, al\u00e9m do significado de \u201cn\u00e3o ter problemas agora\u201d, tamb\u00e9m indica que talvez surjam problemas mais tarde. Assim, \u201cat this moment\u201d \u00e9 ideal para contextos em que a situa\u00e7\u00e3o pode mudar a qualquer instante.<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">at this point<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">\u201cat this point\u201d significa <strong><span style=\"color: #ff0000;\">\u201cagora\u201d, \u201cneste momento\u201d<\/span><\/strong>.<\/p>\n<p dir=\"ltr\">\u201cat this point\u201d e \u201cat this moment\u201d s\u00e3o muito parecidos. Ambas expressam o cen\u00e1rio em um determinado momento, implicando que a situa\u00e7\u00e3o pode mudar em breve.<\/p>\n<p dir=\"ltr\">Como situa\u00e7\u00f5es de trabalho mudam com frequ\u00eancia, ambas s\u00e3o express\u00f5es muito \u00fateis!<\/p>\n<h5 dir=\"ltr\"><strong>I can attend the meeting tomorrow at this point.<\/strong><br \/>\nNeste momento, posso participar da reuni\u00e3o amanh\u00e3.<\/h5>\n<p dir=\"ltr\">A express\u00e3o \u201cat this point\u201d pode ser posicionada tanto no in\u00edcio quanto no fim da frase, sem problemas.<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">at this juncture<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">\u201cat this juncture\u201d significa <strong><span style=\"color: #ff0000;\">\u201cnesta etapa\u201d, \u201cagora\u201d, \u201cneste momento cr\u00edtico\u201d<\/span><\/strong>.<\/p>\n<p dir=\"ltr\">\u201cjuncture\u201d \u00e9 uma palavra de ingl\u00eas avan\u00e7ado e significa \u201cmomento\u201d ou \u201cponto decisivo\u201d, especialmente referindo-se a situa\u00e7\u00f5es importantes ou graves.<\/p>\n<p dir=\"ltr\">Por isso, \u201cat this juncture\u201d \u00e9 apropriado para comunicar conte\u00fados importantes em situa\u00e7\u00f5es de trabalho.<\/p>\n<h5 dir=\"ltr\"><b>At this juncture, we cannot decide which product we should support.<\/b><br \/>\nNeste momento, n\u00e3o podemos decidir qual produto devemos apoiar.<\/h5>\n<p dir=\"ltr\">\u201cat this juncture\u201d tamb\u00e9m pode ser substitu\u00eddo pelas seguintes express\u00f5es:<\/p>\n<h6 dir=\"ltr\"><b>considering the current situation \u201cconsiderando a situa\u00e7\u00e3o atual\u201d<\/b><\/h6>\n<p dir=\"ltr\">\u201cconsider\u201d significa \u201cconsiderar\u201d, enquanto \u201ccurrent\u201d significa \u201catual\u201d.<\/p>\n<h6 dir=\"ltr\"><b>under the current circumstances \u201csob as circunst\u00e2ncias atuais\u201d<\/b><\/h6>\n<p dir=\"ltr\">\u201cunder the circumstances\u201d \u00e9 uma express\u00e3o que deve ser memorizada como um todo. \u201ccircumstances\u201d significa \u201ccircunst\u00e2ncias\u201d ou \u201csitua\u00e7\u00e3o\u201d.<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">Express\u00f5es de recusa em ingl\u00eas no ambiente de trabalho<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">No trabalho, muitas vezes \u00e9 necess\u00e1rio dizer algo como \u201cn\u00e3o posso aceitar desta vez\u201d.<\/p>\n<p dir=\"ltr\">E quando for preciso recusar algu\u00e9m, que formas educadas e pr\u00e1ticas podem ser usadas?<\/p>\n<p dir=\"ltr\">A seguir, apresentaremos algumas formas de se recusar no ambiente profissional sem ser rude ou ofender o outro.<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><b>I\u2019ll pass this time.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">\u201cI\u2019ll pass this time\u201d significa <span style=\"color: #ff0000;\"><strong>\u201cdesta vez vou passar\u201d<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">Geralmente, em e-mails em ingl\u00eas, o conte\u00fado tende a ser direto. Assim, basta agradecer brevemente pelo convite (\u201cThank you\u201d) e depois informar educadamente: \u201cI\u2019ll pass this time\u201d.<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><b>We\u2019re good for now, thank you.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">\u201cWe\u2019re good for now, thank you\u201d significa <span style=\"color: #ff0000;\"><b>\u201cpor enquanto estamos bem, obrigado\u201d<\/b><\/span>.<\/p>\n<p dir=\"ltr\">\u00c9 uma frase simples, ideal para dizer \u201cno momento n\u00e3o precisamos\u201d no ambiente de trabalho.<\/p>\n<p dir=\"ltr\">A express\u00e3o \u201cbe good for now\u201d carrega a ideia de que \u201cj\u00e1 \u00e9 suficiente por enquanto, n\u00e3o h\u00e1 necessidade de mais\u201d, sendo parecida com \u201cbe OK for now\u201d.<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><b>I\u2019Il be declining this time.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">\u201cI\u2019ll be declining this time\u201d significa literalmente <strong><span style=\"color: #ff0000;\">\u201cdesta vez vou recusar educadamente\u201d<\/span><\/strong>. Aqui, \u201cdecline\u201d quer dizer \u201crecusar\u201d.<\/p>\n<p dir=\"ltr\">\u201cI\u2019ll be declining this time\u201d \u00e9 uma express\u00e3o com tom educado. Portanto, \u00e9 ideal para recusar convites ou propostas de forma cort\u00eas.<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><b>I\u2019m afraid I must decline this time.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">\u201cI\u2019m afraid I must decline this time\u201d significa <strong><span style=\"color: #ff0000;\">\u201cSinto muito, desta vez preciso recusar\u201d<\/span><\/strong>.\u00a0 \u201cI\u2019m afraid\u201d significa \u201clamento\u201d ou \u201cdesculpe\u201d.<\/p>\n<p dir=\"ltr\">Quando \u201cI\u2019m afraid\u201d \u00e9 seguido por \u201cthat\u201d, voc\u00ea pode detalhar os motivos do lamento na sequ\u00eancia.<\/p>\n<p dir=\"ltr\">Al\u00e9m disso, \u201cI\u2019m afraid\u201d pode ser trocado por \u201cIt\u2019s a shame\u201d. Mas aten\u00e7\u00e3o! \u201cI\u2019m afraid\u201d usa o adjetivo \u201cafraid\u201d, ent\u00e3o o sujeito \u00e9 \u201cI\u201d. J\u00e1 \u201cIt\u2019s a shame\u201d usa o substantivo \u201cshame\u201d, ent\u00e3o o sujeito \u00e9 \u201cIt\u201d.<\/p>\n<p dir=\"ltr\">Se voc\u00ea usar erroneamente \u201cI\u2019m shame\u201d em vez de \u201cIt\u2019s a shame\u201d, a frase passar\u00e1 a ideia de \u201ceu pessoalmente estou envergonhado\u201d, o que pode causar mal-entendidos!<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><b>That\u2019s too much weight on my shoulders.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">A express\u00e3o em ingl\u00eas \u201cThat\u2019s too much weight on my shoulders\u201d \u00e9 semelhante \u00e0 frase em portugu\u00eas que significa\u00a0 <span style=\"color: #ff0000;\"><strong>\u201cisso \u00e9 pesado demais para mim\u201d<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">\u201cWeight\u201d aqui significa \u201cpeso\u201d, de modo que a tradu\u00e7\u00e3o literal \u00e9 \u201cisso pesa demais nos meus ombros\u201d. Recomendamos memorizar como \u201cisso \u00e9 pesado demais para mim\u201d.<\/p>\n<p dir=\"ltr\">Al\u00e9m disso, \u201cThat\u2019s too much weight on my shoulders\u201d \u00e9 uma maneira indireta e educada de recusar, deixando claro o motivo da recusa.<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><b>be not interested in, thank you.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">\u201cbe not interested in, thank you\u201d significa literalmente <strong><span style=\"color: #ff0000;\">\u201cn\u00e3o tenho interesse em OO, obrigado\u201d<\/span><\/strong>.<\/p>\n<p dir=\"ltr\">\u201cbe interested in\u201d \u00e9 uma express\u00e3o b\u00e1sica aprendida na escola e significa \u201cter interesse em\u201d. Ao negar, basta dizer \u201cbe not interested in\u201d.<\/p>\n<p dir=\"ltr\">Ao adicionar \u201cthank you\u201d ao final, sua rejei\u00e7\u00e3o soar\u00e1 ainda mais educada.<\/p>\n<p dir=\"ltr\">Por\u00e9m, como essa tradu\u00e7\u00e3o literal pode soar muito direta em algumas situa\u00e7\u00f5es, sugerimos que adapte para \u201cno momento ainda n\u00e3o precisamos\u201d para soar mais gentil.<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><b>We\u2019re very grateful for this proposal, but<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">\u201cWe\u2019re very grateful for this proposal, but\u201d significa <span style=\"color: #ff0000;\"><b>\u201cestamos muito gratos pela proposta, por\u00e9m\u2026\u201d<\/b><\/span>.<\/p>\n<p dir=\"ltr\">\u00c9 uma forma de agradecer e ao mesmo tempo recusar a proposta. \u201cproposal\u201d significa \u201cproposta\u201d.<\/p>\n<p dir=\"ltr\">Ao expressar gratid\u00e3o e, em seguida, usar \u201cbut\u201d para recusar, sua mensagem ser\u00e1 ainda mais polida.<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><b>I\u2019m sorry I could not give you a positive answer.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">\u201cI\u2019m sorry I could not give you a positive answer\u201d significa <span style=\"color: #ff0000;\"><b>\u201clamento, n\u00e3o pude lhe dar uma resposta positiva\u201d<\/b><\/span>. \u201cpositive answer\u201d significa \u201cresposta afirmativa\u201d.<\/p>\n<p dir=\"ltr\">Embora \u201cI\u2019m sorry\u201d transmita um pedido de desculpas, neste contexto expressa mais um sentimento de lamento.<\/p>\n<p dir=\"ltr\">Depois de demonstrar pesar, basta concluir com \u201cI could not give you a positive answer\u201d para especificar o motivo.<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">Resumo<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">No ambiente de trabalho, existem v\u00e1rias formas de expressar \u201cdesta vez\u201d em ingl\u00eas.<\/p>\n<p dir=\"ltr\">Embora seja um desafio traduzir essas express\u00f5es para o portugu\u00eas, recomendamos aprender algumas formas pr\u00e1ticas de \u201cdesta vez\u201d em ingl\u00eas para impulsionar sua flu\u00eancia. Sugerimos priorizar as express\u00f5es que voc\u00ea j\u00e1 costuma usar em portugu\u00eas no dia a dia.<\/p>\n<p dir=\"ltr\">Depois de memorizar e se acostumar com elas, voc\u00ea ser\u00e1 capaz de utiliz\u00e1-las naturalmente, adaptando-as ao seu pr\u00f3prio estilo sem precisar decorar palavra por palavra. Esperamos que voc\u00ea encontre as express\u00f5es de \u201cdesta vez\u201d em ingl\u00eas mais adequadas \u00e0 situa\u00e7\u00e3o!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se todos precisam se expressar em ingl\u00eas no ambiente de trabalho, express\u00f5es como\u00a0 \u201cdesta vez\u201d definitivamente merecem ser aprendidas. Por exemplo, \u201cPedimos desculpas sinceras, desta vez n\u00e3o podemos aceitar\u201d ou \u201cO projeto foi aprovado desta vez\u201d s\u00e3o formas frequentemente usadas no trabalho, reuni\u00f5es ou e-mails. Portanto, neste artigo vamos apresentar a todos\u00a0 \u00a0formas de expressar \u201cdesta vez\u201d em conversas em ingl\u00eas. &nbsp; Formas de expressar \u201cdesta vez\u201d em ingl\u00eas &nbsp; Primeiramente, h\u00e1 v\u00e1rias maneiras de expressar o significado de \u201cdesta vez\u201d em ingl\u00eas. Embora essas formas sejam todas conhecidas e semelhantes, aprender mais delas ajudar\u00e1 voc\u00ea a distingui-las com mais facilidade. Depois de entender as sutis diferen\u00e7as de significado entre &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/15418\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":15419,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=15418","footnotes":""},"categories":[118,122,121],"tags":[],"class_list":["post-15418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-study-abroad","category-pronunciation","category-words","pt-BR"],"aioseo_notices":[],"views":166,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/15418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=15418"}],"version-history":[{"count":2,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/15418\/revisions"}],"predecessor-version":[{"id":15421,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/15418\/revisions\/15421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/15419"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=15418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=15418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=15418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}