{"id":15152,"date":"2026-02-22T09:00:12","date_gmt":"2026-02-22T12:00:12","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=15152"},"modified":"2026-02-20T07:20:00","modified_gmt":"2026-02-20T10:20:00","slug":"nomes-em-ingles-e-expressoes-comuns-para-varios-passaros","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/15152\/","title":{"rendered":"Nomes em ingl\u00eas e express\u00f5es comuns para v\u00e1rios p\u00e1ssaros"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">No cotidiano, h\u00e1 muitas oportunidades para ver diferentes tipos de aves. Andando na rua, as mais comuns s\u00e3o o pardal e o pombo, e muitas pessoas criam diamantes de Java ou papagaios como animais de estima\u00e7\u00e3o. Se voc\u00ea gosta de estar em contato com a natureza, pode at\u00e9 ter chance de ver esp\u00e9cies mais especiais.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 que existem tantas esp\u00e9cies de aves, voc\u00ea sabe como dizer o nome delas em ingl\u00eas? Este artigo vai apresentar os <span style=\"color: #d000d4; font-size: 24px;\"><b>nomes em ingl\u00eas das aves mais comuns no cotidiano<\/b><\/span><span style=\"font-weight: 400;\">, al\u00e9m de express\u00f5es idiom\u00e1ticas relacionadas a aves; n\u00e3o deixe de aprender e usar essas express\u00f5es!<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Diversidade das aves<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Existem cerca de dez mil esp\u00e9cies diferentes de aves no mundo, sendo um n\u00famero relativamente alto em compara\u00e7\u00e3o com outros animais, no Brasil tamb\u00e9m possui muitas esp\u00e9cies end\u00eamicas. Al\u00e9m disso, as aves apresentam grande diversidade em forma, h\u00e1bitos e regi\u00f5es de vida.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este artigo vai apresentar os nomes em ingl\u00eas das aves mais comuns e tamb\u00e9m compartilhar curiosidades sobre elas, para que voc\u00ea conhe\u00e7a melhor esses visitantes delicados que vivem ao nosso redor.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Defini\u00e7\u00e3o e caracter\u00edsticas das aves<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Vamos primeiro ver a defini\u00e7\u00e3o de ave. <\/span><span style=\"color: #ff0000;\"><b>Uma ave deve possuir quatro caracter\u00edsticas principais: corpo coberto de penas, membros anteriores desenvolvidos em asas, bico e capacidade de p\u00f4r ovos<\/b><span style=\"font-weight: 400;\">.<\/span><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Muitas pessoas acham que a principal caracter\u00edstica das aves \u00e9 a capacidade de voar, mas na verdade h\u00e1 aves que n\u00e3o voam, como o pinguim. Al\u00e9m disso, embora o morcego voe, ele n\u00e3o p\u00f5e ovos, ent\u00e3o n\u00e3o \u00e9 considerado ave, mas mam\u00edfero.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Diferentes tipos de aves e seus nomes em ingl\u00eas<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A seguir, apresentaremos algumas curiosidades sobre aves famosas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essas aves s\u00e3o bem conhecidas da maioria das pessoas, ent\u00e3o, se voc\u00ea n\u00e3o sabia como diz\u00ea-las em ingl\u00eas, aproveite para aprender agora!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Pardal: Sparrow<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>O nome em ingl\u00eas do pardal \u00e9\u00a0 \u201csparrow\u201d<\/b><\/span><span style=\"font-weight: 400;\">, uma pequena ave muito comum ao nosso redor. Tem uma ampla \u00e1rea de distribui\u00e7\u00e3o, abrangendo toda a Eur\u00e1sia, podendo ser encontrado at\u00e9 no extremo oeste de Portugal.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Corvo: Crow<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #0000ff;\"><b>O nome em ingl\u00eas do corvo \u00e9\u00a0 \u201ccrow\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O som caracter\u00edstico do corvo em ingl\u00eas \u00e9 expresso por \u201ccaw caw\u201d. \u00c9 muito comum em pa\u00edses de l\u00edngua inglesa e, segundo dizem, possuem consider\u00e1vel intelig\u00eancia, gostam de viver em grupo e se comunicam com diferentes sons.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Andorinha: Swallow<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>O nome em ingl\u00eas da andorinha \u00e9\u00a0 \u201cswallow\u201d<\/b><\/span><span style=\"font-weight: 400;\"><span style=\"color: #ff0000;\">.<\/span> Esta palavra tamb\u00e9m significa \u201cengolir\u201d em ingl\u00eas, provavelmente porque os filhotes de andorinha, ao se alimentarem, abrem bem a boca e comem com muita vontade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A andorinha \u00e9 uma das aves migrat\u00f3rias mais comuns do hemisf\u00e9rio norte. Ela ajuda os humanos comendo insetos nocivos, sendo considerada uma ave ben\u00e9fica. H\u00e1 quem acredite que ter um ninho de andorinha na porta de casa traz boa sorte.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Pombo: Pigeon<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #0000ff;\"><b>O nome em ingl\u00eas do pombo \u00e9\u00a0 \u201cpigeon\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por\u00e9m, estrangeiros \u00e0s vezes usam \u201cpigeon\u201d para se referir a algu\u00e9m considerado \u201ctolo\u201d ou \u201cing\u00eanuo\u201d. Isso porque os pombos geralmente n\u00e3o t\u00eam medo das pessoas e, mesmo quando algu\u00e9m chega perto, ficam parados sem voar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os pombos t\u00eam uma distribui\u00e7\u00e3o muito ampla, praticamente podendo ser encontrados em todo o mundo, exceto nas \u00e1reas mais secas do deserto do Saara, no extremo norte do c\u00edrculo polar \u00e1rtico e na Ant\u00e1rtida.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Coruja: Owl<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>O nome em ingl\u00eas da coruja \u00e9\u00a0 \u201cowl\u201d<\/b><\/span><span style=\"font-weight: 400;\">. Ela vive principalmente no norte da Eur\u00e1sia, mas por ser um animal noturno, n\u00e3o \u00e9 t\u00e3o f\u00e1cil de ser avistada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Muitas hist\u00f3rias e romances incluem corujas em suas narrativas, por isso, desde a antiguidade, ela \u00e9 um animal bastante conhecido.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Falc\u00e3o: Hawk<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #0000ff;\"><b>O nome em ingl\u00eas do falc\u00e3o \u00e9\u00a0 \u201chawk\u201d<\/b><\/span><span style=\"font-weight: 400;\">. Muitas pessoas tamb\u00e9m conhecem \u201ceagle\u201d, que \u00e9 uma ave muito parecida, mas de porte maior.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O falc\u00e3o tamb\u00e9m tem um territ\u00f3rio de habita\u00e7\u00e3o bastante amplo, e, por se tratar de uma ave de rapina, muitos times esportivos ou avi\u00f5es usam \u201cHawks\u201d em seus nomes.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Pinguim: Penguin<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><b>O nome em ingl\u00eas do pinguim \u00e9\u00a0 \u201cpenguin\u201d<\/b><\/span><span style=\"font-weight: 400;\">. Esta palavra tem origem em um termo espanhol que significa \u201cgordinho\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O pinguim vive principalmente no hemisf\u00e9rio sul. Apesar de n\u00e3o voar, suas asas o ajudam a nadar com agilidade na \u00e1gua!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Flamingo: Flamingo<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #0000ff;\"><b>O nome em ingl\u00eas do flamingo \u00e9\u00a0 \u201cflamingo\u201d<\/b><\/span><span style=\"font-weight: 400;\">, vindo do latim \u201cflamma\u201d, que significa \u201cchama\u201d. Sua principal caracter\u00edstica s\u00e3o as belas penas cor-de-rosa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, sua cor rosa \u00e9 resultado dos pigmentos vermelhos presentes em sua alimenta\u00e7\u00e3o; se eles comerem ra\u00e7\u00e3o comum por muito tempo, as penas gradualmente ficar\u00e3o brancas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O flamingo \u00e9 uma ave aqu\u00e1tica que vive principalmente em lagos salgados ou \u00e1reas \u00famidas da \u00c1frica, sul da Europa, oeste da \u00c1sia e Am\u00e9rica Central e do Sul.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Diferentes tipos de aves e seus respectivos nomes em ingl\u00eas divididos pelo modo de vida<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Na se\u00e7\u00e3o anterior, apresentamos nomes de aves mais conhecidas. Agora, vamos ver alguns exemplos divididos pelo modo de vida.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Aves polares: Polar Birds<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A regi\u00e3o polar inclui o \u00c1rtico e a Ant\u00e1rtida. Portanto, as aves que vivem nessas \u00e1reas s\u00e3o chamadas genericamente de \u201cpolar birds\u201d.<\/span><\/p>\n<p><span style=\"color: #ff0000;\"><strong>\u201cPolar\u201d pode ser usado como adjetivo ou substantivo, significando \u201cpolar\u201d, \u201cant\u00e1rtico\u201d, \u201c\u00e1rtico\u201d ou \u201ccompletamente oposto\u201d<\/strong><\/span><span style=\"font-weight: 400;\"><span style=\"color: #ff0000;\"><strong>, entre outros sentidos. Outro uso comum \u00e9 o urso polar, em ingl\u00eas chamado de \u201cpolar bear\u201d.<\/strong><\/span><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na regi\u00e3o do \u00c1rtico, podem ser observadas cerca de 180 esp\u00e9cies diferentes de aves, a maioria delas migrat\u00f3rias. J\u00e1 na Ant\u00e1rtica, h\u00e1 aproximadamente 15 esp\u00e9cies, n\u00e3o s\u00f3 com bem menos variedade, como tamb\u00e9m com tipos diferentes, sendo principalmente aves marinhas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Aves tropicais: Tropical Birds<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">As aves que vivem em regi\u00f5es tropicais s\u00e3o chamadas em ingl\u00eas de \u201ctropical birds\u201d. <\/span><span style=\"color: #0000ff;\"><b>\u201cTropical\u201d significa tropical, muito quente<\/b><\/span><span style=\"font-weight: 400;\">, sendo um adjetivo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Normalmente, aves dessas regi\u00f5es apresentam plumagem muito colorida, principalmente para atrair parceiros, j\u00e1 que na selva \u00e9 dif\u00edcil encontrar outros indiv\u00edduos da mesma esp\u00e9cie. Portanto, ao longo da evolu\u00e7\u00e3o, desenvolveram cores mais chamativas para aumentar as chances de sucesso no acasalamento.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Aves noturnas: Nocturnal Birds<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O nome em ingl\u00eas para aves noturnas \u00e9 \u201cnocturnal birds\u201d.\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201cNocturnal\u201d pode se referir a animais noturnos ou atividades noturnas<\/b><\/span><span style=\"font-weight: 400;\">. O prefixo \u201cNoct-\u201d vem do latim \u201cnox\u201d, que significa \u201cnoite\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A maioria das aves \u00e9 diurna; as noturnas representam apenas cerca de 3%. O exemplo mais t\u00edpico \u00e9 a coruja. Dizem que a coruja \u00e9 noturna porque se alimenta principalmente de ratos, que tamb\u00e9m s\u00e3o ativos \u00e0 noite.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Aves migrat\u00f3rias: Migratory Birds<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O nome em ingl\u00eas das aves migrat\u00f3rias \u00e9 \u201cmigratory birds\u201d .<\/span><span style=\"color: #0000ff;\"><b>\u201cMigratory\u201d significa migrat\u00f3rio, de migra\u00e7\u00e3o<\/b><\/span><span style=\"font-weight: 400;\">, sendo um adjetivo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A caracter\u00edstica das aves migrat\u00f3rias \u00e9 que elas mudam de local de acordo com a esta\u00e7\u00e3o para facilitar a alimenta\u00e7\u00e3o. A maioria migra para o sul no inverno para ter acesso a alimento, e volta ao norte no ver\u00e3o, quando os dias s\u00e3o mais longos, para se reproduzir.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Express\u00f5es idiom\u00e1ticas em ingl\u00eas relacionadas a aves<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A conviv\u00eancia entre aves e humanos \u00e9 muito pr\u00f3xima, por isso, existem muitos prov\u00e9rbios e express\u00f5es idiom\u00e1ticas em ingl\u00eas relacionados a aves. Veja algumas das mais comuns:<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\u201cA bird in the hand is worth two in the bush.\u201d<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A tradu\u00e7\u00e3o literal dessa frase \u00e9 \u201cmelhor um p\u00e1ssaro na m\u00e3o do que dois voando\u201d. O significado \u00e9:\u00a0 <\/span><span style=\"color: #ff0000;\"><b>em vez de buscar metas grandiosas e pouco realistas, \u00e9 melhor valorizar pequenos ganhos imediatos<\/b><\/span><span style=\"font-weight: 400;\">, ou seja, aconselha a n\u00e3o ser ambicioso e acabar perdendo o que se tem.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\u201cKill two birds with one stone.\u201d<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A tradu\u00e7\u00e3o literal \u00e9 \u201cmatar dois p\u00e1ssaros com uma s\u00f3 pedra\u201d, ou seja, <span style=\"color: #0000ff;\"><b>\u201cmatar dois coelhos com uma cajadada s\u00f3\u201d<\/b><\/span><span style=\"font-weight: 400;\">. Curiosamente, esse prov\u00e9rbio ingl\u00eas tem exatamente o mesmo sentido do dito popular em portugu\u00eas, significando obter o dobro de resultados com o mesmo esfor\u00e7o.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\u201cThe early bird catches the worm.\u201d<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O sentido literal \u00e9 \u201co p\u00e1ssaro que acorda cedo apanha o verme\u201d, exatamente igual ao ditado portugu\u00eas <span style=\"color: #ff0000;\">\u201c<\/span><\/span><span style=\"color: #ff0000;\"><b>o p\u00e1ssaro madrugador pega o verme<\/b><span style=\"font-weight: 400;\">\u201d<\/span><b>, n\u00e3o \u00e9?<\/b><\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\u201cBirds of a feather flock together\u201d<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O sentido literal \u00e9 \u201caves de mesma plumagem voam juntas\u201d, o que equivale a\u00a0 <span style=\"color: #0000ff;\"><b>\u201cdiga-me com quem andas e te direi quem \u00e9s\u201d<\/b><\/span><span style=\"font-weight: 400;\">. \u201cBirds of a feather\u201d \u00e9 uma met\u00e1fora para pessoas com mesmas caracter\u00edsticas ou interesses.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\u201cFree as a bird\u201d<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 uma express\u00e3o que significa exatamente o que parece: \u201clivre como um p\u00e1ssaro\u201d. Imagine\u00a0 <\/span><span style=\"color: #ff0000;\"><b>um p\u00e1ssaro voando livremente no c\u00e9u, sem restri\u00e7\u00f5es, representando liberdade plena, despreocupa\u00e7\u00e3o<\/b><strong>.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\u201cEagle-eyed\u201d<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #0000ff;\"><strong>Tamb\u00e9m \u00e9 uma express\u00e3o idiom\u00e1tica, significando \u201colhar atento aos pequenos detalhes\u201d, \u201cn\u00e3o deixar passar nada\u201d<\/strong><\/span><span style=\"font-weight: 400;\"><span style=\"color: #0000ff;\"><strong>.<\/strong><\/span> Como dito anteriormente, \u201ceagle\u201d tamb\u00e9m significa \u00e1guia, cuja vis\u00e3o \u00e9 quatro a oito vezes melhor que a humana. Portanto, possuir \u201colhos de \u00e1guia\u201d implica em grande poder de observa\u00e7\u00e3o.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Conclus\u00e3o<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Este artigo apresentou os nomes das aves mais comuns do cotidiano e algumas express\u00f5es idiom\u00e1ticas relacionadas a elas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Claro, as aves no Brasil e de outros pa\u00edses podem ser bem diferentes, mas \u00e9 recomend\u00e1vel come\u00e7ar a aprender uma l\u00edngua pelos aspectos que est\u00e3o presentes em sua vida di\u00e1ria. Nossa sugest\u00e3o \u00e9 que, com o tempo, voc\u00ea aproveite as oportunidades de conversa\u00e7\u00e3o para expandir sua base de vocabul\u00e1rio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E n\u00e3o \u00e9 necess\u00e1rio memorizar tudo de uma \u00fanica vez\u2014basta escolher os nomes das aves que mais lhe interessam, incluir em suas conversas do dia a dia e, com a pr\u00e1tica constante, seu ingl\u00eas vai melhorar naturalmente.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No cotidiano, h\u00e1 muitas oportunidades para ver diferentes tipos de aves. Andando na rua, as mais comuns s\u00e3o o pardal e o pombo, e muitas pessoas criam diamantes de Java ou papagaios como animais de estima\u00e7\u00e3o. Se voc\u00ea gosta de estar em contato com a natureza, pode at\u00e9 ter chance de ver esp\u00e9cies mais especiais. J\u00e1 que existem tantas esp\u00e9cies de aves, voc\u00ea sabe como dizer o nome delas em ingl\u00eas? Este artigo vai apresentar os nomes em ingl\u00eas das aves mais comuns no cotidiano, al\u00e9m de express\u00f5es idiom\u00e1ticas relacionadas a aves; n\u00e3o deixe de aprender e usar essas express\u00f5es! &nbsp; Diversidade das aves &nbsp; Existem cerca de dez mil &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/15152\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":15229,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=15152","footnotes":""},"categories":[128,127,131],"tags":[],"class_list":["post-15152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business","category-travel","category-hint","pt-BR"],"aioseo_notices":[],"views":237,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/15152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=15152"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/15152\/revisions"}],"predecessor-version":[{"id":15154,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/15152\/revisions\/15154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/15229"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=15152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=15152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=15152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}