{"id":15007,"date":"2026-02-11T09:00:32","date_gmt":"2026-02-11T12:00:32","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=15007"},"modified":"2026-02-10T03:26:17","modified_gmt":"2026-02-10T06:26:17","slug":"como-se-diz-alma-em-ingles-frases-praticas-incluidas","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/15007\/","title":{"rendered":"Como se diz \u201calma\u201d em ingl\u00eas? Frases pr\u00e1ticas inclu\u00eddas!"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Neste artigo, vamos apresentar as formas de expressar<span style=\"color: #cb09d9; font-size: 32px;\"> <strong>\u201calma\u201d<\/strong> <\/span>em ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como \u201calma\u201d geralmente carrega um significado mais forte do que \u201ccora\u00e7\u00e3o interior\u201d, o ingl\u00eas \u201cheart\u201d n\u00e3o consegue transmitir o mesmo sentido que \u201calma\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Agora, vamos come\u00e7ar com exemplos pr\u00e1ticos do cotidiano e incorporar a express\u00e3o em ingl\u00eas para \u201calma\u201d em nossas conversas reais!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Formas de expressar \u201calma\u201d em ingl\u00eas<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Sem mais delongas, vamos explicar como dizer \u201calma\u201d em ingl\u00eas! Existem duas formas principais: a primeira \u00e9 \u201csoul\u201d e a segunda \u00e9 \u201cspirit\u201d. Qual o significado espec\u00edfico de cada uma delas? Continue lendo\u2026<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Soul \/ Spirit<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, vamos explicar \u201csoul\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201csoul\u201d significa \u201calma\u201d, trazendo a ideia de \u201cespiritualidade\u201d, podendo tamb\u00e9m exprimir o significado de \u201ceternidade\u201d. Al\u00e9m disso, voc\u00ea j\u00e1 reparou que \u201calma\u201d em portugu\u00eas transmite uma forte sensa\u00e7\u00e3o de espiritualidade? Al\u00e9m disso, como muitas pessoas acreditam que a \u201calma\u201d continua existindo ap\u00f3s a morte, \u201csoul\u201d tamb\u00e9m possui associa\u00e7\u00e3o com o eterno.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, \u201csoul\u201d pode ser usada para expressar as caracter\u00edsticas emocionais ou espirituais de uma pessoa. Assim, ao inv\u00e9s de apenas traduzir como \u201calma\u201d, pode-se dizer que est\u00e1 mais pr\u00f3ximo de termos relacionados a \u201cpersonalidade\u201d ou \u201ccar\u00e1ter\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vejamos alguns exemplos de \u201csoul\u201d:<\/span><\/p>\n<h5><b>I love her because she has a beautiful soul. Don\u2019t you think so?<\/b><br \/>\n<span style=\"font-weight: 400;\">Amo ela porque tem uma alma bonita. Voc\u00ea n\u00e3o acha?<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Vale dizer que \u201csoul\u201d \u00e9 um substantivo cont\u00e1vel. Portanto, quando usada no plural, deve-se acrescentar \u201cs\u201d, tornando-se \u201csouls\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Agora, vejamos a palavra em ingl\u00eas \u201cspirit\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Assim como \u201csoul\u201d, \u201cspirit\u201d tamb\u00e9m pode ser traduzida como \u201calma\u201d e carrega o sentido de \u201cespiritualidade\u201d. A diferen\u00e7a \u00e9 que \u201cspirit\u201d pode tamb\u00e9m significar \u201cesp\u00edrito\u201d (\u00e2nimo), \u201cenergia\u201d, \u201centusiasmo\u201d ou at\u00e9 mesmo \u201ccoragem\u201d. Embora \u201cspirit\u201d pare\u00e7a complicado, com alguns exemplos fica f\u00e1cil compreender seus sentidos sutis.<\/span><\/p>\n<h5><b>Our class showed wonderful spirit and won the game at last!<\/b><br \/>\n<span style=\"font-weight: 400;\">Nossa turma demonstrou um esp\u00edrito incr\u00edvel e finalmente ganhou o jogo!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Apesar de no exemplo acima traduzirmos \u201cspirit\u201d como \u201calma\u201d, aqui a palavra transmite um sentido de \u201c\u00e2nimo interno\u201d ou \u201cmotiva\u00e7\u00e3o\u201d. Assim, tamb\u00e9m \u00e9 poss\u00edvel traduzir como \u201cenergia\u201d ou \u201centusiasmo\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Entregar-se de corpo e alma<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Como dizer \u201centregar-se de corpo e alma\u201d em ingl\u00eas? Quando voc\u00ea quiser expressar \u201ccom todo o cora\u00e7\u00e3o\u201d, pode-se utilizar as express\u00f5es \u201cverbo + one\u2019s alma\u201d da seguinte maneira:<\/span><\/p>\n<h6><b>(1) put one&#8217;s heart and soul into<\/b><\/h6>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, existe outra express\u00e3o semelhante:<\/span><\/p>\n<h6><b>(2) pour one\u2019s soul into<\/b><\/h6>\n<p><span style=\"font-weight: 400;\">Na verdade&#8230; poder\u00edamos pensar que existiria uma palavra simples para isso em ingl\u00eas, mas acabaram sendo duas express\u00f5es um pouco mais longas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A express\u00e3o (1) \u201cheart and soul\u201d significa literalmente \u201ccora\u00e7\u00e3o e alma\u201d, e \u201cput one\u2019s heart and soul\u201d quer dizer colocar o cora\u00e7\u00e3o e a alma em algo, ou seja, \u201centregar-se de corpo e alma\u201d. J\u00e1 na (2) o verbo \u201cpour\u201d significa \u201cderramar\u201d ou \u201cdedicar intensamente\u201d, ent\u00e3o \u201cpour one\u2019s soul into\u201d \u00e9 \u201cdedicar sua alma a\u201d, ou seja, entregar-se por completo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vamos ver exemplos dessas express\u00f5es:<\/span><\/p>\n<h5><b>The designer put her heart and soul into making her client\u2019s web-site.<\/b><br \/>\n<span style=\"font-weight: 400;\">A designer se dedicou de corpo e alma para fazer o site da sua cliente.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">No exemplo, o verbo \u201cput\u201d n\u00e3o muda de forma independentemente do tempo verbal, seja no presente ou passado. Por isso, a tradu\u00e7\u00e3o do tempo deve considerar o contexto. Aqui, usamos o tempo passado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ao reescrever o exemplo acima usando (2), fica assim:<\/span><\/p>\n<h5><b>The designer poured her soul into making her client\u2019s web-site.<\/b><br \/>\n<span style=\"font-weight: 400;\">A designer dedicou toda a sua alma (entregou-se de corpo e alma) para fazer o site de sua cliente.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Usando essas duas express\u00f5es, \u00e9 poss\u00edvel transmitir a ideia de \u201cdedicar-se de todo o cora\u00e7\u00e3o\u201d, colocando o esp\u00edrito e a alma em algo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando quiser usar um substantivo, use \u201csoul\u201d ou \u201cspirit\u201d; se quiser usar um verbo, use \u201cput one\u2019s heart and soul into\u201d ou \u201cpour one\u2019s soul into\u201d. E se preferir um adjetivo para expressar \u201cde todo cora\u00e7\u00e3o\u201d, como fazer?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Basta usar esta express\u00e3o curta a seguir, sem precisar recorrer a voc\u00e1bulos dif\u00edceis, para expressar o sentimento:<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>with all one&#8217;s heart<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u201cwith all one\u2019s heart\u201d literalmente significa \u201ccom todo o cora\u00e7\u00e3o\u201d, ou seja, \u201cde todo o cora\u00e7\u00e3o\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como j\u00e1 vimos, com poucas palavras simples em ingl\u00eas voc\u00ea pode transmitir a ideia de entregar-se de todo o cora\u00e7\u00e3o.<\/span><\/p>\n<h5><b>My grandmother made this cake with all her heart.<\/b><br \/>\n<span style=\"font-weight: 400;\">Minha av\u00f3 fez este bolo de todo o cora\u00e7\u00e3o.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Geralmente, \u201cwith all one\u2019s heart\u201d \u00e9 colocado no final da frase. Portanto, mesmo cobrindo com a m\u00e3o essa express\u00e3o, o restante da frase continua completo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Alma tocada<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quando voc\u00ea sente um profundo impacto ou emo\u00e7\u00e3o interior, dizemos que a \u201calma foi tocada\u201d. Em ingl\u00eas, pode-se usar \u201csoul-stirring\u201d para expressar isso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aqui, \u201csoul\u201d quer dizer \u201calma\u201d, \u201cstir\u201d significa \u201cagitar\u201d ou \u201cemocionar\u201d. Quando usados juntos, deve-se adicionar o h\u00edfen, formando \u201csoul-stirring\u201d.<\/span><\/p>\n<h5><b>The painting was soul-stirring.<\/b><br \/>\n<span style=\"font-weight: 400;\">Esta pintura tocou a alma de quem viu.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Al\u00e9m dessa express\u00e3o, tamb\u00e9m \u00e9 poss\u00edvel usar \u201cmoving\u201d ou \u201ctouching\u201d. Por\u00e9m, essas duas palavras se aproximam mais de \u201cemocionante\u201d, n\u00e3o sendo t\u00e3o intensas quanto \u201csoul-stirring\u201d, que transmite um impacto profundo na alma.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Express\u00f5es relacionadas a \u201calma\u201d<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Agora, vamos aprender outras express\u00f5es relacionadas ao tema \u201calma\u201d!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Fantasma<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Falando em \u201calma\u201d, muitos tamb\u00e9m pensam em fen\u00f4menos sobrenaturais ap\u00f3s a morte. Em ingl\u00eas, \u201cfantasma\u201d costuma ser traduzido como \u201cghost\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Veja este exemplo usando \u201cghost\u201d:<\/span><\/p>\n<h5><b>I\u2019ve heard that some ghosts live in that old house. Let\u2019s go and see them!<\/b><br \/>\n<span style=\"font-weight: 400;\">Ouvi dizer que alguns fantasmas moram naquela casa velha. Vamos l\u00e1 ver!<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Esp\u00edrito \/ mente<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quando algu\u00e9m pergunta a diferen\u00e7a entre \u201calma\u201d e \u201cesp\u00edrito\u201d (ou mente), at\u00e9 em portugu\u00eas \u00e9 dif\u00edcil explicar! Em ingl\u00eas, \u201cesp\u00edrito\u201d (no sentido de mente) costuma ser dito \u201cmind\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cmind\u201d refere-se ao esp\u00edrito respons\u00e1vel pelo pensamento e pelas emo\u00e7\u00f5es. A diferen\u00e7a principal com \u201calma\u201d \u00e9 que \u201cmind\u201d carrega mais sentimentos e pensamentos racionais.<\/span><\/p>\n<h5><b>I don\u2019t mind if you go to the party without me.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu n\u00e3o me importo se voc\u00ea for \u00e0 festa sem mim.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Cora\u00e7\u00e3o\/Interior<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Para expressar \u201cinterior\u201d (sentidos do cora\u00e7\u00e3o) em ingl\u00eas, costuma-se usar \u201cheart\u201d. Esse termo traz o sentido de \u201csentimento interior\u201d, sendo o oposto da raz\u00e3o.<\/span><\/p>\n<h5><b>I love your\u00a0innocent heart so much!<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu gosto muito do seu cora\u00e7\u00e3o puro!<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>\u201cResumo\u201d<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Ao traduzir \u201calma\u201d para o ingl\u00eas, pode-se usar \u201csoul\u201d, relacionado \u00e0 personalidade, ou \u201cspirit\u201d, que sugere algo al\u00e9m do corpo f\u00edsico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tanto dicion\u00e1rios portugu\u00eas-ingl\u00eas quanto ingl\u00eas- portugu\u00eas costumam agrupar palavras semelhantes. Isso pode gerar confus\u00e3o se n\u00e3o compreendermos as sutilezas de cada palavra. Por isso, conforme voc\u00ea ampliar seu vocabul\u00e1rio, recomendo utilizar ativamente esses termos em conversas reais, como em \u201caulas de conversa\u00e7\u00e3o online em ingl\u00eas\u201d. S\u00f3 assim voc\u00ea conseguir\u00e1 dominar o uso correto dessas palavras!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste artigo, vamos apresentar as formas de expressar \u201calma\u201d em ingl\u00eas. Como \u201calma\u201d geralmente carrega um significado mais forte do que \u201ccora\u00e7\u00e3o interior\u201d, o ingl\u00eas \u201cheart\u201d n\u00e3o consegue transmitir o mesmo sentido que \u201calma\u201d. Agora, vamos come\u00e7ar com exemplos pr\u00e1ticos do cotidiano e incorporar a express\u00e3o em ingl\u00eas para \u201calma\u201d em nossas conversas reais! &nbsp; Formas de expressar \u201calma\u201d em ingl\u00eas &nbsp; Sem mais delongas, vamos explicar como dizer \u201calma\u201d em ingl\u00eas! Existem duas formas principais: a primeira \u00e9 \u201csoul\u201d e a segunda \u00e9 \u201cspirit\u201d. Qual o significado espec\u00edfico de cada uma delas? Continue lendo\u2026 &nbsp; Soul \/ Spirit &nbsp; Primeiro, vamos explicar \u201csoul\u201d. \u201csoul\u201d significa \u201calma\u201d, trazendo a ideia &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/15007\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":15008,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=15007","footnotes":""},"categories":[139,140,133],"tags":[],"class_list":["post-15007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultural-exchange","category-study-abroad-nc","category-preparation-for-studying-abroad","pt-BR"],"aioseo_notices":[],"views":319,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/15007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=15007"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/15007\/revisions"}],"predecessor-version":[{"id":15009,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/15007\/revisions\/15009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/15008"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=15007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=15007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=15007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}