{"id":14874,"date":"2026-02-04T09:00:35","date_gmt":"2026-02-04T12:00:35","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=14874"},"modified":"2026-02-02T01:27:59","modified_gmt":"2026-02-02T04:27:59","slug":"quais-sao-as-vantagens-do-hinative-conecte-se-com-falantes-nativos","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/14874\/","title":{"rendered":"Quais s\u00e3o as vantagens do HiNative? Conecte-se com falantes nativos!"},"content":{"rendered":"<h2><strong>O que \u00e9 o aplicativo gratuito de ingl\u00eas &#8220;HiNative&#8221;?<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00ea j\u00e1 encontrou problemas dif\u00edceis de resolver ao aprender ingl\u00eas?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;Mesmo pesquisando no dicion\u00e1rio ou na internet, n\u00e3o entendo a diferen\u00e7a de nuance dessa express\u00e3o?&#8221;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;A gram\u00e1tica est\u00e1 certa, mas ser\u00e1 que esta express\u00e3o \u00e9 realmente comum?&#8221;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Existe um app que nos permite <strong>fazer perguntas simples diretamente para falantes nativos e obter respostas imediatas!<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">O nome dele \u00e9 <strong>&#8220;HiNative&#8221;<\/strong>. Esse \u00e9 um aplicativo incr\u00edvel que nos permite perguntar facilmente aos falantes nativos. Hoje, vamos apresentar <span style=\"font-size: 20px;\"><strong><span style=\"color: #d60dcf;\">as caracter\u00edsticas e como usar o HiNative<\/span>!<\/strong><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"font-weight: 400;\"><strong>O que faz o HiNative especial? Explica\u00e7\u00e3o de suas caracter\u00edsticas e atrativos<\/strong><\/span><\/h2>\n<h3><strong>O parceiro perfeito para aprender ingl\u00eas<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Quando tentamos criar frases em ingl\u00eas e encontramos palavras desconhecidas, normalmente procuramos em dicion\u00e1rios ou fazemos buscas online.<\/p>\n<p>No entanto, voc\u00ea j\u00e1 se preocupou se a express\u00e3o n\u00e3o ficou natural, se conseguiu transmitir exatamente o que queria dizer, ou se o seu ingl\u00eas soa estranho para nativos?<\/p>\n<p>Nessas situa\u00e7\u00f5es, \u00e9 f\u00e1cil cair em d\u00favidas e ficar ainda mais confuso.<\/p>\n<p>O &#8220;HiNative&#8221; nos ajuda a superar esses obst\u00e1culos e armadilhas no aprendizado!<\/p>\n<p><span style=\"font-weight: 400;\">Podemos fazer perguntas facilmente e receber respostas imediatas. Interagir com nativos tamb\u00e9m aumenta nossa motiva\u00e7\u00e3o!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Aprenda ingl\u00eas e outros idiomas atrav\u00e9s do Q&amp;A<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">No<\/span><b>&#8220;HiNative&#8221;<\/b><span style=\"font-weight: 400;\">, podemos obter respostas de <strong>pessoas de diferentes origens<\/strong>. Mesmo tratando-se de ingl\u00eas, \u00e9 surpreendente ver tantas respostas variadas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, se perguntarmos &#8220;Essa express\u00e3o soa natural?&#8221;, um brit\u00e2nico pode responder &#8220;sim, muito natural!&#8221;, enquanto um americano pode dizer &#8220;eu n\u00e3o costumo usar muito&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Isso pode ser um pouco confuso, mas \u00e9 assim que o ingl\u00eas realmente \u00e9! N\u00e3o h\u00e1 apenas uma resposta. Uma das grandes vantagens do HiNative \u00e9 que podemos <strong>experimentar o ingl\u00eas real atrav\u00e9s desse formato de<\/strong><\/span><strong> Q&amp;A<\/strong><span style=\"font-weight: 400;\"><strong>.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Suporte multil\u00edngue! At\u00e9 113 idiomas dispon\u00edveis<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O &#8220;HiNative&#8221; tem <strong>mais de 5 milh\u00f5es de usu\u00e1rios<\/strong> ao redor do mundo. Suas d\u00favidas podem ser respondidas de qualquer lugar do planeta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m do ingl\u00eas, \u00e9 poss\u00edvel aprender franc\u00eas, alem\u00e3o, italiano, russo, espanhol, brasileiro, coreano e <strong>mais de 110 outros idiomas<\/strong>. As perguntas n\u00e3o precisam limitar-se a idiomas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">HiNative \u00e9 um app onde podemos perguntar sobre qualquer assunto: destinos de viagem, cenas de filmes vistos recentemente, quest\u00f5es sobre cultura e costumes, etc. Podemos aprender em um n\u00edvel diferente dos livros did\u00e1ticos e manuais.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Voc\u00ea tamb\u00e9m pode ser professor<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Ao se cadastrar no<\/span><span style=\"font-weight: 400;\"> &#8220;HiNative&#8221;<\/span><span style=\"font-weight: 400;\">, \u00e9 preciso <strong>selecionar seu idioma nativo<\/strong> primeiro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ao abrir o app, a tela inicial mostra a op\u00e7\u00e3o do idioma nativo. Clicando, aparecem perguntas relacionadas a esse idioma, que geralmente s\u00e3o f\u00e1ceis de responder.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Podemos responder perguntas em ingl\u00eas, refletir sobre coisas que normalmente n\u00e3o pensamos, e adquirir experi\u00eancia. Isso n\u00e3o s\u00f3 nos ajuda a aprender como tamb\u00e9m aprofunda a compreens\u00e3o sobre o nosso pr\u00f3prio pa\u00eds e idioma!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, a <strong>troca entre &#8220;perguntar&#8221; e &#8220;responder&#8221;<\/strong> pode aumentar ainda mais a motiva\u00e7\u00e3o para aprender!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Usos e formas de utilizar o HiNative<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Agora vamos mostrar alguns exemplos para <strong>explicar concretamente como usar o HiNative<\/strong>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u2460 Obter respostas<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O &#8220;HiNative&#8221;<\/span><span style=\"font-weight: 400;\"> possui um <strong>&#8220;modelo de perguntas&#8221;<\/strong>, permitindo perguntas como &#8220;Como se diz isso em \u3007\u3007?&#8221; ou &#8220;Qual a diferen\u00e7a entre A e B?&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, situa\u00e7\u00f5es como travar ao escrever em ingl\u00eas, n\u00e3o entender um e-mail mesmo depois de procurar no Google, ou querer descobrir o que dizem as letras de m\u00fasicas estrangeiras: para tudo isso, podemos tentar fazer perguntas simples!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O &#8220;HiNative&#8221;<\/span><span style=\"font-weight: 400;\"> tamb\u00e9m oferece a <strong>fun\u00e7\u00e3o de envio de imagens<\/strong>, permitindo tirar uma foto rapidamente e perguntar &#8220;O que \u00e9 isso?&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 maravilhoso obter uma resposta imediata quando estamos quebrando a cabe\u00e7a! D\u00e1 at\u00e9 vontade de continuar usando, pois parece viciante!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u2461 Corrigir ingl\u00eas<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Esse servi\u00e7o \u00e9 pago, mas podemos usar o modelo <strong>&#8220;Essa express\u00e3o soa natural?&#8221;<\/strong> para corrigir o nosso ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com a aprova\u00e7\u00e3o dos nativos, podemos ter mais confian\u00e7a para enviar conte\u00fado de e-mails de trabalho ou discursos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">H\u00e1 tamb\u00e9m um <strong>modelo de di\u00e1rio<\/strong> (tamb\u00e9m pago), onde nativos corrigem o conte\u00fado do nosso di\u00e1rio. \u00c9 uma experi\u00eancia rara.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mesmo quem normalmente desiste r\u00e1pido pode continuar escrevendo se houver algu\u00e9m ajudando a corrigir o di\u00e1rio, n\u00e3o acha?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas \u00e9 importante lembrar que, mesmo sendo nativos, eles <strong>nem sempre s\u00e3o profissionais em ensino de ingl\u00eas<\/strong>. Como h\u00e1 muitos usu\u00e1rios, o n\u00edvel das corre\u00e7\u00f5es pode variar ocasionalmente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se o documento for realmente importante, \u00e9 melhor pedir revis\u00e3o feita por um profissional.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u2462 Verificar pron\u00fancia<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Como foi citado no item \u2460, o &#8220;HiNative&#8221; possui a fun\u00e7\u00e3o de envio de imagens e, al\u00e9m disso, <strong>permite enviar \u00e1udios<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se enviarmos uma grava\u00e7\u00e3o ao fazer uma pergunta, tamb\u00e9m podemos receber coment\u00e1rios de nativos. Ou seja, <strong>deixe que os nativos verifiquem a nossa pron\u00fancia<\/strong>!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Isso pode ser \u00fatil para praticar apresenta\u00e7\u00f5es e relat\u00f3rios, verificar a pron\u00fancia ao cantar m\u00fasicas em ingl\u00eas, revisar para as aulas de conversa\u00e7\u00e3o ou praticar sotaque brit\u00e2nico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como n\u00e3o estamos falando diretamente na frente dos nativos, n\u00e3o \u00e9 t\u00e3o constrangedor, e a barreira de vergonha ao mostrar a pron\u00fancia diminui bastante.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u2463 Perguntar sobre informa\u00e7\u00f5es locais<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><strong>\u00c0s vezes queremos saber mais sobre um lugar que vamos visitar pela primeira vez<\/strong>, como em viagens, interc\u00e2mbios ou viagens de neg\u00f3cios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 claro que d\u00e1 para consultar guias tur\u00edsticos online, mas \u00e0s vezes nos preocupamos se essas informa\u00e7\u00f5es ainda est\u00e3o atualizadas, ou queremos saber coisas que s\u00f3 os locais sabem&#8230;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nesses casos,<\/span><span style=\"font-weight: 400;\"> o &#8220;HiNative&#8221;<\/span><span style=\"font-weight: 400;\"> tamb\u00e9m \u00e9 muito \u00fatil! E n\u00e3o h\u00e1 restri\u00e7\u00f5es de perguntas apenas sobre gram\u00e1tica ou express\u00f5es de ingl\u00eas.<\/span><\/p>\n<p>Quero saber sobre restaurantes frequentados pelos moradores locais!<\/p>\n<p><span style=\"font-weight: 400;\">Tenho um plano assim, ser\u00e1 que \u00e9 vi\u00e1vel?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quero saber se h\u00e1 pontos tur\u00edsticos recomendados para a pr\u00f3xima visita.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Todos esses s\u00e3o exemplos de perguntas que podemos fazer!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Como usar o HiNative na pr\u00e1tica<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Agora vamos explicar como instalar o app, assim como tudo sobre as vers\u00f5es pagas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Instala\u00e7\u00e3o do app e registro de usu\u00e1rio<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O aplicativo est\u00e1 dispon\u00edvel para <strong>iOS e Android<\/strong>. Pode ser baixado na app store.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ao abri-lo pela primeira vez, ser\u00e1 solicitado registro. Voc\u00ea pode entrar usando sua conta do Twitter, Google ou criar um novo cadastro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se a op\u00e7\u00e3o for<\/span><span style=\"font-weight: 400;\">Email<\/span><span style=\"font-weight: 400;\">, basta fornecer o <\/span><span style=\"font-weight: 400;\">Email<\/span><span style=\"font-weight: 400;\">, nome de usu\u00e1rio e senha.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O pr\u00f3ximo passo \u00e9 a escolha do idioma. Escolha o seu idioma nativo e os idiomas de interesse. Se for um usu\u00e1rio gratuito, pode <strong>configurar o idioma nativo e at\u00e9 dois outros idiomas<\/strong>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Tutorial inicial<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Ap\u00f3s criar a conta, come\u00e7a o <strong>tutorial autom\u00e1tico<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante o tutorial, aprendemos na pr\u00e1tica como responder perguntas e utilizar os modelos para perguntar. As respostas e perguntas inseridas aqui servem apenas para o tutorial e n\u00e3o ser\u00e3o publicadas, fique tranquilo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ao final, surgem notifica\u00e7\u00f5es para permiss\u00f5es, apresenta\u00e7\u00e3o guiada, etc. Assim, come\u00e7a sua trajet\u00f3ria no app!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Como fazer perguntas e responder<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Para perguntar, clique primeiro no <strong>\u00edcone &#8220;Pergunta&#8221; no centro inferior da tela<\/strong>. Aparecer\u00e3o modelos, e a\u00ed \u00e9 s\u00f3 escolher o apropriado, digitar a pergunta e postar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para responder, consulte a lista de perguntas dispon\u00edveis na tela inicial. Se encontrar uma pergunta do seu interesse, clique sobre ela para ver o conte\u00fado completo e escreva sua resposta na caixa apropriada na parte inferior.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De acordo com as configura\u00e7\u00f5es do perfil, se seu idioma nativo \u00e9 portugu\u00eas, aparecer\u00e3o <strong>&#8220;Perguntas sobre portugu\u00eas&#8221; (em vermelho) e &#8220;Perguntas sobre Brasil&#8221; (em azul)<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como \u00e9 poss\u00edvel selecionar outros idiomas, podemos ver perguntas de outros usu\u00e1rios tamb\u00e9m.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Dicas para receber respostas<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Segundo a informa\u00e7\u00e3o oficial do app, a <strong>taxa de resposta supera 90%<\/strong>, mas h\u00e1 usu\u00e1rios que relatam dificuldade de obter respostas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como h\u00e1 muitas perguntas, existe uma tend\u00eancia de os usu\u00e1rios postarem perguntas e, logo em seguida, outras perguntas, o que faz com que as perguntas anteriores acabem descendo na lista e n\u00e3o sejam vistas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, tamb\u00e9m \u00e9 poss\u00edvel <strong>pagar para fixar a pergunta no topo<\/strong>. O pagamento pode ser mensal ou por compra de cr\u00e9ditos \u2014 escolha o que achar melhor.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aqui est\u00e3o dicas para usu\u00e1rios gratuitos conseguirem respostas:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u30fbTente postar quando os nativos provavelmente estejam online.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u30fbEvite fazer perguntas muito longas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essas s\u00e3o algumas sugest\u00f5es.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se n\u00e3o receber respostas, pode acabar desmotivado. Ent\u00e3o, antes de perguntar, sugerimos que <strong>pesquise se j\u00e1 h\u00e1 perguntas parecidas<\/strong>. Perguntas repetidas t\u00eam menos chance de resposta, ent\u00e3o pode levar um tempo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>HiNative \u00e9 recomendado para estas pessoas!<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O &#8220;HiNative&#8221; \u00e9 um app f\u00e1cil, inovador e divertido. \u00c9 altamente recomendado para os seguintes casos:<\/span><\/p>\n<h5><span style=\"font-weight: 400;\">\u30fbQuem quer experimentar o ingl\u00eas real<\/span><br \/>\n<span style=\"font-weight: 400;\">\u30fbQuem deseja verificar se sua escrita\/pron\u00fancia em ingl\u00eas est\u00e1 correta<\/span><br \/>\n<span style=\"font-weight: 400;\">\u30fbQuem trava quando tem d\u00favidas sobre o conte\u00fado estudado<\/span><br \/>\n<span style=\"font-weight: 400;\">\u30fbQuem quer saber letras de m\u00fasicas e frases de filmes dif\u00edceis de traduzir<\/span><br \/>\n<span style=\"font-weight: 400;\">\u30fbQuem busca as novidades tur\u00edsticas mais legais<\/span><br \/>\n<span style=\"font-weight: 400;\">\u30fbQuem quer se comunicar com nativos<\/span><br \/>\n<span style=\"font-weight: 400;\">\u30fbQuem \u00e9 de Brasil e quer ajudar outras pessoas<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Como esse \u00e9 um app de livre intera\u00e7\u00e3o com outras pessoas, <strong>a idade m\u00ednima recomendada \u00e9 12 anos<\/strong>. Fique atento a isso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, por ser uma plataforma de livre express\u00e3o, pode haver alguns usu\u00e1rios que perturbam o ambiente. Por\u00e9m, tamb\u00e9m existem pessoas que refletem e d\u00e3o respostas adequadas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essas respostas podem ser ignoradas. Use o app de forma inteligente para se motivar e experimentar o ingl\u00eas verdadeiro!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O que \u00e9 o aplicativo gratuito de ingl\u00eas &#8220;HiNative&#8221;? &nbsp; Voc\u00ea j\u00e1 encontrou problemas dif\u00edceis de resolver ao aprender ingl\u00eas? &#8220;Mesmo pesquisando no dicion\u00e1rio ou na internet, n\u00e3o entendo a diferen\u00e7a de nuance dessa express\u00e3o?&#8221; &#8220;A gram\u00e1tica est\u00e1 certa, mas ser\u00e1 que esta express\u00e3o \u00e9 realmente comum?&#8221; Existe um app que nos permite fazer perguntas simples diretamente para falantes nativos e obter respostas imediatas! O nome dele \u00e9 &#8220;HiNative&#8221;. Esse \u00e9 um aplicativo incr\u00edvel que nos permite perguntar facilmente aos falantes nativos. Hoje, vamos apresentar as caracter\u00edsticas e como usar o HiNative! &nbsp; O que faz o HiNative especial? Explica\u00e7\u00e3o de suas caracter\u00edsticas e atrativos O parceiro perfeito para aprender &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/14874\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":14875,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=14874","footnotes":""},"categories":[109,107,108],"tags":[],"class_list":["post-14874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-listening","category-speaking","category-writing","pt-BR"],"aioseo_notices":[],"views":232,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/14874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=14874"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/14874\/revisions"}],"predecessor-version":[{"id":14876,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/14874\/revisions\/14876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/14875"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=14874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=14874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=14874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}