{"id":14708,"date":"2026-01-26T09:00:54","date_gmt":"2026-01-26T12:00:54","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=14708"},"modified":"2026-01-22T03:25:41","modified_gmt":"2026-01-22T06:25:41","slug":"qual-e-a-diferenca-entre-ever-never-e-better-em-relacao-a-expressao-em-ingles-para-o-mais-verbo-ate-agora","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/14708\/","title":{"rendered":"Qual \u00e9 a diferen\u00e7a entre ever, never e better? Em rela\u00e7\u00e3o \u00e0 express\u00e3o em ingl\u00eas para \u201co mais [verbo] at\u00e9 agora!\u201d"},"content":{"rendered":"<p dir=\"ltr\">Ol\u00e1, aprendizes de ingl\u00eas! Neste artigo, o \u201cNative Camp\u201d ir\u00e1 explorar algumas d\u00favidas simples encontradas durante o aprendizado do ingl\u00eas, al\u00e9m de express\u00f5es pr\u00e1ticas no idioma. Tamb\u00e9m vamos compartilhar informa\u00e7\u00f5es \u00fateis para ajudar voc\u00ea a aprender ingl\u00eas.<\/p>\n<p dir=\"ltr\">Ali\u00e1s, voc\u00ea ainda se lembra da comida mais deliciosa que j\u00e1 provou? Para mim, a melhor comida que j\u00e1 comi at\u00e9 hoje foi frutos do mar apreciados em um restaurante \u00e0 beira de um lago na Nova Zel\u00e2ndia. Ent\u00e3o, quando quiser expressar em ingl\u00eas\u00a0 <strong>\u201ca melhor comida at\u00e9 agora\u201d<\/strong>, como voc\u00ea diria?<\/p>\n<p dir=\"ltr\">Acreditamos que quem est\u00e1 aprendendo ingl\u00eas pode pensar em usar a <strong>gram\u00e1tica do \u201csuperlativo\u201d para expressar o sentido de \u201co mais \u201d, como em \u201cmaior\u201d, \u201cmais r\u00e1pido\u201d, \u201cmais alto\u201d e outros adjetivos desse tipo<\/strong>. Claro, \u00e9 poss\u00edvel transmitir a ideia de \u201ca melhor de todas at\u00e9 agora\u201d com o superlativo em ingl\u00eas. No entanto, al\u00e9m da gram\u00e1tica do superlativo, existem muitas outras maneiras de expressar <strong>\u201ca melhor de todas at\u00e9 agora\u201d<\/strong> em ingl\u00eas!<\/p>\n<p dir=\"ltr\">Em seguida, vamos aprofundar tr\u00eas formas de expressar em ingl\u00eas o sentido de<strong> <span style=\"color: #c90ac6;\">\u201ca melhor at\u00e9 agora\u201d<\/span><\/strong>. Al\u00e9m disso, o artigo apresentar\u00e1 outras express\u00f5es com significado semelhante para que voc\u00ea possa variar suas falas!<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">\u201cDiferen\u00e7as entre ever, never e better\u201d<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Quando voc\u00ea quiser expressar <strong>\u201co melhor\/ou mais\u00a0 at\u00e9 agora\u201d<\/strong>, pode usar principalmente os tr\u00eas termos <strong>\u201cever\u201d, \u201cnever\u201d e \u201cbetter\u201d<\/strong>. A seguir, analisaremos o significado b\u00e1sico dessas palavras por meio de exemplos em ingl\u00eas, al\u00e9m de explicar como us\u00e1-las em conversas e textos.<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>Significado e uso de \u201cever\u201d<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Primeiro, vamos confirmar o significado b\u00e1sico de <strong>\u201cever\u201d<\/strong>! Se voc\u00ea consultar um dicion\u00e1rio ingl\u00eas-portugu\u00eas, ver\u00e1 que <strong>\u201cever\u201d<\/strong> pode significar: <strong>\u2460 \u201calguma vez, \u00e0s vezes, at\u00e9 agora\u201d, \u2461 \u201cjamais\u201d, \u2462 \u201co mais\u00a0 at\u00e9 o momento, at\u00e9 agora\u201d<\/strong>, entre outros sentidos. Assim, de acordo com esses significados, sempre que voc\u00ea sentir uma alegria, felicidade, sabor, emo\u00e7\u00e3o ou dificuldade in\u00e9ditos, ou seja, em situa\u00e7\u00f5es de <strong>\u201ca melhor\/ou maior\u00a0 at\u00e9 agora\u201d<\/strong>, pode utilizar \u201cever\u201d. Veja abaixo exemplos em ingl\u00eas para diversas situa\u00e7\u00f5es!<\/p>\n<p>\u201cMais bonito at\u00e9 agora\u201d<\/p>\n<h5 dir=\"ltr\"><strong>The sunset we watched over the hill yesterday was the best sunset I&#8217;ve ever seen!<\/strong><br \/>\nO p\u00f4r do sol que vimos ontem na colina foi o mais bonito que j\u00e1 vi.<\/h5>\n<p>\u201cMais dif\u00edcil at\u00e9 agora\u201d<\/p>\n<h5 dir=\"ltr\"><strong>The math test I&#8217;ve just finished was the most difficult test I&#8217;ve ever done.<\/strong><br \/>\nA prova de matem\u00e1tica que acabei de fazer foi a mais dif\u00edcil que j\u00e1 fiz at\u00e9 hoje.<\/h5>\n<p>\u201cMais gostoso at\u00e9 agora\u201d<\/p>\n<h5 dir=\"ltr\"><strong>The slice of pizza I had at this Italian restaurant was the best pizza I&#8217;ve ever had.<\/strong><br \/>\nA fatia de pizza que comi neste restaurante italiano foi a melhor pizza que j\u00e1 provei.<\/h5>\n<p>\u201cMais feliz at\u00e9 agora\u201d<\/p>\n<h5 dir=\"ltr\"><strong>It was the happiest birthday ever because my boyfriend made a proposal to me.<\/strong><br \/>\nFoi meu anivers\u00e1rio mais feliz at\u00e9 agora, porque meu namorado pediu minha m\u00e3o em casamento.<\/h5>\n<p>\u201cMais ruim at\u00e9 agora\u201d<\/p>\n<h5 dir=\"ltr\"><strong>The muffin I ate yesterday was the worst muffin I&#8217;ve ever had.<\/strong><br \/>\nO muffin que comi ontem foi o pior que j\u00e1 provei na vida.<\/h5>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>Significado e uso de \u201cnever\u201d<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Agora, vamos falar sobre como usar <strong>\u201cnever\u201d<\/strong> para expressar <strong>\u201co mais\u00a0 at\u00e9 agora\u201d<\/strong>. Ao procurar <strong>\u201cnever\u201d<\/strong> no dicion\u00e1rio, encontrar\u00e1 o sentido de <strong>\u201cnunca\u201d<\/strong>. Assim, usando \u201cnunca\u201d, voc\u00ea pode dizer frases como \u201cNunca conheci algu\u00e9m t\u00e3o divertido!\u201d ou \u201cNunca vi um cen\u00e1rio t\u00e3o bonito!\u201d.<\/p>\n<p>\u201cNunca t\u00e3o divertido assim\u201d<\/p>\n<h5 dir=\"ltr\"><strong>I&#8217;ve never seen such a funny person before.<\/strong><br \/>\nNunca vi uma pessoa t\u00e3o divertida assim!<\/h5>\n<p>\u201cNunca t\u00e3o solit\u00e1rio assim\u201d<\/p>\n<h5 dir=\"ltr\"><strong>I started living alone last month, and I just thought that I&#8217;ve never felt so lonely before.<\/strong><br \/>\nComecei a morar sozinho no m\u00eas passado e percebi que nunca me senti t\u00e3o sozinho antes.<\/h5>\n<p>\u201cNunca t\u00e3o bonito assim\u201d<\/p>\n<h5 dir=\"ltr\"><strong>I think I&#8217;ve never seen such a beautiful flower.<\/strong><br \/>\nAcho que nunca vi uma flor t\u00e3o bonita.<\/h5>\n<p>\u201cNunca t\u00e3o feliz assim\u201d<\/p>\n<h5 dir=\"ltr\"><strong>I&#8217;ve never had such a happy moment in my life!<\/strong><br \/>\nNunca tive um momento t\u00e3o feliz na minha vida!<\/h5>\n<p>\u201cNunca t\u00e3o estranho assim\u201d<\/p>\n<h5 dir=\"ltr\"><strong>I&#8217;ve never seen such strange clothes before.<\/strong><br \/>\nNunca vi roupas t\u00e3o estranhas!<\/h5>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>Significado e uso de \u201cbetter\u201d<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">O terceiro termo que vamos apresentar \u00e9 <strong>\u201cbetter\u201d<\/strong>. Os termos <strong>\u201cever\u201d e \u201cnever\u201d<\/strong> geralmente s\u00e3o aprendidos juntos quando se estuda <strong>o present perfect<\/strong> em ingl\u00eas. Mas <strong>\u201cbetter\u201d<\/strong> pertence a outra categoria gramatical. Basicamente, <strong>\u201cbetter\u201d \u00e9 o comparativo de \u201cgood\u201d<\/strong>, seguindo a ordem <strong>\u201cgood \u2192 better \u2192 best\u201d<\/strong>. Como o pr\u00f3prio nome diz, <strong>\u201cbetter\u201d serve para expressar \u201cmelhor\u201d ou \u201cmais\u201d<\/strong>. Portanto, quando quiser usar \u201cbetter\u201d para expressar <strong>\u201co melhor at\u00e9 agora\u201d<\/strong>, pode empregar <strong>\u201cCouldn\u2019t be better\u201d<\/strong>.<\/p>\n<p dir=\"ltr\">Por exemplo, ao assistir s\u00e9ries ou filmes estrangeiros, voc\u00ea ver\u00e1 as seguintes situa\u00e7\u00f5es:<\/p>\n<h5 dir=\"ltr\"><strong>Hey Matt, It&#8217;s been a while. How&#8217;s it going?<\/strong><br \/>\nOi, Matt! Faz tempo, tudo bem?<\/h5>\n<h5 dir=\"ltr\"><strong>Hi Melanie, yeah, couldn&#8217;t be better! How about you?<\/strong><br \/>\nOi, Melanie, n\u00e3o poderia estar melhor! E voc\u00ea?<\/h5>\n<p dir=\"ltr\">Como no exemplo acima, quando algu\u00e9m responde a um cumprimento com <strong>\u201cCouldn\u2019t be better\u201d<\/strong>, transmite a ideia de estar em <strong>\u201cestado excelente\u201d, \u201cmaravilhoso\u201d<\/strong>. Obviamente, respostas como <strong>\u201cI\u2019m great!\u201d e \u201cI\u2019ve been good!\u201d<\/strong> est\u00e3o corretas, mas se voc\u00ea responder suavemente com <strong>\u201cCouldn\u2019t be better!\u201d<\/strong>, seu ingl\u00eas soar\u00e1 especialmente natural e elegante!<\/p>\n<p dir=\"ltr\">Al\u00e9m disso, se quiser expressar no passado <strong>\u201cfoi o melhor\u201d, ou \u201cj\u00e1 me senti maravilhoso\u201d<\/strong>, basta mudar o tempo verbal de <strong>\u201ccouldn\u2019t\u201d<\/strong> para <strong>\u201cCouldn\u2019t have been better!\u201d<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">Outras formas semelhantes de express\u00e3o<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">At\u00e9 agora, aprendemos como usar \u201cever\u201d, \u201cnever\u201d e \u201cbetter\u201d para expressar \u201co mais\u00a0 at\u00e9 agora\u201d. Agora, vamos apresentar mais duas palavras ou express\u00f5es semelhantes, como alternativas ou varia\u00e7\u00f5es ao uso de \u201cever\u201d, \u201cnever\u201d e \u201cbetter\u201d. N\u00e3o deixe de memoriz\u00e1-las tamb\u00e9m!<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>\u201cno\u00a0 whatever\u201d<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">A primeira express\u00e3o \u00e9 <strong>\u201cno\u00a0 whatever\u201d<\/strong>. Voc\u00ea pode usar a estrutura <strong>\u201cno + substantivo + whatever\u201d para transmitir o sentido de \u201cnenhum \u201d<\/strong>. Assim como \u201cnever\u201d, <strong>traz a ideia de \u201cnunca at\u00e9 agora \u201d<\/strong>. Por exemplo, \u201cnunca planejei at\u00e9 agora\u201d ou \u201cnunca tive qualquer ideia at\u00e9 agora\u201d.<\/p>\n<p dir=\"ltr\">Exemplos:<\/p>\n<h5 dir=\"ltr\"><strong>We have no plans whatever.<\/strong><br \/>\nNunca fizemos qualquer plano at\u00e9 agora.<\/h5>\n<h5 dir=\"ltr\"><strong>There are no thoughts whatever about it.<\/strong><br \/>\nNunca houve nenhum pensamento sobre isso at\u00e9 agora.<\/h5>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>\u201cnot\u00a0 at all\u201d<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><strong>\u201cnotat all\u201d<\/strong> \u00e9 uma express\u00e3o comum que voc\u00ea pode ouvir em s\u00e9ries e filmes estrangeiros. Sua estrutura \u00e9 <strong>\u201cnot + adjetivo\/verbo + at all\u201d<\/strong>, significando <strong>\u201cde jeito nenhum\/nada \u201d<\/strong>. Por exemplo, voc\u00ea pode combinar <strong>\u201cI didn\u2019t know him\u201d com \u201cHe is the funniest person I\u2019ve ever met\u201d para reescrever: \u201cI didn\u2019t know him at all on the first day of school, but now I know that he is the funniest person I\u2019ve ever met!\u201d (No primeiro dia de aula eu n\u00e3o o conhecia nada, mas agora sei que ele \u00e9 a pessoa mais divertida que j\u00e1 conheci!)<\/strong><\/p>\n<p dir=\"ltr\">Exemplos:<\/p>\n<h5 dir=\"ltr\"><strong>I don&#8217;t know about him at all.<\/strong><br \/>\nEu n\u00e3o sei nada sobre ele.<\/h5>\n<h5 dir=\"ltr\"><strong>I am not interested in him at all.<\/strong><br \/>\nN\u00e3o tenho nenhum interesse nele.<\/h5>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">Resumo<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Neste artigo, apresentamos os significados e usos de <strong>\u201cever\u201d, \u201cnever\u201d e \u201cbetter\u201d<\/strong> para expressar <strong>\u201co mais\u00a0 at\u00e9 agora\u201d<\/strong>. No final, tamb\u00e9m mostramos outras formas \u00fateis que podem substituir ou serem usadas junto com essas tr\u00eas express\u00f5es. O que voc\u00ea achou?<\/p>\n<p dir=\"ltr\"><strong>\u201cO mais\u00a0 at\u00e9 agora\u201d<\/strong> \u00e9 uma express\u00e3o muito comum em conversas cotidianas em ingl\u00eas. Esperamos que voc\u00ea possa dominar todas as express\u00f5es apresentadas hoje e us\u00e1-las bastante em suas conversas em ingl\u00eas!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, aprendizes de ingl\u00eas! Neste artigo, o \u201cNative Camp\u201d ir\u00e1 explorar algumas d\u00favidas simples encontradas durante o aprendizado do ingl\u00eas, al\u00e9m de express\u00f5es pr\u00e1ticas no idioma. Tamb\u00e9m vamos compartilhar informa\u00e7\u00f5es \u00fateis para ajudar voc\u00ea a aprender ingl\u00eas. Ali\u00e1s, voc\u00ea ainda se lembra da comida mais deliciosa que j\u00e1 provou? Para mim, a melhor comida que j\u00e1 comi at\u00e9 hoje foi frutos do mar apreciados em um restaurante \u00e0 beira de um lago na Nova Zel\u00e2ndia. Ent\u00e3o, quando quiser expressar em ingl\u00eas\u00a0 \u201ca melhor comida at\u00e9 agora\u201d, como voc\u00ea diria? Acreditamos que quem est\u00e1 aprendendo ingl\u00eas pode pensar em usar a gram\u00e1tica do \u201csuperlativo\u201d para expressar o sentido de \u201co mais &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/14708\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":14709,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=14708","footnotes":""},"categories":[124,119,120],"tags":[],"class_list":["post-14708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apps","category-basic","category-grammar","pt-BR"],"aioseo_notices":[],"views":412,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/14708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=14708"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/14708\/revisions"}],"predecessor-version":[{"id":14710,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/14708\/revisions\/14710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/14709"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=14708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=14708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=14708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}