{"id":14285,"date":"2026-01-04T09:00:48","date_gmt":"2026-01-04T12:00:48","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=14285"},"modified":"2025-12-25T23:02:08","modified_gmt":"2025-12-26T02:02:08","slug":"o-que-entao-pimenta-nao-significa-apenas-pimenta","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/14285\/","title":{"rendered":"O qu\u00ea? Ent\u00e3o \u201cpimenta\u201d n\u00e3o significa apenas \u201cpimenta\u201d!?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Al\u00e9m do a\u00e7\u00facar, sal e molho de soja, um tempero indispens\u00e1vel em casa \u00e9, claro, a pimenta. Muitas receitas precisam de pimenta para real\u00e7ar todo o sabor.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A maioria das pessoas provavelmente sabe que pimenta em ingl\u00eas \u00e9 pepper, mas voc\u00ea sabia que ela tamb\u00e9m pode ser usada como verbo? E o significado \u00e9 bem interessante!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O tema deste artigo \u00e9 a <\/span>introdu\u00e7\u00e3o ao vocabul\u00e1rio<span style=\"font-size: 36px;\"><b> \u201cpepper\u201d<\/b><\/span><span style=\"font-weight: 400;\">. Espero que, depois de ler, todos possam compreender melhor o uso completo da palavra pepper.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Significado de pepper<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Como mencionamos, pepper n\u00e3o \u00e9 usada apenas para indicar pimenta; ent\u00e3o vamos ver que outros significados ela tem.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>O significado b\u00e1sico de pepper<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos separar as explica\u00e7\u00f5es do uso como substantivo e como verbo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O significado como substantivo inclui\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201c(planta) pimenta\u201d, \u201cmostarda ou especialmente pimenta ardida\u201d, \u201c(termo de beisebol) tipo de exerc\u00edcio de rebatida e defesa\u201d, \u201cpiment\u00e3o\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O significado como verbo inclui\u00a0 <\/span><span style=\"color: #0000ff;\"><b>\u201csalpicar pimenta sobre algo, adicionar ard\u00eancia\u201d, \u201c(na escrita) tornar mais conciso ou interessante\u201d, \u201catacar com arma ou questionamentos\u201d, \u201cespalhar em grande quantidade\u201d<\/b><\/span><span style=\"font-weight: 400;\">, entre outros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00ea j\u00e1 percebeu que costumamos conhecer s\u00f3 o uso como substantivo, e talvez nem soubesse que pepper pode ser verbo tamb\u00e9m.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos ver mais detalhes sobre os significados alimentares de pepper e exemplos do uso como verbo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Tipos de significado de pepper em alimentos<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Pepper basicamente \u00e9 um tipo de especiaria picante, mas existem v\u00e1rias categorias, incluindo\u00a0 <\/span><span style=\"color: #ff0000;\"><b>pimenta-do-reino, pimenta ardida, piment\u00e3o verde, piment\u00e3o doce<\/b><\/span><span style=\"font-weight: 400;\">. O nome completo de pimenta ardida em ingl\u00eas \u00e9 chili pepper, piment\u00e3o verde \u00e9 green pepper, e piment\u00e3o doce \u00e9 bell pepper.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Usando chili pepper como ingrediente principal, pode-se fazer molho Tabasco, molho de pimenta (chili sauce), ou o conhecido chili powder em pratos mexicanos. Quanto ao nome bell pepper para piment\u00e3o doce, parece vir do seu formato de sino.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A pimenta-do-reino vem do fruto de uma pequena planta trepadeira da fam\u00edlia das Piperaceae. Depois de secar o fruto, temos o conhecido pimenta-do-reino preta, branca e a pimenta mo\u00edda.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A pimenta-do-reino preta \u00e9 colhida antes do amadurecimento total e seca, por isso \u00e9 mais ardida. J\u00e1 a pimenta-do-reino branca \u00e9 feita retirando a casca do fruto j\u00e1 maduro, com aroma mais suave e ainda assim picante.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A pimenta verde, quando madura, fica vermelha e \u00e9 a ardida que conhecemos, comum na culin\u00e1ria portugu\u00eas, coreana e mexicana. J\u00e1 o piment\u00e3o doce n\u00e3o \u00e9 picante.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Como usar pepper para se referir a alimentos<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Vamos conferir alguns exemplos de uso relacionados.<\/span><\/p>\n<h5><b>Can you pass the pepper, please?<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea pode me passar a pimenta, por favor?<\/span><\/h5>\n<h5><b>I put some salt and pepper on my vegetables.<\/b><br \/>\n<span style=\"font-weight: 400;\">Coloquei um pouco de sal e pimenta nos meus vegetais.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Para muitas pessoas, sal e pimenta s\u00e3o pr\u00e1ticos em pequenos sach\u00eas. Nas refei\u00e7\u00f5es de avi\u00e3o tamb\u00e9m costumam ser oferecidos, e, em vez de molhos pesados, muitos preferem esse tempero simples. <\/span><span style=\"color: #ff0000;\"><b>\u201cColocar pimenta\u201d em ingl\u00eas \u00e9 \u201cput some pepper on\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, <\/span><span style=\"color: #0000ff;\"><b>o sabor de pimenta em ingl\u00eas \u00e9 chamado peppery, palavra derivada de pepper<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h5><b>Black pepper makes food delicious and peppery.<\/b><br \/>\n<span style=\"font-weight: 400;\">A pimenta-do-reino deixa a comida deliciosa e com sabor de pimenta.<\/span><\/h5>\n<h5><b>Why does pepper make you sneeze?<\/b><br \/>\n<span style=\"font-weight: 400;\">Por que a pimenta faz voc\u00ea espirrar?<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">De fato, algumas pessoas espirram ao cheirar pimenta. Espirrar em ingl\u00eas \u00e9 sneeze. Quando vir algu\u00e9m espirrar, lembre-se de dizer \u201cBless you!\u201d (Sa\u00fade).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Diz-se que antigamente acreditavam que a alma podia sair junto ao espirro; por isso, falavam \u201cBless you\u201d como forma de cuidar da pessoa, h\u00e1bito que continua at\u00e9 hoje nos pa\u00edses de l\u00edngua inglesa.<\/span><\/p>\n<h5><b>I love spicy foods, especially anything with chili pepper.<\/b><br \/>\n<span style=\"font-weight: 400;\">Eu adoro comida apimentada, principalmente tudo que leva chili pepper.<\/span><\/h5>\n<h5><b>My sister made a colorful salad with green, red and yellow peppers.<\/b><br \/>\n<span style=\"font-weight: 400;\">Minha irm\u00e3 fez uma salada colorida com piment\u00f5es verdes, vermelhos e amarelos.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Os piment\u00f5es n\u00e3o s\u00e3o apenas bonitos, tamb\u00e9m fazem bem \u00e0 sa\u00fade. Prepar\u00e1-los em salada \u00e9 uma forma simples de consumo. Aqui em casa, geralmente s\u00e3o mantidos como verdura coringa, seja para assar ou comer cru em tiras.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Uso verbal de pepper<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Vamos agora ver a forma verbal de pepper. Talvez muitos n\u00e3o a conhe\u00e7am, mas ao se familiarizar com esses usos, seu ingl\u00eas do dia a dia ficar\u00e1 ainda melhor.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Bombardear algu\u00e9m de perguntas<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p>Um dos usos \u00e9 <b><span style=\"color: #ff0000;\">bombardear algu\u00e9m com perguntas<\/span><\/b><span style=\"font-weight: 400;\">, por exemplo, interrogar duramente um parceiro sobre quem \u00e9 um novo amigo, \u00e9 um \u00f3timo exemplo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m de bombardear com palavras, tamb\u00e9m pode se referir a atacar algu\u00e9m fisicamente com socos ou armas. Nesse caso, pode-se usar a preposi\u00e7\u00e3o with.<\/span><\/p>\n<h5><b>I was peppered with a lot of questions by my friend who has recently got a boyfriend.<\/b><br \/>\n<span style=\"font-weight: 400;\">Fui bombardeado por muitas perguntas pela minha amiga que acabou de arranjar um namorado.<\/span><\/h5>\n<h5><b>Stop peppering me with so many questions about my trip to London, I need a coffee!<\/b><br \/>\n<span style=\"font-weight: 400;\">Pare de me bombardear com tantas perguntas sobre minha viagem a Londres, preciso de um caf\u00e9!<\/span><\/h5>\n<h5><b>The President of Brazil has been peppered with many questions from journalists about relationship between China and Brazil.<\/b><br \/>\n<span style=\"font-weight: 400;\">Jornalistas bombardearam o presidente de Brasil com v\u00e1rias perguntas sobre a rela\u00e7\u00e3o entre China e Brasil.<\/span><\/h5>\n<h5><b>The car was peppered with bullets.<\/b><br \/>\n<span style=\"font-weight: 400;\">O carro foi crivado de balas.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Nos filmes de a\u00e7\u00e3o, sempre que o protagonista se esconde atr\u00e1s do carro como prote\u00e7\u00e3o, o inimigo dispara sem parar. Usar pepper neste contexto \u00e9 divertido, n\u00e3o acha? S\u00f3 de imaginar pimenta voando por todo lado, fica dif\u00edcil esquecer essa express\u00e3o.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Coberto de algo, espalhado<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Pepper tamb\u00e9m pode significar\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201cespalhar em grande quantidade, salpicar\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, ao decorar um bolo com confeitos coloridos, o sentido de pepper se aproxima bastante de sprinkle. Ou ao polvilhar muita pimenta sobre um bife. Fica f\u00e1cil imaginar pepper como verbo nesses casos, n\u00e3o \u00e9?<\/span><\/p>\n<h5><b>My face is peppered with freckles.<\/b><br \/>\n<span style=\"font-weight: 400;\">Meu rosto \u00e9 cheio de sardas.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">As sardas \u00e0s vezes s\u00e3o uma caracter\u00edstica especial da pessoa. Usar pepper para expressar que o rosto est\u00e1 coberto de pequenas sardas \u00e9 muito apropriado.<\/span><\/p>\n<h5><b>I heavily peppered my steak with a variety of herbs because it was bland.<\/b><br \/>\n<span style=\"font-weight: 400;\">Como o bife estava muito sem sabor, coloquei uma camada generosa de ervas variadas em cima.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Animar algu\u00e9m<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Em Viena, na \u00c1ustria, h\u00e1 uma banda chamada Peppy Pep Pepper. A inspira\u00e7\u00e3o veio de pepper no sentido de dar mais \u201card\u00eancia\u201d, originando a express\u00e3o <\/span><span style=\"color: #ff0000;\"><b>pep up, que significa animar algu\u00e9m<\/b><\/span><span style=\"font-weight: 400;\">; ent\u00e3o, se algu\u00e9m estiver desanimado, voc\u00ea pode usar essa express\u00e3o para incentivar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Outras express\u00f5es com sentido parecido s\u00e3o <\/span><span style=\"color: #0000ff;\"><b>quicken (estimular) ou jazz up (tornar algo ou algu\u00e9m mais animado e interessante)<\/b><\/span><span style=\"font-weight: 400;\">, ideais para ocasi\u00f5es em que \u00e9 preciso motivar algu\u00e9m.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, pepper up pode ser usado no sentido de se arrumar para ficar sexy, se preparar para curtir a noite ou chamar a aten\u00e7\u00e3o de algu\u00e9m.<\/span><\/p>\n<h5><b>I&#8217;m more than happy to pep you up, shall we go for a drink?<\/b><br \/>\n<span style=\"font-weight: 400;\">Vou adorar te animar, vamos tomar um drink?<\/span><\/h5>\n<h5><b>The coach wanted to give all the players a pep talk before the rugby match started.<\/b><br \/>\n<span style=\"font-weight: 400;\">O t\u00e9cnico queria dar uma palestra motivacional para todos os jogadores antes do in\u00edcio da partida de r\u00fagbi.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Al\u00e9m do pep up, a pep talk \u00e9 outro uso comum como substantivo. <\/span><span style=\"color: #0000ff;\"><b>a pep talk refere-se a um breve discurso motivacional<\/b><\/span><span style=\"font-weight: 400;\">, ou seja, um chamado para aumentar a moral e o \u00e2nimo, incentivando todos a nunca desistir at\u00e9 o final.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Uso de pepper em g\u00edrias<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Por fim, vamos conhecer algumas g\u00edrias relacionadas a pepper.<\/span><\/p>\n<p><span style=\"color: #ff0000;\"><b>Pepper pode ser g\u00edria para anfetamina<\/b><\/span><span style=\"font-weight: 400;\">. Todos sabemos que \u00e9 uma droga, de uso controlado por lei. Fora isso, pepper pode tamb\u00e9m se referir a maconha ou outras drogas.<\/span><\/p>\n<h5><b>My sister lived in the US and she was addicted to pepper for quite some time. Now she has got off pepper and has recovered from it.<\/b><br \/>\n<span style=\"font-weight: 400;\">Minha irm\u00e3 morou nos EUA e ficou viciada em drogas por um tempo. Mas agora ela parou e se recuperou completamente.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Como j\u00e1 foi dito, o tempero comum sal e pimenta em ingl\u00eas \u00e9 salt and pepper e, na g\u00edria, pode se referir a maconha, carro de pol\u00edcia (por causa da cor preta e branca) ou cabelo com mistura de fios brancos e pretos. Em alguns casos, tamb\u00e9m pode ter conota\u00e7\u00e3o sexual.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por fim, vamos ver o uso de peppercorn (gr\u00e3o de pimenta) como g\u00edria.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em termos jur\u00eddicos, representa uma pequena quantia em dinheiro como requisito para firmar um contrato. O tamanho min\u00fasculo do gr\u00e3o de pimenta ajuda a lembrar disso.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Resumo<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Essas foram as diversas formas de uso de pepper que aparecem no dia a dia. Al\u00e9m de tempero, como verbo, pode significar <strong>\u201cinterrogar\u201d, \u201ccobrir\u201d, \u201canimar\u201d,<\/strong> entre outros. Espero que, com os exemplos, todos tenham compreendido bem.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para muitos, talvez seja a primeira vez sabendo que pepper tem tantos significados interessantes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o s\u00f3 pode indicar ataque com socos ou muni\u00e7\u00e3o, mas tamb\u00e9m descrever um rosto cheio de sardas ou ser sin\u00f4nimo de droga, e essas aplica\u00e7\u00f5es n\u00e3o se aprendem na escola. Espero que este artigo ajude voc\u00ea a aprender usos pr\u00e1ticos do ingl\u00eas do dia a dia, que \u00e9 o verdadeiro objetivo de aprender uma l\u00edngua.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al\u00e9m do a\u00e7\u00facar, sal e molho de soja, um tempero indispens\u00e1vel em casa \u00e9, claro, a pimenta. Muitas receitas precisam de pimenta para real\u00e7ar todo o sabor. A maioria das pessoas provavelmente sabe que pimenta em ingl\u00eas \u00e9 pepper, mas voc\u00ea sabia que ela tamb\u00e9m pode ser usada como verbo? E o significado \u00e9 bem interessante! O tema deste artigo \u00e9 a introdu\u00e7\u00e3o ao vocabul\u00e1rio \u201cpepper\u201d. Espero que, depois de ler, todos possam compreender melhor o uso completo da palavra pepper. &nbsp; Significado de pepper &nbsp; Como mencionamos, pepper n\u00e3o \u00e9 usada apenas para indicar pimenta; ent\u00e3o vamos ver que outros significados ela tem. &nbsp; O significado b\u00e1sico de pepper &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/14285\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":14286,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=14285","footnotes":""},"categories":[134,139,140],"tags":[],"class_list":["post-14285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-overseas-info","category-cultural-exchange","category-study-abroad-nc","pt-BR"],"aioseo_notices":[],"views":415,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/14285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=14285"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/14285\/revisions"}],"predecessor-version":[{"id":14287,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/14285\/revisions\/14287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/14286"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=14285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=14285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=14285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}