{"id":14131,"date":"2026-01-11T09:00:27","date_gmt":"2026-01-11T12:00:27","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=14131"},"modified":"2026-01-07T23:10:04","modified_gmt":"2026-01-08T02:10:04","slug":"como-se-diz-parentes-em-ingles-exemplos-praticos-incluidos","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/14131\/","title":{"rendered":"Como se diz \u201cparentes\u201d em ingl\u00eas? Exemplos pr\u00e1ticos inclu\u00eddos!"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Voc\u00ea tamb\u00e9m acha que os\u00a0 \u00a0<span style=\"font-size: 36px;\"><strong>\u201ct\u00edtulos de parentesco\u201d\u00a0\u00a0<\/strong><\/span> em portugu\u00eas s\u00e3o um conjunto complicado e confuso?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, t\u00edtulos como \u201csobrinho\u201d e \u201csobrinho-neto\u201d, se n\u00e3o estiverem relacionados ao seu cotidiano, dificilmente ter\u00e3o oportunidade de aparecer.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas h\u00e1 pessoas que simplesmente se esquecem de como dizer devido \u00e0 grande variedade de tipos!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ent\u00e3o, se pedirmos que voc\u00ea expresse \u201ct\u00edtulos de parentesco\u201d em ingl\u00eas,<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">provavelmente muitos achar\u00e3o um pouco dif\u00edcil!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 que \u00e9 melhor manter uma boa rela\u00e7\u00e3o com os parentes, isso \u00e9 ainda mais importante em conex\u00f5es familiares internacionais.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea pensa<\/span><\/p>\n<p><b>\u201cPorque a pessoa com quem vou me casar \u00e9 brasileira&#8230;\u201d\u00a0\u00a0<\/b><\/p>\n<p><b>\u201cMeus parentes s\u00e3o todos brasileiros, n\u00e3o preciso aprender isso&#8230;\u201d<\/b><\/p>\n<p><span style=\"font-weight: 400;\">isso pode trazer riscos para o seu futuro!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Porque, talvez um dia voc\u00ea tenha encontros internacionais&#8230;<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Ou talvez existam parentes estrangeiros que voc\u00ea ainda n\u00e3o conhece&#8230;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Portanto, j\u00e1 que estamos aprendendo ingl\u00eas, que tal memorizar tamb\u00e9m as formas de expressar \u201cparentes\u201d e os vocabul\u00e1rios correspondentes? Esse conhecimento definitivamente ser\u00e1 \u00fatil para o seu futuro!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este artigo organiza algumas formas de express\u00e3o em ingl\u00eas relacionadas a \u201cparentes\u201d e, na segunda metade, ainda traz uma explica\u00e7\u00e3o extra sobre situa\u00e7\u00f5es reais de conv\u00edvio com parentes no exterior.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o deixe de ler at\u00e9 o fim e dominar bem essas formas de expressar \u201cparentes\u201d em ingl\u00eas!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>A express\u00e3o em ingl\u00eas para \u201cparente\u201d \u00e9 \u201cRelative\u201d<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Vamos direto ao ponto! Como dizemos \u201cparente\u201d em ingl\u00eas?\u00a0\u00a0<\/span><\/p>\n<p><b>A resposta \u00e9\u00a0 \u00a0<span style=\"font-size: 36px;\">\u201cRelative\u201d<\/span><\/b><span style=\"font-weight: 400;\">, e o plural \u00e9 <strong>\u201cRelatives\u201d<\/strong>.\u00a0 <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Voc\u00ea pode usar \u201cRelatives\u201d para se referir, de forma geral, a \u201ctio, tia, sobrinho, sobrinha\u201d e outros parentes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, no Brasil, durante o Festival Qingming e o Ano Novo, geralmente todos os \u201cparentes\u201d se re\u00fanem em uma casa para uma refei\u00e7\u00e3o de reuni\u00e3o familiar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ent\u00e3o, como podemos expressar esse tipo de \u201cencontro de parentes\u201d em ingl\u00eas?<\/span><\/p>\n<p><strong><span style=\"font-size: 36px;\">\u201cFamily Reunion\u201d<\/span><\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Vale notar aqui que, no termo \u201cencontro de parentes\u201d, em ingl\u00eas n\u00e3o usamos \u201cRelative\u201d mas sim \u201cFamily\u201d, que representa a ideia de \u201cfam\u00edlia\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 que \u201cparentes\u201d s\u00e3o membros da fam\u00edlia com la\u00e7os de sangue, esse modo de expressar soa mais natural.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, <span style=\"color: #d41ed1;\">\u201cReunion\u201d<\/span> significa \u201creuni\u00e3o, reencontro\u201d ou at\u00e9 \u201creuni\u00e3o de ex-colegas\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ao traduzir como \u201creencontro familiar\u201d, n\u00e3o sente que essa express\u00e3o ganhou um tom mais dram\u00e1tico?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como s\u00f3 temos algumas poucas \u201creuni\u00f5es de parentes\u201d por ano, que tal pendurar uma faixa com \u201cFamily Reunion\u201d na pr\u00f3xima vez para celebrar?<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Formas de expressar \u201capresentando parentes\u201d em ingl\u00eas<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quando voc\u00ea encontra amigos andando na rua com um parente ou ao apresentar parentes em casamentos de irm\u00e3os, h\u00e1 situa\u00e7\u00f5es em que precisa apresentar seus \u201cparentes\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como podemos nos expressar em ingl\u00eas nesses momentos?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea mora fora ou vai participar de um casamento internacional, esses m\u00e9todos v\u00e3o ser logo \u00fateis! Vamos aproveitar para estud\u00e1-los agora!<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><b>Vocabul\u00e1rio em ingl\u00eas para \u201ct\u00edtulos de parentesco\u201d<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, vejamos algumas palavras em ingl\u00eas indispens\u00e1veis na hora de apresentar nossos \u201cparentes\u201d.<\/span><\/p>\n<p><b>\u30fbUncle (tio)<\/b><\/p>\n<p><b>\u30fbAunt (tia)<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u201cUncle\u201d e \u201cAunt\u201d s\u00e3o t\u00edtulos para \u201cos irm\u00e3os dos seus pais\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Eles s\u00e3o usados assim:<\/span><\/p>\n<h5><b>\u30fbShe is my aunt.<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">Ela \u00e9 irm\u00e3 do meu pai = tia.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, os filhos de \u201cUncle\u201d e \u201cAunt\u201d podem ser chamados assim:<\/span><\/p>\n<p><b>\u30fbCousin (primos e primas)<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Vale mencionar que, embora em ingl\u00eas chame-se todos apenas de \u201ccousin\u201d, no Brasil diferencia-se primos de lado paterno e materno. Muitas pessoas, inclusive, t\u00eam mais contato com primos do lado materno e cresceram juntos.<\/span><\/p>\n<p><b>\u30fbNephew (sobrinho)<\/b><\/p>\n<p><b>\u30fbNiece (sobrinha)<\/b><\/p>\n<p><span style=\"font-weight: 400;\">No exterior, chamam os filhos dos irm\u00e3os como \u201cNephew\u201d (para meninos) e \u201cNiece\u201d (para meninas). No Brasil, entretanto, \u201csobrinho e sobrinha\u201d s\u00e3o filhos dos irm\u00e3os (mesmo sobrenome), enquanto \u201csobrinho-neto e sobrinha-neta\u201d s\u00e3o filhos das irm\u00e3s (sobrenome diferente).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando for dar envelopes de dinheiro para essas crian\u00e7as no Ano Novo, use as palavras \u201cNephew\u201d e \u201cNiece\u201d!<\/span><\/p>\n<h5><b>\u30fbMy nephew stares at me with shining eyes.<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">Meu sobrinho olha para mim com olhos brilhantes.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Se acontecer isso no Ano Novo, n\u00e3o precisa dizer nada! Apenas entregue o envelope para seu sobrinho ou sobrinha.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Agora, vejamos alguns exemplos de frases em ingl\u00eas ligadas a \u201cparentes\u201d.<\/span><\/p>\n<h5><b>\u30fbAre you related to him?<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">Voc\u00ea \u00e9 parente dele?<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Esta \u00e9 uma frase \u00fatil quando encontrar amigos na rua. Se seu amigo conhecer seu \u201cparente\u201d pela primeira vez, pode perguntar isso!<\/span><\/p>\n<h5><b>\u30fbHe is my nephew.<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">Ele \u00e9 meu sobrinho.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Voc\u00ea pode usar esta frase para responder a um amigo. Apenas substitua \u201cNephew\u201d pelo outro t\u00edtulo em ingl\u00eas conforme o contexto!<\/span><\/p>\n<h5><b>He is one year younger than me.<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">Ele \u00e9 um ano mais novo que eu.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Se quiser apresentar mais detalhes sobre seu \u201cparente\u201d, este \u00e9 um exemplo \u00fatil. Idade \u00e9 um tema comum, ent\u00e3o vale lembrar dessa express\u00e3o.<\/span><\/p>\n<h5><b>\u30fbHe is living in\u00a0<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">Ele mora em .<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Use essa frase para explicar onde mora um \u201cparente\u201d distante.<\/span><\/p>\n<h5><b>\u30fbWe get together a few times a year.<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">N\u00f3s nos encontramos algumas vezes por ano.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">\u00d3tima frase para falar de parentes que voc\u00ea n\u00e3o v\u00ea com tanta frequ\u00eancia, como aqueles que s\u00f3 aparecem em feriados.<\/span><\/p>\n<p><b>\u30fbWe are really close actually, I always go out with him.<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">Na verdade, somos muito pr\u00f3ximos, eu sempre saio com ele.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se o seu relacionamento com um parente \u00e9 pr\u00f3ximo, como se fossem amigos, use esta frase para transmitir essa boa rela\u00e7\u00e3o.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><b>Expressando \u201cparentes por afinidade\u201d em ingl\u00eas<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ap\u00f3s o casamento, ganhamos \u201cparentes por afinidade\u201d, incluindo irm\u00e3os e at\u00e9 pais do c\u00f4njuge, os quais podem ser chamados em ingl\u00eas com as seguintes palavras.<\/span><\/p>\n<p><b>\u30fbIn-Law (parente por afinidade)<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u201cin-law\u201d indica um \u201cparente por afinidade\u201d, sem la\u00e7os de sangue.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O termo \u201claw\u201d de \u201cin-law\u201d significa \u201clei\u201d. Ao adicionar \u201cin-law\u201d ap\u00f3s o t\u00edtulo de parentesco, expressa-se o la\u00e7o familiar pelo casamento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Veja como usar:<\/span><\/p>\n<h5><b>\u30fbThey are my parents-in-law.<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">Eles s\u00e3o meus sogros.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Como na frase acima, basta adicionar \u201cin-law\u201d ao final do t\u00edtulo correspondente em ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aqui vai uma frase completa para refer\u00eancia:<\/span><\/p>\n<h5><b>\u30fbHe is my brother-in-law who has been married to my sister since last year. He\u2019s now living in the United States with his family, and working as an engineer at Google.<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">Ele \u00e9 meu cunhado, se casou com minha irm\u00e3 no ano passado. Agora mora nos Estados Unidos com sua fam\u00edlia e trabalha como engenheiro no Google.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Esse \u00e9 o caso de um casal internacional que se mudou para os EUA ap\u00f3s o casamento. Na verdade, n\u00e3o \u00e9 raro. Portanto, n\u00e3o deixe de memorizar essa express\u00e3o!<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><b>Parentela pr\u00f3xima e distante<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em portugu\u00eas, tamb\u00e9m existem as express\u00f5es \u201cparentela pr\u00f3xima\u201d e \u201cparentela distante\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Podemos expressar esses t\u00edtulos em ingl\u00eas das seguintes formas:<\/span><\/p>\n<p><b>\u30fbClose relative (parente pr\u00f3ximo)<\/b><\/p>\n<p><b>\u30fbDistant relative (parente distante)<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Embora n\u00e3o usemos estes termos com tanta frequ\u00eancia, \u00e9 bom conhec\u00ea-los para aumentar seu leque de express\u00f5es em ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A prop\u00f3sito, mesmo que n\u00e3o haja uma defini\u00e7\u00e3o clara para ambos, \u201cparente pr\u00f3ximo\u201d geralmente refere-se a parentes at\u00e9 quarto grau e \u201cparente distante\u201d acima disso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se quiser, tamb\u00e9m pode guardar essa informa\u00e7\u00e3o como uma \u201ccuriosidade\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Como \u00e9 a conviv\u00eancia com \u201cparentes estrangeiros\u201d?<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Falando em \u201crela\u00e7\u00f5es de parentesco\u201d no exterior, voc\u00ea tem a impress\u00e3o de que s\u00e3o \u201cespecialmente pr\u00f3ximos\u201d?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Muitas pessoas associtam logo \u00e0 ideia de que parentes estrangeiros sempre festejam juntos anivers\u00e1rios e Natal, ou frequentemente saem juntos para almo\u00e7ar ou jantar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na verdade, segundo os brasileiros que vivem nos EUA, os americanos d\u00e3o ainda mais import\u00e2ncia \u00e0s \u201crela\u00e7\u00f5es de parentesco\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Eles t\u00eam o h\u00e1bito de dar\u00a0 <strong><span style=\"font-size: 36px; color: #09e03f;\">\u201ccart\u00f5es comemorativos\u201d<\/span><\/strong>\u00a0 tanto em datas especiais quanto em dias comuns.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora cada caso seja diferente, podemos afirmar que as rela\u00e7\u00f5es entre parentes no exterior s\u00e3o de fato mais frequentes que as nossas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso,no Brasil, durante \u201creuni\u00f5es de parentes\u201d no Festival Qingming e Ano Novo, geralmente s\u00e3o as mulheres que organizam e cozinham.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora esse h\u00e1bito esteja mudando, ainda \u00e9 mais comum que no exterior.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No exterior, a divis\u00e3o de tarefas dom\u00e9sticas entre casais ou pais \u00e9 muito mais igualit\u00e1ria em compara\u00e7\u00e3o no Brasil. Em \u201creuni\u00f5es de parentes\u201d estrangeiras, vemos muitas vezes mulheres relaxando enquanto os homens cuidam da prepara\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essa \u00e9 a maior diferen\u00e7a no conv\u00edvio com \u201cparentes\u201d entre brasileiros e outros pa\u00edses. Pode-se dizer que <strong>o conceito de \u201cigualdade de g\u00eanero\u201d est\u00e1 profundamente enraizado na mentalidade dos estrangeiros.<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, ainda h\u00e1 pessoas de alguns pa\u00edses que n\u00e3o se sentem \u00e0 vontade para manter uma rela\u00e7\u00e3o pr\u00f3xima com familiares do c\u00f4njuge ou outros parentes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora isso varie de pessoa para pessoa, \u00e9 certo que cada pa\u00eds tem vis\u00f5es e ideias diferentes sobre \u201crela\u00e7\u00f5es de parentesco\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Dicas para construir bons relacionamentos com \u201cparentes\u201d em ingl\u00eas: \u201ccompet\u00eancia lingu\u00edstica\u201d e \u201cproatividade\u201d<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Neste artigo, apresentamos as formas de se expressar sobre <span style=\"font-size: 36px;\"><strong>\u201cparentes\u201d<\/strong><\/span> em ingl\u00eas. Ser\u00e1 que esse vocabul\u00e1rio e exemplos foram \u00fateis para voc\u00ea?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, sobre o b\u00f4nus das situa\u00e7\u00f5es reais de conv\u00edvio entre \u201cestrangeiros e parentes\u201d, talvez te tenha surpreendido!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ao ter \u201cparentes estrangeiros\u201d e querer estreitar os la\u00e7os, o mais indispens\u00e1vel com certeza \u00e9<\/span><\/p>\n<p><b><span style=\"font-size: 36px;\">\u201ccompet\u00eancia lingu\u00edstica\u201d = \u201chabilidade em ingl\u00eas\u201d<\/span>.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea n\u00e3o conseguir se comunicar bem, ser\u00e1 dif\u00edcil conhecer o outro e tamb\u00e9m dif\u00edcil que o outro te entenda.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nesses casos, experimente as aulas de ingl\u00eas online do \u201cNative Camp\u201d, com as quais voc\u00ea pode aprender ingl\u00eas a qualquer hora e em qualquer lugar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00ea pode fazer as aulas facilmente pelo computador, tablet ou smartphone. At\u00e9 caf\u00e9s e escrit\u00f3rios podem virar sua sala de aula de ingl\u00eas!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, esses cursos est\u00e3o dispon\u00edveis 24 horas por dia, 365 dias por ano, sem limite de quantidade de aulas, para que voc\u00ea possa aproveitar ao m\u00e1ximo!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Depois de aprimorar de fato sua \u201chabilidade em ingl\u00eas\u201d, \u00e9 hora de agir! Use o que aprendeu na comunica\u00e7\u00e3o real com seus parentes!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea tamb\u00e9m acha que os\u00a0 \u00a0\u201ct\u00edtulos de parentesco\u201d\u00a0\u00a0 em portugu\u00eas s\u00e3o um conjunto complicado e confuso? Por exemplo, t\u00edtulos como \u201csobrinho\u201d e \u201csobrinho-neto\u201d, se n\u00e3o estiverem relacionados ao seu cotidiano, dificilmente ter\u00e3o oportunidade de aparecer. Mas h\u00e1 pessoas que simplesmente se esquecem de como dizer devido \u00e0 grande variedade de tipos! Ent\u00e3o, se pedirmos que voc\u00ea expresse \u201ct\u00edtulos de parentesco\u201d em ingl\u00eas, provavelmente muitos achar\u00e3o um pouco dif\u00edcil! J\u00e1 que \u00e9 melhor manter uma boa rela\u00e7\u00e3o com os parentes, isso \u00e9 ainda mais importante em conex\u00f5es familiares internacionais. Se voc\u00ea pensa \u201cPorque a pessoa com quem vou me casar \u00e9 brasileira&#8230;\u201d\u00a0\u00a0 \u201cMeus parentes s\u00e3o todos brasileiros, n\u00e3o preciso aprender isso&#8230;\u201d &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/14131\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":14504,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=14131","footnotes":""},"categories":[128,127,131],"tags":[],"class_list":["post-14131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business","category-travel","category-hint","pt-BR"],"aioseo_notices":[],"views":282,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/14131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=14131"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/14131\/revisions"}],"predecessor-version":[{"id":14133,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/14131\/revisions\/14133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/14504"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=14131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=14131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=14131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}