{"id":13822,"date":"2025-12-13T09:00:18","date_gmt":"2025-12-13T12:00:18","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=13822"},"modified":"2025-12-10T03:43:57","modified_gmt":"2025-12-10T06:43:57","slug":"como-se-diz-agua-viva-em-ingles-apresentando-alguns-fatos-curiosos-sobre-as-aguas-vivas","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/13822\/","title":{"rendered":"Como se diz \u201c\u00e1gua-viva\u201d em ingl\u00eas? Apresentando alguns fatos curiosos sobre as \u00e1guas-vivas!"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Voc\u00eas sabem como se diz<strong><span style=\"color: #0000ff; font-size: 28px;\">\u00a0 \u00a0&#8220;\u00e1gua-viva&#8221; <\/span><\/strong>em ingl\u00eas?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O nome em ingl\u00eas de \u00e1gua-viva \u00e9\u00a0 <span style=\"color: #cb04cf;\"><strong>jellyfish<\/strong><\/span>, que literalmente significa &#8220;peixe de gelatina&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esse nome possivelmente vem do formato da \u00e1gua-viva, seu corpo el\u00e1stico com apar\u00eancia de gelatina e a maneira como nada. As \u00e1gua-viva s\u00e3o populares por terem formas e cores muito distintas e porque existem muitos tipos diferentes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Muitos aqu\u00e1rios criam \u00e1gua-viva, e h\u00e1 entusiastas pelo mundo inteiro \u2013 at\u00e9 mesmo pessoas que os criam em casa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, neste artigo, ao apresentar o \u00e1gua-viva, tamb\u00e9m abordaremos algumas palavras, express\u00f5es e frases pouco familiares do cotidiano.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vamos aproveitar a \u00e1gua-viva como uma oportunidade para expandir nosso vocabul\u00e1rio de ingl\u00eas e melhorar nossa conversa\u00e7\u00e3o!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Qual \u00e9 a palavra em ingl\u00eas para \u00e1gua-viva?<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Para muitas pessoas, \u00e1gua-viva \u00e9 uma daquelas palavras em ingl\u00eas &#8220;que voc\u00ea j\u00e1 ouviu falar, mas n\u00e3o consegue lembrar de imediato&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como citado no come\u00e7o, o nome em ingl\u00eas \u00e9 <strong><span style=\"color: #cb04cf;\">&#8220;jellyfish&#8221;<\/span><\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Traduzindo ao p\u00e9 da letra, significa <strong>&#8220;peixe de gelatina&#8221;<\/strong>; parece macio, fofo e el\u00e1stico, uma descri\u00e7\u00e3o perfeita para \u00e1gua-viva.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, se procurarmos <span style=\"font-weight: 400;\">jellyfish<\/span> no dicion\u00e1rio, veremos que, al\u00e9m de \u00e1gua-viva, tamb\u00e9m pode significar <strong><span style=\"color: #00ccff;\">&#8220;pessoa indecisa&#8221;, &#8220;covarde&#8221;<\/span><\/strong> e outras ideias semelhantes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Acredita-se que isso tamb\u00e9m esteja <strong>relacionado ao jeito balan\u00e7ante do nado do \u00e1gua-viva<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vejamos tamb\u00e9m algumas formas de usar &#8220;jellyfish&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O \u00e1gua-viva \u00e9 um ser perigoso; dependendo da esp\u00e9cie, pode ser venenoso, portanto at\u00e9 adultos devem tomar cuidado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se formos picados por um \u00e1gua-viva, podemos usar a seguinte frase!<\/span><\/p>\n<h5><b>\u30fbI was stung by a jellyfish.<\/b><br \/>\n<span style=\"font-weight: 400;\">(Fui picado(a) por uma \u00e1gua-viva.)<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">&#8220;stung&#8221; \u00e9 o passado e partic\u00edpio de &#8220;sting&#8221;, que significa picar, espetar com ferr\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;by&#8221; \u00e9 uma palavra bem \u00fatil, podendo indicar v\u00e1rias situa\u00e7\u00f5es, como nos exemplos abaixo:<\/span><\/p>\n<p><b>I was stung by a bee.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">(Fui picado(a) por uma abelha.)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Veja a seguir algumas frases em ingl\u00eas que descrevem caracter\u00edsticas da \u00e1gua-viva!<\/span><\/p>\n<h5><b>\u30fbJellyfish is a kind of plankton.<\/b><br \/>\n<span style=\"font-weight: 400;\">(A \u00e1gua-viva \u00e9 um tipo de pl\u00e2ncton.)<\/span><br \/>\n<b>\u30fbJellyfish are about 95 to 98 percent water.<\/b><br \/>\n<span style=\"font-weight: 400;\">(A \u00e1gua-viva \u00e9 composta por cerca de 95 a 98% de \u00e1gua.)<\/span><br \/>\n<b>\u30fbMost Jellyfish are bell-shaped and transparent.<\/b><br \/>\n<span style=\"font-weight: 400;\">(A maioria das \u00e1gua-viva t\u00eam formato de sino e \u00e9 transparente.)<\/span><br \/>\n<b>\u30fb Jellyfish don&#8217;t have bones, and lack organs such as a brain or a heart.<\/b><br \/>\n<span style=\"font-weight: 400;\">(A \u00e1gua-viva n\u00e3o tem ossos, nem \u00f3rg\u00e3os como c\u00e9rebro ou cora\u00e7\u00e3o.)<\/span><br \/>\n<b>\u30fbBut, they have a mouth and tentacles.<\/b><br \/>\n<span style=\"font-weight: 400;\">(Mas, elas t\u00eam boca e tent\u00e1culos)<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea consegue explicar todas essas informa\u00e7\u00f5es sobre \u00e1gua-viva em ingl\u00eas, j\u00e1 pode ser considerado um especialista em \u00e1gua-viva!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>\u00e1gua-viva em Taiwan<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Em Taiwan h\u00e1 muitos tipos diferentes de \u00e1gua-viva, como a famosa &#8221; Lua do Mar&#8221;. Outras incluem a \u00e1gua-viva de tent\u00e1culos curtos, a \u00e1gua-viva azul-portuguesa (caravela-portuguesa) e a caixa d&#8217;\u00e1gua (caravela-portuguesa). As duas primeiras t\u00eam venenos mais fracos, causando apenas irrita\u00e7\u00e3o ou vermelhid\u00e3o na pele; por\u00e9m, a \u00e1gua-viva azul-portuguesa e a caixa d&#8217;\u00e1gua t\u00eam veneno forte, podendo causar dor prolongada por horas e at\u00e9 risco de morte.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Saiba mais sobre \u00e1gua-viva!<\/strong><\/h2>\n<h3><strong>Muitos tipos de \u00e1gua-viva<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Como sabemos, existem muitos tipos de \u00e1gua-viva, variando em formato, cor e tamanho.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando vemos \u00e1gua-vivaem aqu\u00e1rios, geralmente ficamos fascinados pelo formato disc\u00f3ide e pelos tent\u00e1culos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vamos aproveitar para conhecer os tipos mais comuns de \u00e1gua-viva em Taiwan e comparar seus nomes em ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Uma das mais comuns \u00e9 a Lua do Mar \u00e1gua-viva.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ela aparece com frequ\u00eancia no canal de Tainan e em v\u00e1rios lugares ao redor do mundo. Seu veneno \u00e9 fraco, ent\u00e3o mesmo que algu\u00e9m seja picado, o desconforto ou ferimento n\u00e3o \u00e9 grave. No entanto, pessoas sens\u00edveis ou crian\u00e7as devem ter cuidado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O nome cient\u00edfico da Lua do Mar\u00a0\u00e1gua-viva \u00e9 <span style=\"font-weight: 400;\">&#8220;Aurelia aurita&#8221;<\/span>, <strong>e por se parecer com a lua, muitas vezes \u00e9 chamada de\u00a0 <\/strong><strong>&#8220;moon jellyfish&#8221;.<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Outro tipo, uma<span style=\"font-size: 36px;\"><strong> \u00e1gua-viva altamente venenosa<\/strong><\/span> chamada caravela-portuguesa, \u00e9 conhecida pela sua toxicidade e pela dor que causa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em ingl\u00eas, \u00e9 chamada de <b>&#8220;Portuguese man o&#8217; war&#8221;<\/b>, nome inspirado nas caravelas de guerra portuguesas da era dos grandes navegadores.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Trata-se de um nome ingl\u00eas muito peculiar; o fato de ser nomeada em homenagem a um navio de guerra tamb\u00e9m remete ao perigo de suas picadas. Sua principal caracter\u00edstica \u00e9 um &#8220;bal\u00e3o&#8221; que permite flutuar na superf\u00edcie. Mesmo que a veja na praia, n\u00e3o toque de jeito nenhum! Pode causar sensa\u00e7\u00e3o de queimadura, dores musculares, dificuldade para respirar e outros sintomas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Habitats das \u00e1gua-viva em Taiwan<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #0000ff;\"><strong>J\u00e1 foram encontradas \u00e1gua-viva em Tainan, Taitung e em v\u00e1rias partes da costa de Taiwan.<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na verdade, \u00e9 bom estar atento a qualquer tipo de \u00e1gua-viva . Se voc\u00ea n\u00e3o sabe identificar a esp\u00e9cie, consulte imagens e informa\u00e7\u00f5es em sites especializados. Caso toque sem querer numa \u00e1gua-viva venenosa, pode ser potencialmente fatal.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>\u00e1gua-viva nos oceanos do mundo? Em que pa\u00edses se come <span style=\"font-weight: 400; font-size: 24px;\">\u00e1gua-viva<\/span>?<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #0000ff;\">As \u00e1gua-viva vivem em \u00e1guas doces e salgadas ao redor do mundo.<\/span><\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Dependendo do tipo, variam em formato, cor, tamanho e toxicidade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Diversos aqu\u00e1rios exibem \u00e1gua-viva, o que nos permite comparar tipos, habitats e caracter\u00edsticas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apesar de estarem espalhadas pelo mundo, poucas regi\u00f5es as consomem como alimento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O mais famoso s\u00e3o os\u00a0 <span style=\"font-size: 36px;\">pratos Chineses<\/span>!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Eles utilizam \u00e1gua-viva comuns do Jap\u00e3o, como a \u00e1gua-viva de Echizen e a \u00e1gua-viva comest\u00edvel, que, ap\u00f3s secas e salgadas, s\u00e3o hidratadas e servidas em saladas chinesas frias ou pratos avinagrados com \u00f3timo resultado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em outros pa\u00edses, a \u00e1gua-viva comest\u00edvel \u00e9 chamada de <b>&#8220;edible jellyfish&#8221;,<\/b> principalmente utilizada na culin\u00e1ria asi\u00e1tica. &#8220;edible&#8221; significa <strong>&#8220;comest\u00edvel&#8221;<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Muitos professores do Native Camp tamb\u00e9m s\u00e3o de pa\u00edses asi\u00e1ticos \u2013 experimente conversar com eles sobre o tema de comer \u00e1gua-viva, voc\u00ea pode ter surpresas!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Uma subst\u00e2ncia extra\u00edda da \u00e1gua-viva ganhou um Pr\u00eamio Nobel?<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Na costa do Jap\u00e3o tamb\u00e9m \u00e9 comum encontrar \u00e1gua-viva, e curiosamente existe aqui um importante motivo para um japon\u00eas ter recebido o Pr\u00eamio Nobel.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em 2008, o Dr. Osamu Shimomura recebeu o Nobel de Qu\u00edmica pelo\u00a0 <strong>prote\u00edna fluorescente verde<\/strong> extra\u00edda da \u00e1gua-viva.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essa prote\u00edna permite que tumores cancerosos sejam vistos enquanto crescem, facilitando sua remo\u00e7\u00e3o completa durante a cirurgia e tornando mais precisos os exames de acompanhamento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O nome cient\u00edfico da \u00e1gua-viva respons\u00e1vel por essa descoberta \u00e9 <span style=\"font-weight: 400;\">&#8220;Aequorea victoria&#8221;<\/span>, \u00e0s vezes chamada de <span style=\"font-weight: 400;\">&#8220;crystal jelly&#8221;<\/span>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, o nome da prote\u00edna descoberta pelo Dr. Shimomura em ingl\u00eas \u00e9 &#8220;green Fluorescent Protein\/ GFP&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;fluorescent&#8221; significa &#8220;fluorescente&#8221;, <span style=\"font-weight: 400;\">e &#8220;a fluorescent lamp&#8221; \u00e9 &#8220;l\u00e2mpada fluorescente&#8221;.<\/span> <span style=\"font-weight: 400;\">&#8220;protein&#8221; (prote\u00edna) tamb\u00e9m \u00e9 um componente comum em suplementos de muscula\u00e7\u00e3o no Jap\u00e3o.<\/span><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Parece que os componentes da \u00e1gua-viva tamb\u00e9m s\u00e3o muito ben\u00e9ficos para os seres humanos!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Vamos aproveitar uma palavra em ingl\u00eas para aprender mais curiosidades!<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Desta vez apresentamos o vocabul\u00e1rio em ingl\u00eas de \u00e1gua-viva e algumas curiosidades \u2013 espero que tenha sido \u00fatil para voc\u00ea!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se ficou interessado em \u00e1gua-viva ap\u00f3s ler este artigo, por que n\u00e3o visitar um aqu\u00e1rio para observ\u00e1-los ao vivo?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para quem quer\u00a0 <span style=\"font-size: 36px;\">melhorar o n\u00edvel de ingl\u00eas<\/span>, tamb\u00e9m recomendamos as aulas de conversa\u00e7\u00e3o online do Native Camp!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Temos materiais originais, n\u00e3o s\u00f3 para quem deseja estudar no exterior ou treinar a fala, mas tamb\u00e9m para iniciantes!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m de materiais did\u00e1ticos, tamb\u00e9m temos aulas de conversa\u00e7\u00e3o livre, onde voc\u00ea pode escolher o tema de acordo com seu interesse! Tamb\u00e9m oferecemos 7 dias de teste gratuito \u2013 venha experimentar uma aula!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00eas sabem como se diz\u00a0 \u00a0&#8220;\u00e1gua-viva&#8221; em ingl\u00eas? O nome em ingl\u00eas de \u00e1gua-viva \u00e9\u00a0 jellyfish, que literalmente significa &#8220;peixe de gelatina&#8221;. Esse nome possivelmente vem do formato da \u00e1gua-viva, seu corpo el\u00e1stico com apar\u00eancia de gelatina e a maneira como nada. As \u00e1gua-viva s\u00e3o populares por terem formas e cores muito distintas e porque existem muitos tipos diferentes. Muitos aqu\u00e1rios criam \u00e1gua-viva, e h\u00e1 entusiastas pelo mundo inteiro \u2013 at\u00e9 mesmo pessoas que os criam em casa. Por isso, neste artigo, ao apresentar o \u00e1gua-viva, tamb\u00e9m abordaremos algumas palavras, express\u00f5es e frases pouco familiares do cotidiano. Vamos aproveitar a \u00e1gua-viva como uma oportunidade para expandir nosso vocabul\u00e1rio de ingl\u00eas &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/13822\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":13861,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=13822","footnotes":""},"categories":[126,125,133],"tags":[],"class_list":["post-13822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-daily","category-practice","category-preparation-for-studying-abroad","pt-BR"],"aioseo_notices":[],"views":914,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=13822"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13822\/revisions"}],"predecessor-version":[{"id":13824,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13822\/revisions\/13824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/13861"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=13822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=13822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=13822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}