{"id":13805,"date":"2025-12-10T09:00:37","date_gmt":"2025-12-10T12:00:37","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=13805"},"modified":"2025-12-08T03:26:22","modified_gmt":"2025-12-08T06:26:22","slug":"como-se-diz-voce-poderia-se-afastar-um-pouco-em-ingles","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/13805\/","title":{"rendered":"Como se diz \u201cVoc\u00ea poderia se afastar um pouco?\u201d em ingl\u00eas?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Atualmente moro em Londres, e pela minha experi\u00eancia, n\u00e3o importa o qu\u00e3o movimentada seja a esta\u00e7\u00e3o, as pessoas nunca se esbarram umas nas outras.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, sempre que h\u00e1 pessoas idosas, com mobilidade reduzida ou acompanhadas de crian\u00e7as, seja no trem ou no \u00f4nibus, algu\u00e9m imediatamente cede o assento, sem exce\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No transporte, os passageiros tamb\u00e9m n\u00e3o dormem. E se, por acaso, os olhares se cruzam, ainda costumam trocar sorrisos educados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nos trens movimentados de Londres, muitas vezes n\u00e3o h\u00e1 assentos dispon\u00edveis e \u00e9 preciso ficar em p\u00e9. Nessa hora, se voc\u00ea perceber uma pequena abertura entre dois assentos, pode ser tentador pensar: \u201cSe a pessoa ao lado se apertar s\u00f3 um pouco, talvez eu consiga sentar!\u201d Na verdade, basta pedir educadamente, e geralmente \u00e9 poss\u00edvel. Mas, voc\u00ea sabe como expressar isso em ingl\u00eas?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este artigo tem como foco o tema <span style=\"font-size: 32px;\"><span style=\"color: #c51dd1;\"><strong>\u201cpedir para que algu\u00e9m ceda espa\u00e7o\u201d<\/strong><\/span>.<\/span> Se voc\u00ea aprender essas express\u00f5es, poder\u00e1 us\u00e1-las em viagens, interc\u00e2mbios ou at\u00e9 durante miss\u00f5es de trabalho no exterior. No final do texto, ainda compartilho outras express\u00f5es relacionadas a \u201capertar\u201d ou \u201cencaixar\u201d. N\u00e3o perca!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Como pedir em ingl\u00eas para \u201cceder um espa\u00e7o\u201d?<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Pedir para algu\u00e9m<strong> \u201cceder espa\u00e7o\u201d<\/strong> significa encontrar um lugar dispon\u00edvel em um espa\u00e7o limitado. A situa\u00e7\u00e3o mais comum \u00e9 em meios de transporte, mas pode acontecer em qualquer lugar cheio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O ideal \u00e9 encontrar um assento livre logo de cara, mas caso n\u00e3o encontre, voc\u00ea sabe como pedir em ingl\u00eas para algu\u00e9m abrir espa\u00e7o? Seguem algumas express\u00f5es \u00fateis. Antes disso, vejamos algumas formas em ingl\u00eas de pedir para<strong> \u201cse apertar um pouco\u201d.<\/strong><\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Listei abaixo quatro express\u00f5es com conceitos parecidos em ingl\u00eas.<\/span><\/p>\n<h6><span style=\"font-weight: 400;\"> move over<\/span><br \/>\n<span style=\"font-weight: 400;\"> slide over<\/span><br \/>\n<span style=\"font-weight: 400;\"> squeeze oneself in<\/span><br \/>\n<span style=\"font-weight: 400;\"> scoot over<\/span><\/h6>\n<p>&nbsp;<\/p>\n<h3><b>move over<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quando voc\u00ea quer pedir para algu\u00e9m \u201csentar mais para o lado\u201d, essa \u00e9 a express\u00e3o mais comum e aceita.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Muitos j\u00e1 conhecem o verbo move, que significa \u201cmover\u201d. Pode ser usado para mudan\u00e7as de casa, troca de emprego, at\u00e9 para outras situa\u00e7\u00f5es diversas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como queremos pedir para o vizinho de assento mover ligeiramente, faz todo sentido usar move\u00a0 \u00e9 f\u00e1cil de lembrar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vamos agora para o over, que tamb\u00e9m aparece nas outras express\u00f5es deste artigo. Basicamente, indica atravessar uma refer\u00eancia com um \u201carco\u201d ou cobrir algo. Imagine que todos est\u00e3o sentados, e voc\u00ea pede para algu\u00e9m sair um pouco, como se levantasse o corpo e mudasse para o lado\u00a0 assim fica f\u00e1cil visualizar porque dizemos move over.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>slide over<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Agora, slide over. Usu\u00e1rios de produtos da Apple talvez conhe\u00e7am esse termo como uma fun\u00e7\u00e3o do iPad, permitindo abrir m\u00faltiplos aplicativos e alternar deslizando na tela.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas tamb\u00e9m pode ser uma forma suave de pedir para algu\u00e9m ceder espa\u00e7o; \u00e9 muito comum ouvir estrangeiros usando assim.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>squeeze oneself in<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Squeeze significa \u201capertar\u201d; espremer um lim\u00e3o em ingl\u00eas \u00e9 squeeze a lemon.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tamb\u00e9m pode significar <strong>\u201capertar-se em um lugar pequeno\u201d<\/strong> ou <strong>\u201carranjar espa\u00e7o para algu\u00e9m\u201d;<\/strong> claro, serve perfeitamente para o tema do artigo: \u201capertar-se para conseguir um assento\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A palavra squeeze expressa bem o aperto no espa\u00e7o, ideal para situa\u00e7\u00f5es de lota\u00e7\u00e3o.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>scoot over<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Scoot significa \u201cdeslizar rapidamente\u201d. Voc\u00ea talvez j\u00e1 tenha visto scooter, que significa patinete ou lambreta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">S\u00f3 de imaginar adolescentes acelerando pelos corredores j\u00e1 causa certo receio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com over, scoot pode ser usado para \u201cceder espa\u00e7o\u201d, especialmente nos Estados Unidos. Se voc\u00ea estuda ingl\u00eas americano, essa express\u00e3o \u00e9 importante.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Formas de pedir para algu\u00e9m se acomodar<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A maioria dos cursos de ingl\u00eas para viagens foca em como pedir informa\u00e7\u00f5es ou comprar bilhetes, mas pedir para algu\u00e9m ceder espa\u00e7o tamb\u00e9m \u00e9 importante. Afinal, em qualquer lugar lotado, \u00e9 preciso garantir seu pr\u00f3prio espa\u00e7o.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">At\u00e9 mesmo durante um jantar com amigos, pode surgir a necessidade de pedir para \u201cabrir um lugar\u201d. Portanto, vale a pena aprender essas express\u00f5es.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ao falar em \u201cpedir um espa\u00e7o para sentar\u201d, organizei as seguintes express\u00f5es:<\/span><\/p>\n<h6><span style=\"font-weight: 400;\"> move over<\/span><br \/>\n<span style=\"font-weight: 400;\"> slide over<\/span><br \/>\n<span style=\"font-weight: 400;\"> squeeze oneself in<\/span><br \/>\n<span style=\"font-weight: 400;\"> scoot over<\/span><\/h6>\n<p><span style=\"font-weight: 400;\">Quando precisar que algu\u00e9m se mova, use as frases acima nas suas senten\u00e7as.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas como pedir educadamente em ingl\u00eas? Veja exemplos abaixo:<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Usando Can you please ou Could you please para pedidos educados<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Muitos j\u00e1 aprenderam esse tipo de pedido educado: comece com<strong> \u201cCan you please\u201d<\/strong> ou <strong>\u201cCould you please\u201d<\/strong>, e depois acrescente o verbo apresentado neste artigo, como move over.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, falando com estranhos, para evitar soar abrupto, \u00e9 melhor come\u00e7ar com \u201cExcuse me\u201d.<\/span><\/p>\n<h5><b>Excuse me. Can you please move over to your left?<\/b><br \/>\n<span style=\"font-weight: 400;\">Com licen\u00e7a, voc\u00ea pode se mover um pouco para a esquerda?<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Excuse me. Can you please slide over to your right?<\/b><br \/>\n<span style=\"font-weight: 400;\">Com licen\u00e7a, pode chegar um pouco para a direita?<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Excuse me. Can you please move over so my mother can sit?<\/b><br \/>\n<span style=\"font-weight: 400;\">Com licen\u00e7a, voc\u00ea pode se mover um pouco para que minha m\u00e3e possa sentar?<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Como visto nos exemplos acima, \u00e9 poss\u00edvel ser claro usando to your left (para a esquerda) ou to your right (para a direita) para pedir que algu\u00e9m se mova em determinada dire\u00e7\u00e3o. Ou simplesmente<strong> \u201cExcuse me. Can you please move over?\u201d<\/strong> j\u00e1 funciona.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se trocar Can por Could, a frase soa ainda mais educada. Mas, para passageiros desconhecidos no transporte, Can j\u00e1 \u00e9 suficiente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando se viaja com pessoas mais velhas, \u00e9 natural evitar situa\u00e7\u00f5es em que fiquem de p\u00e9 por muito tempo. No entanto, chamar algu\u00e9m para ceder o assento pode ser constrangedor, ent\u00e3o pelo menos tente pedir um espa\u00e7o. \u00c0s vezes, pessoas gentis at\u00e9 se antecipam e perguntam aos outros: Can you move over for her.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essas situa\u00e7\u00f5es n\u00e3o se limitam ao transporte. Por exemplo, num jantar com amigos, algu\u00e9m que chega depois pode pedir para os demais \u201capertarem para abrir um espa\u00e7o\u201d. Essas frases tamb\u00e9m s\u00e3o \u00fateis nesses momentos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Express\u00e3o: squeeze oneself in<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m das tr\u00eas express\u00f5es com over, temos a squeeze oneself in, que \u00e9 um pouco diferente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Squeeze oneself in soa mais invasivo, como se a pessoa soubesse que est\u00e1 tudo apertado, mas mesmo assim queira entrar. A maior diferen\u00e7a \u00e9 o sujeito da frase: aqui, quem quer sentar \u00e9 o pr\u00f3prio sujeito, n\u00e3o quem j\u00e1 est\u00e1 sentado.<\/span><\/p>\n<h5><b>Can I squeeze myself in?<\/b><br \/>\n<span style=\"font-weight: 400;\">Posso me apertar a\u00ed?<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Ao dizer isso, mostra-se que, mesmo sabendo que est\u00e1 apertado, ainda assim se pede educadamente permiss\u00e3o aos que est\u00e3o ao redor.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essa express\u00e3o \u00e9 pr\u00e1tica especialmente para bancos longos ou bancos compartilhados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, n\u00e3o serve apenas para assentos: ao entrar em uma cabine cheia, elevador ou at\u00e9 na hora de \u201capertar\u201d em uma foto de grupo, pode-se usar esta frase.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Como pedir para algu\u00e9m mover para frente ou para tr\u00e1s<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 vimos express\u00f5es para pedir que algu\u00e9m se mova para o lado; agora, vejamos para frente ou para tr\u00e1s.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Antes dos exemplos, vamos revisar as palavras relacionadas em ingl\u00eas:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para frente: \u201cforward\u201d<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Para tr\u00e1s: \u201cbackward\u201d<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Pedir para algu\u00e9m ir para frente<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Ao ver forward, muitos pensam logo em look forward to, que significa \u201cesperar com expectativa\u201d. Mas forward tamb\u00e9m indica movimento no espa\u00e7o ou tempo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, ao esperar numa fila para entrar num restaurante ou comprar um lan\u00e7amento eletr\u00f4nico, se as pessoas da frente n\u00e3o avan\u00e7am, pode-se usar as frases a seguir para pedir movimento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tamb\u00e9m funciona em eventos ao ar livre, se desejar que as pessoas \u00e0 frente avancem um pouco.<\/span><\/p>\n<h5><b>Can you please move forward?<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea pode avan\u00e7ar um pouco, por favor?<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Can you please shift a little forward?<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea pode chegar um pouco mais para frente?<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Pedir para algu\u00e9m recuar<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O oposto de forward \u00e9 backward. Mas na linguagem cotidiana, normalmente se usa back, mais simples e coloquial.<\/span><\/p>\n<h5><b>Can you please move back?<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea pode recuar um pouco, por favor?<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Can you please scoot back a little as I have no space in front of me?<\/b><br \/>\n<span style=\"font-weight: 400;\">Pode recuar um pouco? N\u00e3o tenho espa\u00e7o \u00e0 minha frente.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Outras express\u00f5es em ingl\u00eas sobre \u201capertar\u201d<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Por fim, compartilho algumas express\u00f5es em ingl\u00eas relacionadas a \u201capertar\u201d ou \u201cencaixar\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Colocar algo na mochila<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quer seja para organizar itens antes de sair ou arrumar as malas antes da viagem, use os verbos \u201cput\u201d ou \u201cpack\u201d.<\/span><\/p>\n<h5><b>She put\/packed her passport in her small handbag.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ela colocou\/guardou o passaporte em sua bolsa pequena.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>I have to pack my suitcase tonight.<\/b><br \/>\n<span style=\"font-weight: 400;\">Preciso arrumar minha mala esta noite.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Pack tem um ant\u00f4nimo, unpack, que significa desfazer a mala ou abrir a bagagem. Ao chegar ao hotel, \u00e9 a primeira coisa a fazer. \u00c9 bom memorizar as duas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Apertar no v\u00e3o<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A a\u00e7\u00e3o de encaixar algo em um v\u00e3o \u00e9 familiar a todos. Na hora de arrumar as malas, queremos colocar o m\u00e1ximo poss\u00edvel ou espremer mais um livro na estante; afinal, sempre queremos aproveitar bem o espa\u00e7o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esse ato de encher um espa\u00e7o ou recipiente usa-se \u201cfill\u201d. Fill significa \u201cencher\u201d ou \u201cpreencher\u201d. At\u00e9 no dentista, ao preencher uma c\u00e1rie, usa-se fill.<\/span><\/p>\n<h5><b>Gaps in the wall were filled with some newspapers.<\/b><br \/>\n<span style=\"font-weight: 400;\">Os v\u00e3os da parede foram preenchidos com alguns jornais.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Reduzir espa\u00e7o entre linhas<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Ao digitar\/formatar um documento, se falta espa\u00e7o na p\u00e1gina, normalmente reduzimos o espa\u00e7amento entre linhas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ou seja, encurtamos o espa\u00e7o entre linhas; para isso, usamos \u201creduce\u201d, que significa reduzir\/diminuir.<\/span><\/p>\n<h5><b>He had to reduce the space between the lines on his document.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ele precisou reduzir o espa\u00e7o entre as linhas do documento.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Resumo<\/b><\/h2>\n<p>&nbsp;<\/p>\n<h6><span style=\"font-weight: 400;\"> move over<\/span><br \/>\n<span style=\"font-weight: 400;\"> slide over<\/span><br \/>\n<span style=\"font-weight: 400;\"> squeeze oneself in<\/span><br \/>\n<span style=\"font-weight: 400;\"> scoot over<\/span><\/h6>\n<p><span style=\"font-weight: 400;\">Utilizando Can you please ou Could you please com as express\u00f5es acima, voc\u00ea pode pedir espa\u00e7o de v\u00e1rias formas, como em portugu\u00eas:\u00a0 \u201cVoc\u00ea pode sentar um pouco mais para o lado?\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pela minha experi\u00eancia, normalmente estrangeiros respondem com um<strong> \u201csure\u201d<\/strong> ou j\u00e1 abrem espa\u00e7o imediatamente. N\u00e3o esque\u00e7a de agradecer com um sorriso e um <strong>\u201cThank you\u201d!<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atualmente moro em Londres, e pela minha experi\u00eancia, n\u00e3o importa o qu\u00e3o movimentada seja a esta\u00e7\u00e3o, as pessoas nunca se esbarram umas nas outras. Al\u00e9m disso, sempre que h\u00e1 pessoas idosas, com mobilidade reduzida ou acompanhadas de crian\u00e7as, seja no trem ou no \u00f4nibus, algu\u00e9m imediatamente cede o assento, sem exce\u00e7\u00e3o. No transporte, os passageiros tamb\u00e9m n\u00e3o dormem. E se, por acaso, os olhares se cruzam, ainda costumam trocar sorrisos educados. Nos trens movimentados de Londres, muitas vezes n\u00e3o h\u00e1 assentos dispon\u00edveis e \u00e9 preciso ficar em p\u00e9. Nessa hora, se voc\u00ea perceber uma pequena abertura entre dois assentos, pode ser tentador pensar: \u201cSe a pessoa ao lado se apertar &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/13805\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":13806,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=13805","footnotes":""},"categories":[128,127,131],"tags":[],"class_list":["post-13805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business","category-travel","category-hint","pt-BR"],"aioseo_notices":[],"views":191,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=13805"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13805\/revisions"}],"predecessor-version":[{"id":13807,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13805\/revisions\/13807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/13806"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=13805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=13805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=13805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}