{"id":13759,"date":"2025-12-12T09:00:19","date_gmt":"2025-12-12T12:00:19","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=13759"},"modified":"2025-12-10T03:36:58","modified_gmt":"2025-12-10T06:36:58","slug":"como-se-deve-expressar-dar-uma-festa-em-ingles","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/13759\/","title":{"rendered":"Como se deve expressar \u201cdar uma festa\u201d em ingl\u00eas?"},"content":{"rendered":"<p dir=\"ltr\">Os estrangeiros gostam muito de\u00a0 \u201cfestas\u201d.<\/p>\n<p dir=\"ltr\">Se voc\u00ea mora h\u00e1 muito tempo no exterior, provavelmente tamb\u00e9m recebe convites para festas com frequ\u00eancia!<\/p>\n<p dir=\"ltr\">E hoje em dia, n\u00e3o \u00e9 s\u00f3 no exterior: em Brasil, eventos internacionais, festas de Natal, confraterniza\u00e7\u00f5es empresariais, festas de solteiro e v\u00e1rios outros formatos de festas t\u00eam aumentado cada vez mais.<\/p>\n<p dir=\"ltr\">Quem sabe, talvez voc\u00ea tamb\u00e9m seja o organizador de uma festa da empresa ou de um evento de boas-vindas.<\/p>\n<p dir=\"ltr\">Mas, se voc\u00ea n\u00e3o tem confian\u00e7a na conversa em ingl\u00eas e por isso n\u00e3o consegue participar das festas organizadas por estrangeiros, podemos te dizer que, na verdade, basta conhecer algumas frases b\u00e1sicas em ingl\u00eas para dar facilmente o primeiro passo e participar de uma festa!<\/p>\n<p dir=\"ltr\">Como aprender ingl\u00eas n\u00e3o deve ser s\u00f3 teoria; voc\u00ea deve aproveitar o processo e experimentar bastante.<\/p>\n<p dir=\"ltr\">Portanto, vamos avan\u00e7ar com mais confian\u00e7a!<\/p>\n<p dir=\"ltr\">Neste artigo, vamos apresentar express\u00f5es em ingl\u00eas relacionadas a \u201corganizar uma festa\u201d.<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">Sobre \u201cfestas no exterior\u201d<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">No exterior, festas animadas s\u00e3o realizadas frequentemente. Para eles, n\u00e3o \u00e9 um evento exclusivo para jovens, mas uma forma bem comum de socializar.<\/p>\n<p dir=\"ltr\">Entre elas, vemos muitos tipos diferentes de festas.<\/p>\n<p dir=\"ltr\">Por exemplo, festas de anivers\u00e1rio,<\/p>\n<p dir=\"ltr\">eventos de boas-vindas e despedidas em empresas,<\/p>\n<p dir=\"ltr\">festas sazonais como Halloween, Natal,<\/p>\n<p dir=\"ltr\">comemora\u00e7\u00f5es entre fam\u00edlia e amigos pelo novo emprego ou mudan\u00e7a de casa,<\/p>\n<p dir=\"ltr\">al\u00e9m disso, festas de fim de ano ou festas de solteiro, entre tantas outras formas variadas de festa.<\/p>\n<p dir=\"ltr\">Al\u00e9m dessas festas mais comuns, algumas s\u00e3o menos frequentes em Brasil (mas t\u00eam sido introduzidas nos \u00faltimos anos).<\/p>\n<p dir=\"ltr\">Como cada pa\u00eds tem diferentes religi\u00f5es e culturas, ao pesquisarmos essas festas, descobrimos que elas s\u00e3o bem interessantes!<\/p>\n<p dir=\"ltr\">Por exemplo, quando o autor deste texto estava no Canad\u00e1, participou e presenciou alguns tipos de festas grandes:<\/p>\n<p dir=\"ltr\"><span style=\"text-decoration: underline;\"><strong>P\u00e1scoa<\/strong><\/span><\/p>\n<p dir=\"ltr\"><strong>P\u00e1scoa<\/strong> \u00e9 um dia para celebrar a ressurrei\u00e7\u00e3o de Jesus Cristo.<\/p>\n<p dir=\"ltr\">O mais famoso nesses dias s\u00e3o os \u201covos de P\u00e1scoa\u201d coloridos!<\/p>\n<p dir=\"ltr\"><strong><span style=\"text-decoration: underline;\">Dia de A\u00e7\u00e3o de Gra\u00e7as<\/span><\/strong><\/p>\n<p dir=\"ltr\"><strong>Dia de A\u00e7\u00e3o de Gra\u00e7as<\/strong> \u00e9 um grande feriado em pa\u00edses como Estados Unidos e Canad\u00e1.<\/p>\n<p dir=\"ltr\">O feriado teve origem na celebra\u00e7\u00e3o da primeira colheita bem-sucedida pelos imigrantes da Inglaterra. Normalmente, todos comemoram comendo \u201cperu assado\u201d na festa.<\/p>\n<p dir=\"ltr\"><span style=\"text-decoration: underline;\"><strong>Ch\u00e1 de Beb\u00ea<\/strong><\/span><\/p>\n<p dir=\"ltr\">O \u201cCh\u00e1 de Beb\u00ea\u201d \u00e9 realizado principalmente nos EUA, e \u00e9 uma celebra\u00e7\u00e3o para desejar um bom parto \u00e0 gestante.<\/p>\n<p dir=\"ltr\"><strong><span style=\"text-decoration: underline;\">Festa de Inaugura\u00e7\u00e3o de Casa<\/span><\/strong><\/p>\n<p dir=\"ltr\">A \u201cFesta de Inaugura\u00e7\u00e3o de Casa\u201d \u00e9 oferecida pelo dono da casa rec\u00e9m-mudado, para celebrar com todos no novo lar.<\/p>\n<p dir=\"ltr\">O objetivo da festa \u00e9 trazer boas energias \u00e0 casa nova com as b\u00ean\u00e7\u00e3os de todos.<\/p>\n<p dir=\"ltr\">Essas festas costumam ser bem descontra\u00eddas. Como o motivo para realiz\u00e1-las \u00e9 simples, os convidados participam naturalmente e o n\u00famero de festas organizadas s\u00f3 aumenta.<\/p>\n<p dir=\"ltr\">Especialmente as \u201cfestas em fam\u00edlia\u201d.<\/p>\n<p dir=\"ltr\">Durante a festa, familiares e amigos levam bebidas ou comidas preparadas em casa, como se todos estivessem juntos para um ch\u00e1 da tarde.<\/p>\n<p dir=\"ltr\">O autor, que agora mora no M\u00e9xico, nota que l\u00e1 tamb\u00e9m se realizam festas de fam\u00edlia com bastante frequ\u00eancia.<\/p>\n<p dir=\"ltr\">A \u201cfesta\u201d parece j\u00e1 fazer parte da vida cotidiana deles. E essas festas t\u00e3o frequentes me fazem at\u00e9 pensar \u201cser\u00e1 que n\u00e3o t\u00eam nada mais a fazer?\u201d de t\u00e3o comuns que s\u00e3o.<\/p>\n<p dir=\"ltr\">\u00c0s vezes s\u00e3o pequenas festas internas, mas muitas fam\u00edlias acabam indo para o quintal, montando tendas, mesas e at\u00e9 fazendo churrasco.<\/p>\n<p dir=\"ltr\">Por isso, nos fins de semana, \u00e9 comum ouvir m\u00fasica vinda dos quintais das casas,<\/p>\n<p dir=\"ltr\">desde o entardecer at\u00e9 tarde da noite.<\/p>\n<p dir=\"ltr\">Mesmo tendo crian\u00e7as em casa, ningu\u00e9m se incomoda! Isso mostra um tra\u00e7o da diferen\u00e7a cultural em rela\u00e7\u00e3o a Brasil.<\/p>\n<p dir=\"ltr\">Certa vez, perguntei a uma amiga mexicana sobre a frequ\u00eancia das festas,<\/p>\n<p dir=\"ltr\">e ela respondeu: \u201cEu almo\u00e7o com parentes pelo menos duas vezes por m\u00eas. A gente s\u00f3 se re\u00fane para comer e conversar.\u201d<\/p>\n<p dir=\"ltr\">Acredito que, como este pa\u00eds valoriza muito os la\u00e7os familiares, reunir-se para compartilhar uma refei\u00e7\u00e3o se tornou um s\u00edmbolo de felicidade!<\/p>\n<p dir=\"ltr\">Nas festas de anivers\u00e1rio, \u00e9 comum o pr\u00f3prio aniversariante ser o anfitri\u00e3o da festa.<\/p>\n<p dir=\"ltr\">Claro, \u00e0s vezes os amigos tamb\u00e9m organizam a festa para o aniversariante,<\/p>\n<p dir=\"ltr\">mas express\u00f5es como \u201cVoc\u00ea tem que vir \u00e0 minha festa de anivers\u00e1rio!\u201d s\u00e3o perfeitamente normais,<\/p>\n<p dir=\"ltr\">j\u00e1 que o aniversariante convidar todos para a pr\u00f3pria festa \u00e9 algo bem comum.<\/p>\n<p dir=\"ltr\">Em geral, quem \u00e9 convidado leva um presente.<\/p>\n<p dir=\"ltr\">Mas h\u00e1 festas nas quais s\u00f3 \u00e9 preciso comparecer, sem levar presente algum!<\/p>\n<p dir=\"ltr\">Nesses momentos, como brasileiros , voc\u00ea talvez fique pensando \u201cSer\u00e1 mesmo que posso ir de m\u00e3os vazias?\u201d, sentindo-se um pouco inseguro.<\/p>\n<p dir=\"ltr\">Por\u00e9m, para eles, o objetivo \u00e9 apenas reunir todos!<\/p>\n<p dir=\"ltr\">Portanto, <strong><span style=\"color: #0000ff;\">\u201ca ideia de excluir a obriga\u00e7\u00e3o do presente, valorizando mais o tempo passado junto\u201d<\/span><\/strong> \u00e9 perfeita para quem sente muita press\u00e3o ao escolher presentes!<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">Sobre a moda no exterior<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Voc\u00ea j\u00e1 ouviu algo assim?<\/p>\n<p dir=\"ltr\">\u201cOs estrangeiros se vestem de forma bem casual durante o dia, mas capricham no visual quando saem \u00e0 noite\u201d.<\/p>\n<p dir=\"ltr\">Incluindo maquiagem e acess\u00f3rios bem chamativos.<\/p>\n<p dir=\"ltr\">Esse comportamento est\u00e1 em contraste com o jeito de Brasil!<\/p>\n<p dir=\"ltr\">Assim, a ideia de \u201cescolher a roupa certa de acordo com a ocasi\u00e3o, mostrando seu estilo\u201d pode ser um conceito novo para quem \u00e9 de Brasil.<\/p>\n<p dir=\"ltr\">Por exemplo, os brasileiros acham que <strong>\u201cvestir-se bem \u00e9 o m\u00ednimo de educa\u00e7\u00e3o\u201d<\/strong>, por isso costumam estar sempre bem arrumados e maquiados.<\/p>\n<p dir=\"ltr\">Principalmente no ambiente de trabalho, para n\u00e3o dar m\u00e1 impress\u00e3o, todos se preocupam e mant\u00eam a apar\u00eancia. J\u00e1 entre estrangeiros, mesmo usando o termo \u201cmoda\u201d, eles transmitem uma sensa\u00e7\u00e3o de mais descontra\u00e7\u00e3o.<\/p>\n<p dir=\"ltr\">Nos seriados e filmes ocidentais que o autor gosta, \u00e9 comum ver homens no escrit\u00f3rio sem gravata.<\/p>\n<p dir=\"ltr\">Por outro lado, nas festas, as mulheres v\u00e3o muito mais maquiadas do que o normal e se produzem com bastante glamour,<\/p>\n<p dir=\"ltr\">como se dissessem <strong><span style=\"color: #d604cf;\">&#8220;Sou uma estrela de Hollywood!&#8221;<\/span><\/strong>.<\/p>\n<p dir=\"ltr\">Eu mesma n\u00e3o costumo me adaptar facilmente a esse estilo t\u00e3o glamouroso do exterior, e \u00e0s vezes me sinto at\u00e9 intimidada pelo ambiente. No entanto, dependendo do tema da festa, \u00e0s vezes ir casual \u00e9 o apropriado. Ent\u00e3o, recomendo que pergunte aos amigos que ir\u00e3o \u00e0 festa o que acham!<\/p>\n<p dir=\"ltr\">Al\u00e9m disso, exig\u00eancias sobre roupas muitas vezes aparecem no convite da festa; vale a pena confirmar de antem\u00e3o.<\/p>\n<h2 dir=\"ltr\">O significado da palavra em ingl\u00eas \u201cparty\u201d<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Ent\u00e3o, o que significa \u201cParty\u201d?<\/p>\n<p dir=\"ltr\">A seguir, vamos apresentar alguns usos em ingl\u00eas para \u201cparty\u201d.<\/p>\n<p dir=\"ltr\">Estas express\u00f5es podem ser usadas diretamente na conversa do dia a dia. Portanto, lembre-se delas!<\/p>\n<p dir=\"ltr\">Primeiro, embora pare\u00e7a uma pergunta \u00f3bvia, sabem o significado de \u201cParty\u201d?<\/p>\n<p dir=\"ltr\">Algumas pessoas podem pensar \u201cEsta pergunta \u00e9 simples demais!\u201d, mas para confirmar, vejamos juntos o significado do dicion\u00e1rio:<\/p>\n<p dir=\"ltr\">O dicion\u00e1rio define \u201cparty\u201d assim:<\/p>\n<p><samp dir=\"ltr\"><strong>\u201cParty\u201d\u00a0 <\/strong><br \/>\n1. Reuni\u00e3o social.<br \/>\n2. Partido, agremia\u00e7\u00e3o, grupo pol\u00edtico.<br \/>\n3. Companhia, grupo de pessoas. Especialmente um grupo engajado em atividades como alpinismo ou expedi\u00e7\u00f5es.<br \/>\n<\/samp><\/p>\n<p dir=\"ltr\">O que achou?<\/p>\n<p dir=\"ltr\">Podemos ver que \u201cparty\u201d al\u00e9m do significado de \u201cfesta\u201d, tamb\u00e9m pode ser \u201cpartido\u201d e outros sentidos!<\/p>\n<p dir=\"ltr\">Al\u00e9m disso, \u201cparty\u201d pode ser um substantivo (\u201creuni\u00e3o social\u201d) ou um verbo significando \u201cir a uma festa\u201d, \u201cfestejar\u201d, \u201ccurtir\u201d.<\/p>\n<p dir=\"ltr\">Veja a seguir alguns voc\u00e1bulos relacionados a \u201cparty\u201d:<\/p>\n<h5 dir=\"ltr\"><strong>\u30fbParty goods<\/strong><br \/>\n\uff1d Itens para festa<br \/>\n<strong>\u30fbParty venue<\/strong><br \/>\n\uff1d Local da festa (venue: lugar, local do evento)<br \/>\n<strong>\u30fbParty dress<\/strong><br \/>\n\uff1d Vestido de festa<br \/>\n<strong>\u30fbDrinking party<\/strong><br \/>\n\uff1d Festa\/Confraterniza\u00e7\u00e3o com bebida<br \/>\n<strong>\u30fbA political party<\/strong><br \/>\n\uff1d Partido pol\u00edtico<br \/>\n<strong>\u30fbThe ruling party<\/strong><br \/>\n\uff1d Partido governista<br \/>\n<strong>\u30fbThe opposition party<\/strong><br \/>\n\uff1d Partido de oposi\u00e7\u00e3o<\/h5>\n<h2 dir=\"ltr\">Express\u00f5es em ingl\u00eas para \u201corganizar uma festa\u201d<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">A express\u00e3o mais comum para \u201corganizar uma festa\u201d em ingl\u00eas \u00e9<\/p>\n<p dir=\"ltr\"><span style=\"color: #0000ff;\">\u201chave a party\u201d. <\/span><\/p>\n<p dir=\"ltr\">Alguns talvez pensem: \u201cN\u00e3o seria open party?\u201d<\/p>\n<p dir=\"ltr\">Na verdade, \u201copen\u201d se refere principalmente a \u201cabrir janela\u201d, \u201cabrir porta\u201d ou \u201cabrir loja\u201d ou algo <strong>fisicamente \u201cabrir\u201d<\/strong>.<\/p>\n<p dir=\"ltr\">No Brasil costuma-se dizer \u201cabrir festa\u201d para indicar que vai organizar uma festa. Mas, <strong>em ingl\u00eas, o \u201cabrir\u201d da express\u00e3o brasileira tem sentido mais pr\u00f3ximo de \u201cter\u201d<\/strong>. Por isso, \u201cI have a party\u201d pode ser traduzido como \u201ceu tenho (organizei) uma festa\u201d.<\/p>\n<p dir=\"ltr\">Se pensarmos ao contr\u00e1rio, torna-se bem interessante!<\/p>\n<p dir=\"ltr\">Para os estrangeiros aprendendo portugu\u00eas,<\/p>\n<p dir=\"ltr\">eles podem se perguntar \u201chave a party\u201d \u00e9 literalmente \u201cter uma festa\u201d, ent\u00e3o por que usamos \u201cabrir festa\u201d em portugu\u00eas?<\/p>\n<p dir=\"ltr\">Assim, certas express\u00f5es realmente s\u00e3o dif\u00edceis de traduzir diretamente!<\/p>\n<p dir=\"ltr\">Al\u00e9m disso, \u201chold\u201d ou \u201cthrow\u201d tamb\u00e9m podem ser usados no sentido de \u201corganizar uma festa\u201d.<\/p>\n<p dir=\"ltr\"><strong>hold = segurar algo<\/strong><\/p>\n<p dir=\"ltr\"><strong>throw = lan\u00e7ar<\/strong><\/p>\n<p dir=\"ltr\">Essas palavras parecem n\u00e3o ter rela\u00e7\u00e3o com o conceito de \u201cabrir\u201d, mas tamb\u00e9m significam <strong>\u201corganizar\u201d, \u201crealizar\u201d<\/strong>.<\/p>\n<p dir=\"ltr\">have a party = forma comum de expressar a organiza\u00e7\u00e3o de uma festa<\/p>\n<p dir=\"ltr\">hold a party = o organizador planeja e realiza a festa<\/p>\n<p dir=\"ltr\">throw a party = normalmente usado para festas de comemora\u00e7\u00e3o<\/p>\n<h5 dir=\"ltr\">Exemplos:<br \/>\n<strong>\u30fbWe are going to have a party on Friday night!<\/strong><br \/>\nVamos fazer uma festa na sexta-feira \u00e0 noite!<br \/>\n<strong>\u30fbWe had our friend\u2019s birthday party yesterday.<\/strong><br \/>\nOntem fizemos a festa de anivers\u00e1rio do nosso amigo.<br \/>\n<strong>\u30fbWe held a birthday party for one of our friends.<\/strong><br \/>\nN\u00f3s organizamos uma festa de anivers\u00e1rio para um dos nossos amigos.<br \/>\n<strong>\u30fbWe threw a birthday party for her.<\/strong><br \/>\nFizemos uma festa de anivers\u00e1rio para ela.<\/h5>\n<p dir=\"ltr\">Ali\u00e1s, o autor descobriu que \u201copen\u201d n\u00e3o significa \u201corganizar\u201d, por causa da express\u00e3o <strong>\u201corganizar uma exposi\u00e7\u00e3o\u201d<\/strong>.<\/p>\n<p dir=\"ltr\">E \u201corganizar uma exposi\u00e7\u00e3o\u201d tamb\u00e9m usa <strong>\u201chave\u201d e \u201chold\u201d<\/strong> em ingl\u00eas.<\/p>\n<p dir=\"ltr\">Neste caso, dizemos \u201chave(hold) an exhibition\u201d!<\/p>\n<h2 dir=\"ltr\">Express\u00f5es em ingl\u00eas para \u201cconvidar\u201d e \u201cser convidado\u201d<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Agora vamos apresentar as express\u00f5es relacionadas a <strong>\u201cconvidar\u201d e \u201cser convidado\u201d<\/strong> em ingl\u00eas.<\/p>\n<p dir=\"ltr\">Convidar em ingl\u00eas \u00e9 <strong><span style=\"color: #ff0000;\">\u201cinvite\u201d<\/span>.<\/strong><\/p>\n<p dir=\"ltr\"><span style=\"color: #0000ff;\">Convidar = invite <\/span><\/p>\n<p dir=\"ltr\"><span style=\"color: #0000ff;\">Ser convidado = be invited <\/span><\/p>\n<p dir=\"ltr\">Essas duas palavras tamb\u00e9m significam \u201cquem convida\u201d e \u201cquem \u00e9 convidado\u201d.<\/p>\n<h5 dir=\"ltr\"><strong>\u30fbI invited her to my house.<\/strong><br \/>\nConvidei ela para minha casa.<br \/>\n<strong>\u30fbWho should we invite to the party?<\/strong><br \/>\nQuem devemos convidar para a festa?<br \/>\n<strong>\u30fbYou can invite whomever you like!<\/strong><br \/>\nVoc\u00ea pode convidar quem quiser!<br \/>\n<strong>\u30fbI was invited in for dinner.<\/strong><br \/>\nFui convidado para o jantar.<br \/>\n<strong>\u30fbHe wanted to be invited to the party.<\/strong><br \/>\nEle queria ser convidado para a festa.<\/h5>\n<h2 dir=\"ltr\">Express\u00f5es em ingl\u00eas usadas em \u201cconvites para festas\u201d<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Se voc\u00ea for o anfitri\u00e3o, talvez precise usar algumas frases para convidar em ingl\u00eas.<\/p>\n<p dir=\"ltr\">Ent\u00e3o aqui v\u00e3o algumas express\u00f5es pr\u00e1ticas para mandar convites por e-mail, mensagem, etc.<\/p>\n<h5 dir=\"ltr\"><strong>\u30fbI would love\/like to have you over for dinner.<\/strong><br \/>\nAdoraria\/gostaria de te convidar para jantar.<br \/>\n(\u201cwould love to\u201d \u00e9 mais educado e expressa um desejo mais forte do que \u201cwant to\u201d)<br \/>\n<strong>\u30fbIf you have time, please come and join our party!<\/strong><br \/>\nSe tiver tempo, venha participar da nossa festa!<br \/>\n<strong>\u30fbPlease save the date for the party \uff0d1st March.<\/strong><br \/>\nPor favor, reserve o dia 1\u00ba de mar\u00e7o para a festa.<br \/>\n<strong>\u30fbPlease bring a dish to share. <\/strong><br \/>\nPor favor, traga um prato para compartilhar. (*Para festas onde cada um leva comida)<br \/>\n<strong>\u30fbJust bring yourself\uff01<\/strong><br \/>\nS\u00f3 precisa trazer voc\u00ea mesmo!<br \/>\n<strong>\u30fbBring your spouse \/ partner.<\/strong><br \/>\nTraga seu c\u00f4njuge\/namorado(a)\/parceiro(a).<br \/>\n(Nos pa\u00edses estrangeiros, geralmente \u00e9 normal levar acompanhante)<br \/>\n<strong>\u30fbHope to see you all there!<\/strong><br \/>\nEspero ver todos voc\u00eas l\u00e1!<br \/>\n<strong>\u30fbI hope you can make it.<\/strong><br \/>\nEspero que voc\u00ea possa vir.<br \/>\n<strong>\u30fbTime and Date<\/strong><br \/>\nData e hor\u00e1rio<br \/>\n<strong>\u30fbVenue \/Place<\/strong><br \/>\nLocal<br \/>\n<strong>\u30fbAgenda<\/strong><br \/>\nPrograma\u00e7\u00e3o, conte\u00fado do evento<br \/>\n<strong>\u30fbFee free<\/strong><br \/>\nGratuito<br \/>\n<strong>\u30fbDress code<\/strong><br \/>\nC\u00f3digo de vestimenta (*Quando houver exig\u00eancia sobre a roupa)<\/h5>\n<h2 dir=\"ltr\">Express\u00f5es em ingl\u00eas para responder a convites<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Ao receber um convite, voc\u00ea deve responder o quanto antes se vai comparecer.<\/p>\n<p dir=\"ltr\"><strong>\u30fbI will be there.<\/strong><br \/>\nEu vou (comparecerei).<\/p>\n<p dir=\"ltr\"><strong>\u30fbThank you for inviting me to the party. <\/strong><br \/>\n<strong>\u00a0 \u00a0 I am looking forward to seeing you soon!<\/strong><br \/>\nObrigado por me convidar para a festa. Estou ansioso(a) para v\u00ea-lo(a) em breve!<\/p>\n<p dir=\"ltr\"><strong>\u30fbThank you for inviting me, but I\u2019m afraid I have another meeting tomorrow.<\/strong><br \/>\nObrigado pelo convite, mas infelizmente tenho outro compromisso amanh\u00e3.<\/p>\n<p dir=\"ltr\"><strong>\u30fbI would love to come next time.<\/strong><br \/>\nAdoraria ir na pr\u00f3xima vez.<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">Agradecimentos ap\u00f3s ter participado da festa<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">O que achou?<\/p>\n<p dir=\"ltr\">Hoje, apresentamos express\u00f5es em ingl\u00eas sobre \u201corganizar festas\u201d.<\/p>\n<p dir=\"ltr\">Na verdade, o autor n\u00e3o \u00e9 muito de participar de \u201cfestas\u201d&#8230;<\/p>\n<p dir=\"ltr\">Quando ainda n\u00e3o somos fluentes em ingl\u00eas ou na l\u00edngua local, reunir coragem para conhecer um monte de gente nova \u00e9 realmente um desafio.<\/p>\n<p dir=\"ltr\">Mas,<\/p>\n<p dir=\"ltr\">o autor ainda acredita que \u201c\u00e9 uma \u00f3tima chance de fazer novos amigos!\u201d<\/p>\n<p dir=\"ltr\">\u201c\u00c9 uma experi\u00eancia cultural!\u201d<\/p>\n<p dir=\"ltr\">\u201c\u00c9 para o aprendizado do idioma!\u201d e se anima para ir \u00e0s \u201cfestas\u201d.<\/p>\n<p dir=\"ltr\">\u00c0s vezes, o autor fica frustrado por n\u00e3o conseguir conversar bem\u2026<\/p>\n<p dir=\"ltr\">Mas, geralmente, acaba pensando \u201cainda bem que fui!\u201d<\/p>\n<p dir=\"ltr\">Pois nas festas, al\u00e9m de viver experi\u00eancias diferentes, voc\u00ea aprende express\u00f5es em ingl\u00eas aut\u00eanticas que n\u00e3o aparecem nos livros!<\/p>\n<p dir=\"ltr\">Por fim, aqui v\u00e3o algumas frases de despedida em ingl\u00eas que voc\u00ea pode usar ao final da festa.<\/p>\n<h5 dir=\"ltr\"><strong>\u30fbThank you for having me.<\/strong><br \/>\nObrigado(a) por me receber\/convidar.<br \/>\n<strong>\u30fbThis party was great! \/<\/strong><br \/>\n<strong>\u3000It was a wonderful party!<\/strong><br \/>\nA festa foi maravilhosa!\/Foi uma festa incr\u00edvel!<br \/>\n<strong>\u30fbI hope we can get together again sometime soon.<\/strong><br \/>\nEspero que possamos nos encontrar de novo em breve.<\/h5>\n<p dir=\"ltr\">Al\u00e9m de coragem, todos talvez precisem de um empurr\u00e3ozinho extra para dar esse passo!<\/p>\n<p dir=\"ltr\">Se voc\u00ea est\u00e1 nessa situa\u00e7\u00e3o, recomendamos que fa\u00e7a um ensaio usando a plataforma de conversa\u00e7\u00e3o online da \u201cNative Camp\u201d!<\/p>\n<p dir=\"ltr\">Nas aulas, voc\u00ea pode conversar com professores do mundo todo e praticar o tema \u201cfesta\u201d de verdade.<\/p>\n<p dir=\"ltr\">Desejamos sinceramente que todos aprendam mais ingl\u00eas e aproveitem as festas!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os estrangeiros gostam muito de\u00a0 \u201cfestas\u201d. Se voc\u00ea mora h\u00e1 muito tempo no exterior, provavelmente tamb\u00e9m recebe convites para festas com frequ\u00eancia! E hoje em dia, n\u00e3o \u00e9 s\u00f3 no exterior: em Brasil, eventos internacionais, festas de Natal, confraterniza\u00e7\u00f5es empresariais, festas de solteiro e v\u00e1rios outros formatos de festas t\u00eam aumentado cada vez mais. Quem sabe, talvez voc\u00ea tamb\u00e9m seja o organizador de uma festa da empresa ou de um evento de boas-vindas. Mas, se voc\u00ea n\u00e3o tem confian\u00e7a na conversa em ingl\u00eas e por isso n\u00e3o consegue participar das festas organizadas por estrangeiros, podemos te dizer que, na verdade, basta conhecer algumas frases b\u00e1sicas em ingl\u00eas para dar facilmente &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/13759\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":13857,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=13759","footnotes":""},"categories":[129,128,127],"tags":[],"class_list":["post-13759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-children","category-business","category-travel","pt-BR"],"aioseo_notices":[],"views":166,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=13759"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13759\/revisions"}],"predecessor-version":[{"id":13761,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13759\/revisions\/13761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/13857"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=13759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=13759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=13759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}