{"id":13756,"date":"2025-12-12T09:00:09","date_gmt":"2025-12-12T12:00:09","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=13756"},"modified":"2025-12-10T03:35:50","modified_gmt":"2025-12-10T06:35:50","slug":"voce-sabe-como-dizer-descontar-em-outra-pessoa-em-ingles","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/13756\/","title":{"rendered":"Voc\u00ea sabe como dizer \u201cdescontar em outra pessoa\u201d em ingl\u00eas?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">O tema de hoje \u00e9\u00a0 <\/span><span style=\"color: #c711d1; font-size: 28px;\"><b>\u201cdescontar\u201d <\/b><\/span><span style=\"font-weight: 400;\">em ingl\u00eas!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Muitas pessoas estudam ingl\u00eas h\u00e1 algum tempo, mas \u00e0s vezes podem n\u00e3o ter certeza de como expressar o conceito de \u201cdescontar\u201d. Com a explica\u00e7\u00e3o deste artigo, sua habilidade em ingl\u00eas vai subir de n\u00edvel imediatamente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o vamos apenas discutir as v\u00e1rias formas de expressar \u201cdescontar\u201d, mas tamb\u00e9m compartilhar formas de pedir desculpas quando descontamos em algu\u00e9m. N\u00e3o perca!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Uso de \u201cdescontar\u201d em ingl\u00eas<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Vamos ver como se diz <strong>\u201cdescontar\u201d<\/strong> em ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea procurar no dicion\u00e1rio, descobrir\u00e1 muitas express\u00f5es equivalentes em ingl\u00eas. Por\u00e9m, o importante \u00e9 saber como us\u00e1-las, ent\u00e3o a seguir vou explicar cada uma com exemplos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nos dicion\u00e1rios online, voc\u00ea pode encontrar o seguinte uso como substantivo.<\/span><\/p>\n<h5><span style=\"font-weight: 400;\">\u201ckick-the-cat<\/span><br \/>\n<span style=\"font-weight: 400;\">Tradu\u00e7\u00e3o: venting one&#8217;s anger (on someone or something); taking out one&#8217;s anger on\u201d<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Al\u00e9m do substantivo kick-the-cat, h\u00e1 tamb\u00e9m muitos usos como verbo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos apresentar as frases verbais e express\u00f5es idiom\u00e1ticas mais comuns.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>take it out on\u00a0<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, vamos apresentar a express\u00e3o \u201cdescontar\u201d: <\/span><span style=\"color: #ff0000;\"><b>\u201ctake it out on \u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Depois dela, voc\u00ea deve colocar o objeto, ou seja, a quem voc\u00ea est\u00e1 descontando a raiva. Pensando um pouco, n\u00e3o \u00e9 dif\u00edcil entender o conceito.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201ctake out\u201d significa \u201ctirar\u201d, e junto com \u201con\u201d transmite a ideia de \u201ccolocar sobre algu\u00e9m\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ou seja, quando algu\u00e9m desconta seus sentimentos negativos em outra pessoa, temos o significado de \u201cdescontar\u201d.<\/span><\/p>\n<h5><b>Don&#8217;t take it out on me if you can\u2019t pass the exam.<\/b><br \/>\n<span style=\"font-weight: 400;\">Mesmo que voc\u00ea n\u00e3o passe na prova, n\u00e3o desconte em mim.<\/span><br \/>\n<b>Oh my goddess! I didn&#8217;t mean to take it out on her.<\/b><br \/>\n<span style=\"font-weight: 400;\">Oh! Poxa! N\u00e3o foi minha inten\u00e7\u00e3o descontar nela.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Como \u00e9 uma express\u00e3o verbal come\u00e7ando com take, basta coloc\u00e1-la na posi\u00e7\u00e3o correta de verbo na frase, completando com a gram\u00e1tica certa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pode ser usada tanto na escrita quanto na fala do dia a dia. Mas claro, \u00e9 importante treinar bastante para conseguir usar de forma natural nas conversas depois.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>vent \u2026. anger on<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Outra forma de dizer \u201cdescontar\u201d \u00e9 <\/span><span style=\"color: #ff0000;\"><b>\u201cvent someone&#8217;s anger on~\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O significado \u00e9 bem parecido com \u201ctake it out on \u201d. Mas <\/span><strong><span style=\"color: #0000ff;\">\u201cvent someone&#8217;s anger on\u201d passa uma sensa\u00e7\u00e3o mais formal na l\u00edngua escrita, ent\u00e3o aparece com menos frequ\u00eancia em conversas entre familiares e amigos<\/span><\/strong><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aqui, \u201cvent\u201d como substantivo significa \u201csa\u00edda de ar, v\u00e1lvula de escape\u201d e, por isso, como verbo, acabou assumindo o sentido de \u201cextravasar emo\u00e7\u00f5es\u201d. Basta imaginar uma sa\u00edda para as emo\u00e7\u00f5es e ficar\u00e1 f\u00e1cil entender.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Portanto, \u201cvent someone&#8217;s anger on\u201d \u00e9 espalhar a raiva para fora de si, afetando os outros ao redor. Veja os exemplos:<\/span><\/p>\n<h5><b>Actually, I don\u2019t like her. She always vents her anger on me.<\/b><br \/>\n<span style=\"font-weight: 400;\">Na verdade, eu n\u00e3o gosto muito dela; ela sempre desconta a raiva em mim.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>My husband vents his anger on me when he loses a game.<\/b><br \/>\n<span style=\"font-weight: 400;\">Meu marido desconta a raiva em mim sempre que perde um jogo.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">N\u00e3o sabemos exatamente onde est\u00e1 essa \u201csaida de raiva\u201d nas frases em ingl\u00eas, mas sempre que envolve outra pessoa, pode ser considerado \u201cdescontar\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea tamb\u00e9m costuma ser o alvo do estresse dos outros em casa ou no trabalho, vai entender esse uso facilmente!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Express\u00f5es relacionadas a \u201cdescontar\u201d<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Acabamos de apresentar algumas formas de falar \u201cdescontar\u201d em ingl\u00eas, deu para aprender?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na pr\u00f3xima parte, apresentaremos outras express\u00f5es relacionadas. Talvez voc\u00ea ache que tamb\u00e9m t\u00eam significado parecido com \u201cdescontar\u201d, ent\u00e3o aproveite para aprender todas juntas!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Ser v\u00edtima sem motivo<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Ningu\u00e9m gosta de ser uma \u201cv\u00edtima sem motivo\u201d, mas j\u00e1 que \u00e9 dif\u00edcil evitar totalmente, melhor aprender como se diz isso em ingl\u00eas. H\u00e1 v\u00e1rias maneiras de expressar, ent\u00e3o aproveite para aprender as novas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>be a victim of circumstance<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Para falar de \u201cser envolvido em uma situa\u00e7\u00e3o sem culpa\u201d em ingl\u00eas, comece aprendendo esta express\u00e3o.<\/span><\/p>\n<h6><b>victim \u201cv\u00edtima\u201d<\/b><br \/>\n<b>circumstance \u201ccircunst\u00e2ncia, situa\u00e7\u00e3o\u201d<\/b><\/h6>\n<p><span style=\"font-weight: 400;\">Ser v\u00edtima inocente por conta dos acontecimentos ao redor, isso \u00e9 definitivamente ser alvo de \u201cinfort\u00fanio\u201d. Lembre-se de usar circumstances no plural ao falar das situa\u00e7\u00f5es em volta.<\/span><\/p>\n<h5><b>What did I do? Did I do something wrong!? I was a victim of circumstance!<\/b><br \/>\n<span style=\"font-weight: 400;\">O que eu fiz? Fiz algo errado!? Fui s\u00f3 uma v\u00edtima inocente!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Quando voc\u00ea se sente correto mas foi envolvido em algo sem culpa, use esta frase para se defender. Afinal, ningu\u00e9m gosta de levar a culpa injustamente!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Agora, vamos apresentar outra estrutura idiom\u00e1tica usando \u201cvictim\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>be an innocent victim<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Traduzindo literalmente \u00e9 \u201cv\u00edtima inocente\u201d. N\u00e3o \u00e9 praticamente igual ao que vimos agora h\u00e1 pouco?<\/span><\/p>\n<h5><b>get involved in other people\u2019s quarrels<\/b><\/h5>\n<p><span style=\"font-weight: 400;\">Significa se envolver nas brigas dos outros, outra express\u00e3o bem \u00fatil.<\/span><\/p>\n<h6><b>get involved \u201cenvolver-se\u201d<\/b><br \/>\n<b>quarrel \u201cbriga, discuss\u00e3o\u201d<\/b><\/h6>\n<p><span style=\"font-weight: 400;\">Ambas as palavras aparecem frequentemente em exames como o TOEIC. Involve sozinho j\u00e1 significa \u201cincluir\u201d, ent\u00e3o get involved na forma passiva significa \u201cser envolvido\u201d.<\/span><\/p>\n<h5><b>I got involved in other people\u2019s quarrels yesterday.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ontem me envolvi nas brigas dos outros.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Esta express\u00e3o idiom\u00e1tica \u00e9 um pouco longa, e como \u00e9 fixa, n\u00e3o mude as palavras: memorize como est\u00e1.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Pedir desculpas ao alvo da raiva<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea n\u00e3o conseguiu se controlar e acabou descontando em algu\u00e9m, lembre de se desculpar depois.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas, quais s\u00e3o as melhores formas de pedir desculpas sinceramente? Minha sugest\u00e3o \u00e9: n\u00e3o rodeie. Confira essas express\u00f5es:<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>I\u2019m sorry I took it out on you.<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Esta frase \u00e9 uma das formas mais diretas e b\u00e1sicas de pedir desculpas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Comece com I\u2019m sorry para mostrar arrependimento e, em seguida, explique o motivo da desculpa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como o epis\u00f3dio de <strong>\u201cdescontar\u201d<\/strong> j\u00e1 aconteceu, lembre-se de usar o passado em<strong> \u201ctake it out on \u201d.<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Normalmente, s\u00f3 dizer Sorry j\u00e1 resolve a maioria das situa\u00e7\u00f5es, inclusive para falantes nativos. Mas, se quiser saber mais formas de expressar, veja os exemplos a seguir.<\/span><\/p>\n<h5><b>I\u2019m sorry about yesterday.<\/b><br \/>\n<span style=\"font-weight: 400;\">Sinto muito pelo que aconteceu ontem.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>I\u2019m sorry about before.<\/b><br \/>\n<span style=\"font-weight: 400;\">Sinto muito pelo que aconteceu antes.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>I\u2019m sorry about earlier.<\/b><br \/>\n<span style=\"font-weight: 400;\">Sinto muito pelo que acabou de acontecer.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Voc\u00ea j\u00e1 deve ter notado: basta colocar o tempo do acontecimento depois de I\u2019m sorry about, muito pr\u00e1tico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora n\u00e3o mencione diretamente que foi por descontar a raiva, se a pessoa entender pela refer\u00eancia ao tempo, tamb\u00e9m serve como uma forma sutil de pedir desculpas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se o epis\u00f3dio aconteceu hoje, use \u201cI\u2019m sorry about earlier.\u201d\u00a0 Por outro lado, se disser\u00a0 \u201cI\u2019m sorry about today.\u201d, o per\u00edodo fica mais longo e parece que voc\u00ea se desculpa por ter incomodado durante o dia todo, n\u00e3o apenas por um caso espec\u00edfico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apesar de ser um detalhe, ao entender essas diferen\u00e7as de nuance, seu ingl\u00eas ficar\u00e1 mais preciso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Outra coisa \u00e9 a intensidade no pedido de desculpas, que vai aumentando: Sorry, I\u2019m sorry, I\u2019m so sorry.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 que diferentes frases expressam diferentes graus de sinceridade, em textos, recomendo usar frases mais longas, como I\u2019m so sorry, para mostrar mais sinceridade. Afinal, na fala tem o tom de voz, mas na escrita, s\u00f3 temos as palavras.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Resumo<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Depois de ler este artigo, voc\u00ea j\u00e1 sabe como usar \u201cdescontar\u201d em ingl\u00eas, n\u00e3o \u00e9? Basicamente, o significado \u00e9 id\u00eantico ao do portugu\u00eas, ent\u00e3o pode usar diretamente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em outras palavras, basta estudar o conte\u00fado de hoje e praticar o suficiente para dominar o uso correto de \u201cdescontar\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tamb\u00e9m recomendo anotar essas formas \u00fateis de pedir desculpas, j\u00e1 que ningu\u00e9m garante que vai sempre conseguir controlar o pr\u00f3prio temperamento. Para manter bons relacionamentos, comece sempre com um pedido de desculpa sincero!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O tema de hoje \u00e9\u00a0 \u201cdescontar\u201d em ingl\u00eas! Muitas pessoas estudam ingl\u00eas h\u00e1 algum tempo, mas \u00e0s vezes podem n\u00e3o ter certeza de como expressar o conceito de \u201cdescontar\u201d. Com a explica\u00e7\u00e3o deste artigo, sua habilidade em ingl\u00eas vai subir de n\u00edvel imediatamente. N\u00e3o vamos apenas discutir as v\u00e1rias formas de expressar \u201cdescontar\u201d, mas tamb\u00e9m compartilhar formas de pedir desculpas quando descontamos em algu\u00e9m. N\u00e3o perca! &nbsp; Uso de \u201cdescontar\u201d em ingl\u00eas &nbsp; Vamos ver como se diz \u201cdescontar\u201d em ingl\u00eas. Se voc\u00ea procurar no dicion\u00e1rio, descobrir\u00e1 muitas express\u00f5es equivalentes em ingl\u00eas. Por\u00e9m, o importante \u00e9 saber como us\u00e1-las, ent\u00e3o a seguir vou explicar cada uma com exemplos. Nos dicion\u00e1rios &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/13756\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":13856,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=13756","footnotes":""},"categories":[134,139,140],"tags":[],"class_list":["post-13756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-overseas-info","category-cultural-exchange","category-study-abroad-nc","pt-BR"],"aioseo_notices":[],"views":290,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=13756"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13756\/revisions"}],"predecessor-version":[{"id":13758,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13756\/revisions\/13758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/13856"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=13756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=13756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=13756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}