{"id":13570,"date":"2025-11-28T09:00:59","date_gmt":"2025-11-28T12:00:59","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=13570"},"modified":"2025-11-25T01:24:51","modified_gmt":"2025-11-25T04:24:51","slug":"o-que-e-mais-natural-em-ingles-backpack-ou-rucksack","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/13570\/","title":{"rendered":"O que \u00e9 mais natural em ingl\u00eas: \u201cbackpack\u201d ou \u201crucksack\u201d?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Existem v\u00e1rios tipos de bolsas, como bolsas de ombro, mochilas ou tote bags, entre outros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora em ingl\u00eas exista a palavra <strong>\u201cbag\u201d<\/strong> para bolsas em geral, termos como <strong>\u201crucksack\u201d, \u201cPochette\u201d, \u201cTote bag\u201d<\/strong> talvez n\u00e3o sejam do conhecimento de muita gente quanto aos nomes espec\u00edficos em ingl\u00eas para cada tipo de bolsa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desta vez, vou come\u00e7ar com rucksack e explicar detalhadamente como expressar os v\u00e1rios tipos de bolsas em ingl\u00eas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Diferen\u00e7a entre Backpack e rucksack<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">As bolsas usadas nas costas geralmente s\u00e3o chamadas de backpack ou rucksack. Pessoas que viajam pelo mundo carregando muita bagagem ou um saco de dormir s\u00e3o chamadas de <\/span><b><span style=\"color: #ff0000;\">\u201cbackpacker\u201d<\/span>.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Algumas pessoas podem pensar: \u201cBackpack e rucksack n\u00e3o s\u00e3o a mesma coisa?\u201d, mas na verdade esses dois termos t\u00eam origens e contextos hist\u00f3ricos distintos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na d\u00e9cada de 1930, o Jap\u00e3o foi influenciado pelo Wandervogelboom (movimento Wandervogel). O chamado Wandervogel foi uma atividade ao ar livre iniciada no final do s\u00e9culo XVIII por jovens alem\u00e3es, <\/span><span style=\"color: #ff0000;\"><b>com o objetivo de fazer caminhadas pelas montanhas e campos, conversando e curtindo a vida na natureza para fortalecer corpo e mente.<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">O item indispens\u00e1vel para essa atividade era o\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201crucksack\u201d<\/b><\/span><span style=\"font-weight: 400;\">. Essa palavra originalmente vem do alem\u00e3o,\u00a0 <\/span>significando\u00a0 <span style=\"color: #ff0000;\"><b>\u201csaco usado nas costas\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando essa palavra de origem alem\u00e3\u00a0 \u00a0\u201crucksack\u201d passou para o ingl\u00eas, sua pron\u00fancia mudou um pouco e ela passou a ser chamada de <strong>\u201crucksack\u201d\u00a0<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">As pessoas entusiastas do Wandervogel colocavam tendas e outros equipamentos em seu rucksack para as atividades ao ar livre.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Originalmente, as \u00e1reas de atividade do Wandervogel inclu\u00edam n\u00e3o s\u00f3 montanhas, mas tamb\u00e9m mar e campos, sendo atividades centradas na natureza. No entanto, devido \u00e0 geografia predominantemente montanhosa do Brasil, com o tempo as atividades passaram naturalmente a acontecer principalmente em regi\u00f5es montanhosas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Assim, sob forte influ\u00eancia da cultura Wandervogel, muitos nomes de equipamentos de montanhismo no Brasil. Por exemplo,\u00a0 <\/span><span style=\"font-weight: 400;\"><strong><span style=\"color: #ff0000;\">\u201cEisen (crampons)\u201d ou \u201cKarabiner (mosquet\u00e3o)\u201d<\/span><\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, h\u00e1 muitos aspectos da cultura de montanhismo presentes no cotidiano dos brasilieros. Por exemplo, passeios escolares incluem subidas em montanhas e muitos t\u00eam como hobby escalar os montes pr\u00f3ximos de casa nos finais de semana, ent\u00e3o o termo \u201crucksack\u201d foi naturalmente amplamente utilizado como o nome do equipamento de montanhismo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por outro lado, a origem da palavra inglesa \u201cbackpack\u201d \u00e9\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201cbagagem nas costas\u201d<\/b><\/span><span style=\"font-weight: 400;\">, pois \u201cback\u201d = costas, \u201cpack\u201d = bagagem, ent\u00e3o significa literalmente \u201cbagagem nas costas\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na d\u00e9cada de 1960, nos Estados Unidos, estava em alta a cultura hippie: pessoas vivendo livremente, sem seguir regras dos mais velhos e sem um trabalho fixo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os hippies, sem resid\u00eancia fixa, vagavam carregando seus pertences nas costas. Roupas, comida, saco de dormir, tudo era levado nas costas enquanto viajavam dentro e fora do pa\u00eds. Da\u00ed vem o termo backpack.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O rucksack de montanhismo \u00e9 feito para ser compacto, leve e f\u00e1cil de transportar, sem atrapalhar durante trilhas ou atividades Wandervogel. J\u00e1 o backpack hippie \u00e9 desenvolvido para carregar o maior volume poss\u00edvel, mesmo sendo transportado nas costas, geralmente sendo uma bolsa de grande porte.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com essas diferen\u00e7as, hoje temos a impress\u00e3o estabelecida de que <span style=\"color: #ff0000;\"><strong>\u201crucksack\u201d <\/strong><\/span>\u00e9 uma bolsa pequena nas costas; <span style=\"color: #ff0000;\"><strong>\u201cbackpack\u201d <\/strong><\/span>\u00e9 uma mochila de grande porte.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Qual termo usar em ingl\u00eas para soar mais natural?<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Agora que sabemos a origem e diferen\u00e7a entre<strong> \u201crucksack\u201d<\/strong> e <strong>\u201cbackpack\u201d,<\/strong> vejamos como expressar em ingl\u00eas esse tipo de bolsa usada nas costas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em ingl\u00eas, bolsas usadas nas costas como \u201crucksack\u201d ou \u201cbackpack\u201d podem ser chamadas genericamente de <\/span><span style=\"color: #ff0000;\"><b>\u201cbackpack\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, ao falar em ingl\u00eas, mesmo para mochilas de montanhismo pode-se usar \u201cbackpack\u201d. Nos Estados Unidos, especialmente, \u201cbackpack\u201d \u00e9 mais comum, soando mais natural e f\u00e1cil de entender do que \u201crucksack\u201d.<\/span><\/p>\n<h5><b>You should buy a big backpack if you are going to climb <strong class=\"Yjhzub\" data-processed=\"true\">Pico das Agulhas Negras\u00a0<\/strong>.<\/b><br \/>\n<span style=\"font-weight: 400;\">Se voc\u00ea vai escalar o <strong class=\"Yjhzub\" data-processed=\"true\">Pico das Agulhas Negras\u00a0<\/strong>, \u00e9 melhor comprar uma mochila grande.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Ali\u00e1s, quando quiser dizer \u201ccolocar a mochila nas costas\u201d ou \u201cpegar a mochila\u201d, pode-se usar <span style=\"color: #ff0000;\"><strong>\u201cwear\u201d (vestir, usar) ou \u201cput on\u201d (colocar, p\u00f4r)<\/strong><\/span>.<\/span><\/p>\n<h5><b>Have you already worn your backpack?<\/b><br \/>\n<span style=\"font-weight: 400;\">\u203b<\/span><span style=\"font-weight: 400;\"> \u201cworn\u201d \u00e9 o partic\u00edpio passado de \u201cwear\u201d<\/span><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea j\u00e1 colocou a mochila?<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>She put on her backpack 30 minutes before departure.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ela colocou a mochila 30 minutos antes de sair.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Informa\u00e7\u00e3o extra: knapsack \u00e9 um termo antigo<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m de<strong> \u201crucksack\u201d<\/strong> e<strong> \u201cbackpack\u201d<\/strong>, existe tamb\u00e9m a palavra semelhante <strong>\u201cknapsack\u201d.<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">No Brasil, alunos do ensino fundamental usam um saco de tecido grande com cord\u00e3o para levar roupas de gin\u00e1stica. Essa bolsa de pano com fechadura por cord\u00e3o que se usa nas costas \u00e9 chamada de <span style=\"color: #ff0000;\"><strong>Knapsack<\/strong><\/span>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na verdade, esta palavra vem do ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No ingl\u00eas, \u201cknapsack\u201d, diferentemente do Brasil, n\u00e3o significa necessariamente \u201cfeito de tecido\u201d ou \u201cde cord\u00e3o\u201d; assim como nos Estados Unidos, o significado \u00e9 <span style=\"color: #ff0000;\"><strong>\u201c saco ou bagagem usada nas costas\u201d<\/strong><\/span>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hoje em dia, a palavra \u201cknapsack\u201d \u00e9 usada principalmente por pessoas com mais de 60 anos no Reino Unido e nos Estados Unidos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ali\u00e1s, se voc\u00ea quiser dizer \u201cbolsa de cord\u00e3o\u201d em ingl\u00eas, pode dizer\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201cdrawstring bag\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cDraw\u201d significa puxar, \u201cstring\u201d \u00e9 corda, e \u201cbag\u201d significa bolsa ou saco; juntando, significa\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201cbolsa que se puxa o cord\u00e3o\u201d<\/b><\/span><span style=\"font-weight: 400;\">, ou seja, bolsa de cord\u00e3o.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Diversos estilos de bolsas<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"color: #ff0000;\"><strong>Bag<\/strong><\/span>\u00a0 \u00a0pode assumir v\u00e1rias formas, do pequeno ao grande, de acordo com suas diferentes fun\u00e7\u00f5es.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vou explicar como expressar esses tipos de bolsas em ingl\u00eas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>clutch bag<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"color: #ff0000;\"><strong>Clutch bag<\/strong><\/span> \u00e9 uma bolsa pequena sem al\u00e7a nem correia. Como pode ser colocada dentro de uma bolsa maior, tamb\u00e9m \u00e9 chamada de <span style=\"color: #ff0000;\"><strong>\u201csecond bag\u201d<\/strong><\/span>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em ingl\u00eas, ela \u00e9 chamada de\u00a0 <\/span><b><span style=\"color: #ff0000;\">\u201cclutch bag\u201d\u00a0 <\/span>.<\/b><span style=\"font-weight: 400;\">\u201cClutch\u201d significa \u201csegurar firmemente\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O nome deriva do fato de que a bolsa \u00e9 segurada firmemente com a m\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Originalmente, \u201cclutch bag\u201d referia-se a uma bolsa elegante usada por mulheres para levar apenas itens essenciais como batom ou len\u00e7o, principalmente quando estavam vestindo vestidos sem bolso, funcionando tamb\u00e9m como acess\u00f3rio de moda.<\/span><\/p>\n<h5><b>Her grandmother made her a dress and a clutch bag made of the same fabric.<\/b><br \/>\n<span style=\"font-weight: 400;\">A av\u00f3 dela fez um vestido e uma clutch bag com o mesmo tecido para ela.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Mas hoje em dia, os estilos de clutch bag s\u00e3o mais variados, alguns com al\u00e7as ou correias para o pulso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por ser pequena, n\u00e3o interfere no estilo, podendo facilmente ser usada como um acess\u00f3rio de moda casual.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>pochette<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Pochette \u00e9 um termo para bolsas pequenas com al\u00e7a longa. Podem ser usadas a tiracolo ou transversalmente, deixando as m\u00e3os livres \u2014 muito \u00fatil para sair \u00e0s compras.<\/span><\/p>\n<p><b>\u201cpochette\u201d<\/b><span style=\"font-weight: 400;\"> vem do franc\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na verdade, em ingl\u00eas n\u00e3o existe uma palavra \u00fanica que signifique<\/span><b>\u00a0<span style=\"color: #ff0000;\">\u201cpochette\u201d<\/span>.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Bolsas pequenas e fofas podem ser chamadas de \u201cpurse\u201d ou \u201chandbag\u201d, mas essas palavras n\u00e3o indicam que tenham al\u00e7a longa ou se usem transversalmente. Se quiser enfatizar isso, pode fazer as seguintes combina\u00e7\u00f5es em ingl\u00eas:<\/span><\/p>\n<h6><b>Bolsa pequena com al\u00e7a longa: a purse with a shoulder strap<\/b><br \/>\n<b>Bolsa transversal pequena: small crossbody bag<\/b><\/h6>\n<p>&nbsp;<\/p>\n<h3><b>crossbody bag\u30fbsling bag<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Tanto as bolsas a tiracolo quanto as pochetes ficam pr\u00f3ximas ao corpo, por isso usam al\u00e7as ou cord\u00f5es para manter a bolsa justa ao corpo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Normalmente, o estilo tiracolo \u00e9 chamado de crossbody bag, e o estilo na cintura \u00e9 chamado de pochete.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em ingl\u00eas, esse tipo de bolsa \u00e9 chamado de\u00a0 <\/span><b><span style=\"color: #ff0000;\">\u201ccrossbody bag\u201d ou \u201csling bag\u201d<\/span>.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u201cCrossbody bag\u201d significa bolsa que cruza o corpo, ou seja, usada a tiracolo, sendo um termo gen\u00e9rico para esse estilo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cSling bag\u201d, sendo \u201csling\u201d o verbo \u201cpendurar\/suspender\u201d, indica uma bolsa pendurada no ombro por uma al\u00e7a ou tira de tecido.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>handbag\u30fbpurse<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Bolsas com al\u00e7a ou pegador para serem carregadas na m\u00e3o s\u00e3o chamadas de bolsas de m\u00e3o, e em ingl\u00eas podem ser chamadas de <\/span><b>\u00a0<span style=\"color: #ff0000;\">\u201cpurse\u201d ou \u201chandbag\u201d<\/span><\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No ingl\u00eas americano, \u201cpurse\u201d \u00e9 o termo para\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201cbolsa de m\u00e3o\/bolsa pequena feminina\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por\u00e9m, em ingl\u00eas brit\u00e2nico, significa\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201ccarteira feminina\u201d<\/b><\/span><span style=\"font-weight: 400;\">, sem o sentido de \u201cbolsa de m\u00e3o\u201d, ent\u00e3o \u00e9 preciso aten\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 \u201chandbag\u201d, pelo pr\u00f3prio nome, \u00e9\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201cbolsa de m\u00e3o\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h6><b>I bought a purse for my mother.<\/b><b><br \/>\n<\/b><b>\u00a0\uff1dI bought a handbag for my mother.<\/b><br \/>\n<span style=\"font-weight: 400;\">Comprei uma bolsa de m\u00e3o para minha m\u00e3e.<\/span><\/h6>\n<p>&nbsp;<\/p>\n<h3><b>tote bag\u30fbtote<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Uma bolsa com abertura grande na parte superior, f\u00e1cil de colocar e tirar objetos, com al\u00e7as nas laterais e formato simples, \u00e9 chamada de tote bag.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em ingl\u00eas, usamos \u201ctote bag\u201d ou apenas\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201ctote\u201d<\/b><\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h5><b>Tote bags are very convenient for all genders.<\/b><br \/>\n<span style=\"font-weight: 400;\">Tote bags s\u00e3o muito pr\u00e1ticas para todos os g\u00eaneros.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Tote bag n\u00e3o tem defini\u00e7\u00e3o precisa, mas a diferen\u00e7a para a bolsa de m\u00e3o \u00e9 que muitas tote bags t\u00eam al\u00e7as mais compridas, podendo ser usadas sobre o ombro.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>traveling bag<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Em ingl\u00eas, qualquer bolsa grande para viagem \u00e9 chamada de\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201ctraveling bag\u201d<\/b><\/span><span style=\"font-weight: 400;\">. No entanto, \u201ctraveling bag\u201d pode tamb\u00e9m incluir malas com rodinhas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, existe a chamada\u00a0 <\/span><span style=\"color: #ff0000;\"><b>\u201cgym bag\u201d<\/b><\/span><span style=\"font-weight: 400;\">, que, como o nome diz, \u00e9 para levar roupas, toalhas ou t\u00eanis quando vai \u00e0 academia, geralmente com fundo largo e espa\u00e7oso.<\/span><\/p>\n<h5><b>Your gym bag looks full! What\u2019s in it?<\/b><br \/>\n<span style=\"font-weight: 400;\">Sua gym bag parece cheia! O que tem dentro?<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Resumo<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Come\u00e7amos explicando o rucksack e apresentamos v\u00e1rios termos em ingl\u00eas relacionados a bolsas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Alguns deles talvez tenham surpreendido voc\u00ea\u00a0 como palavras que parecem inglesas, mas na verdade v\u00eam de outros idiomas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Seja em conversas do dia a dia ou numa viagem a pa\u00edses de l\u00edngua inglesa, se surgir um assunto sobre \u201cbolsas\u201d, n\u00e3o hesite em consultar este artigo e experimentar usar esses termos em ingl\u00eas!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Existem v\u00e1rios tipos de bolsas, como bolsas de ombro, mochilas ou tote bags, entre outros. Embora em ingl\u00eas exista a palavra \u201cbag\u201d para bolsas em geral, termos como \u201crucksack\u201d, \u201cPochette\u201d, \u201cTote bag\u201d talvez n\u00e3o sejam do conhecimento de muita gente quanto aos nomes espec\u00edficos em ingl\u00eas para cada tipo de bolsa. Desta vez, vou come\u00e7ar com rucksack e explicar detalhadamente como expressar os v\u00e1rios tipos de bolsas em ingl\u00eas. &nbsp; Diferen\u00e7a entre Backpack e rucksack &nbsp; As bolsas usadas nas costas geralmente s\u00e3o chamadas de backpack ou rucksack. Pessoas que viajam pelo mundo carregando muita bagagem ou um saco de dormir s\u00e3o chamadas de \u201cbackpacker\u201d. Algumas pessoas podem pensar: \u201cBackpack &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/13570\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":13571,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=13570","footnotes":""},"categories":[134,139,140],"tags":[],"class_list":["post-13570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-overseas-info","category-cultural-exchange","category-study-abroad-nc","pt-BR"],"aioseo_notices":[],"views":578,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=13570"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13570\/revisions"}],"predecessor-version":[{"id":13572,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/13570\/revisions\/13572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/13571"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=13570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=13570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=13570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}