{"id":12691,"date":"2025-10-11T09:00:10","date_gmt":"2025-10-11T12:00:10","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=12691"},"modified":"2025-10-07T04:56:52","modified_gmt":"2025-10-07T07:56:52","slug":"como-se-diz-introvertido-e-extrovertido-em-ingles","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/12691\/","title":{"rendered":"Como se diz \u201cintrovertido\u201d e \u201cextrovertido\u201d em ingl\u00eas?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><span style=\"font-size: 24px;\"><strong>&#8220;Personalidade&#8221;\u00a0<\/strong> <\/span>\u00e9 dividida em v\u00e1rios tipos diferentes. Entre eles,<span style=\"font-size: 32px;\"><strong><span style=\"color: #993300;\"> &#8220;introvertido&#8221; e &#8220;extrovertido&#8221;<\/span> <\/strong><\/span>representam dois desses tipos de personalidade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Geralmente, chamamos uma pessoa quieta de &#8220;introvertido&#8221;. Por outro lado, uma pessoa que consegue conversar amigavelmente com qualquer um logo ao conhec\u00ea-lo \u00e9 chamada de &#8220;extrovertido&#8221;. Ent\u00e3o, como se diz &#8220;introvertido&#8221; e &#8220;extrovertido&#8221; em ingl\u00eas?<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Este artigo vai apresentar as formas de express\u00e3o em ingl\u00eas para <span style=\"font-size: 16px;\"><strong>&#8220;introvertido&#8221; e &#8220;extrovertido&#8221;,<\/strong><\/span>\u00a0com exemplos de frases em ingl\u00eas para sua refer\u00eancia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ambas as express\u00f5es podem ser usadas para descrever &#8220;personalidade&#8221; em ingl\u00eas. Certifique-se de consult\u00e1-las e memoriz\u00e1-las!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Como se diz &#8220;introvertido&#8221; e &#8220;extrovertido&#8221; em ingl\u00eas?<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">As formas em ingl\u00eas para &#8220;introvertido&#8221; e &#8220;extrovertido&#8221; s\u00e3o:<\/span><\/p>\n<p><span style=\"color: #ff0000;\"><b><span style=\"color: #993300;\">Introvertido:<\/span> introvert<\/b><\/span><\/p>\n<p><span style=\"color: #0000ff;\"><b>Extrovertido: extrovert<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apesar de existirem muitas outras formas de expressar <strong><span style=\"color: #0000ff;\">&#8220;personalidade&#8221;<\/span> <\/strong>em ingl\u00eas. Por exemplo, express\u00f5es semelhantes a <span style=\"color: #ff0000;\"><strong><span style=\"color: #993300;\">&#8220;introvertido&#8221;<\/span><\/strong><span style=\"color: #000000;\">, como<\/span><strong><span style=\"color: #993300;\">&#8220;reserved&#8221;<\/span><\/strong><span style=\"color: #000000;\">e<\/span><strong><span style=\"color: #993300;\"> &#8220;shy&#8221;<\/span><\/strong><\/span><span style=\"color: #993300;\">,<\/span> bem como <span style=\"color: #993300;\"><strong>&#8220;extrovertido&#8221; como &#8220;outgoing&#8221;<\/strong>.<\/span><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas, neste artigo, vamos focar em apresentar os termos mais usados em conversa\u00e7\u00e3o cotidiana:<strong> <span style=\"color: #993300;\">&#8220;introvert (introvertido)&#8221;<\/span><\/strong> e <strong><span style=\"color: #993300;\">&#8220;extrovert (extrovertido)&#8221;.<\/span><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>O significado de introvert<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quando estamos aprendendo ingl\u00eas, frequentemente descobrimos que muitas palavras em portugu\u00eas e ingl\u00eas n\u00e3o podem ser simplesmente equiparadas. Portanto, aqui precisamos analisar detalhadamente o significado de introvert.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De acordo com a defini\u00e7\u00e3o do Cambridge Dictionary, &#8220;introvert&#8221; significa:<\/span><\/p>\n<h5><b>someone who is shy, quiet, and prefers to spend time alone rather than often being with other people<\/b><br \/>\n<span style=\"font-weight: 400;\">Tradu\u00e7\u00e3o: representa uma pessoa introvertida, t\u00edmida e tranquila, que prefere ficar sozinha do que estar frequentemente com outras pessoas<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Fonte: Cambridge Dictionary <\/span><br \/>\n<span style=\"font-weight: 400;\">( <\/span><a href=\"https:\/\/dictionary.cambridge.org\/zht\/%E8%A9%9E%E5%85%B8\/%E8%8B%B1%E8%AA%9E-%E6%BC%A2%E8%AA%9E-%E7%B0%A1%E9%AB%94\/introvert\"><span style=\"font-weight: 400;\">https:\/\/dictionary.cambridge.org\/zht\/\u8a5e\u5178\/\u82f1\u8a9e-\u6f22\u8a9e-\u7c21\u9ad4\/introvert<\/span><\/a><span style=\"font-weight: 400;\"> )<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Ou seja, <span style=\"color: #ff0000;\"><span style=\"color: #000000;\">a palavra<\/span><strong> &#8220;introvert&#8221; <\/strong><span style=\"color: #000000;\">carrega o sentido de<\/span><strong> &#8220;shy&#8221;<\/strong><\/span>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na tradu\u00e7\u00e3o em portugu\u00eas, <strong>&#8220;gostar de ficar s\u00f3&#8221;<\/strong> pode passar a impress\u00e3o de que pessoas<strong> &#8220;introvertidas&#8221;<\/strong> est\u00e3o sempre em casa. Mas, na verdade, elas n\u00e3o ficam sempre em casa. Tamb\u00e9m podem sair para frequentar aulas ou at\u00e9 viajar sozinhas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Elas apenas preferem <strong>&#8220;ficar sozinhas do que estar com outras pessoas&#8221;!<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>O significado de extrovert<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Agora, vejamos o significado de &#8220;extrovert&#8221;. De acordo com o Cambridge Dictionary, <strong><span style=\"color: #993300;\">&#8220;extrovert&#8221;<\/span><\/strong> significa:<\/span><\/p>\n<h6><b>an energetic person who enjoys being with other people:<\/b><br \/>\n<span style=\"font-weight: 400;\">Tradu\u00e7\u00e3o: uma pessoa cheia de energia, que gosta de estar com outras pessoas<\/span><\/h6>\n<p><span style=\"font-weight: 400;\">Fonte: Cambridge Dictionary<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0( <\/span><a href=\"https:\/\/dictionary.cambridge.org\/zht\/%E8%A9%9E%E5%85%B8\/%E8%8B%B1%E8%AA%9E-%E6%BC%A2%E8%AA%9E-%E7%B0%A1%E9%AB%94\/extrovert\"><span style=\"font-weight: 400;\">https:\/\/dictionary.cambridge.org\/zht\/\u8a5e\u5178\/\u82f1\u8a9e-\u6f22\u8a9e-\u7c21\u9ad4\/extrovert<\/span><\/a><span style=\"font-weight: 400;\"> \uff09<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Essa tradu\u00e7\u00e3o pode rapidamente fazer voc\u00ea pensar em algu\u00e9m animado, que conversa com v\u00e1rias pessoas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na tradu\u00e7\u00e3o,<span style=\"color: #993300;\"><strong> &#8220;energetic (cheio de energia)&#8221;<\/strong><\/span> \u00e9 um ponto-chave para descrever uma &#8220;pessoa extrovertida&#8221;. Isso mostra que <span style=\"color: #0000ff;\"><strong>&#8220;extrovert&#8221; <\/strong><span style=\"color: #000000;\">descreve algu\u00e9m que sempre causa a impress\u00e3o de ser cheio de vida<\/span><\/span><span style=\"color: #000000;\">.<\/span><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por outro lado, algu\u00e9m descrito como &#8220;introvert&#8221; geralmente passa a impress\u00e3o de ser quieto. Portanto, &#8220;introvert&#8221; e &#8220;extrovert&#8221; s\u00e3o palavras em ingl\u00eas com sentidos opostos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Express\u00f5es comuns em ingl\u00eas: &#8220;introvert&#8221; e &#8220;extrovert&#8221;<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Em portugu\u00eas, n\u00e3o usamos muito as express\u00f5es &#8220;sou introvertido&#8221; ou &#8220;ele \u00e9 extrovertido&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em vez disso, \u00e9 mais comum dizermos <strong>&#8220;t\u00edmido&#8221;<\/strong> ou <strong>&#8220;amig\u00e1vel&#8221;<\/strong>. Em ingl\u00eas, <span style=\"color: #ff0000;\"><strong>&#8220;t\u00edmido&#8221; \u00e9 &#8220;shy&#8221;<\/strong><\/span>, enquanto <span style=\"color: #0000ff;\"><strong>&#8220;soci\u00e1vel&#8221; \u00e9 &#8220;sociable&#8221;<\/strong><\/span>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De fato, &#8220;pessoas introvertidas&#8221; tendem a ser t\u00edmidas, enquanto &#8220;pessoas extrovertidas&#8221; s\u00e3o muito soci\u00e1veis. Mas, voc\u00ea sabe qual \u00e9 a diferen\u00e7a entre &#8220;shy&#8221; e &#8220;sociable&#8221; e &#8220;introvert&#8221; e &#8220;extrovert&#8221;?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, o ant\u00f4nimo de &#8220;soci\u00e1vel&#8221; \u00e9 &#8220;unsociable (antissocial)&#8221;. Este termo tem uma conota\u00e7\u00e3o negativa, <span style=\"color: #ff0000;\"><span style=\"color: #000000;\">mas<\/span><strong> &#8220;introvert (introvertido)&#8221; <\/strong><span style=\"color: #000000;\">n\u00e3o tem qualquer sentido negativo<\/span><\/span><span style=\"color: #000000;\">.<\/span><\/span><br \/>\n<b><br \/>\n<\/b><span style=\"font-weight: 400;\">Como &#8220;introvert&#8221; e &#8220;extrovert&#8221; n\u00e3o t\u00eam sentido positivo nem negativo, s\u00e3o considerados termos neutros em ingl\u00eas. Portanto, ao descrever a personalidade dos outros, &#8220;introvert&#8221; e &#8220;extrovert&#8221; s\u00e3o palavras muito utilizadas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando voc\u00ea diz &#8220;She is an introvert. (Ela \u00e9 uma pessoa introvertida)&#8221; para descrever algu\u00e9m, isso n\u00e3o ser\u00e1 considerado rude. Da mesma forma, se descrever a si mesmo como &#8220;I am an extrovert. (Sou uma pessoa extrovertida)&#8221;, n\u00e3o parece exibido nem depreciativo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Portanto, por serem neutros, &#8220;introvert&#8221; e &#8220;extrovert&#8221; s\u00e3o \u00f3timas escolhas em ingl\u00eas para descrever a si mesmo ou outras pessoas.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Vale mencionar que algumas pessoas podem pensar que estrangeiros s\u00e3o &#8220;soci\u00e1veis (extrovertidos)&#8221;. Mas, na verdade, h\u00e1 muitas pessoas introvertidas nos pa\u00edses de l\u00edngua inglesa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Resumindo, ao se apresentar em ingl\u00eas, n\u00e3o importa se voc\u00ea diz que \u00e9 &#8220;introvert&#8221; ou &#8220;extrovert&#8221;. O outro vai responder &#8220;ah, entendi&#8221; e aceitar numa boa. Por isso, use com confian\u00e7a os termos neutros &#8220;introvert&#8221; e &#8220;extrovert&#8221;!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Exemplos de frases em ingl\u00eas com &#8220;Introvert&#8221; e &#8220;Extrovert&#8221;<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A seguir, apresentamos alguns exemplos de frases com &#8220;introvert&#8221; e &#8220;extrovert&#8221;, junto com a tradu\u00e7\u00e3o para refer\u00eancia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esses di\u00e1logos s\u00e3o frases simples que voc\u00ea pode usar diretamente ao conversar com outras pessoas. Tente memoriz\u00e1-las e use-as em conversas reais!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Exemplos com &#8220;Introvert&#8221;<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>I\u2019m an introvert. Interacting with other people isn\u2019t my thing.<\/b><br \/>\n<span style=\"font-weight: 400;\">Sou uma pessoa introvertida. Interagir com outras pessoas n\u00e3o \u00e9 algo que eu costumo fazer.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">No exemplo acima, usamos a palavra &#8220;introvert&#8221;. Para falar de si mesmo, use &#8220;I\u2019m&#8221; para indicar sua personalidade. \u00c9 poss\u00edvel trocar por &#8220;He&#8221;, &#8220;She&#8221;, &#8220;They&#8221;, &#8220;My family&#8221; como sujeito para descrever a personalidade de outras pessoas. Voc\u00ea at\u00e9 pode usar frases como &#8220;My dog seems to be an introvert. (Meu cachorro parece ser introvertido)&#8221; para descrever o temperamento de animais.<\/span><\/p>\n<h5><b>Introverted people tend to spend time alone, but it doesn\u2019t mean they don\u2019t have friends.<\/b><br \/>\n<span style=\"font-weight: 400;\">Pessoas introvertidas tendem a passar tempo sozinhas, mas isso n\u00e3o significa que n\u00e3o tenham amigos.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Neste exemplo, usamos o adjetivo &#8220;introverted&#8221;. &#8220;Introverted&#8221; \u00e9 um adjetivo, e &#8220;introvert&#8221; \u00e9 um substantivo. Sem conhecimento de gram\u00e1tica, pode ser dif\u00edcil diferenciar o uso dos dois. Embora seja poss\u00edvel dizer &#8220;I am beautiful.&#8221; (Eu sou bonita) usando o padr\u00e3o &#8220;sujeito + verbo to be + adjetivo&#8221;, no caso de &#8220;introvertido&#8221;, a frase &#8220;I am an introvert. (Sou introvertido)&#8221; \u00e9 bem mais comum do que &#8220;I am introverted. (Sou introvertido)&#8221;.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Exemplos com &#8220;Extrovert&#8221;<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O uso de extrovert \u00e9 igual ao de introvert, confira os exemplos abaixo:<\/span><\/p>\n<h5><b>He is such an extrovert! He finds new friends everywhere.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ele \u00e9 t\u00e3o extrovertido! Ele faz novos amigos em qualquer lugar.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Although she is an introvert herself, she likes extroverted guys.<\/b><br \/>\n<span style=\"font-weight: 400;\">Embora ela seja introvertida, ela gosta de homens extrovertidos.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Como mostrado acima, para dizer &#8220;algu\u00e9m extrovertido&#8221;, use &#8220;extroverted + substantivo&#8221;. Funciona como &#8220;beautiful lady&#8221;, com o padr\u00e3o &#8220;adjetivo + substantivo&#8221;.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Resumo<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quando voc\u00ea conhecer estrangeiros ou encontrar professores pela primeira vez em plataformas de conversa\u00e7\u00e3o online como o &#8220;Native Camp&#8221;, talvez precise se apresentar em ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os exemplos de frases com &#8220;introvert&#8221; e &#8220;extrovert&#8221; apresentados neste artigo podem ser muito \u00fateis para voc\u00ea se apresentar de forma mais detalhada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Certifique-se de usar &#8220;introvert&#8221; e &#8220;extrovert&#8221; ao se apresentar para professores no &#8220;Native Camp&#8221;, ou ent\u00e3o ao perguntar sobre a personalidade do seu professor tamb\u00e9m!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Personalidade&#8221;\u00a0 \u00e9 dividida em v\u00e1rios tipos diferentes. Entre eles, &#8220;introvertido&#8221; e &#8220;extrovertido&#8221; representam dois desses tipos de personalidade. Geralmente, chamamos uma pessoa quieta de &#8220;introvertido&#8221;. Por outro lado, uma pessoa que consegue conversar amigavelmente com qualquer um logo ao conhec\u00ea-lo \u00e9 chamada de &#8220;extrovertido&#8221;. Ent\u00e3o, como se diz &#8220;introvertido&#8221; e &#8220;extrovertido&#8221; em ingl\u00eas? Este artigo vai apresentar as formas de express\u00e3o em ingl\u00eas para &#8220;introvertido&#8221; e &#8220;extrovertido&#8221;,\u00a0com exemplos de frases em ingl\u00eas para sua refer\u00eancia. Ambas as express\u00f5es podem ser usadas para descrever &#8220;personalidade&#8221; em ingl\u00eas. Certifique-se de consult\u00e1-las e memoriz\u00e1-las! &nbsp; Como se diz &#8220;introvertido&#8221; e &#8220;extrovertido&#8221; em ingl\u00eas? &nbsp; As formas em ingl\u00eas para &#8220;introvertido&#8221; e &#8220;extrovertido&#8221; s\u00e3o: &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/12691\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":12692,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=12691","footnotes":""},"categories":[126,129,128],"tags":[],"class_list":["post-12691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-daily","category-children","category-business","pt-BR"],"aioseo_notices":[],"views":962,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=12691"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12691\/revisions"}],"predecessor-version":[{"id":12693,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12691\/revisions\/12693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/12692"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=12691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=12691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=12691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}