{"id":12684,"date":"2025-10-11T09:00:45","date_gmt":"2025-10-11T12:00:45","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=12684"},"modified":"2025-10-07T04:15:03","modified_gmt":"2025-10-07T07:15:03","slug":"como-usar-complement-e-compliment","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/12684\/","title":{"rendered":"Como usar \u201cComplement\u201d e \u201cCompliment\u201d?"},"content":{"rendered":"<p dir=\"ltr\">&#8220;O significado de uma palavra em ingl\u00eas pode mudar drasticamente por causa de apenas uma letra.&#8221; Muitas pessoas encontram esse tipo de palavra e acham um pouco dif\u00edcil na hora de pensar a respeito.<\/p>\n<p dir=\"ltr\">Desta vez, vamos focar nas diferen\u00e7as entre<span style=\"font-size: 32px;\"><span style=\"color: #db12b3;\"><strong> &#8220;Complement&#8221; e &#8220;Compliment&#8221;<\/strong><\/span>.<\/span><\/p>\n<p dir=\"ltr\">Como ambas s\u00e3o palavras mais longas, \u00e9 dif\u00edcil perceber de imediato as diferen\u00e7as. No di\u00e1logo di\u00e1rio, se usar a palavra errada, a mensagem que voc\u00ea deseja passar pode ser completamente diferente. Para evitar isso, tamb\u00e9m podemos aprender juntos outras palavras em ingl\u00eas de ortografia similar, mas com significados diferentes.<\/p>\n<h2 dir=\"ltr\"><strong>Cada uma tem seu significado<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Primeiro, vamos ver o significado de\u00a0 <strong><span style=\"color: #ff0000;\">&#8220;complement&#8221;<\/span> e <span style=\"color: #0000ff;\">&#8220;compliment&#8221;<\/span><\/strong>.<\/p>\n<p dir=\"ltr\">Essas palavras t\u00eam um n\u00edvel de dificuldade bastante alto, acima do b\u00e1sico dos exames de ingl\u00eas, por isso alguns podem estar vendo-as pela primeira vez. Se for o seu caso, memorize a dica de distin\u00e7\u00e3o abaixo.<\/p>\n<h3 dir=\"ltr\"><strong>Complement<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">&#8220;Complement&#8221; \u00e9 pronunciado como k\u0251\u0301mpl\u0259m\u0259nt (usada como substantivo). Quando usada como substantivo, significa <span style=\"color: #ff0000;\"><strong>&#8220;complemento&#8221;<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">Isto inclui a ideia de &#8220;algo que completa por meio da adi\u00e7\u00e3o&#8221;. Tamb\u00e9m pode ter o significado de totalidade.<\/p>\n<p dir=\"ltr\">Quando &#8220;Complement&#8221; \u00e9 verbo, \u00e9 um verbo transitivo que acompanha um objeto, significando <span style=\"color: #ff0000;\"><strong>&#8220;completar, suplementar, complementar ou real\u00e7ar (algo)&#8221;<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">[Exemplo como substantivo]<\/p>\n<h5 dir=\"ltr\"><strong>Rice makes an excellent complement to a curry dish.<\/strong><br \/>\nArroz \u00e9 um excelente complemento para um prato de curry.<\/h5>\n<h5 dir=\"ltr\"><strong>The shoes were the perfect complement to the entire outfit.<\/strong><br \/>\nO sapato era o complemento perfeito para todo o conjunto.<\/h5>\n<p dir=\"ltr\"><span style=\"color: #ff9900;\">[Exemplo como verbo]<\/span><\/p>\n<h5 dir=\"ltr\"><strong>There will be a written examination to complement the practical test.<\/strong><br \/>\nHaver\u00e1 um exame escrito para complementar o teste pr\u00e1tico.<\/h5>\n<h5 dir=\"ltr\"><strong>The two suggestions complement each other.<\/strong><br \/>\nAs duas sugest\u00f5es se complementam.<\/h5>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>Compliment<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">&#8220;Compliment&#8221; \u00e9 pronunciado como k\u0251\u0301mpl\u0259m\u0259nt (usada como substantivo). O som \u00e9 o mesmo de &#8220;complement&#8221;, ent\u00e3o n\u00e3o d\u00e1 para distinguir apenas pela audi\u00e7\u00e3o.<\/p>\n<p dir=\"ltr\">&#8220;Compliment&#8221; como substantivo significa <span style=\"color: #0000ff;\"><strong>&#8220;elogio, cumprimento&#8221;<\/strong><\/span>. Tamb\u00e9m, quando usada como verbo, significa <span style=\"color: #0000ff;\"><strong>&#8220;elogiar, cumprimentar, fazer um agrado, bajular, enaltecer&#8221;<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">[Exemplo como substantivo]<\/p>\n<h5 dir=\"ltr\"><strong>Nigel said his teacher gave him a compliment on how well he played the guitar.<\/strong><br \/>\nNigel disse que seu professor lhe fez um elogio pela forma como tocou guitarra.<\/h5>\n<h5 dir=\"ltr\"><strong>He received a nice compliment the day before yesterday.<\/strong><br \/>\nEle recebeu um \u00f3timo elogio anteontem.<\/h5>\n<p dir=\"ltr\">Ali\u00e1s, <span style=\"color: #ff0000;\">&#8220;compliment&#8221;<\/span> j\u00e1 significa<span style=\"color: #00ff00;\"> &#8220;elogio&#8221;,<\/span> mas tamb\u00e9m pode ser usada na express\u00e3o <span style=\"color: #0000ff;\"><strong>&#8220;give a compliment (elogiar)&#8221;<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">[Exemplo como verbo]<\/p>\n<h5 dir=\"ltr\"><strong>John said he always gets complimented when he gets a fresh haircut.<\/strong><br \/>\nJohn disse que sempre recebe elogios quando corta o cabelo.<\/h5>\n<h5 dir=\"ltr\"><strong>He complimented the child on his good behavior.<\/strong><br \/>\nEle elogiou a boa conduta da crian\u00e7a.<\/h5>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">Dicas para diferenciar Complement e Compliment<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">\u00c9 dif\u00edcil lembrar de &#8220;complement&#8221; e &#8220;compliment&#8221;, pois s\u00f3 diferem por uma letra, n\u00e3o \u00e9? Existem algumas dicas para ajudar a diferenciar e memorizar. Uma delas \u00e9 &#8220;memorizar o significado de uma delas&#8221;.<\/p>\n<p dir=\"ltr\">Como j\u00e1 mencionado, a \u00fanica diferen\u00e7a de ortografia entre as duas est\u00e1 na letra ap\u00f3s o L, que pode ser E ou I. Por isso, memorize firme que com I ap\u00f3s o L, &#8220;compliment&#8221; significa &#8220;elogio, cumprimento&#8221;!<\/p>\n<p dir=\"ltr\">Nossa t\u00e9cnica sugerida \u00e9 brincar de associa\u00e7\u00e3o: <strong><span style=\"color: #0000ff;\">&#8220;O I de compliment \u2192 eu (I) \u2192 elogio para mim&#8221;.<\/span><\/strong><\/p>\n<p dir=\"ltr\">Ali\u00e1s, lembre-se de frases que elogiam a si mesmo, como I like my face (gosto do meu rosto), junto com compliment contendo a letra I, que significa &#8220;elogio&#8221;.<\/p>\n<p dir=\"ltr\">Se, ao memorizar, voc\u00ea imaginar &#8220;ficar encantado com seu reflexo no espelho&#8221;, vai se lembrar ainda mais r\u00e1pido!<\/p>\n<p dir=\"ltr\">Ao decorar vocabul\u00e1rio, se tentar guardar apenas significado e grafia, pode levar um pouco mais de tempo. Mas usando associa\u00e7\u00f5es e imagens, o aprendizado ser\u00e1 mais r\u00e1pido!<\/p>\n<p dir=\"ltr\">Assim, compliment significa &#8220;elogio&#8221;, ent\u00e3o quando aparece o E ap\u00f3s outro L, \u00e9 &#8220;complement&#8221; = &#8220;complemento&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\">Outros pares de palavras similares<\/h2>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">Al\u00e9m de &#8220;complement&#8221; e &#8220;compliment&#8221;, h\u00e1 outras palavras em ingl\u00eas cujo significado muda completamente devido a uma \u00fanica letra.<\/p>\n<p dir=\"ltr\">Vamos conhecer algumas delas a seguir. N\u00e3o s\u00f3 os significados e diferen\u00e7as, mas tamb\u00e9m a pron\u00fancia e dicas para memorizar.<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>&#8220;Desert&#8221; e &#8220;Dessert&#8221;<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"color: #ff0000;\"><strong>&#8220;Desert&#8221;,<\/strong><span style=\"color: #000000;\"> como substantivo<\/span><strong><span style=\"color: #000000;\">,<\/span><\/strong><span style=\"color: #000000;\"> significa <\/span><strong>&#8220;deserto&#8221;<\/strong><\/span> e, como adjetivo, quer dizer &#8220;\u00e1rido, inabitado&#8221;. Por outro lado, <span style=\"color: #0000ff;\"><strong>&#8220;dessert&#8221; significa &#8220;sobremesa&#8221;<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">Voc\u00ea deve ter notado que a diferen\u00e7a est\u00e1 na quantidade de &#8220;s&#8221;. Se tem um &#8220;s&#8221;, \u00e9 &#8220;desert&#8221;; se s\u00e3o dois &#8220;s&#8221;, \u00e9 &#8220;dessert&#8221;. E a pron\u00fancia tamb\u00e9m \u00e9 diferente.<\/p>\n<p dir=\"ltr\">&#8220;Desert&#8221; (deserto) tem a \u00eanfase no in\u00edcio: &#8220;de&#8221; (s\u00edlaba t\u00f4nica). J\u00e1 &#8220;dessert&#8221; (sobremesa) tem \u00eanfase no segundo &#8220;e&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>&#8220;Bear&#8221; e &#8220;Bare&#8221;<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">S\u00e3o parecidas, mas os significados s\u00e3o bem diferentes. <span style=\"color: #ff0000;\"><span style=\"color: #000000;\">O substantivo<\/span><strong> &#8220;Bear&#8221; (pron\u00fancia: b\u03ad\u0259r<\/strong><span style=\"color: #000000;\">) significa urso. Como verbo, pode significar<\/span><strong> &#8220;nascer&#8221;, &#8220;suportar&#8221;, &#8220;adquirir&#8221;<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">J\u00e1 como adjetivo, <span style=\"color: #0000ff;\"><strong>&#8220;bare&#8221; quer dizer &#8220;nu, exposto, pouco&#8221;. Como verbo, significa &#8220;expor, desnudar&#8221;<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">Ali\u00e1s, &#8220;bare&#8221; como g\u00edria brit\u00e2nica quer dizer &#8220;muito&#8221;, e \u00e0s vezes se usa &#8220;Bare cool!&#8221;, mas \u00e9 uma express\u00e3o vulgar; evite utiliz\u00e1-la.<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>&#8220;Lose&#8221; e &#8220;Loose&#8221;<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"color: #ff0000;\"><strong>&#8220;Lose&#8221; como transitivo significa &#8220;perder&#8221;, &#8220;excluir&#8221;. Como intransitivo, &#8220;falhar (em exame)&#8221; ou &#8220;sofrer preju\u00edzo&#8221;.<\/strong><\/span><\/p>\n<p dir=\"ltr\">J\u00e1 &#8220;loose&#8221;, com dois &#8220;o&#8221;, como adjetivo, significa <span style=\"color: #0000ff;\"><strong>&#8220;solto&#8221; ou &#8220;afrouxado&#8221;<\/strong><\/span>. Como verbo intransitivo, <span style=\"color: #0000ff;\"><strong>&#8220;afrouxar&#8221;<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">A melhor forma de memorizar \u00e9 igual \u00e0 de dessert: lembre-se que com dois &#8220;o&#8221; (&#8220;loose&#8221;) significa &#8220;afrouxar&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><strong>&#8220;Plain&#8221; e &#8220;Plane&#8221;<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"color: #ff0000;\"><strong>&#8220;Plain&#8221; como adjetivo significa &#8220;f\u00e1cil de entender, \u00f3bvio, claro&#8221;<\/strong><\/span>. <span style=\"color: #0000ff;\"><strong>&#8220;Plane&#8221; como substantivo \u00e9 &#8220;avi\u00e3o&#8221;, e como adjetivo, &#8220;plano&#8221;<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">A transcri\u00e7\u00e3o fon\u00e9tica para ambas \u00e9 &#8220;pl\u00e9in&#8221;. Infelizmente, n\u00e3o d\u00e1 para distinguir pela pron\u00fancia. Ent\u00e3o, recorra novamente \u00e0 associa\u00e7\u00e3o!<\/p>\n<p dir=\"ltr\">Plain = &#8220;f\u00e1cil de entender&#8221;<\/p>\n<p dir=\"ltr\">Lembre-se de que, depois de &#8220;f\u00e1cil de entender&#8221;, vem &#8220;explicar&#8221;. &#8220;Explicar&#8221; em ingl\u00eas \u00e9 &#8220;explain&#8221;.<\/p>\n<p dir=\"ltr\">Se voc\u00ea reparar, &#8220;plain&#8221; est\u00e1 escondido dentro de &#8220;explain&#8221;! Assim, quando estiver em d\u00favida sobre &#8220;plain&#8221;, pense em &#8220;explain&#8221; e lembre-se: &#8220;de f\u00e1cil entendimento&#8221;.<\/p>\n<h3 dir=\"ltr\"><strong>&#8220;Adapt&#8221; e &#8220;Adopt&#8221;<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\"><span style=\"color: #ff0000;\"><strong>&#8220;Adapt&#8221; significa &#8220;adaptar-se\/mudar de acordo com circunst\u00e2ncias&#8221;<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">Ali\u00e1s, a pron\u00fancia \u00e9 &#8220;\u0259d\u01fdpt&#8221;. Por outro lado, <span style=\"color: #0000ff;\"><strong>&#8220;adopt&#8221; significa &#8220;escolher (entre v\u00e1rias op\u00e7\u00f5es), adotar, introduzir, adotar uma crian\u00e7a&#8221;<\/strong><\/span>.<\/p>\n<p dir=\"ltr\">A pron\u00fancia \u00e9 &#8220;\u0259d\u0251\u0301pt&#8221;, que difere um pouco de &#8220;adapt&#8221;. No som de &#8220;adapt&#8221;, o &#8220;a&#8221; ap\u00f3s o &#8220;d&#8221; soa como (\u01fd), enquanto em &#8220;adopt&#8221;, o &#8220;o&#8221; ap\u00f3s o &#8220;d&#8221; soa como (a).<\/p>\n<p dir=\"ltr\">As pron\u00fancias s\u00e3o semelhantes, fique atento ao ouvir. Sugerimos memorizar essas palavras de ortografias e sons parecidos junto com as palavras que costumam ser usadas com elas.<\/p>\n<p dir=\"ltr\">Por exemplo, &#8220;adopt&#8221; aparece em &#8220;adopted child&#8221; (crian\u00e7a adotada = filho adotivo) ou &#8220;adopt an idea&#8221; (adotar uma ideia).<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\"><strong>Resumo<\/strong><\/h2>\n<p>Desta vez apresentamos &#8220;complement&#8221; e &#8220;compliment&#8221;, palavras de ortografia parecida, mas significados completamente diferentes. A primeira \u00e9 &#8220;complemento&#8221; e a segunda significa &#8220;elogio&#8221;.<\/p>\n<p dir=\"ltr\">Apresentamos tamb\u00e9m outros pares de palavras semelhantes. Memorizar palavras de ortografia e pron\u00fancia igual pode ser dif\u00edcil, n\u00e3o \u00e9?<\/p>\n<p dir=\"ltr\">Nestes casos, algumas t\u00e9cnicas de memoriza\u00e7\u00e3o s\u00e3o &#8220;memorizar palavra e imagem juntos&#8221;, &#8220;utilizar jogos de associa\u00e7\u00e3o com outras palavras&#8221; e &#8220;memorizar junto de express\u00f5es comumente usadas&#8221;. Experimente pelo menos uma dessas t\u00e9cnicas! Com certeza vai melhorar!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O significado de uma palavra em ingl\u00eas pode mudar drasticamente por causa de apenas uma letra.&#8221; Muitas pessoas encontram esse tipo de palavra e acham um pouco dif\u00edcil na hora de pensar a respeito. Desta vez, vamos focar nas diferen\u00e7as entre &#8220;Complement&#8221; e &#8220;Compliment&#8221;. Como ambas s\u00e3o palavras mais longas, \u00e9 dif\u00edcil perceber de imediato as diferen\u00e7as. No di\u00e1logo di\u00e1rio, se usar a palavra errada, a mensagem que voc\u00ea deseja passar pode ser completamente diferente. Para evitar isso, tamb\u00e9m podemos aprender juntos outras palavras em ingl\u00eas de ortografia similar, mas com significados diferentes. Cada uma tem seu significado &nbsp; Primeiro, vamos ver o significado de\u00a0 &#8220;complement&#8221; e &#8220;compliment&#8221;. Essas palavras &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/12684\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":12685,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=12684","footnotes":""},"categories":[119,126,125],"tags":[],"class_list":["post-12684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basic","category-daily","category-practice","pt-BR"],"aioseo_notices":[],"views":210,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=12684"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12684\/revisions"}],"predecessor-version":[{"id":12686,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12684\/revisions\/12686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/12685"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=12684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=12684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=12684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}