{"id":12539,"date":"2025-10-13T09:00:41","date_gmt":"2025-10-13T12:00:41","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=12539"},"modified":"2025-10-08T00:38:24","modified_gmt":"2025-10-08T03:38:24","slug":"2024-como-viver-de-forma-simples-nos-estados-unidos-em-meio-ao-aumento-dos-precos","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/12539\/","title":{"rendered":"[2024] Como viver de forma simples nos Estados Unidos em meio ao aumento dos pre\u00e7os?"},"content":{"rendered":"<h2><strong>Os pre\u00e7os nos Estados Unidos s\u00e3o mais altos do que em Taiwan?<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Frequentemente ouvimos a afirma\u00e7\u00e3o &#8220;os pre\u00e7os nos EUA s\u00e3o muito altos&#8221;, mas ser\u00e1 que isso \u00e9 verdade?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nos \u00faltimos anos, devido \u00e0 s\u00e9ria quest\u00e3o da infla\u00e7\u00e3o, os pre\u00e7os realmente dispararam em Nova Iorque e S\u00e3o Francisco. Por exemplo, <span style=\"color: #ff0000;\"><strong>uma caixa de ovos no supermercado pode custar at\u00e9 6 d\u00f3lares americanos (aproximadamente 200 TWD)<\/strong><\/span>. Em Taiwan, uma caixa de ovos por 100 TWD j\u00e1 \u00e9 considerada cara, ainda assim, \u00e9 metade do pre\u00e7o nos EUA \u2014 a diferen\u00e7a de pre\u00e7os \u00e9 evidente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Outros exemplos incluem <span style=\"color: #ff0000;\"><strong>um sandu\u00edche de 18 d\u00f3lares americanos (aproximadamente 600 TWD), tarifas de t\u00e1xi aumentaram 23% e alugu\u00e9is subiram 500 d\u00f3lares de uma vez (aproximadamente 16.500 TWD)<\/strong><\/span>, for\u00e7ando muitos residentes a se mudarem. Isso mostra o qu\u00e3o amplo \u00e9 o impacto da infla\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voltando o olhar para Taiwan, \u00e9 verdade que desde a era p\u00f3s-pandemia, todos os pre\u00e7os relacionados \u00e0 vida cotidiana aumentaram gradualmente, mas ainda assim, a diferen\u00e7a em rela\u00e7\u00e3o aos EUA \u00e9 grande.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Qu\u00e3o alto \u00e9 o \u00edndice de pre\u00e7os ao consumidor nos Estados Unidos?<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Desde 2000, o \u00edndice de pre\u00e7os ao consumidor dos EUA j\u00e1 atingiu a meta de 2%. Sob a \u00f3tica do desenvolvimento econ\u00f4mico, uma infla\u00e7\u00e3o moderada n\u00e3o \u00e9 algo ruim; com o aumento dos sal\u00e1rios, o poder de consumo das pessoas cresce, impulsionando a economia nacional. Por isso, na \u00e9poca, a situa\u00e7\u00e3o fiscal dos EUA era considerada muito boa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, em vez de atribuir o sucesso dos EUA apenas a decis\u00f5es financeiras corretas, o principal motivo foi o r\u00e1pido crescimento econ\u00f4mico da Brasil naquele per\u00edodo, aumentando a demanda por petr\u00f3leo cru e, consequentemente, elevando o pre\u00e7o do petr\u00f3leo a um resultado adicional desse processo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Naquele tempo, os maiores aumentos de pre\u00e7os aconteceram principalmente em bens de primeira necessidade como gasolina, eletricidade e alimentos. Segundo estat\u00edsticas, desde 2000, <span style=\"color: #0000ff;\"><strong>a gasolina chegou a ter um aumento de at\u00e9 2,9 vezes, contas de eletricidade subiram 1,7 vezes e o pre\u00e7o dos alimentos foi 1,5 vezes maior<\/strong><\/span>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>A renda m\u00e9dia nos EUA tamb\u00e9m \u00e9 mais alta?<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Em muitos pa\u00edses desenvolvidos do mundo, incluindo os Estados Unidos, pre\u00e7os e sal\u00e1rios geralmente flutuam com o livre com\u00e9rcio do mercado de capitais.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Isso \u00e9 muito diferente de Taiwan, onde, mesmo que n\u00e3o haja grandes mudan\u00e7as econ\u00f4micas, o Banco Central pode regular e controlar o valor do d\u00f3lar taiwan\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em Taiwan, normalmente consideramos uma renda anual acima de um milh\u00e3o de NTD como muito boa, j\u00e1 sendo parte do 1% mais rico do pa\u00eds. Em contraste, em muitos pa\u00edses desenvolvidos, o desenvolvimento econ\u00f4mico causa grande impacto nas flutua\u00e7\u00f5es de pre\u00e7os. Por isso, <span style=\"color: #0000ff;\"><strong>um americano com renda anual de apenas um milh\u00e3o de NTD pode sentir bastante press\u00e3o em sua vida. De acordo com pesquisas, nos EUA \u00e9 necess\u00e1rio ter uma renda anual de 122.000 d\u00f3lares americanos (cerca de 4 milh\u00f5es de NTD) para manter o padr\u00e3o m\u00ednimo de vida<\/strong><\/span>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Comparando, em 2021 a renda m\u00e9dia em Taiwan foi de 30 mil d\u00f3lares americanos, enquanto nos EUA foi de 94.700 d\u00f3lares americanos (cerca de 3,11 milh\u00f5es de NTD), uma diferen\u00e7a de cerca de tr\u00eas vezes.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Como ir trabalhar nos Estados Unidos<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea deseja estudar nos Estados Unidos, \u00e9 necess\u00e1rio primeiro obter um visto. Como a documenta\u00e7\u00e3o exigida para a solicita\u00e7\u00e3o \u00e9 extensa, \u00e9 importante come\u00e7ar a se preparar cedo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, para viver no local, talvez voc\u00ea precise considerar a busca de emprego. Abaixo est\u00e3o alguns pontos importantes sobre como conseguir trabalho nos EUA.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>O programa de trabalho nas f\u00e9rias para jovens n\u00e3o se aplica aos EUA<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O chamado trabalho de f\u00e9rias \u00e9 destinado a jovens entre 18 e 30 anos, permitindo que viajem e trabalhem por um a tr\u00eas anos em dezoito pa\u00edses que possuem acordo firmado com Taiwan.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por meio do trabalho de f\u00e9rias, al\u00e9m de vivenciar a cultura local, \u00e9 poss\u00edvel compartilhar a cultura e caracter\u00edsticas do seu pr\u00f3prio pa\u00eds com outros jovens estrangeiros. Durante a experi\u00eancia, al\u00e9m do tempo livre para planejar suas pr\u00f3prias atividades, \u00e9 necess\u00e1rio realizar uma certa quantidade de trabalho em troca de alimenta\u00e7\u00e3o e hospedagem. \u00c9 uma atividade muito popular entre os jovens.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"color: #ff0000;\"><strong>Atualmente, Taiwan possui acordo de trabalho de f\u00e9rias com 18 pa\u00edses: Nova Zel\u00e2ndia, Austr\u00e1lia, Jap\u00e3o, Canad\u00e1, Alemanha, Coreia do Sul, Reino Unido, Irlanda, B\u00e9lgica, Eslov\u00e1quia, Pol\u00f4nia, Hungria, \u00c1ustria, Rep\u00fablica Tcheca, Fran\u00e7a, Luxemburgo, Holanda e Israel<\/strong><\/span>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O trabalho de f\u00e9rias \u00e9 uma experi\u00eancia internacional que combina viagem, aprendizagem de idiomas e trabalho. O objetivo principal n\u00e3o \u00e9 ganhar dinheiro, mas sim interagir constantemente com estrangeiros, o que pode ser visto como uma alternativa ao interc\u00e2mbio tradicional para quem quer aprender outro idioma.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, <span style=\"color: #0000ff;\"><strong>quem quer ir para os EUA fazer trabalho de f\u00e9rias para aprender ingl\u00eas pode se decepcionar, pois Taiwan e os Estados Unidos ainda n\u00e3o assinaram esse tipo de acordo. Ou seja, se quiser ficar mais tempo nos EUA, provavelmente ter\u00e1 que conseguir um emprego por conta pr\u00f3pria<\/strong><\/span>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, se seu objetivo \u00e9 apenas vivenciar o trabalho nas f\u00e9rias em um pa\u00eds de l\u00edngua inglesa, Austr\u00e1lia e Canad\u00e1 tamb\u00e9m s\u00e3o escolhas populares.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Obtenha o visto J-1<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Uma das formas de trabalhar nos EUA \u00e9 conseguir o <span style=\"color: #ff0000;\"><strong>visto de interc\u00e2mbio para visitantes<\/strong><\/span> emitido pelo Departamento de Estado americano, conhecido como visto J-1. Com o visto J-1, o requerente pode trabalhar como estagi\u00e1rio remunerado em ocupa\u00e7\u00f5es permitidas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como voc\u00ea pode imaginar, muitas pessoas em todo o mundo se inscrevem para trabalhar nos EUA todos os anos, por isso, nos \u00faltimos anos, a obten\u00e7\u00e3o de vistos de trabalho tornou-se extremamente dif\u00edcil.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No caso do visto J-1, os requisitos s\u00e3o mais flex\u00edveis do que os vistos de trabalho tradicionais, e o per\u00edodo m\u00e1ximo de perman\u00eancia \u00e9 de um ano e meio, o que se assemelha ao per\u00edodo de trabalho em programas de f\u00e9rias, sendo por isso popular entre quem quer experi\u00eancias de trabalho tempor\u00e1rio nos EUA.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apesar de ter semelhan\u00e7as com o programa de trabalho e f\u00e9rias mencionado anteriormente, \u00e9 importante notar que o trabalho de f\u00e9rias \u00e9 voltado para vivenciar o pa\u00eds e viajar, enquanto o visto J-1 tem como principal objetivo o est\u00e1gio profissional. Afinal, o participante tamb\u00e9m recebe sal\u00e1rio, que pode ser utilizado para cobrir custos de vida e estudo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante o processo de obten\u00e7\u00e3o do visto J-1, um dos documentos essenciais \u00e9 o DS-2019, que s\u00f3 pode ser emitido atrav\u00e9s de institui\u00e7\u00f5es espec\u00edficas aprovadas pelo governo dos EUA.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Outra diferen\u00e7a importante em rela\u00e7\u00e3o ao trabalho de f\u00e9rias \u00e9 que <span style=\"color: #ff0000;\"><strong>para o visto J-1 voc\u00ea precisa garantir um local de est\u00e1gio antes de ir para os Estados Unidos. Portanto, \u00e9 necess\u00e1rio que o candidato encontre por conta pr\u00f3pria uma empresa ou institui\u00e7\u00e3o com vagas dispon\u00edveis e fa\u00e7a a solicita\u00e7\u00e3o<\/strong><\/span>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Trabalhar nos Estados Unidos como estudante<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Acredito que a maioria das pessoas que v\u00e3o estudar nos EUA obt\u00e9m o visto de estudante! Em princ\u00edpio, <span style=\"color: #ff0000;\"><strong>este visto \u00e9 concedido a estrangeiros para estudar, por isso, exceto por trabalhos de at\u00e9 20 horas semanais, realizar outros empregos remunerados \u00e9 ilegal<\/strong><\/span>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O que foi dito acima <span style=\"color: #0000ff;\"><strong>refere-se a estudantes universit\u00e1rios ou de p\u00f3s-gradua\u00e7\u00e3o, j\u00e1 para quem vai a escolas de idiomas, h\u00e1 regras diferenciadas<\/strong><\/span>. Outro ponto a observar \u00e9 que algumas universidades imp\u00f5em crit\u00e9rios m\u00ednimos de desempenho acad\u00eamico para autorizar o trabalho, ent\u00e3o \u00e9 importante verificar os requisitos da universidade ao se inscrever.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Trabalhar nos Estados Unidos como volunt\u00e1rio internacional<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Se o objetivo \u00e9 apenas vivenciar a experi\u00eancia de vida nos EUA sem considerar a renda, participar de atividades de voluntariado pode ser uma excelente alternativa. Os americanos valorizam muito o engajamento social, por isso h\u00e1 uma ampla variedade de atividades volunt\u00e1rias, como distribui\u00e7\u00e3o de alimentos no centro da cidade ou em igrejas, limpeza da comunidade, ou at\u00e9 recrea\u00e7\u00e3o infantil, todas com participa\u00e7\u00e3o volunt\u00e1ria.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c0s vezes, participar dessas atividades volunt\u00e1rias ainda pode render alguns cr\u00e9ditos universit\u00e1rios. Para os americanos, diversas a\u00e7\u00f5es de caridade s\u00e3o insepar\u00e1veis do cotidiano. Se tiver oportunidade, vale a pena prestar aten\u00e7\u00e3o para saber se asilos, brigadas de inc\u00eandio ou igrejas est\u00e3o recrutando volunt\u00e1rios, motoristas para levar fi\u00e9is aos cultos, ou promovendo campanhas de doa\u00e7\u00e3o.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Se quiser economizar em alimenta\u00e7\u00e3o e moradia, recomendo experimentar o Workaway<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00ea j\u00e1 ouviu falar do termo Workaway?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em resumo, em lares anfitri\u00f5es que fornecem hospedagem, <span style=\"color: #ff0000;\"><strong>basta dedicar quatro a cinco horas por dia a trabalhos dom\u00e9sticos designados para garantir refei\u00e7\u00f5es e alojamento gratuitos<\/strong><\/span>. \u00c9 uma plataforma que conecta pessoas procurando por hospedagem a anfitri\u00f5es precisando de ajuda com tarefas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O esp\u00edrito do trabalho em troca de hospedagem \u00e9 que nada envolve dinheiro. Como quem trabalha presta apenas assist\u00eancia em tarefas simples, n\u00e3o h\u00e1 sal\u00e1rio, mas sim a chance de obter alimenta\u00e7\u00e3o e acomoda\u00e7\u00e3o sem custo. Ambos os lados t\u00eam status igual, convivendo sob o mesmo teto como amigos ou fam\u00edlia. <span style=\"color: #0000ff;\"><strong>Para quem quer experimentar culturas diferentes e economizar com refei\u00e7\u00f5es e hospedagem, \u00e9 extremamente atraente.<\/strong><\/span><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Workaway foi criado em 2002 por um mochileiro brit\u00e2nico. Em Taiwan, talvez algumas pessoas j\u00e1 tenham participado ou ouvido falar, sendo uma forma bastante popular de viajar pelo mundo. Al\u00e9m dos EUA, h\u00e1 oportunidades em mais de 176 pa\u00edses.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O ponto mais atrativo do trabalho em troca de hospedagem \u00e9 que, ao fornecer cerca de cinco horas de servi\u00e7o, cinco dias na semana, voc\u00ea ganha alimenta\u00e7\u00e3o e moradia; para o viajante, basta se preocupar com os custos do transporte, podendo viajar o mundo com or\u00e7amento m\u00ednimo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por outro lado, os anfitri\u00f5es podem solicitar uma ampla variedade de tarefas, como ajudar no cultivo, limpeza do quintal, conserto de m\u00f3veis, cuidar de pets, arrumar as camas ou cuidar de crian\u00e7as. Em geral, s\u00e3o atividades que n\u00e3o exigem habilidades t\u00e9cnicas especializadas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com Workaway, mesmo que voc\u00ea fique mais tempo nos EUA, n\u00e3o precisa se preocupar tanto com as despesas, sendo muito adequado para mochileiros ou quem deseja experimentar a vida americana de forma econ\u00f4mica. Os anfitri\u00f5es muitas vezes recebem v\u00e1rios h\u00f3spedes, aumentando a chance de fazer amigos de outros pa\u00edses e adquirir diferentes experi\u00eancias. Se algum desses pontos chamou sua aten\u00e7\u00e3o, vale a pena se aprofundar no assunto.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Conclus\u00e3o<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Como l\u00edder global em economia, educa\u00e7\u00e3o e tecnologia, os EUA s\u00e3o o sonho de muitas pessoas.<\/span><\/p>\n<p><span style=\"font-size: 20px;\"><strong>Por\u00e9m comparando com a corvers\u00e3o para o Real Brasileiro, trabalhar nos Estados Unidos se torna um sonho j\u00e1 que\u00a0 em materia de convers\u00e3o muitos Brasileiros que moram no EUA, sempre gastam metade de sua renda e manda o restante ara o Brasil, porque quando converdido o valor se torna maior j\u00e1 que a moeda Brasileira est\u00e1 muito desvalorizada no momento.<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mesmo que aprender ingl\u00eas n\u00e3o seja seu principal objetivo, apenas vivenciar culturas e valores t\u00e3o diferentes de Taiwan j\u00e1 proporciona in\u00fameras experi\u00eancias valiosas de crescimento. Se tiver a oportunidade de estudar nos EUA, voc\u00ea ainda poder\u00e1 interagir profundamente com pessoas de diferentes etnias, religi\u00f5es e origens culturais. Ao aprender a apreciar e entender uns aos outros, ampliamos nossos horizontes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, os EUA t\u00eam in\u00fameras cidades famosas e pontos tur\u00edsticos mundialmente conhecidos. Enquanto aprende sobre cultura, certamente tamb\u00e9m ir\u00e1 se divertir bastante nas viagens. Espero que este artigo possa proporcionar mais compreens\u00e3o sobre futuros estudos ou oportunidades de trabalho nos EUA.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os pre\u00e7os nos Estados Unidos s\u00e3o mais altos do que em Taiwan? &nbsp; Frequentemente ouvimos a afirma\u00e7\u00e3o &#8220;os pre\u00e7os nos EUA s\u00e3o muito altos&#8221;, mas ser\u00e1 que isso \u00e9 verdade? Nos \u00faltimos anos, devido \u00e0 s\u00e9ria quest\u00e3o da infla\u00e7\u00e3o, os pre\u00e7os realmente dispararam em Nova Iorque e S\u00e3o Francisco. Por exemplo, uma caixa de ovos no supermercado pode custar at\u00e9 6 d\u00f3lares americanos (aproximadamente 200 TWD). Em Taiwan, uma caixa de ovos por 100 TWD j\u00e1 \u00e9 considerada cara, ainda assim, \u00e9 metade do pre\u00e7o nos EUA \u2014 a diferen\u00e7a de pre\u00e7os \u00e9 evidente. Outros exemplos incluem um sandu\u00edche de 18 d\u00f3lares americanos (aproximadamente 600 TWD), tarifas de t\u00e1xi aumentaram &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/12539\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":12702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=12539","footnotes":""},"categories":[128,131,130],"tags":[],"class_list":["post-12539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business","category-hint","category-usable","pt-BR"],"aioseo_notices":[],"views":185,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=12539"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12539\/revisions"}],"predecessor-version":[{"id":12541,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12539\/revisions\/12541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/12702"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=12539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=12539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=12539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}