{"id":12527,"date":"2025-10-12T09:00:27","date_gmt":"2025-10-12T12:00:27","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=12527"},"modified":"2025-10-08T00:36:09","modified_gmt":"2025-10-08T03:36:09","slug":"voce-sabia-qual-e-a-palavra-em-ingles-para-molheira","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/12527\/","title":{"rendered":"Voc\u00ea sabia? Qual \u00e9 a palavra em ingl\u00eas para \u201cmolheira\u201d?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Desta vez, vamos apresentar especialmente as <span style=\"color: #ab00d1;\"><strong><span style=\"color: #000000;\">express\u00f5es em ingl\u00eas relacionadas a\u00a0 <\/span><span style=\"color: #ff6600; font-size: 28px;\">&#8220;pintas&#8221; <\/span><span style=\"color: #000000;\">, partes do rosto e termos de beleza<\/span><\/strong><\/span><span style=\"color: #000000;\">.<\/span><\/span><\/p>\n<p><span style=\"font-weight: 400;\">A maioria das pessoas provavelmente n\u00e3o sabe como dizer em ingl\u00eas <strong>&#8220;pinta&#8221;, &#8220;mancha&#8221;, &#8220;ruga&#8221;<\/strong> ou<strong> &#8220;sardas&#8221;<\/strong> no rosto! Antes de eu estudar no Brasil, nunca tinha ido a uma loja de cosm\u00e9ticos no exterior, ent\u00e3o, quando procurei produtos de beleza l\u00e1, n\u00e3o fazia ideia de como perguntar ao atendente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, hoje vamos aprender nomes pouco conhecidos de partes do rosto, bem como palavras e express\u00f5es em ingl\u00eas relacionadas \u00e0 beleza e maquiagem. Espero que, depois de ler este artigo, voc\u00ea se sinta confiante para ir a uma farm\u00e1cia ou a um balc\u00e3o de cosm\u00e9ticos mesmo estando no exterior. Para que todos possam usar na vida real, tamb\u00e9m preparamos alguns exemplos aut\u00eanticos de frases em ingl\u00eas com tradu\u00e7\u00e3o para o portugu\u00eas. Espero que essas dicas possam servir de refer\u00eancia para suas conversas no exterior.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>O significado de &#8220;pinta&#8221;<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Primeiramente, em portugu\u00eas, <strong>&#8220;pinta&#8221;<\/strong> se pronuncia<strong> &#8220;zh\u00ec&#8221;.<\/strong> Dependendo da localiza\u00e7\u00e3o da pinta, acredita-se que \u00e9 poss\u00edvel deduzir a personalidade e a sorte da pessoa. Por isso, no Brasil, pintas muitas vezes s\u00e3o usadas na leitura facial ou para an\u00e1lise de personalidade. Al\u00e9m disso, alguns brasileiros pensam que, dependendo da localiza\u00e7\u00e3o da pinta no rosto, ela pode causar diferentes impress\u00f5es: algumas pintas podem ser consideradas fofas, outras devem ser removidas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E no exterior, como as pessoas veem as pintas? Na Fran\u00e7a, as pintas s\u00e3o consideradas parte da <strong>&#8220;beleza&#8221;<\/strong>, sendo vistas como um s\u00edmbolo de charme. J\u00e1 em alguns pa\u00edses, pintas s\u00e3o vistas como origem de doen\u00e7as e fortemente recomendam remov\u00ea-las. Ou seja, a vis\u00e3o sobre pintas varia bastante de pa\u00eds para pa\u00eds.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Como expressar &#8220;pinta&#8221; em ingl\u00eas<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Agora, vamos conferir como se diz &#8220;pinta&#8221; em ingl\u00eas! <span style=\"color: #ff0000;\"><strong><span style=\"color: #000000;\">Em ingl\u00eas, pinta se diz<\/span> \u00a0<span style=\"color: #ff6600;\">&#8220;mole&#8221;<\/span><\/strong><\/span>. Essa palavra tem a mesma grafia da palavra <strong><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">para o animal\u00a0<\/span> <span style=\"color: #ff6600;\">&#8220;toupeira (mole)&#8221;<\/span><\/span><\/strong>.<\/span><\/p>\n<h5><b>I have some moles on my face.<\/b><br \/>\n<span style=\"font-weight: 400;\">Tenho algumas pintas no meu rosto.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>How many moles do you have on your face?<\/b><br \/>\n<span style=\"font-weight: 400;\">Quantas pintas voc\u00ea tem no rosto?<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>I want to remove the moles on my face.<\/b><br \/>\n<span style=\"font-weight: 400;\">Quero remover as pintas do meu rosto!<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>You can use concealer to cover up the mole on your nose.<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea pode usar corretivo para cobrir a pinta do seu nariz.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>I am thinking about removing some moles on my face using laser mole removal treatment.<\/b><br \/>\n<span style=\"font-weight: 400;\">Estou pensando em remover algumas pintas do meu rosto com tratamento a laser.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Ali\u00e1s, <span style=\"color: #0000ff;\"><strong><span style=\"color: #000000;\">nos Estados Unidos e no Reino Unido, a maioria das pessoas tem uma boa impress\u00e3o das pintas. Al\u00e9m de<\/span> <span style=\"color: #ff6600;\">&#8220;mole&#8221;<\/span>,<span style=\"color: #000000;\"> existem as express\u00f5es informais\u00a0<\/span><span style=\"color: #ff6600;\"> &#8220;beauty spot&#8221;\u00a0 (Reino Unido)\u00a0 ou &#8220;beauty mark&#8221; (EUA)<\/span><\/strong><\/span><span style=\"color: #ff6600;\">. <span style=\"color: #000000;\">\u00c0<\/span><\/span>s vezes, as pessoas at\u00e9 desenham pintas falsas para compor o visual ou se divertir com maquiagem. Ultimamente, algumas pessoas t\u00eam at\u00e9 usado delineadores resistentes \u00e0 \u00e1gua para criar pintas no rosto.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Como dizer &#8220;sardas&#8221; e &#8220;manchas&#8221; em ingl\u00eas<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Depois de aprender as express\u00f5es em ingl\u00eas para &#8220;pinta&#8221; e os termos informais, vamos ver outros nomes relativos ao rosto!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Sardas<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quem toma muito sol ou tem mais feomelanina (um tipo de melanina castanho-escura) costuma desenvolver sardas. De fato, pessoas brancas t\u00eam mais tend\u00eancia a ter sardas, mas tamb\u00e9m existem asi\u00e1ticos que nascem com sardas. Embora os gostos variem, na Europa e nos EUA, muita gente acha sardas fofas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"color: #ff0000;\"><strong><span style=\"color: #000000;\">A express\u00e3o em ingl\u00eas para<\/span> <span style=\"color: #ff6600;\">&#8220;sardas&#8221;<\/span> \u00a0<span style=\"color: #000000;\">\u00e9\u00a0<\/span> <span style=\"color: #ff6600;\">&#8220;freckles&#8221;<\/span><\/strong><\/span>. Como geralmente s\u00e3o v\u00e1rias sardas, a palavra costuma aparecer no plural.<\/span><\/p>\n<h5><b>I have so many freckles on my cheeks.<\/b><br \/>\n<span style=\"font-weight: 400;\">Tenho muitas sardas nas bochechas.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>She\u2019s not ashamed of having many freckles.<\/b><br \/>\n<span style=\"font-weight: 400;\">Ela n\u00e3o tem vergonha de ter muitas sardas.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>Mary\u2019s face is slightly marked with freckles.<\/b><br \/>\n<span style=\"font-weight: 400;\">O rosto da Mary tem algumas sardas.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Manchas<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><strong>&#8220;Manchas&#8221;<\/strong> s\u00e3o semelhantes \u00e0s sardas, mas as pessoas costumam se preocupar mais com as manchas do que com as sardas. H\u00e1 a impress\u00e3o de que as manchas aumentam com a idade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em ingl\u00eas, geralmente se usa <span style=\"color: #ff6600;\"><strong>&#8220;facial spot&#8221;<\/strong><\/span> para se referir a manchas no rosto.<\/span><\/p>\n<h5><b>I need to buy a concealer to cover up my facial spots.<\/b><br \/>\n<span style=\"font-weight: 400;\">Preciso comprar corretivo para cobrir as manchas do meu rosto.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>I want to get rid of my facial spots.<\/b><br \/>\n<span style=\"font-weight: 400;\">Quero me livrar das manchas do meu rosto.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Como se diz &#8220;partes do rosto&#8221; em ingl\u00eas<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">At\u00e9 agora, apresentamos as express\u00f5es em ingl\u00eas para <strong>&#8220;pinta&#8221;<\/strong>, <strong>&#8220;sardas&#8221;<\/strong> e <strong>&#8220;manchas&#8221;<\/strong>. A partir daqui, vamos mostrar os nomes das partes do rosto em ingl\u00eas! Ap\u00f3s cada nome em ingl\u00eas, vem uma frase de exemplo. Vamos ver como s\u00e3o usados nas conversas cotidianas!<\/span><\/p>\n<h5><span style=\"color: #ff6600;\"><b>Testa \u2013 forehead<\/b><\/span><br \/>\n<b>Can you show me your forehead?<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea pode me mostrar sua testa?<\/span><br \/>\n<b>You bumped your forehead!<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea bateu a testa!<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>Costeleta \u2013 sideburn<\/b><\/span><br \/>\n<b>I want to shave the fuzz on my sideburns.<\/b><br \/>\n<span style=\"font-weight: 400;\">Quero raspar a penugem das minhas costeletas.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>T\u00eampora \u2013 temple<\/b><\/span><br \/>\n<b>My temples are throbbing.<\/b><br \/>\n<span style=\"font-weight: 400;\">Minhas t\u00eamporas est\u00e3o latejando.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>P\u00e1lpebra \u2013 eyelids<\/b><\/span><br \/>\n<b>I have a mole on my eyelid.<\/b><br \/>\n<span style=\"font-weight: 400;\">Tenho uma pinta na p\u00e1lpebra.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>P\u00e1lpebra simples \u2013 single-edged eyelids<\/b><\/span><br \/>\n<b>I have single-edged eyelids.<\/b><br \/>\n<span style=\"font-weight: 400;\">Tenho p\u00e1lpebras simples.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>P\u00e1lpebra dupla \u2013 double-edged eyelids<\/b><\/span><br \/>\n<b>I have double-edged eyelids.<\/b><br \/>\n<span style=\"font-weight: 400;\">Tenho p\u00e1lpebras duplas.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>Olheira \u2013 dark circle<\/b><\/span><br \/>\n<b>I\u2019ve got dark circles under my eyes.<\/b><br \/>\n<span style=\"font-weight: 400;\">Estou com olheiras.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>L\u00f3bulo da orelha \u2013 earlobe<\/b><\/span><br \/>\n<b>I have big \/ long earlobes.<\/b><br \/>\n<span style=\"font-weight: 400;\">Tenho l\u00f3bulos das orelhas grandes \/ longos.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>Ponte nasal \u2013 bridge of the nose<\/b><\/span><br \/>\n<b>I don\u2019t like my high-bridged nose.<\/b><br \/>\n<span style=\"font-weight: 400;\">N\u00e3o gosto do meu nariz com a ponte alta.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>Asa do nariz \u2013 wings of the nose<\/b><\/span><br \/>\n<b>I just found a small mole on the right wing of my nose.<\/b><br \/>\n<span style=\"font-weight: 400;\">Acabei de encontrar uma pequena pinta na asa direita do nariz.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>Covinha \u2013 dimple<\/b><\/span><br \/>\n<b>Her dimples are cute.<\/b><br \/>\n<span style=\"font-weight: 400;\">As covinhas dela s\u00e3o fofas.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>Filtro nasal \u2013 philtrum<\/b><\/span><br \/>\n<b>I\u2019ve got a small pimple on my philtrum.<\/b><br \/>\n<span style=\"font-weight: 400;\">Apareceu uma espinha pequena no meu filtro nasal.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>Gengiva \u2013 gum<\/b><\/span><br \/>\n<b>We need to take good care of our gums.<\/b><br \/>\n<span style=\"font-weight: 400;\">Precisamos cuidar bem das nossas gengivas.<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>Dente de leite \u2013 milk teeth<\/b><\/span><br \/>\n<b>Does your baby still have baby teeth?<\/b><br \/>\n<span style=\"font-weight: 400;\">Seu beb\u00ea ainda tem dentes de leite?<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>Dente permanente \u2013 permanent teeth<\/b><\/span><br \/>\n<b>Are they all permanent teeth?<\/b><br \/>\n<span style=\"font-weight: 400;\">S\u00e3o todos dentes permanentes?<\/span><br \/>\n<b><\/b><\/h5>\n<h5><span style=\"color: #ff6600;\"><b>Dente canino \u2013 vampire teeth<\/b><\/span><br \/>\n<b>People in the US think they should remove vampire teeth.<\/b><br \/>\n<span style=\"font-weight: 400;\">Nos EUA, acham que deveriam extrair os dentes caninos.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Resumo<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Neste artigo, aprendemos as express\u00f5es em ingl\u00eas para <strong><span style=\"color: #ff6600;\">&#8220;pinta&#8221; <\/span><\/strong>e outras marcas faciais, incluindo termos informais. Tamb\u00e9m apresentamos os nomes em ingl\u00eas de partes do rosto como testa, l\u00f3bulo da orelha e filtro nasal, acompanhados de frases de exemplo. O que voc\u00ea achou?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na verdade, h\u00e1 muitas express\u00f5es em ingl\u00eas que s\u00f3 aprendemos vivendo num pa\u00eds de l\u00edngua inglesa. As partes do corpo e do rosto s\u00e3o um exemplo. Eu mesma s\u00f3 aprendi esses termos quando morei no exterior durante meu interc\u00e2mbio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea vai estudar, morar por um tempo ou viajar para um pa\u00eds de idioma ingl\u00eas, com certeza vai usar essas palavras sobre rosto e beleza que aprendeu hoje! N\u00e3o deixe de usar nas suas conversas do dia a dia!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desta vez, vamos apresentar especialmente as express\u00f5es em ingl\u00eas relacionadas a\u00a0 &#8220;pintas&#8221; , partes do rosto e termos de beleza. A maioria das pessoas provavelmente n\u00e3o sabe como dizer em ingl\u00eas &#8220;pinta&#8221;, &#8220;mancha&#8221;, &#8220;ruga&#8221; ou &#8220;sardas&#8221; no rosto! Antes de eu estudar no Brasil, nunca tinha ido a uma loja de cosm\u00e9ticos no exterior, ent\u00e3o, quando procurei produtos de beleza l\u00e1, n\u00e3o fazia ideia de como perguntar ao atendente. Por isso, hoje vamos aprender nomes pouco conhecidos de partes do rosto, bem como palavras e express\u00f5es em ingl\u00eas relacionadas \u00e0 beleza e maquiagem. Espero que, depois de ler este artigo, voc\u00ea se sinta confiante para ir a uma farm\u00e1cia ou &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/12527\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":12700,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=12527","footnotes":""},"categories":[129,128,127],"tags":[],"class_list":["post-12527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-children","category-business","category-travel","pt-BR"],"aioseo_notices":[],"views":184,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=12527"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12527\/revisions"}],"predecessor-version":[{"id":12529,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12527\/revisions\/12529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/12700"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=12527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=12527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=12527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}