{"id":12495,"date":"2025-10-07T09:00:52","date_gmt":"2025-10-07T12:00:52","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=12495"},"modified":"2025-10-06T00:31:53","modified_gmt":"2025-10-06T03:31:53","slug":"qual-e-o-termo-em-ingles-para-o-besouro-rinoceronte","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/12495\/","title":{"rendered":"Qual \u00e9 o termo em ingl\u00eas para o besouro rinoceronte?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Hoje vamos falar sobre o tema besouros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nos Estados Unidos dos anos 60, surgiu uma banda muito famosa chamada The Beatles. Por esse motivo, muitas pessoas passaram a conhecer a palavra em ingl\u00eas para besouro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00ea se lembra que, a partir de mais de dez anos atr\u00e1s, tamb\u00e9m surgiu em Taiwan a moda dos besouros-rinocerontes? Muitas crian\u00e7as, e at\u00e9 adultos, passaram a criar besouros como animais de estima\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na verdade, quando crian\u00e7a, eu tamb\u00e9m acompanhei essa onda. Pensando nas experi\u00eancias mais marcantes, al\u00e9m de estar frequentemente comprando diversos itens para criar os besouros, como caixas e gelatinas para besouros, \u00e0s vezes at\u00e9 tentava fazer com que eles procriassem, na esperan\u00e7a de observar o nascimento de pequenos besouros-rinocerontes. Foram experi\u00eancias bem interessantes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vou testar voc\u00ea com uma palavra em ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00ea sabe como se diz &#8220;Besouro rinoceronte&#8221; (besouro-serra-pontuda) em ingl\u00eas?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A resposta \u00e9&#8230;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><span style=\"font-size: 36px;\"><strong>\u201cstag beetle\u201d<\/strong><\/span>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cbeetle\u201d \u00e9 como geralmente chamamos o besouro-rinoceronte. \u201cstag\u201d originalmente se refere aos chifres de um veado macho.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O uso dessa palavra aqui se deve ao fato de o besouro-serra-pontuda macho tamb\u00e9m possuir um par de chifres duros em forma de tesoura na cabe\u00e7a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em seguida, vamos continuar explicando mais diferen\u00e7as entre o besouro-serra-pontuda e o besouro-rinoceronte.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Diferen\u00e7a entre besouro-serra-pontuda e besouro-rinoceronte<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><samp><b>Besouro-rinoceronte <\/b><span style=\"font-weight: 400;\">\uff1d\u201cbeetle\u201d<\/span><br \/>\n<b>Besouro-serra-pontuda <\/b><span style=\"font-weight: 400;\">\uff1d\u201cstag beetle\u201d<\/span><\/samp><\/p>\n<p><span style=\"font-weight: 400;\">As palavras em ingl\u00eas para besouro-rinoceronte e besouro-serra-pontuda s\u00e3o basicamente essas duas acima, mas, estritamente falando,<\/span><span style=\"font-weight: 400;\"><strong>\u201cbeetle\u201d<\/strong> n\u00e3o se refere apenas ao besouro-rinoceronte.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Traduzir \u201cbeetle\u201d como besouro-rinoceronte n\u00e3o est\u00e1 errado, mas esta palavra na verdade significa<strong> \u201cbesouros em geral\u201d.<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando falamos de besouro, referimo-nos a insetos com exoesqueleto duro, sendo o besouro-rinoceronte apenas um deles. Portanto, igualar \u201cbeetle\u201d ao besouro-rinoceronte n\u00e3o \u00e9 exato.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Assim como na palavra <strong>\u201cstag beetle\u201d<\/strong> em ingl\u00eas h\u00e1 o termo <strong>\u201cstag\u201d<\/strong> (veado) para destacar uma caracter\u00edstica, a principal caracter\u00edstica do macho do besouro-rinoceronte est\u00e1 na cabe\u00e7a, que tem um chifre grande semelhante ao do rinoceronte (Rhinoceros). Ent\u00e3o, provavelmente voc\u00ea j\u00e1 sabe como \u00e9 chamado em ingl\u00eas.<\/span><\/p>\n<p><strong>Besouro-rinoceronte \uff1d \u201cRhinoceros beetle\u201d<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Correto, essa \u00e9 a forma padr\u00e3o em ingl\u00eas para besouro-rinoceronte, embora, no dia a dia, todos ainda chamem de \u201cbeetle\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Frases com \u201cstag beetle\u201d<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Agora, algumas frases usando a palavra \u201cstag beetle\u201d.<\/span><\/p>\n<h5><b>\u30fbAcordei cedo para pegar um besouro-serra-pontuda.<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">\u201cI got up early to catch a stag beetle.\u201d<\/span><\/h5>\n<h5><span style=\"font-weight: 400;\">\u00a0<\/span><b>\u30fbPreciso comprar uma rede para pegar insetos.<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">\u201cI need to buy an insect net.\u201d<\/span><br \/>\n<b>\u203b \u201cinsect\u201d<\/b><span style=\"font-weight: 400;\">\uff1dinseto<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>\u30fbCuido de besouros-serra-pontuda desde o ano passado.<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">\u201cI have kept the stag beetle from last year.\u201d<\/span><br \/>\n<b>\u203b \u201chave + partic\u00edpio passado\u201d<\/b><span style=\"font-weight: 400;\">\uff1dpresente perfeito<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>\u30fbDizem que existem 1.500 esp\u00e9cies diferentes de besouros-serra-pontuda no mundo.<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">\u201cStag beetles are said to have 1,500 species in the world.\u201d<\/span><br \/>\n<b>\u203b \u201ctype\u201d <\/b><span style=\"font-weight: 400;\">\uff1d tipo, esp\u00e9cie<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>\u203b \u201csaid to\u201d <\/b><span style=\"font-weight: 400;\">\uff1d dizem que\u00a0<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>\u203b \u201cspecies\u201d <\/b><span style=\"font-weight: 400;\">\uff1d esp\u00e9cie<\/span><br \/>\n<b><\/b><\/h5>\n<h5><b>\u30fbEm alguns pa\u00edses, besouros-serra-pontuda s\u00e3o comidos.<\/b><b><br \/>\n<\/b><span style=\"font-weight: 400;\">\u201cSome countries eat stag beetles.\u201d<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><strong>Como dizer o nome dos diferentes tipos de besouro-serra-pontuda em ingl\u00eas<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<h3><strong>Besouros-serra-pontuda nativos de Taiwan<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Segundo informa\u00e7\u00f5es conhecidas, existem cerca de 1.500 esp\u00e9cies diferentes de besouro-serra-pontuda no mundo, sendo que at\u00e9 60% vivem principalmente em pa\u00edses do Sudeste Asi\u00e1tico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">(Claro que no continente europeu tamb\u00e9m h\u00e1 algumas esp\u00e9cies nativas.)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, apresento os nomes em ingl\u00eas de alguns besouros-serra-pontuda que podem ser encontrados em Taiwan.<\/span><\/p>\n<p><span style=\"text-decoration: underline; font-size: 36px; color: #339966;\"><strong>Lucanus maculifemoratus (Besouro rinoceronte das montanhas profundas )<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">= <\/span><span style=\"font-weight: 400;\">Lucanus maculifemoratus<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como o nome sugere, este besouro-serra-pontuda habita principalmente \u00e1reas de alta montanha, podendo ser encontrado n\u00e3o s\u00f3 em Taiwan, mas tamb\u00e9m no Jap\u00e3o e na Coreia.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline; font-size: 36px; color: #339966;\"><strong>Dorcus rectus (Besouro rinoceronte pequeno)<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">\uff1d Dorcus rectus<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este \u00e9 um tipo muito comum no mercado e de f\u00e1cil manejo. Sua principal caracter\u00edstica \u00e9 o porte pequeno, com mand\u00edbulas n\u00e3o muito fortes. Al\u00e9m de Taiwan, China, Jap\u00e3o e Coreia tamb\u00e9m s\u00e3o principais habitats.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Besouros-serra-pontuda estrangeiros<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Existem ainda mais variedades de besouros-serra-pontuda fora do Brasil, abaixo est\u00e3o alguns dos mais populares e representativos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline; font-size: 36px; color: #339966;\"><strong>Phalacrognathus muelleri (Besouro-do-arco-\u00edris)<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">\uff1d <\/span><span style=\"font-weight: 400;\">Phalacrognathus muelleri<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Conhecido como <strong><span style=\"color: #339966;\">&#8220;o besouro-serra-pontuda mais bonito do mundo&#8221;,<\/span><\/strong> sua principal caracter\u00edstica \u00e9 a carapa\u00e7a que reflete cores iridescentes como um arco-\u00edris. Ele se encontra principalmente na Austr\u00e1lia e Papua-Nova Guin\u00e9. Atualmente, a exporta\u00e7\u00e3o para outros pa\u00edses \u00e9 proibida, ent\u00e3o os vistos \u00e0 venda foram criados em cativeiro. Em rela\u00e7\u00e3o \u00e0 apar\u00eancia, diferentes indiv\u00edduos podem apresentar cores variadas, como tonalidade verde ou vermelha.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 36px; color: #339966;\"><strong><span style=\"text-decoration: underline;\">Prosopocoilus giraffa (Girafa Escaravelho)<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">\uff1d Prosopocoilus giraffa<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Conhecido como <strong>&#8220;o maior besouro-serra-pontuda do mundo&#8221;<\/strong>, pode ser encontrado desde o Sudeste Asi\u00e1tico at\u00e9 a \u00cdndia. Curiosamente, a forma da mand\u00edbula varia conforme o local de origem, sendo mais grossa em algumas regi\u00f5es e mais fina em outras.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 36px; color: #339966;\"><strong><span style=\"text-decoration: underline;\">Cyclommatus metallifer (Metaphylaea gracilis)<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">\uff1d Cyclommatus metallifer<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este tamb\u00e9m \u00e9 considerado um dos maiores, podendo alcan\u00e7ar at\u00e9 dez cent\u00edmetros de comprimento. Suas principais caracter\u00edsticas s\u00e3o as mand\u00edbulas longas e finas e a carapa\u00e7a com brilho met\u00e1lico. Vive principalmente no Sudeste Asi\u00e1tico, mas a cor da carapa\u00e7a pode variar de acordo com o ambiente, o que \u00e9 bem interessante.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline; font-size: 36px; color: #339966;\"><strong>Dorcus grandis (Besouro rinoceronte gigante)<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">\uff1d Dorcus grandis<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 o maior entre os besouros do g\u00eanero Dorcus, podendo atingir nove cent\u00edmetros. Seu habitat inclui Laos, Vietn\u00e3 e o leste da \u00cdndia.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 36px; color: #339966;\"><strong><span style=\"text-decoration: underline;\">Mesotopus tarandus (Besouro rinoceronte gigante africano)<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">\uff1d Mesotopus tarandus<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com comprimento de nove cent\u00edmetros, suas mand\u00edbulas curtas deixaram seu corpo ainda mais robusto. Possui corpo espesso e um brilho como se tivesse sido polido, raz\u00e3o pela qual \u00e9 muito apreciado pelos criadores. Sua \u00e1rea de distribui\u00e7\u00e3o \u00e9 a oeste das Am\u00e9ricas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Insetos como comida: uma nova tend\u00eancia?<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Embora no Brasil esteja enfrentando atualmente o problema da baixa taxa de natalidade, a popula\u00e7\u00e3o mundial s\u00f3 faz crescer rapidamente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, o problema da<span style=\"color: #339966;\"> escassez de alimentos <\/span>tem recebido cada vez mais aten\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E os insetos t\u00eam sido apontados como uma das fontes alternativas de alimento mais promissoras no futuro. Na verdade, em Taiwan hoje, j\u00e1 existe um grupo consider\u00e1vel de entusiastas da culin\u00e1ria de insetos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em Taiwan, a maioria dos pratos de insetos \u00e9 feita principalmente com grilos e pupas de abelha fritos, mas em outros pa\u00edses existem muitos outros insetos usados na culin\u00e1ria.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, a fam\u00edlia dos <span style=\"color: #339966;\"><strong>\u201cbeetle\u201d<\/strong>,<\/span> que inclui besouro-rinoceronte e besouro-serra-pontuda, \u00e9 um dos ingredientes representativos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 se sabe que existem cerca de 1.900 esp\u00e9cies de insetos utilizados como alimento, sendo que cerca de 600 delas pertencem \u00e0 fam\u00edlia dos<span style=\"color: #339966;\"><strong> \u201cbeetle\u201d<\/strong>.<\/span><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em muitos pa\u00edses pr\u00f3ximos, pratos t\u00edpicos com insetos s\u00e3o bastante populares, como na Tail\u00e2ndia, Vietn\u00e3, Laos, Mianmar e China. Surpreendentemente, at\u00e9 a Coreia \u00e9 famosa nesse quesito.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na \u00c1sia, os pratos com insetos geralmente s\u00e3o feitos com gafanhotos e grilos, mas na China e na Austr\u00e1lia \u00e9 comum o uso de larvas de mariposas na culin\u00e1ria.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na China, <strong><span style=\"color: #339966;\">\u201cvermes de bambu\u201d<\/span> <\/strong>s\u00e3o considerados uma iguaria sofisticada!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se falarmos do inseto com o sabor mais popular, n\u00e3o podemos deixar de citar a cigarra, que \u00e9 consumida na \u00c1sia, China e at\u00e9 Estados Unidos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dizem que depois de frita, a cigarra fica deliciosa, surpreendendo quem experimenta!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os gafanhotos fritos que mencionamos s\u00e3o um petisco de rua muito comum na Tail\u00e2ndia. S\u00e3o crocantes e, dizem, muito nutritivos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Que tal experimentar um prato de besouro-serra-pontuda?<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Se formos falar especificamente dos besouros-serra-pontuda, dizem que em<strong> <span style=\"color: #339966;\">Papua-Nova Guin\u00e9<\/span>,<\/strong> eles s\u00e3o t\u00e3o comuns quanto um lanche para os moradores locais.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L\u00e1 existe uma esp\u00e9cie chamada besouro-serra-pontuda dourado da Indon\u00e9sia, que \u00e9 abundante e de f\u00e1cil captura. Os habitantes removem as pernas e asas e comem apenas o corpo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De modo geral, o m\u00e9todo de comer besouro-rinoceronte e besouro-serra-pontuda \u00e9 parecido: remove-se a carapa\u00e7a dura e consome-se a carne do interior, que \u00e9 mais f\u00e1cil de mastigar. Apesar das boas avalia\u00e7\u00f5es, sinceramente, ainda n\u00e3o tive coragem de experimentar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em v\u00e1rios pa\u00edses do Sudeste Asi\u00e1tico e em muitas regi\u00f5es da \u00c1sia \u00e9 poss\u00edvel encontrar besouros-serra-pontuda, e, se estiver disposto a provar algo novo, talvez voc\u00ea mesmo possa tentar capturar e saborear um.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas, pensando bem, se algum dia realmente tivermos que comer pratos de besouros por causa da falta de alimentos, s\u00f3 de imaginar j\u00e1 \u00e9 dif\u00edcil aceitar!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Resumo<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Este artigo teve como protagonista o besouro-serra-pontuda, detalhando desde seus nomes em ingl\u00eas at\u00e9 as esp\u00e9cies famosas de todo o mundo\u00a0 espero que tenha achado interessante!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea conhece crian\u00e7as apaixonadas por besouros, aproveite para ensinar a elas os nomes em ingl\u00eas dos diferentes tipos de besouro-serra-pontuda.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mesmo sendo adulto, sempre d\u00e1 para aproveitar o aprendizado de hoje para conversar com outras pessoas, em ingl\u00eas, sobre conhecimentos curiosos sobre insetos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, n\u00e3o adianta acumular muito conhecimento se n\u00e3o conseguir conversar com estrangeiros\u00a0 assim n\u00e3o d\u00e1 para compartilhar os t\u00f3picos interessantes sobre besouros.<\/span><\/p>\n<p><strong><span style=\"color: #339966;\">\u201cAprimorar o ingl\u00eas \u00e9 a base de tudo\u201d.<\/span><\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, recomendo o \u201cNativeCamp\u201d, uma plataforma de ensino online onde \u00e9 poss\u00edvel praticar conversa\u00e7\u00e3o \u00e0 vontade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mesmo para iniciantes no ingl\u00eas, n\u00e3o h\u00e1 motivo para se preocupar, j\u00e1 que h\u00e1 materiais introdut\u00f3rios especializados para todos os n\u00edveis.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, h\u00e1 materiais tem\u00e1ticos, ideais para aplicar os conhecimentos de besouros-serra-pontuda aprendidos hoje e compartilhar com professores estrangeiros. N\u00e3o deixe de experimentar!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje vamos falar sobre o tema besouros. Nos Estados Unidos dos anos 60, surgiu uma banda muito famosa chamada The Beatles. Por esse motivo, muitas pessoas passaram a conhecer a palavra em ingl\u00eas para besouro. Voc\u00ea se lembra que, a partir de mais de dez anos atr\u00e1s, tamb\u00e9m surgiu em Taiwan a moda dos besouros-rinocerontes? Muitas crian\u00e7as, e at\u00e9 adultos, passaram a criar besouros como animais de estima\u00e7\u00e3o. Na verdade, quando crian\u00e7a, eu tamb\u00e9m acompanhei essa onda. Pensando nas experi\u00eancias mais marcantes, al\u00e9m de estar frequentemente comprando diversos itens para criar os besouros, como caixas e gelatinas para besouros, \u00e0s vezes at\u00e9 tentava fazer com que eles procriassem, na esperan\u00e7a &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/12495\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":12617,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=12495","footnotes":""},"categories":[120,118,122],"tags":[],"class_list":["post-12495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grammar","category-study-abroad","category-pronunciation","pt-BR"],"aioseo_notices":[],"views":424,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=12495"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12495\/revisions"}],"predecessor-version":[{"id":12497,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12495\/revisions\/12497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/12617"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=12495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=12495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=12495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}