{"id":12373,"date":"2025-10-01T09:00:31","date_gmt":"2025-10-01T12:00:31","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=12373"},"modified":"2025-09-24T23:54:16","modified_gmt":"2025-09-25T02:54:16","slug":"dicas-e-pontos-chave-para-iniciar-conversas-com-estrangeiros-como-voce-deve-comecar","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/12373\/","title":{"rendered":"Dicas e pontos-chave para iniciar conversas com estrangeiros: como voc\u00ea deve come\u00e7ar&#8230;"},"content":{"rendered":"<h2><strong>O que devo fazer se quero conversar ou interagir com estrangeiros?<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Antes da dissemina\u00e7\u00e3o da pandemia de Covid-19 pelo mundo, era comum ver muitos estrangeiros nas cidades e pontos tur\u00edsticos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Naquela \u00e9poca, ao encontrar turistas estrangeiros visivelmente inseguros, ser\u00e1 que voc\u00ea j\u00e1 pensou:\u00a0 <strong>\u201cO que houve com ele?\u00a0 Quero ajud\u00e1-lo\u201d<\/strong>, mas n\u00e3o sabia como iniciar a conversa? Ou talvez, <strong>\u201cOh! Ele tamb\u00e9m gosta de como eu?\u00a0 Quero bater um papo com ele\u201d<\/strong>, mas ficou preocupado em ser rejeitado. No final, ficou arrependido por n\u00e3o ter feito nada?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cHoje em dia, apesar de existirem v\u00e1rios aplicativos de tradu\u00e7\u00e3o, quando surge a oportunidade voc\u00ea gostaria de falar ingl\u00eas, mas ainda hesita em dar o primeiro passo.\u201d Eu acredito que muitos t\u00eam essa experi\u00eancia e esse sentimento!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, neste artigo quero apresentar a todos <span style=\"font-size: 20px;\"><strong><span style=\"color: #ff6600;\">\u201cpontos importantes e observa\u00e7\u00f5es ao conversar com estrangeiros\u201d,<\/span><\/strong><span style=\"color: #000000;\"> assim como<\/span><strong><span style=\"color: #ff6600;\"> \u201cfrases em ingl\u00eas muito \u00fateis para memorizar\u201d.<\/span><\/strong><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Pontos principais para conversar com estrangeiros<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Muitos estrangeiros que v\u00eam ao Brasil (turistas estrangeiros) t\u00eam muito interesse neste\u00a0 <strong>\u201cpa\u00eds ex\u00f3tico\u201d\u00a0 e nos\u00a0 \u201cbrasileiros\u201d<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na verdade, para muitos, um dos grandes prazeres de viajar ao exterior \u00e9 justamente interagir com os locais (inclusive os brasileiros). Em outras palavras, <strong>\u201cpara a maioria dos estrangeiros, eles tamb\u00e9m querem conversar com brasilieros\u201d<\/strong>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\u201cD\u00favida 1\u201d: Como come\u00e7ar a conversa?<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Entre desconhecidos, \u00e9 necess\u00e1rio algum tipo de <strong><span style=\"color: #ff6600;\">\u201coportunidade\u201d<\/span> ou <span style=\"color: #ff6600;\">\u201cmotivo\u201d<\/span><\/strong> para iniciar uma conversa. Se a conversa come\u00e7ar sem uma raz\u00e3o aparente, geralmente parece um pouco artificial.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mesmo entre brazilian ao iniciar um papo, alguns s\u00e3o bons nisso, outros n\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se o alvo \u00e9 um estrangeiro, tudo fica ainda mais dif\u00edcil. Por exemplo, imagine se um desconhecido chega de repente e pergunta: <strong><span style=\"color: #ff6600;\">\u201cHello, how are you?\u201d<\/span> ou <span style=\"color: #ff6600;\">\u201cHi, can I help you?<\/span>\u201d<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cIsso \u00e9 uma abordagem de vendas?\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cSer\u00e1 sequestro?\u00a0 Ou flerte?\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ouvir esse tipo de abordagem pode causar suspeita ou d\u00favida, e isso \u00e9 totalmente compreens\u00edvel! Se voc\u00ea j\u00e1 esteve no exterior e passou por algo parecido, certamente entende ainda melhor essa sensa\u00e7\u00e3o.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\u201cD\u00favida 2\u201d: Como iniciar a conversa sem levantar suspeitas?<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A resposta correta \u00e9 <strong>\u201celogiar a pessoa\u201d<\/strong>! Por exemplo, a bolsa, os sapatos, o chap\u00e9u, o animal de estima\u00e7\u00e3o, a camiseta&#8230; qualquer coisa serve.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>No Brasil, <span style=\"color: #ff6600;\">\u201cafagar\u201d<\/span> significa, na verdade, <span style=\"color: #ff6600;\">\u201celogiar\u201d<\/span><\/strong>. Mas mesmo elogiar algu\u00e9m de maneira educada exige um pouco de coragem ao falar com estranhos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cElogios deixam as pessoas felizes, isso \u00e9 entendido no mundo todo!\u201d Comece com esse pensamento e tente dar o primeiro passo!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\u201cD\u00favida 3\u201d: Existem frases simples e pr\u00e1ticas em ingl\u00eas?<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Claro que existem!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com uma frase bem simples como <strong>\u201cI like your \u201d<\/strong>, basta inserir o objeto que deseja elogiar (camiseta, bolsa, etc.) e voc\u00ea j\u00e1 pode usar na hora.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Talvez voc\u00ea pense \u201cisso \u00e9 mesmo um elogio?\u201d, mas est\u00e1 demonstrando boa vontade, como o nosso \u201cque legal isso!\u201d<\/span><\/p>\n<h5><b>I like your earrings!<\/b><br \/>\n<span style=\"font-weight: 400;\">\uff1d Seus brincos s\u00e3o lindos!<\/span><br \/>\n<b>I like your wrist watch.<\/b><br \/>\n<span style=\"font-weight: 400;\">\uff1d Que rel\u00f3gio bacana!<\/span><br \/>\n<span style=\"font-weight: 400;\">Se quiser mostrar que gostou ainda mais, pode tentar:<\/span><br \/>\n<b>\u201cI love your \u201d <\/b><span style=\"font-weight: 400;\">\u00a0esta \u00e9 uma express\u00e3o pr\u00e1tica do ingl\u00eas.<\/span><br \/>\n<b>I love your T-shirt.<\/b><br \/>\n<span style=\"font-weight: 400;\">\uff1d Sua camiseta \u00e9 demais!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, h\u00e1 outras formas simples de expressar. <span style=\"color: #ff6600;\"><strong>\u201cThat\u00a0 is so nice\u201d <\/strong><\/span>equivale a<span style=\"color: #ff6600;\"><strong> \u201ctal coisa \u00e9 t\u00e3o legal!\u201d<\/strong><\/span>. Al\u00e9m de <span style=\"color: #ff6600;\"><strong>\u201cso nice\u201d<\/strong><\/span>, voc\u00ea pode trocar por<span style=\"color: #ff6600;\"> <strong>\u201cvery nice\u201d, \u201cpretty cool\u201d, \u201cunique\u201d<\/strong><\/span> e outros adjetivos.<\/span><\/p>\n<h5><b>That wrist watch is pretty cool!<\/b><br \/>\n<span style=\"font-weight: 400;\">Que rel\u00f3gio legal!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Voc\u00ea tamb\u00e9m pode mudar\u00a0 <strong>\u201cThat\u201d <\/strong>para<strong> \u201cYou\u201d<\/strong> e usar <strong>\u201clovely\u201d<\/strong>, um adjetivo que as mulheres gostam, para expressar \u201cfofo\u201d.<\/span><\/p>\n<h5><b>Your bag is so lovely!<\/b><br \/>\n<span style=\"font-weight: 400;\">Sua bolsa \u00e9 super fofa!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Usar elogios para iniciar uma conversa \u00e9 a forma mais natural entre pessoas do mesmo sexo. E no caso de mulheres elogiando homens, essas frases tamb\u00e9m n\u00e3o t\u00eam problema. O cuidado deve ser principalmente quando homens elogiam mulheres, pois pode ser mal interpretado como uma cantada. Fique atento a isso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Depois de elogiar, a conversa pode ser encerrada ali mesmo. Quando n\u00e3o estiver seguro para continuar, pode dizer:<\/span><\/p>\n<h5><b>Nice chatting with you! Thanks.<\/b><br \/>\n<span style=\"font-weight: 400;\">Adorei conversar com voc\u00ea! Obrigado.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Aqui, <strong>\u201cChat\u201d<\/strong> significa um bate-papo informal. Basta dizer essa frase em ingl\u00eas, e pode sair em seguida sem problemas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>\u201cD\u00favida 3\u201d: Que tipo de abordagem N\u00c3O se deve usar?<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quando voc\u00ea encontra algu\u00e9m precisando de ajuda, a primeira frase que vem \u00e0 mente \u00e9:<\/span><\/p>\n<p><b>\u201cCan I help you?\u201d<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u201cVoc\u00ea precisa de ajuda?\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essa frase pode ser vaga ou amb\u00edgua para os estrangeiros. Para eles, de forma at\u00e9 exagerada, \u00e9 como <strong>\u201ceu n\u00e3o pedi nada, por que est\u00e1 me ajudando?\u201d<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em pa\u00edses anglo-sax\u00f5es, \u00e0s vezes essa frase lembra \u201ccenas suspeitas em becos\u201d. Se a pessoa j\u00e1 passou por isso, pode recusar na hora e sair rapidamente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">At\u00e9 aqui, talvez voc\u00ea ainda ache:\u00a0 \u201cPara mim, elogiar o outro \u00e9 dif\u00edcil&#8230;\u201d, ou pense:\u00a0 \u201cN\u00e3o tem outra maneira al\u00e9m do elogio?\u201d. Para quem tem esses receios, <strong>voc\u00ea pode se adaptar \u00e0 situa\u00e7\u00e3o<\/strong> e escolher a express\u00e3o mais adequada.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Express\u00f5es conforme a situa\u00e7\u00e3o<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h4><span style=\"color: #ff6600;\"><strong><span style=\"color: #000000;\">\u201cSitua\u00e7\u00e3o 1\u201d:<\/span> Algu\u00e9m parece estar desconfort\u00e1vel<\/strong><\/span><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea vir um estrangeiro na esta\u00e7\u00e3o olhando mapas ou celular sem se mover, ou que parece perdido depois de perguntar algo para um brasileiro,<\/span><\/p>\n<p><span style=\"font-weight: 400;\">se sentir que pode ajudar, d\u00ea antes um\u00a0 <strong>\u201cHi\u201d\u00a0 ou\u00a0 \u201cHello\u201d<\/strong>\u00a0 e ent\u00e3o pergunte:<\/span><\/p>\n<h5><b>Is everything okay?<\/b><br \/>\n<span style=\"font-weight: 400;\">Est\u00e1 tudo bem? (Voc\u00ea est\u00e1 bem?)<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Em ingl\u00eas, literalmente \u00e9 <strong>\u201cest\u00e1 tudo bem?\u201d<\/strong>, mas na pr\u00e1tica quer dizer: <strong>\u201cvoc\u00ea est\u00e1 bem?\u201d<\/strong>.<\/span><\/p>\n<h5><b>Is there anything I can do for you?<\/b><br \/>\n<span style=\"font-weight: 400;\">Tem algo em que eu possa ajudar?<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Essa express\u00e3o n\u00e3o causa a sensa\u00e7\u00e3o de \u201cfor\u00e7ar ajuda\u201d, sendo do tipo \u201cse quiser, posso te ajudar?\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><strong>\u201cSitua\u00e7\u00e3o 2\u201d: <span style=\"color: #ff6600;\">Encontrando uma pessoa que parece perdida<\/span><\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea vir um estrangeiro parado na rua olhando o celular ou vagando pr\u00f3ximo a um mapa em uma esta\u00e7\u00e3o, comece com um <strong>\u201cHi\u201d<\/strong> e pergunte:<\/span><\/p>\n<h5><b>Are you lost?<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea est\u00e1 perdido?<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Mesmo com GPS no celular (como Google Maps), nem sempre \u00e9 f\u00e1cil. Em um lugar estranho, placas diferentes podem confundir qualquer um. Ent\u00e3o, perguntar\u00a0<strong> \u201cvoc\u00ea est\u00e1 perdido?\u201d<\/strong>\u00a0 geralmente n\u00e3o incomoda ningu\u00e9m.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Talvez o estrangeiro estivesse at\u00e9 esperando encontrar algu\u00e9m para poder dizer umas palavras em ingl\u00eas\u2026 mas acabou n\u00e3o dizendo nada.<\/span><\/p>\n<h5><b>Can I help you find your way?<\/b><br \/>\n<span style=\"font-weight: 400;\">Posso te ajudar a encontrar o caminho?<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Lembro que, h\u00e1 muito tempo, viajando em Nova York, uma jovem veio nos ajudar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Naquela \u00e9poca, minha fam\u00edlia e eu est\u00e1vamos parados numa rua comercial, examinando um mapa\u2026 embora isso n\u00e3o seja muito seguro em alguns pa\u00edses (pode ser perigoso, j\u00e1 que algu\u00e9m pode fingir ajudar, mas na verdade desejar te levar a algum lugar e roubar seus pertences\u2026)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas at\u00e9 hoje, lembro que s\u00f3 conseguimos chegar ao nosso destino gra\u00e7as \u00e0 jovem que nos deu indica\u00e7\u00f5es em ingl\u00eas lento e claro.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><strong>\u201cSitua\u00e7\u00e3o 3\u201d: <span style=\"color: #ff6600;\">Estrangeiro parece procurar algo<\/span><\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea perceber um estrangeiro olhando um mapa de algum pr\u00e9dio ou parecendo estar procurando algo, diga antes um leve\u00a0 <strong>\u201cHi\u201d<\/strong>.<\/span><\/p>\n<h5><b>Are you looking for something?<\/b><br \/>\n<span style=\"font-weight: 400;\">Voc\u00ea est\u00e1 procurando algo?<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Aqui \u00e9 importante notar a diferen\u00e7a em rela\u00e7\u00e3o \u00e0 frase seguinte:<\/span><\/p>\n<h5><b>What are you looking for?<\/b><br \/>\n<span style=\"font-weight: 400;\">O que voc\u00ea est\u00e1 procurando?<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Esta frase sugere que a pessoa est\u00e1 atr\u00e1s de um objeto espec\u00edfico.\u00a0 <strong>\u201cWhat = objetivo\u201d<\/strong>. Por exemplo, se procuram um item concreto em uma loja.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas, se voc\u00ea n\u00e3o tem certeza se o outro est\u00e1 buscando algo, melhor perguntar <strong>\u201cAre you looking for something?\u201d<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Something<\/strong> pode significar qualquer coisa\u00a0 lugar, pessoa ou objeto. O outro pode responder simplesmente <strong>\u201cNo, I\u2019m not\u201d<\/strong>. Neste caso, voc\u00ea pode dizer:<\/span><\/p>\n<h5><b>OK, that\u2019s good<\/b><br \/>\n<span style=\"font-weight: 400;\">\u00d3timo, que bom ent\u00e3o.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Ou seja,\u00a0 \u201cainda bem que est\u00e1 tudo certo\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Cuidados ao conversar e atitudes indelicadas<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">No in\u00edcio do artigo foi mencionado que \u201cpara a maioria dos estrangeiros, eles tamb\u00e9m querem conversar com brasileiro\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por\u00e9m, ao puxar conversa, \u00e9 preciso estar atento para n\u00e3o fazer o estrangeiro pensar \u201c<strong>Falar com brasiliero \u00e9 chato\u201d<\/strong>. Veja seis pontos essenciais:<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><b>(1) <span style=\"color: #ff6600;\">Observe a situa\u00e7\u00e3o do outro<\/span><\/b><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Isso vale tamb\u00e9m para brasileiro. Antes de falar, observe a situa\u00e7\u00e3o da pessoa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, \u00e9 diferente tentar conversar com \u201cum estrangeiro\u201d do que com \u201cum grupo de turistas estrangeiros\u201d. Neste caso, voc\u00ea deve ter um motivo mais concreto para que a conversa seja natural. Ou seja, ao se preparar para conversar, verifique antes a situa\u00e7\u00e3o para escolher a melhor abordagem.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><b>(2) <span style=\"color: #ff6600;\">Observe a express\u00e3o da outra pessoa<\/span><\/b><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Durante a conversa, fique de olho nas express\u00f5es da outra pessoa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se notar sinais como desvio de olhar ou respostas frias, diga:<\/span><\/p>\n<h5><b>Thanks for your time!<\/b><br \/>\n<span style=\"font-weight: 400;\">Obrigado pelo seu tempo!<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Mantenha a educa\u00e7\u00e3o e se retire.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><b>(3) Dizer<span style=\"color: #ff6600;\"> \u201cHello!\u201d e sair em seguida<\/span><\/b><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Falar apressado um <strong>\u201cHello!\u201d ou \u201cHi!\u201d<\/strong> para um estrangeiro que est\u00e1 fazendo compras ou caminhando, e logo sair do local,<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00e9 muito artificial. O estrangeiro talvez pense: \u201cN\u00e3o somos vizinhos, por que me cumprimentou assim?\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Refor\u00e7ando: n\u00e3o se esque\u00e7a de que para iniciar papo entre desconhecidos \u00e9 preciso ter algum <strong>\u201cmotivo\u201d ou \u201coportunidade\u201d<\/strong>!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><b>(4)<span style=\"color: #ff6600;\"> Aproximar-se de repente e perguntar<\/span><\/b><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Chegar de repente e perguntar <strong>\u201cWhere are you from?\u201d<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essa frase em si n\u00e3o tem problema, mas desrespeita a regra de \u201ciniciar uma conversa antes de perguntar\u201d uma regra fundamental!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><b>(5) <span style=\"color: #ff6600;\">Falar demais, fazer perguntas em excesso<\/span><\/b><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Alguns pensam que, se o outro est\u00e1 ouvindo, podem ficar falando sem parar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Isso \u00e9 comum para quem come\u00e7ou a gostar de conversas em ingl\u00eas e j\u00e1 tem vocabul\u00e1rio intermedi\u00e1rio. Recomenda-se que voc\u00ea pense se o outro est\u00e1 desconfort\u00e1vel, e que ambos possam aproveitar o prazer do di\u00e1logo em ingl\u00eas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><b>(6) <span style=\"color: #ff6600;\">Obrigar o outro a falar em ingl\u00eas quando ele quer falar Portugu\u00eas<\/span><\/b><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Se o estrangeiro \u00e9 turista, isso n\u00e3o costuma acontecer.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas lembre que h\u00e1 quem j\u00e1 estudou portugu\u00eas. Quando for assim, tente falar em portugu\u00eas primeiro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se perceber que o outro n\u00e3o est\u00e1 entendendo alguma palavra, tente misturar ingl\u00eas. Di\u00e1logos alternando portugu\u00eas e ingl\u00eas podem ser divertidos. Se partilharem gostos em comum, a conversa ser\u00e1 ainda mais animada!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Procure ter respeito ao conversar com estrangeiros<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Como se sentiu ao chegar at\u00e9 aqui? Se pensar <strong>\u201cAinda acho muito dif\u00edcil&#8230;\u201d<\/strong>, saiba que \u00e9 totalmente normal!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mesmo entre brasileiros, falar com desconhecidos exige <strong>\u201cum pouco de coragem\u201d e \u201cexperi\u00eancia\u201d<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No geral, s\u00f3 de conversar com respeito e sem incomodar o outro, os estrangeiros n\u00e3o ter\u00e3o m\u00e1 impress\u00e3o.<\/span><\/p>\n<p><samp><span style=\"font-weight: 400;\">(1) Observe bem a situa\u00e7\u00e3o do outro.<\/span><br \/>\n<span style=\"font-weight: 400;\">(2) Fale um \u201cHi\u201d gentil, e fa\u00e7a um elogio de forma simp\u00e1tica, como \u201cacho o seu\u00a0 muito legal\u201d.<\/span><br \/>\n<span style=\"font-weight: 400;\">(3) Escolha palavras adequadas para a situa\u00e7\u00e3o.<\/span><br \/>\n<span style=\"font-weight: 400;\">(4) Acompanhe o ritmo do outro.<\/span><\/samp><\/p>\n<p><span style=\"font-weight: 400;\">Seguindo esses passos, tenho certeza de que qualquer um ser\u00e1 recebido com gentileza. Vamos nos preparar para esse momento treinando ingl\u00eas na <strong>\u201cNative Camp\u201d<\/strong>!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O que devo fazer se quero conversar ou interagir com estrangeiros? &nbsp; Antes da dissemina\u00e7\u00e3o da pandemia de Covid-19 pelo mundo, era comum ver muitos estrangeiros nas cidades e pontos tur\u00edsticos. Naquela \u00e9poca, ao encontrar turistas estrangeiros visivelmente inseguros, ser\u00e1 que voc\u00ea j\u00e1 pensou:\u00a0 \u201cO que houve com ele?\u00a0 Quero ajud\u00e1-lo\u201d, mas n\u00e3o sabia como iniciar a conversa? Ou talvez, \u201cOh! Ele tamb\u00e9m gosta de como eu?\u00a0 Quero bater um papo com ele\u201d, mas ficou preocupado em ser rejeitado. No final, ficou arrependido por n\u00e3o ter feito nada? \u201cHoje em dia, apesar de existirem v\u00e1rios aplicativos de tradu\u00e7\u00e3o, quando surge a oportunidade voc\u00ea gostaria de falar ingl\u00eas, mas ainda hesita &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/12373\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":12421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=12373","footnotes":""},"categories":[107,130,122],"tags":[],"class_list":["post-12373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-speaking","category-usable","category-pronunciation","pt-BR"],"aioseo_notices":[],"views":603,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=12373"}],"version-history":[{"count":2,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12373\/revisions"}],"predecessor-version":[{"id":12376,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12373\/revisions\/12376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/12421"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=12373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=12373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=12373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}