{"id":12313,"date":"2025-09-27T09:00:44","date_gmt":"2025-09-27T12:00:44","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=12313"},"modified":"2025-09-22T00:11:23","modified_gmt":"2025-09-22T03:11:23","slug":"caracteristicas-do-ingles-australiano-explique-as-diferencas-de-pronuncia-e-expressao","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/12313\/","title":{"rendered":"Caracter\u00edsticas do ingl\u00eas australiano! Explique as diferen\u00e7as de pron\u00fancia e express\u00e3o."},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Em muitos pa\u00edses do mundo fala-se ingl\u00eas. Mas, dependendo do pa\u00eds, o ingl\u00eas pode apresentar diferen\u00e7as.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00ea pode se perguntar<\/span><\/p>\n<p><span style=\"font-size: 20px; color: #3366ff;\"><strong>&#8220;Qual \u00e9 a diferen\u00e7a entre o ingl\u00eas australiano e o ingl\u00eas de outros pa\u00edses?&#8221;<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">O ingl\u00eas australiano \u00e9 bastante distinto em compara\u00e7\u00e3o ao ingl\u00eas brit\u00e2nico \/ americano; se voc\u00ea n\u00e3o entender ou n\u00e3o estiver habituado, pode haver muitas situa\u00e7\u00f5es em que ficar\u00e1 confuso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desta vez, vamos apresentar as caracter\u00edsticas da pron\u00fancia do ingl\u00eas australiano e as diferen\u00e7as nas formas de express\u00e3o.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Hist\u00f3ria do ingl\u00eas australiano<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Em ingl\u00eas, o ingl\u00eas australiano \u00e9 chamado de<\/span><\/p>\n<p><samp><b>Australian English<\/b><br \/>\n<b>Aussie English<\/b><\/samp><\/p>\n<p><span style=\"font-weight: 400;\">Segundo a\u00a0 <\/span><b>Wikipedia<\/b><span style=\"font-weight: 400;\">, a origem da pron\u00fancia australiana vem dos sotaques falados por muitos dos primeiros imigrantes na Austr\u00e1lia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como o sotaque do centro de Londres ou o sotaque irland\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No s\u00e9culo XVIII, o Reino Unido colonizou a Austr\u00e1lia, tornando-a tamb\u00e9m um destino para ex\u00edlio de criminosos brit\u00e2nicos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ou seja, muitas pessoas emigraram do Reino Unido para a Austr\u00e1lia, ent\u00e3o o ingl\u00eas australiano se baseia no ingl\u00eas brit\u00e2nico da \u00e9poca.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, pessoas com v\u00e1rios sotaques emigraram para a Austr\u00e1lia, e devido \u00e0 influ\u00eancia dos abor\u00edgenes, o ingl\u00eas australiano acabou se dividindo grosseiramente em <strong>tr\u00eas tipos de sotaques<\/strong>.<\/span><\/p>\n<p><samp><b>\u30fbCultivated accent<\/b><br \/>\n<b>\u30fbGeneral accent<\/b><br \/>\n<b>\u30fbBroad accent<\/b><\/samp><\/p>\n<p><span style=\"color: #dd10e8;\"><b>&#8220;Cultivated accent&#8221;<\/b><\/span><span style=\"font-weight: 400;\">\u00a0 significa um sotaque associado a alto n\u00edvel social e educacional.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante a campanha de corre\u00e7\u00e3o de pron\u00fancia do final do s\u00e9culo XIX, os locutores da BBC (British Broadcasting Company) do Reino Unido falavam dessa forma:<\/span><\/p>\n<p><span style=\"color: #dd10e8;\"><b>&#8220;Received pronunciation&#8221;<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aparentemente, \u00e9 uma pron\u00fancia baseada no que foi considerado como correto.<\/span><\/p>\n<p><span style=\"color: #dd10e8;\"><b>&#8220;General accent&#8221;<\/b><\/span><span style=\"font-weight: 400;\"> \u00e9 o sotaque australiano mais comum e amplamente utilizado. \u00c9 o sotaque das pessoas que vivem nas \u00e1reas urbanas e \u00e9 considerado o sotaque padr\u00e3o usado em programas de TV e filmes.<\/span><\/p>\n<p><span style=\"color: #dd10e8;\"><b>&#8220;Broad accent&#8221;<\/b><\/span><span style=\"font-weight: 400;\"> \u00e9 considerado por falantes nativos de ingl\u00eas de v\u00e1rias partes do mundo como<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>&#8220;o famoso sotaque australiano&#8221;<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por\u00e9m, esse sotaque \u00e9 comum nas \u00e1reas rurais da Austr\u00e1lia.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Principais caracter\u00edsticas do ingl\u00eas australiano<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Como mencionado acima, o ingl\u00eas australiano \u00e9 baseado no ingl\u00eas brit\u00e2nico, portanto h\u00e1 muitas semelhan\u00e7as.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, o ingl\u00eas australiano se desenvolveu ao longo do tempo, criando pron\u00fancias e express\u00f5es peculiares.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aqui apresentamos algumas caracter\u00edsticas b\u00e1sicas do ingl\u00eas australiano que aprendizes de ingl\u00eas deveriam conhecer.<\/span><\/p>\n<h3><strong>Caracter\u00edsticas da pron\u00fancia do ingl\u00eas australiano<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>1. &#8220;can\u2019t&#8221; \u00e9 pronunciado como &#8220;kant&#8221;<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">No ingl\u00eas americano, <strong>&#8220;can&#8217;t&#8221; \u00e9 pronunciado como &#8220;ke-ent&#8221;<\/strong>, mas no australiano \u00e9 <strong>&#8220;ca-nt&#8221;<\/strong>, semelhante ao ingl\u00eas brit\u00e2nico.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>2. O &#8220;R&#8221; \u00e9 pronunciado como &#8220;AH&#8221;<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">No ingl\u00eas americano, palavras que terminam com <strong>&#8220;R&#8221; ou &#8220;ER&#8221;<\/strong> geralmente t\u00eam o <strong>&#8220;R&#8221;<\/strong> pronunciado de forma clara, mas no australiano a pron\u00fancia \u00e9 <strong>&#8220;AH&#8221;<\/strong>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>3. O &#8220;g&#8221; em &#8220;ing&#8221; n\u00e3o \u00e9 pronunciado<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Na Austr\u00e1lia, em palavras terminadas em <strong>&#8220;ing&#8221;<\/strong>, geralmente n\u00e3o se pronuncia o <strong>&#8220;g&#8221;<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ou seja, a pron\u00fancia fica como<\/span><\/p>\n<h5><b>somethin<\/b><br \/>\n<b>nothin<\/b><br \/>\n<b>singin<\/b><\/h5>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>4. O som de &#8220;i&#8221; vira &#8220;oi&#8221;<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">No australiano, o som de <strong>&#8220;i&#8221;<\/strong> do ingl\u00eas americano pode virar <strong>&#8220;oi&#8221;<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo,<\/span><\/p>\n<h5><b>like <\/b><span style=\"font-weight: 400;\">\uff1d loik<\/span><br \/>\n<b>bike\u00a0<\/b><span style=\"font-weight: 400;\"> = boik<\/span><br \/>\n<b>right<\/b><span style=\"font-weight: 400;\"> = roit<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea n\u00e3o estiver acostumado, pode soar estranho para voc\u00ea.<\/span><\/p>\n<p><span style=\"text-decoration: underline;\"><strong>5. &#8220;a&#8221; vira &#8220;ai&#8221;<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Na Austr\u00e1lia, muitas pessoas pronunciam o <strong>&#8220;a&#8221; como &#8220;ai&#8221;<\/strong> em rela\u00e7\u00e3o ao ingl\u00eas americano.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo,<\/span><\/p>\n<h5><span style=\"font-weight: 400;\">today \uff1d todai<\/span><br \/>\n<span style=\"font-weight: 400;\">say = sai<\/span><br \/>\n<span style=\"font-weight: 400;\">face = faice<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Muita gente tamb\u00e9m lembra da famosa sauda\u00e7\u00e3o australiana:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">pensando em<\/span><\/p>\n<p><samp><span style=\"font-weight: 400;\">G\u2019day, mate.<\/span><\/samp><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, <strong>&#8220;day&#8221; vira &#8220;dai&#8221;, &#8220;mate&#8221; vira &#8220;might&#8221;<\/strong>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>6. Entona\u00e7\u00e3o ascendente no final das frases<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">No ingl\u00eas australiano, mesmo frases afirmativas podem terminar com a entona\u00e7\u00e3o subindo. \u00c0s vezes, parece uma pergunta, sendo chamado de<\/span><\/p>\n<p><b>&#8220;Australian Question Intonation (AQI)&#8221;<\/b><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, isso n\u00e3o \u00e9 exclusivo da Austr\u00e1lia; muitos jovens nos EUA tamb\u00e9m usam esse tipo de entona\u00e7\u00e3o, ent\u00e3o \u00e9 bom prestar aten\u00e7\u00e3o.<\/span><\/p>\n<h3><strong>Abrevia\u00e7\u00f5es do ingl\u00eas australiano<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">No ingl\u00eas australiano h\u00e1 muitas abrevia\u00e7\u00f5es. Por isso, mesmo com americanos ou brit\u00e2nicos, pode haver momentos em que n\u00e3o consigam se comunicar bem.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aqui apresentamos algumas das abrevia\u00e7\u00f5es mais populares do ingl\u00eas australiano.<\/span><\/p>\n<p><samp><b>\u30fbArvo<\/b><span style=\"font-weight: 400;\"> : Abrevia\u00e7\u00e3o de Afternoon.<\/span><br \/>\n<b>\u30fbBarbie\uff1a<\/b><span style=\"font-weight: 400;\">Abrevia\u00e7\u00e3o de Barbecue.<\/span><br \/>\n<b>\u30fbBrekky\uff1a<\/b><span style=\"font-weight: 400;\"> Abrevia\u00e7\u00e3o de Breakfast.<\/span><br \/>\n<b>\u30fbChoccy\uff1a<\/b><span style=\"font-weight: 400;\"> Abrevia\u00e7\u00e3o de Chocolate.<\/span><br \/>\n<b>\u30fbChrissie<\/b><span style=\"font-weight: 400;\"> : Abrevia\u00e7\u00e3o de Christmas.<\/span><br \/>\n<b>\u30fbLappy<\/b><span style=\"font-weight: 400;\"> : Abrevia\u00e7\u00e3o de Laptop.<\/span><br \/>\n<b>\u30fbMaccas<\/b><span style=\"font-weight: 400;\"> : Abrevia\u00e7\u00e3o de McDonald&#8217;s.<\/span><br \/>\n<b>\u30fbMozzie<\/b><span style=\"font-weight: 400;\"> : Abrevia\u00e7\u00e3o de Mosquito.<\/span><br \/>\n<b>\u30fbRellie<\/b><span style=\"font-weight: 400;\"> : Abrevia\u00e7\u00e3o de Relative.<\/span><br \/>\n<b>\u30fbSanga<\/b><span style=\"font-weight: 400;\"> : Abrevia\u00e7\u00e3o de Sandwich.<\/span><br \/>\n<b>\u30fbSunnies<\/b><span style=\"font-weight: 400;\"> : Abrevia\u00e7\u00e3o de Sunglasses.<\/span><br \/>\n<b>\u30fbServo<\/b><span style=\"font-weight: 400;\"> : Abrevia\u00e7\u00e3o de Service station, ou seja, posto de gasolina.<\/span><\/samp><\/p>\n<p><span style=\"font-weight: 400;\">Essas s\u00e3o algumas das abrevia\u00e7\u00f5es usadas na Austr\u00e1lia. Existem muitas outras abrevia\u00e7\u00f5es usadas frequentemente, n\u00e3o sendo poss\u00edvel listar todas aqui. De maneira geral, as abrevia\u00e7\u00f5es costumam terminar em &#8220;o&#8221; ou &#8220;e&#8221;, ent\u00e3o fique atento a isso.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Por que o interc\u00e2mbio na Austr\u00e1lia \u00e9 t\u00e3o popular?<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Apesar da pron\u00fancia e das express\u00f5es do ingl\u00eas australiano serem \u00fanicas, a Austr\u00e1lia ainda \u00e9 uma escolha muito popular entre os estudantes de interc\u00e2mbio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, listamos alguns motivos para a popularidade do interc\u00e2mbio na Austr\u00e1lia.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Mensalidades e passagens a\u00e9reas baratas<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">As escolas de idiomas na Austr\u00e1lia costumam ser mais baratas do que nos EUA \/ Reino Unido.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, h\u00e1 muitas companhias a\u00e9reas de baixo custo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para quem quer reduzir o custo total do interc\u00e2mbio (que pode ser bastante alto) ou para quem deseja voltar para casa facilmente, a Austr\u00e1lia \u00e9 uma op\u00e7\u00e3o de \u00f3timo custo-benef\u00edcio.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Clima agrad\u00e1vel<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A Austr\u00e1lia \u00e9 um pa\u00eds extenso e o clima varia de regi\u00e3o para regi\u00e3o, mas em geral tem um clima considerado confort\u00e1vel para muitos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, Brisbane e Gold Coast t\u00eam clima subtropical e, mesmo no inverno, as temperaturas durante o dia chegam a cerca de 25\u2103, sendo poss\u00edvel usar s\u00f3 uma camiseta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, em Sydney, que tem as quatro esta\u00e7\u00f5es bem definidas, a temperatura m\u00e9dia anual tamb\u00e9m fica em torno de 25\u2103, dando uma sensa\u00e7\u00e3o de ser mais fresca do que no Brasil.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, algumas pessoas escolhem a Austr\u00e1lia para interc\u00e2mbio por n\u00e3o gostarem do frio.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Relativamente seguro<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Dizem que a Austr\u00e1lia \u00e9 um dos pa\u00edses mais seguros do mundo. No<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Ranking de Seguran\u00e7a de 60 Cidades Globais de 2019<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Sydney ficou em 5\u1d52 lugar e Melbourne em 10\u1d52<\/strong>, mostrando o n\u00edvel de seguran\u00e7a do pa\u00eds.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Pequena diferen\u00e7a de fuso hor\u00e1rio<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Existem diferentes fusos hor\u00e1rios dentro da Austr\u00e1lia, mas em compara\u00e7\u00e3o com os Estados Unidos\/Reino Unido, a diferen\u00e7a em rela\u00e7\u00e3oao Brasil \u00e9 menor.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, <strong>o hor\u00e1rio de Sydney \u00e9 13 horas \u00e0 frente de Brasil<\/strong>.<\/span><\/p>\n<p><strong>Londres \u00e9 4 horas atr\u00e1s de Brasil<\/strong><\/p>\n<p><strong>Nova York est\u00e1 2 horas atr\u00e1s<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Comparando, vemos que o fuso hor\u00e1rio da Austr\u00e1lia \u00e9 bem menor.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Portanto, se voc\u00ea mant\u00e9m contato frequente com fam\u00edlia e amigos em Brasil, morar na Austr\u00e1lia pode ser mais conveniente para voc\u00ea.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>No fim, o ingl\u00eas \u00e9 o mesmo<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Apesar das pron\u00fancias e express\u00f5es pr\u00f3prias do ingl\u00eas australiano, no final das contas o ingl\u00eas \u00e9 ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estudar ingl\u00eas na Austr\u00e1lia n\u00e3o impede sua comunica\u00e7\u00e3o com americanos ou brit\u00e2nicos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Afinal, australianos, americanos e brit\u00e2nicos todos podem se entender conversando em ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quem pensa em interc\u00e2mbio normalmente n\u00e3o se preocupa muito com as diferen\u00e7as do ingl\u00eas, mas foca nos outros benef\u00edcios e escolhe o destino que mais se adequa \u00e0s suas necessidades.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ali\u00e1s, depois que voc\u00ea aprender a falar ingl\u00eas com sotaque australiano, pode adaptar sua pron\u00fancia para o americano ou brit\u00e2nico, ent\u00e3o n\u00e3o precisa se preocupar muito.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Resumo<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Algumas pessoas podem achar que o ingl\u00eas australiano tem regras de pron\u00fancia e formas de express\u00e3o completamente desconhecidas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sobre a pron\u00fancia, voc\u00ea pode consultar o <strong>YouTube\u00a0 \u00a0<\/strong><\/span><b>&#8220;Australian accent&#8221;<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Se procurar na internet, encontrar\u00e1 muitos v\u00eddeos sobre o sotaque australiano. Vale a pena conferir.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora este artigo seja sobre ingl\u00eas australiano, h\u00e1 ainda o ingl\u00eas de outros pa\u00edses angl\u00f3fonos.<\/span><\/p>\n<p><samp><strong>Estados Unidos<\/strong><br \/>\n<strong>Canad\u00e1<\/strong><br \/>\n<strong>Inglaterra<\/strong><br \/>\n<strong>Nova Zel\u00e2ndia<\/strong><br \/>\n<strong>\u00c1frica do Sul<\/strong><\/samp><\/p>\n<p><span style=\"font-weight: 400;\">e outros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cada pa\u00eds tem sua pr\u00f3pria pron\u00fancia e express\u00f5es \u00fanicas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Claro, ao aprender ingl\u00eas, mesmo sem conhecer as diferen\u00e7as dos ingleses de outros pa\u00edses, voc\u00ea ainda pode falar ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, entender essas diferen\u00e7as pode tornar o estudo do ingl\u00eas ainda mais interessante e divertido, ent\u00e3o n\u00e3o deixe de conferir as caracter\u00edsticas do ingl\u00eas de outros pa\u00edses!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em muitos pa\u00edses do mundo fala-se ingl\u00eas. Mas, dependendo do pa\u00eds, o ingl\u00eas pode apresentar diferen\u00e7as. Voc\u00ea pode se perguntar &#8220;Qual \u00e9 a diferen\u00e7a entre o ingl\u00eas australiano e o ingl\u00eas de outros pa\u00edses?&#8221; O ingl\u00eas australiano \u00e9 bastante distinto em compara\u00e7\u00e3o ao ingl\u00eas brit\u00e2nico \/ americano; se voc\u00ea n\u00e3o entender ou n\u00e3o estiver habituado, pode haver muitas situa\u00e7\u00f5es em que ficar\u00e1 confuso. Desta vez, vamos apresentar as caracter\u00edsticas da pron\u00fancia do ingl\u00eas australiano e as diferen\u00e7as nas formas de express\u00e3o. &nbsp; Hist\u00f3ria do ingl\u00eas australiano &nbsp; Em ingl\u00eas, o ingl\u00eas australiano \u00e9 chamado de Australian English Aussie English Segundo a\u00a0 Wikipedia, a origem da pron\u00fancia australiana vem dos sotaques &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/12313\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":12353,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=12313","footnotes":""},"categories":[130,111,112],"tags":[],"class_list":["post-12313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-usable","category-exam","category-toeic","pt-BR"],"aioseo_notices":[],"views":530,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=12313"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12313\/revisions"}],"predecessor-version":[{"id":12315,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/12313\/revisions\/12315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/12353"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=12313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=12313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=12313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}