{"id":11209,"date":"2025-08-04T09:00:37","date_gmt":"2025-08-04T12:00:37","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=11209"},"modified":"2025-07-23T01:45:12","modified_gmt":"2025-07-23T04:45:12","slug":"a-diferenca-entre-maybe-probably-e-perhaps-com-base-no-grau-de-certeza","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/11209\/","title":{"rendered":"A diferen\u00e7a entre maybe, probably e perhaps com base no grau de certeza."},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Voc\u00ea costuma usar as palavras\u00a0 \u201cdeve ser\u201d\u00a0 ou\u00a0 \u201cprovavelmente\u201d\u00a0 em conversas do dia a dia? Acredito que a maioria das pessoas pode acabar dizendo essas palavras sem perceber.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No ingl\u00eas, tamb\u00e9m existem palavras como \u201cdeve ser\u201d e \u201cprovavelmente\u201d, e s\u00e3o frequentemente usadas em conversas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essas palavras s\u00e3o muito familiares para n\u00f3s, mas, pensando bem, como os falantes nativos diferenciam o uso delas?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora as palavras do t\u00edtulo tenham significados semelhantes, o importante \u00e9 saber como e quando us\u00e1-las corretamente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na verdade, muitas pessoas podem usar apenas maybe para expressar \u201cdeve ser\u201d ou \u201cprovavelmente\u201d em conversas cotidianas. No entanto, os falantes nativos realmente diferenciam o uso dessas palavras.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para quem est\u00e1 come\u00e7ando a aprender ingl\u00eas, maybe \u00e9 uma palavra muito pr\u00e1tica. Mas, se voc\u00ea conseguir entender e diferenciar o uso de outras palavras com o mesmo significado, isso ajudar\u00e1 a melhorar suas habilidades em ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desta vez, vou apresentar <strong><span style=\"color: #cf00c1;\">tr\u00eas palavras que significam \u201cdeve ser\u201d ou \u201cprovavelmente\u201d<\/span><\/strong>, al\u00e9m de outras palavras em ingl\u00eas que ajudar\u00e3o a aprimorar seu ingl\u00eas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Diferen\u00e7as entre maybe \/ probably \/ perhaps<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, vamos explicar as diferen\u00e7as entre as representativas <strong><span style=\"color: #ff0000;\">maybe, probably e perhaps<\/span><\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00ea sente que essas tr\u00eas palavras em ingl\u00eas s\u00e3o familiares? J\u00e1 as viu em algum lugar?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Acho que muitas pessoas j\u00e1 viram essas palavras ao estudar vocabul\u00e1rio, ou as ouviram em cursos de ingl\u00eas online, filmes ou s\u00e9ries durante o aprendizado do idioma.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Isso porque s\u00e3o palavras muito \u00fateis e aparecem com frequ\u00eancia em conversas em ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aqui, conversas em ingl\u00eas n\u00e3o incluem apenas di\u00e1logos entre nativos, mas tamb\u00e9m filmes, s\u00e9ries, anima\u00e7\u00f5es, etc.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Basicamente, a diferen\u00e7a entre essas tr\u00eas palavras est\u00e1 no grau de certeza. Os falantes nativos escolhem usar maybe, probably ou perhaps de acordo com o n\u00edvel de certeza do conte\u00fado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ent\u00e3o, qual \u00e9 o grau de certeza e em que n\u00edvel se usa cada palavra?<\/span><\/p>\n<h6><span style=\"font-weight: 400;\">perhaps 30\/40%: talvez, possivelmente, provavelmente<\/span><br \/>\n<span style=\"font-weight: 400;\">maybe 40\/50%: talvez, possivelmente, provavelmente<\/span><br \/>\n<span style=\"font-weight: 400;\">probably 80\/90%: muito provavelmente, provavelmente<\/span><\/h6>\n<p><span style=\"font-weight: 400;\">Essas s\u00e3o, em linhas gerais, as faixas de certeza de cada palavra.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ao ver essa lista, voc\u00ea pode pensar: ent\u00e3o, qual palavra usar para 70%? E para 60%? Nesses casos, pode-se escolher entre maybe ou probably.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essa tabela \u00e9 apenas um padr\u00e3o aproximado, pois a sensa\u00e7\u00e3o de certeza varia de pessoa para pessoa. Basta escolher a palavra de acordo com o grau de certeza que voc\u00ea sente sobre o assunto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Maybe pode ser usada de forma mais casual, por isso \u00e9 frequentemente ouvida em conversas em ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por outro lado, perhaps \u00e9 uma express\u00e3o mais formal, sendo mais comum em textos, mas tamb\u00e9m pode ser usada em conversas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vamos explicar detalhadamente cada uma dessas tr\u00eas palavras e apresentar alguns exemplos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Como usar maybe<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Vamos come\u00e7ar falando sobre como usar maybe.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Grau de certeza de maybe: 40\/50%<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quando voc\u00ea <strong><span style=\"color: #ff0000;\">tem um certo grau de certeza<\/span><\/strong> sobre algo, usar maybe \u00e9 uma boa escolha.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 uma das palavras mais f\u00e1ceis e descontra\u00eddas de usar em ingl\u00eas, por isso \u00e9 muito pr\u00e1tica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tamb\u00e9m pode ser usada quando o grau de certeza \u00e9 baixo, sendo a palavra mais flex\u00edvel. Mas \u00e9 importante notar que, por ser t\u00e3o livre, \u00e0s vezes o uso de maybe pode deixar o interlocutor irritado devido \u00e0 sua ambiguidade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O uso excessivo de maybe pode passar a impress\u00e3o de hesita\u00e7\u00e3o ou resposta vaga, fazendo o outro sentir que voc\u00ea est\u00e1 evitando a quest\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por outro lado, se quiser evitar responder diretamente, usar maybe \u00e9 uma op\u00e7\u00e3o, mas tome cuidado para n\u00e3o exagerar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se o grau de certeza for apenas \u201cmaybe\u201d, mas na verdade for ainda menor, mudar a forma de falar tamb\u00e9m \u00e9 uma alternativa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, dizer maybe com um tom hesitante, ou antes de responder maybe, dizer Well\u2026maybe??, transmite a sensa\u00e7\u00e3o de \u201chmm, talvez?\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No entanto, esse tipo de resposta tamb\u00e9m pode irritar o interlocutor, ent\u00e3o avalie se deve mudar a forma de falar de acordo com o ritmo da conversa e o n\u00edvel de confian\u00e7a com a pessoa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Maybe geralmente \u00e9 usada no in\u00edcio da frase, mas em alguns casos pode aparecer no meio ou no final. Por exemplo:<\/span><\/p>\n<h5><strong>The day after tomorrow will maybe clear up.<\/strong><br \/>\n<span style=\"font-weight: 400;\">Depois de amanh\u00e3 talvez fa\u00e7a sol.<\/span><\/h5>\n<h5><strong>Maybe tomorrow I&#8217;ll get my package.<\/strong><br \/>\n<span style=\"font-weight: 400;\">Talvez eu receba meu pacote amanh\u00e3.<\/span><\/h5>\n<h5><strong>Maybe I&#8217;ll show up at the party tomorrow.<\/strong><br \/>\n<span style=\"font-weight: 400;\">Talvez eu apare\u00e7a na festa amanh\u00e3.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><strong>Como usar probably<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Agora vamos falar sobre como usar probably.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Grau de certeza de probably: 80\/90%<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Use \u201cprobably\u201d para\u00a0 <strong><span style=\"color: #ff0000;\">as respostas ou conte\u00fados de que voc\u00ea tem mais certeza<\/span><\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cProbably\u201d significa \u201cprovavelmente\u201d, \u201ctalvez\u201d, e \u00e9 usada para indicar que a chance de algo acontecer \u00e9 alta, mas n\u00e3o 100% certa. Ao usar \u201cprobably\u201d, normalmente h\u00e1 uma base razo\u00e1vel para acreditar nisso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, se um amigo perguntar: \u201cSexta-feira que vem vou jantar com colegas em um restaurante na rua XX, se puder, quer ir junto?\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se nesse dia voc\u00ea estiver trabalhando a cerca de 10 minutos do local, mas ainda n\u00e3o souber o hor\u00e1rio de sa\u00edda, pode responder: \u201cEu (provavelmente) posso ir. Mas ainda n\u00e3o sei o hor\u00e1rio, te aviso depois.\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nessas situa\u00e7\u00f5es, em que h\u00e1 uma base clara, \u00e9 adequado usar probably em ingl\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Probably geralmente aparece no meio da frase, mas em alguns casos pode ser usada no in\u00edcio ou no final. Por exemplo:<\/span><\/p>\n<h5><strong>She&#8217;ll probably come to the party today.<\/strong><br \/>\n<span style=\"font-weight: 400;\">Ela provavelmente vai \u00e0 festa hoje.<\/span><\/h5>\n<h5><strong>I will probably be in the US next year.<\/strong><br \/>\n<span style=\"font-weight: 400;\">Provavelmente estarei nos EUA no ano que vem.<\/span><\/h5>\n<h5><strong>I will probably be in Fortaleza that day.<\/strong><br \/>\n<span style=\"font-weight: 400;\">Provavelmente estarei em Fortaleza naquele dia.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><strong>Como usar perhaps<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Por fim, vamos discutir o uso de perhaps.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Grau de certeza de perhaps: 30\/40%<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Entre todas as palavras que discutimos, use <strong><span style=\"color: #ff0000;\">perhaps quando o grau de certeza for o mais baixo<\/span><\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se houver muitos fatores incertos, pode-se usar \u201cperhaps\u201d, mas como expliquei acima, essa palavra em ingl\u00eas \u00e9 mais formal, ent\u00e3o \u00e9 menos usada em conversas cotidianas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em conversas em ingl\u00eas, geralmente se usa Maybe, enquanto <strong><span style=\"color: #0000ff;\">perhaps \u00e9 mais comum na linguagem escrita, por isso os nativos parecem usar pouco perhaps no dia a dia<\/span><\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Portanto, mesmo em situa\u00e7\u00f5es de baixa certeza, recomenda-se usar maybe, em parte porque perhaps \u00e9 mais usado em linguagem formal e escrita, sendo menos comum em conversas cotidianas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ou seja, em conversas em ingl\u00eas, geralmente se usa maybe para expressar o grau de certeza de perhaps.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Perhaps pode ser usado no in\u00edcio, meio ou fim da frase.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora os exemplos aqui sejam de estilo oral, na pr\u00e1tica, como dito antes, \u00e9 pouco usado em conversas do dia a dia. Por exemplo:<\/span><\/p>\n<h5><strong>I will perhaps go to the show next week, but it depends on my work schedule.<\/strong><br \/>\n<span style=\"font-weight: 400;\">Talvez eu v\u00e1 ao show na pr\u00f3xima semana, mas depende da minha agenda de trabalho.<\/span><\/h5>\n<h5><strong>Perhaps what he said was true.<\/strong><br \/>\n<span style=\"font-weight: 400;\">Talvez o que ele disse seja verdade.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><strong>Outras formas semelhantes de express\u00e3o<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A seguir, vou apresentar mais duas palavras em ingl\u00eas que podem ser usadas para expressar \u201ctalvez\u201d ou \u201cpossivelmente\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00ea pode achar que n\u00e3o consegue memorizar mais nada! Mas, como conhecimento, \u00e9 importante saber sobre elas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o \u00e9 necess\u00e1rio memoriz\u00e1-las de prop\u00f3sito, mas tente deix\u00e1-las em algum canto da sua mente.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>presumably<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, presumably.<\/span><\/p>\n<h5><strong>Presumably<\/strong><br \/>\n<span style=\"font-weight: 400;\">Presumivelmente, deve ser. O grau de possibilidade \u00e9 semelhante ao de probably.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Probably \u00e9 usado para expressar uma credibilidade acima de 80%, enquanto <strong><span style=\"color: #ff0000;\">presumably carrega o sentido de \u201cconsiderando logicamente, a possibilidade \u00e9 alta\u201d<\/span><\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como presumably inclui mais base l\u00f3gica, em situa\u00e7\u00f5es em que h\u00e1 uma justificativa mais concreta, pode-se optar por presumably em vez de probably, que pode ser usado junto com maybe.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>possibly<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Outra palavra \u00e9 possibly.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Muitas pessoas provavelmente j\u00e1 ouviram essa palavra.<\/span><\/p>\n<h5><strong>possibly<br \/>\n<\/strong><span style=\"font-weight: 400;\">Deve ser. Grau de certeza abaixo de 10%.<\/span><\/h5>\n<p><span style=\"font-weight: 400;\">Quando <strong><span style=\"color: #ff0000;\">o grau de certeza \u00e9 muito baixo, embora n\u00e3o seja zero, mas quase nulo<\/span><\/strong>, usa-se possibly.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ao conversar com nativos, se ouvir possibly, pode entender que a possibilidade de acontecer \u00e9 quase nula.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Resumo<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Essas tr\u00eas palavras em ingl\u00eas que expressam \u201cdeve ser\u201d aparecem com frequ\u00eancia nas conversas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora express\u00f5es como \u201cdeve ser\u201d sejam pr\u00e1ticas no dia a dia, lembre-se de que h\u00e1 v\u00e1rias palavras assim no ingl\u00eas e \u00e9 preciso escolher a mais adequada para cada situa\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, essas tr\u00eas palavras tamb\u00e9m podem ser usadas em ambientes de neg\u00f3cios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em discuss\u00f5es de neg\u00f3cios, \u00e9 comum falar sobre o grau de certeza de v\u00e1rias situa\u00e7\u00f5es, ent\u00e3o n\u00e3o \u00e9 raro usar essas palavras para responder.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ao aprender a diferenciar corretamente o uso dessas palavras em ingl\u00eas, voc\u00ea ampliar\u00e1 suas habilidades no idioma, o que naturalmente melhorar\u00e1 seu ingl\u00eas. Mesmo que seja pouco a pouco, lembre-se de aprender e distinguir o uso delas.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea costuma usar as palavras\u00a0 \u201cdeve ser\u201d\u00a0 ou\u00a0 \u201cprovavelmente\u201d\u00a0 em conversas do dia a dia? Acredito que a maioria das pessoas pode acabar dizendo essas palavras sem perceber. No ingl\u00eas, tamb\u00e9m existem palavras como \u201cdeve ser\u201d e \u201cprovavelmente\u201d, e s\u00e3o frequentemente usadas em conversas. Essas palavras s\u00e3o muito familiares para n\u00f3s, mas, pensando bem, como os falantes nativos diferenciam o uso delas? Embora as palavras do t\u00edtulo tenham significados semelhantes, o importante \u00e9 saber como e quando us\u00e1-las corretamente. Na verdade, muitas pessoas podem usar apenas maybe para expressar \u201cdeve ser\u201d ou \u201cprovavelmente\u201d em conversas cotidianas. No entanto, os falantes nativos realmente diferenciam o uso dessas palavras. Para quem est\u00e1 &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/11209\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":11210,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=11209","footnotes":""},"categories":[128,120,122],"tags":[],"class_list":["post-11209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business","category-grammar","category-pronunciation","pt-BR"],"aioseo_notices":[],"views":450,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/11209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=11209"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/11209\/revisions"}],"predecessor-version":[{"id":11211,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/11209\/revisions\/11211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/11210"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=11209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=11209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=11209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}