{"id":10792,"date":"2025-07-24T09:00:18","date_gmt":"2025-07-24T12:00:18","guid":{"rendered":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=10792"},"modified":"2025-07-11T04:50:29","modified_gmt":"2025-07-11T07:50:29","slug":"ir-ao-massagista-frases-e-dialogos-em-ingles-que-voce-pode-usar-explicacao-dos-dois-pontos-de-vista-do-estabelecimento-e-do-cliente","status":"publish","type":"post","link":"https:\/\/nativecamp.net\/pt-br\/blog\/10792\/","title":{"rendered":"Ir ao massagista: frases e di\u00e1logos em ingl\u00eas que voc\u00ea pode usar! Explica\u00e7\u00e3o dos dois pontos de vista: do estabelecimento e do cliente."},"content":{"rendered":"<h2><b>Fazer massagem durante viagens ao exterior \u00e9 muito popular!<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Devido \u00e0 pandemia de COVID-19, n\u00e3o pudemos viajar para o exterior livremente. Acho que muitas pessoas decidiram\u00a0 <\/span><b>\u201cAssim que a pandemia acabar, vou viajar para o exterior imediatamente!\u201d<\/b><span style=\"font-weight: 400;\">, n\u00e3o \u00e9?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pensar para onde ir e o que fazer, planejar v\u00e1rias atividades \u00e9 realmente algo muito divertido. E, por outro lado, agora que temos mais tempo livre, pode ser uma \u00f3tima oportunidade para planejar bem sua viagem.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Atividades como passear comendo, visitar pontos tur\u00edsticos famosos ou fazer compras s\u00e3o muito divertidas, mas tratamentos como massagem ou cuidados de beleza, que permitem relaxar completamente e aliviar o cansa\u00e7o da viagem, tamb\u00e9m s\u00e3o muito populares!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quem experimenta uma vez com certeza vai se apaixonar!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, desta vez vou apresentar para voc\u00eas<strong> <span style=\"color: #d609d6;\">frases e di\u00e1logos em ingl\u00eas que podem ser usados em situa\u00e7\u00f5es de massagem e tratamentos de beleza durante a viagem<\/span>.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Frases e di\u00e1logos em ingl\u00eas para usar ao receber uma massagem<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Primeiro, frases pr\u00e1ticas e \u00fateis para <strong>quem \u00e9 cliente e vai receber a massagem<\/strong>. Vou apresentar as principais frases de acordo com a situa\u00e7\u00e3o.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Fazendo uma reserva<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>May I make a reservation, please?<\/b><br \/>\nPosso fazer uma reserva?<br \/>\n<b>I\u2019d like to make an appointment at 5 p.m.<\/b><br \/>\nGostaria de marcar um hor\u00e1rio \u00e0s 17h.<br \/>\n<b>Can I make a reservation this afternoon?<\/b><br \/>\nPosso reservar para esta tarde?<br \/>\n<b>Do you have any slots open today?<\/b><br \/>\nTem algum hor\u00e1rio dispon\u00edvel hoje?<br \/>\n<b>Is it available?<\/b><br \/>\nEst\u00e1 dispon\u00edvel hoje?<br \/>\n<b>Hello, may I make a reservation for two people on July 14th around 5 p.m?<br \/>\nMy name is Karina. My phone number is 000-0000-0000.<\/b><br \/>\nOl\u00e1, posso reservar para duas pessoas no dia 14 de julho, por volta das 17h?<br \/>\nMeu nome \u00e9 Karina. Meu telefone \u00e9 000-0000-0000.<br \/>\n<b>I\u2019d like to make a reservation. Is it available at 5 p.m. on July 14th?<\/b><br \/>\nGostaria de fazer uma reserva. Est\u00e1 dispon\u00edvel \u00e0s 17h do dia 14 de julho?<br \/>\n<b>Is it possible to get a massage now?<\/b><br \/>\n\u00c9 poss\u00edvel fazer uma massagem agora?<br \/>\n<b>When is the massage open?<\/b><br \/>\nQual o hor\u00e1rio de funcionamento da massagem?<br \/>\n<b>Do I need to make a reservation?<\/b><br \/>\nPreciso fazer reserva?<br \/>\n<b>I prefer a masseuse.<\/b><br \/>\nPrefiro uma massagista mulher.<\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Escolhendo o tratamento<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>Can I see the menu?<\/b><br \/>\nPosso ver o card\u00e1pio de tratamentos?<br \/>\n<b>What kinds of courses do you have?<\/b><br \/>\nQuais tipos de tratamentos voc\u00eas oferecem?<br \/>\n<b>Which course\/service do you recommend?<\/b><br \/>\nQual tratamento voc\u00ea recomenda?<br \/>\n<b>I\u2019d like to have a full-body massage.<\/b><br \/>\nQuero uma massagem corporal completa.<br \/>\n<b>So, I&#8217;ll go for a head massage.<\/b><br \/>\nEnt\u00e3o, vou querer uma massagem na cabe\u00e7a.<br \/>\n<b>I\u2019d like to book a leg massage.<\/b><br \/>\nQuero reservar uma massagem nas pernas.<\/h5>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Quando a pessoa responder \u201cQue tal escolher ?\u201d, se voc\u00ea quiser dizer\u00a0 <strong>\u201cPode ser esse!\u201d<\/strong>, pode responder\u00a0 <\/span><b>\u201cThat&#8217;d be wonderful.\u201d ou \u201cThat&#8217;d be great.\u201d.<\/b><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Quando a reserva for confirmada<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>Thank you. We are looking forward to it.<\/b><br \/>\nObrigado. Estamos ansiosos.<\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Na hora de pagar<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>Do you take credit cards?<\/b><br \/>\nAceita cart\u00e3o de cr\u00e9dito?<\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Para confirmar ou alterar a reserva<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>I\u2019d like to reconfirm my reservation.<\/b><br \/>\nGostaria de confirmar minha reserva novamente.<br \/>\n<b>I\u2019d like to cancel my reservation, please.<\/b><br \/>\nGostaria de cancelar minha reserva.<br \/>\n<b>Is it possible to rebook?<\/b><br \/>\n\u00c9 poss\u00edvel remarcar minha reserva?<\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Frases para usar durante a massagem<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>I have a stiff shoulder.<\/b><br \/>\nEstou com o ombro r\u00edgido.<br \/>\n<b>Could you please concentrate on my neck and shoulder, and upper back areas?<\/b><br \/>\nPode focar no meu pesco\u00e7o, ombros e parte superior das costas?<\/h5>\n<p><span style=\"font-weight: 400;\">Se quiser dizer \u201cna regi\u00e3o da lombar\u201d, basta falar\u00a0 <\/span><b>\u201clower back areas\u201d<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Para pedir mais ou menos for\u00e7a<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>A little stronger, please.<\/b><br \/>\nUm pouco mais forte, por favor.<br \/>\n<b>A little softer, please.<\/b><br \/>\nUm pouco mais suave, por favor.<br \/>\n<b>It\u2019s a little too strong.<\/b><br \/>\nEst\u00e1 um pouco forte demais.<br \/>\n<b>It\u2019s a little too soft.<\/b><br \/>\nEst\u00e1 um pouco fraco.<br \/>\n<b>It hurts a little.<\/b><br \/>\nEst\u00e1 doendo um pouco.<br \/>\n<b>I feel so good.<\/b><br \/>\nEstou me sentindo muito bem.<\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Frases para usar ap\u00f3s o tratamento<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Depois do tratamento, agrade\u00e7a ao massagista ou terapeuta!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m de\u00a0 <\/span><b>\u201cThank you.\u201d<\/b><span style=\"font-weight: 400;\"> e o nome do terapeuta, acrescentar mais uma frase vai deixar seu ingl\u00eas ainda mais sofisticado!<\/span><\/p>\n<h5><b>Thank you, \u25cf\u25cf\uff08Name\uff09. I am very grateful for your help.<\/b><br \/>\nObrigado, <span style=\"font-weight: 400;\">\u25cf\u25cf(nome). Sou muito grato(a) pela sua ajuda.<\/span><br \/>\n<b>I had a great time here. Thank you, \u25cf\u25cf\uff08Name\uff09.<\/b><br \/>\nGostei muito daqui. Obrigado(a), <span style=\"font-weight: 400;\">\u25cf\u25cf(nome).<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Frases e di\u00e1logos em ingl\u00eas para quem atende clientes de massagem<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Aqui vou apresentar frases do <strong>ponto de vista do estabelecimento ou do massagista<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea souber de antem\u00e3o quais perguntas os funcion\u00e1rios e massagistas costumam fazer, na pr\u00f3xima vez que for receber uma massagem, n\u00e3o ficar\u00e1 perdido(a) ao ouvir o que o terapeuta est\u00e1 dizendo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, com a diminui\u00e7\u00e3o da pandemia, quando as viagens internacionais forem liberadas, o n\u00famero de clientes estrangeiros tamb\u00e9m deve aumentar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As frases em ingl\u00eas apresentadas aqui s\u00e3o \u00fateis para massagistas e esteticistas que atendem clientes estrangeiros, e mesmo quem n\u00e3o \u00e9 profissional pode memoriz\u00e1-las.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Recebendo reservas<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>When would you like to book it?<\/b><br \/>\nPara quando voc\u00ea gostaria de reservar?<br \/>\n<b>Thank you. How about 4 p.m?<\/b><br \/>\nObrigado. Que tal \u00e0s 16h?<br \/>\n<b>Certainly. May I have your name and phone number, please?<\/b><br \/>\nClaro. Posso anotar seu nome e telefone?<br \/>\n<b>I\u2019m afraid it\u2019s not available. How about 1 p.m. on July 18?<\/b><br \/>\nInfelizmente n\u00e3o est\u00e1 dispon\u00edvel. Que tal \u00e0s 13h do dia 18 de julho?<br \/>\n<b>How about 6 p.m?<\/b><br \/>\nQue tal \u00e0s 18h?<\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Quando o cliente escolhe o tratamento<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>What kind of service would you like?<\/b><br \/>\nQue tipo de servi\u00e7o voc\u00ea gostaria?<br \/>\n<b>Is there anyone in particular you would like for the massage course?<\/b><br \/>\nVoc\u00ea gostaria de algum massagista em especial para o tratamento?<\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Informando que a reserva foi confirmada<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>S<\/b><b>o, your reservation is confirmed.<\/b><br \/>\nSua reserva est\u00e1 confirmada.<br \/>\n<b>That\u2019s all booked in for you.<\/b><br \/>\nTudo est\u00e1 reservado para voc\u00ea.<br \/>\n<b>Please call us if something has changed.<\/b><br \/>\nSe houver alguma altera\u00e7\u00e3o, por favor, nos avise.<br \/>\n<b>We are looking forward to seeing you on Saturday. Have a nice day!<\/b><br \/>\nEsperamos v\u00ea-lo(a) no s\u00e1bado. Tenha um \u00f3timo dia!<\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Na hora do pagamento<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>Your total is 100 Reais.<\/b><br \/>\nO total \u00e9 100 Real.<br \/>\n<b>Would you like to pay in cash or by credit card or debit card?<\/b><br \/>\nVoc\u00ea gostaria de pagar em dinheiro, cart\u00e3o de cr\u00e9dito ou d\u00e9bito?<br \/>\n<b>Cash or charge?<\/b><br \/>\nDinheiro ou cart\u00e3o?<br \/>\n<b>I\u2019m afraid we don\u2019t accept credit cards or debit cards.<\/b><br \/>\nDesculpe, n\u00e3o aceitamos cart\u00e3o de cr\u00e9dito ou d\u00e9bito.<br \/>\n<b>You&#8217;ll pay by card. Certainly. Please enter your PIN. And could you sign here, please?<\/b><br \/>\nVoc\u00ea vai pagar com cart\u00e3o. Certo. Por favor, digite sua senha e assine aqui.<\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Explica\u00e7\u00f5es ou perguntas antes da massagem<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>Hello, I&#8217;m Sabrina. I&#8217;ll be your massage therapist today.<\/b><br \/>\nOl\u00e1, sou Sabrina, sua massagista hoje.<br \/>\n<b>Please change to this bathrobe.<\/b><br \/>\nPor favor, troque por este roup\u00e3o.<br \/>\n<b>How\u2019s the room temperature?<\/b><br \/>\nComo est\u00e1 a temperatura da sala?<br \/>\n<b>What parts of your body are stiff or tender?<\/b><br \/>\nQuais partes do seu corpo est\u00e3o r\u00edgidas ou doloridas?<br \/>\n<b>Do you have any injuries?<\/b><br \/>\nVoc\u00ea tem alguma les\u00e3o?<br \/>\n<b>Please lie down on the bed.<\/b><br \/>\nPor favor, deite-se na cama.<br \/>\n<b>Please lie on your back.<\/b><br \/>\nPor favor, deite-se de costas.<br \/>\n<b>Please lie on your stomach. \/ Please lie face down.<\/b><br \/>\nPor favor, deite-se de bru\u00e7os.<br \/>\n<b>I\u2019m going to start by giving you a head massage.<\/b><br \/>\nVou come\u00e7ar com uma massagem na cabe\u00e7a.<\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Perguntando sobre a press\u00e3o durante a massagem<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>How is the pressure?<\/b><br \/>\nComo est\u00e1 a press\u00e3o?<br \/>\n<b>Is this position comfortable for you?<\/b><br \/>\nEssa posi\u00e7\u00e3o est\u00e1 confort\u00e1vel para voc\u00ea?<br \/>\n<b>Do you have anywhere else you feel stiff?<\/b><br \/>\nTem mais algum lugar que est\u00e1 r\u00edgido?<\/h5>\n<p>&nbsp;<\/p>\n<h3><b>Frases para usar ap\u00f3s a massagem<\/b><\/h3>\n<p>&nbsp;<\/p>\n<h5><b>OK, we&#8217;re done for today. Please put on your clothes.<\/b><br \/>\nPronto, terminamos por hoje. Por favor, pode se vestir.<br \/>\n<b>How did you like your foot massage today?<\/b><br \/>\nO que achou da massagem nos p\u00e9s de hoje?<br \/>\n<b>Can I get you anything to drink? We have tea, coffee, green tea, and herbal tea.<\/b><br \/>\nGostaria de beber algo? Temos ch\u00e1, caf\u00e9, ch\u00e1 verde e ch\u00e1 de ervas.<br \/>\n<b>I\u2019m happy to hear that!<\/b><br \/>\nFico feliz em ouvir isso!<br \/>\n<b>Thank you so much for coming today. We hope to see you soon. You have a great day!<\/b><br \/>\nMuito obrigado por ter vindo hoje. Esperamos v\u00ea-lo(a) novamente em breve. Tenha um \u00f3timo dia!<\/h5>\n<p>&nbsp;<\/p>\n<h2><b>Memorize as frases em ingl\u00eas que voc\u00ea quer usar durante a massagem e experimente!<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O que acharam?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desta vez, selecionei algumas frases f\u00e1ceis e frequentemente usadas para ensinar a voc\u00eas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se a conversa durante a massagem fluir bem, voc\u00ea pode evitar nervosismo desnecess\u00e1rio e relaxar corpo e mente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, se voc\u00ea conseguir conversar mais com o massagista usando essas frases, isso pode se tornar uma das lembran\u00e7as felizes da sua viagem.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fazer massagem durante viagens ao exterior \u00e9 muito popular! &nbsp; Devido \u00e0 pandemia de COVID-19, n\u00e3o pudemos viajar para o exterior livremente. Acho que muitas pessoas decidiram\u00a0 \u201cAssim que a pandemia acabar, vou viajar para o exterior imediatamente!\u201d, n\u00e3o \u00e9? Pensar para onde ir e o que fazer, planejar v\u00e1rias atividades \u00e9 realmente algo muito divertido. E, por outro lado, agora que temos mais tempo livre, pode ser uma \u00f3tima oportunidade para planejar bem sua viagem. Atividades como passear comendo, visitar pontos tur\u00edsticos famosos ou fazer compras s\u00e3o muito divertidas, mas tratamentos como massagem ou cuidados de beleza, que permitem relaxar completamente e aliviar o cansa\u00e7o da viagem, tamb\u00e9m s\u00e3o &hellip; <a href=\"https:\/\/nativecamp.net\/pt-br\/blog\/10792\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":10996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_locale":"pt_BR","_original_post":"https:\/\/nativecamp.net\/pt-br\/blog\/?p=10792","footnotes":""},"categories":[118,122,121],"tags":[],"class_list":["post-10792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-study-abroad","category-pronunciation","category-words","pt-BR"],"aioseo_notices":[],"views":530,"_links":{"self":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/10792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=10792"}],"version-history":[{"count":1,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/10792\/revisions"}],"predecessor-version":[{"id":10794,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/10792\/revisions\/10794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media\/10996"}],"wp:attachment":[{"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=10792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=10792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nativecamp.net\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=10792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}